{"id":6936,"date":"2023-04-14T00:01:35","date_gmt":"2023-04-13T22:01:35","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=6936"},"modified":"2023-04-13T16:15:41","modified_gmt":"2023-04-13T14:15:41","slug":"chitosano-plastiche-stampa-3d-140420239","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/","title":{"rendered":"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D?"},"content":{"rendered":"<p style=\"text-align: justify;\">Perch\u00e9 non utilizzare le nostre risorse naturali per ideare nuovi <a href=\"https:\/\/www.3dnatives.com\/it\/category\/materiali-3d\/\">materiali per la stampa 3D<\/a>? \u00c8 questo il pensiero di un gruppo di ricercatori di Malesia, Singapore, Thailandia e India. Hanno cercato di capire come utilizzare il chitosano, un polimero naturale presente in alcuni insetti, per creare una termoplastica composita compatibile con i <a href=\"https:\/\/www.3dnatives.com\/it\/modellazione-deposizione-fusa-021120219\/\">processi di estrusione<\/a>. L&#8217;obiettivo \u00e8 promuovere una produzione e un consumo pi\u00f9 sostenibili e rispettosi dell&#8217;ambiente. I test hanno portato allo sviluppo di diversi polimeri, tra cui un <a href=\"https:\/\/www.3dnatives.com\/it\/filamenti-pla-stampa-3d-261020219\/\">PLA<\/a> composito pi\u00f9 denso e pi\u00f9 resistente alla temperatura.<\/p>\n<p style=\"text-align: justify;\">Il chitosano deriva dalla chitina, una sostanza dura e impermeabile presente in alcuni insetti e nel guscio dei crostacei. \u00c8 un polimero naturale utilizzato in vari settori, come la cosmetica, la lavorazione degli alimenti e la medicina. Si caratterizza per la sua biodegradabilit\u00e0 e biocompatibilit\u00e0. Il chitosano pu\u00f2 essere estratto in vari modi e, se i nostri ricercatori erano interessati solo agli insetti terrestri, \u00e8 per evitare di dover ricorrere a processi come la deacetilazione, poco rispettosi dell&#8217;ambiente.<\/p>\n<div id=\"attachment_76565\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-76565\" class=\"size-full wp-image-76565\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2023\/04\/chitosane.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-76565\" class=\"wp-caption-text\">l chitosano \u00e8 spesso recuperato dai gusci dei crostacei<\/p><\/div>\n<p style=\"text-align: justify;\">Il team si \u00e8 quindi rivolto agli insetti terrestri come fonte sostenibile di chitosano, in quanto facilmente coltivabili senza danneggiare la salute del nostro pianeta. Tuttavia, l&#8217;uso del loro chitosano nella stampa rimane discusso. I ricercatori hanno dovuto condurre diversi esperimenti e test prima di ottenere risultati soddisfacenti. Innanzitutto, hanno scoperto che una matrice di PLA arricchita con chitosano e chitina di insetti terrestri era meno resistente e rigida. Maggiore \u00e8 la concentrazione, minore \u00e8 la resistenza. Che senso ha quindi aggiungere questa risorsa naturale alle plastiche in commercio?<\/p>\n<p style=\"text-align: justify;\">In ulteriori test, i ricercatori hanno osservato che i compositi PLA\/chitosano e PLA\/chitina presentavano una migliore duttilit\u00e0 rispetto al PLA puro. Va ricordato che la duttilit\u00e0 rappresenta la capacit\u00e0 di un materiale di deformarsi senza rompersi. Il chitosano potrebbe quindi essere utilizzato per indurire il PLA. I test hanno anche indicato che questi compositi hanno una buona stabilit\u00e0 termica e propriet\u00e0 di compressione interessanti per applicazioni, ad esempio, nel settore degli imballaggi alimentari.<\/p>\n<p style=\"text-align: justify;\">Una cosa \u00e8 certa: questo composito, compatibile con il processo di stampa 3D FFF, sarebbe pi\u00f9 eco-compatibile. Resta da vedere come il chitosano reagirebbe con altre matrici come <a href=\"https:\/\/www.3dnatives.com\/it\/abs-stampa-3d-200120239\/\">l&#8217;ABS<\/a> o il <a href=\"https:\/\/www.3dnatives.com\/it\/policarbonato-stampa-3d-170220239\/\">policarbonato<\/a>, ad esempio. Nel frattempo, \u00e8 possibile trovare ulteriori informazioni sullo studio: <a href=\"https:\/\/link.springer.com\/article\/10.1007\/s10924-023-02758-5\" target=\"_blank\" rel=\"noopener\">QUI<\/a>.<\/p>\n<p style=\"text-align: justify;\">Cosa ne pensi di questa notizia? Condividi la tua opinione sui nostri social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>\u00a0e <a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">LinkedIn<\/a>. Trovi tutti i nostri video sul nostro canale <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra <a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">Newsletter<\/a> settimanale per ricevere tutte le notizie sulla stampa 3D direttamente nella casella di posta!<\/p>\n<p style=\"text-align: justify;\"><em>*Crediti foto copertina: David Boily\/La Presse<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perch\u00e9 non utilizzare le nostre risorse naturali per ideare nuovi materiali per la stampa 3D? \u00c8 questo il pensiero di un gruppo di ricercatori di Malesia, Singapore, Thailandia e India. Hanno cercato di capire come utilizzare il chitosano, un polimero&hellip;<\/p>\n","protected":false},"author":6086,"featured_media":6943,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,20],"tags":[],"class_list":["post-6936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiali-3d","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D? &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"Il chitosano, un polimero naturale presente in alcuni insetti, potrebbe migliorare la sostenibilit\u00e0 delle materie plastiche nella stampa 3D.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D? &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"Il chitosano, un polimero naturale presente in alcuni insetti, potrebbe migliorare la sostenibilit\u00e0 delle materie plastiche nella stampa 3D.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-13T22:01:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/04\/chitosane_cover-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nunzia A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nunzia A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/\"},\"author\":{\"name\":\"Nunzia A.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\"},\"headline\":\"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D?\",\"datePublished\":\"2023-04-13T22:01:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/\"},\"wordCount\":452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/chitosane_cover-1.jpg\",\"articleSection\":[\"Materiali 3D\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/\",\"name\":\"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D? &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/chitosane_cover-1.jpg\",\"datePublished\":\"2023-04-13T22:01:35+00:00\",\"description\":\"Il chitosano, un polimero naturale presente in alcuni insetti, potrebbe migliorare la sostenibilit\u00e0 delle materie plastiche nella stampa 3D.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/chitosane_cover-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/chitosane_cover-1.jpg\",\"width\":850,\"height\":500,\"caption\":\"chitosano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/chitosano-plastiche-stampa-3d-140420239\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\",\"name\":\"Nunzia A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"caption\":\"Nunzia A.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/nunzia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D? &#8211; 3Dnatives","description":"Il chitosano, un polimero naturale presente in alcuni insetti, potrebbe migliorare la sostenibilit\u00e0 delle materie plastiche nella stampa 3D.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/","og_locale":"it_IT","og_type":"article","og_title":"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D? &#8211; 3Dnatives","og_description":"Il chitosano, un polimero naturale presente in alcuni insetti, potrebbe migliorare la sostenibilit\u00e0 delle materie plastiche nella stampa 3D.","og_url":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2023-04-13T22:01:35+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/04\/chitosane_cover-1.jpg","type":"image\/jpeg"}],"author":"Nunzia A.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Nunzia A.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/"},"author":{"name":"Nunzia A.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714"},"headline":"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D?","datePublished":"2023-04-13T22:01:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/"},"wordCount":452,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/04\/chitosane_cover-1.jpg","articleSection":["Materiali 3D","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/","url":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/","name":"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D? &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/04\/chitosane_cover-1.jpg","datePublished":"2023-04-13T22:01:35+00:00","description":"Il chitosano, un polimero naturale presente in alcuni insetti, potrebbe migliorare la sostenibilit\u00e0 delle materie plastiche nella stampa 3D.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/04\/chitosane_cover-1.jpg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/04\/chitosane_cover-1.jpg","width":850,"height":500,"caption":"chitosano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/chitosano-plastiche-stampa-3d-140420239\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.3dnatives.com\/it\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Il chitosano pu\u00f2 rendere pi\u00f9 sostenibili le plastiche per la stampa 3D?"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714","name":"Nunzia A.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","caption":"Nunzia A."},"url":"https:\/\/www.3dnatives.com\/it\/author\/nunzia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/6936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6086"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=6936"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/6936\/revisions"}],"predecessor-version":[{"id":6961,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/6936\/revisions\/6961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/6943"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=6936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=6936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=6936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}