{"id":5318,"date":"2023-02-01T00:01:51","date_gmt":"2023-01-31T23:01:51","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=5318"},"modified":"2023-02-01T13:44:14","modified_gmt":"2023-02-01T12:44:14","slug":"xyzbag-borse-personalizzate-stampa-3d-010220239","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/","title":{"rendered":"XYZBAG produce borse personalizzate stampate in 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">XYZBAG \u00e8 un marchio italiano con sede a Torino che ha scelto l&#8217;artigianato digitale: combina metodi di progettazione tradizionali e <a href=\"https:\/\/www.3dnatives.com\/it\/tecnologie-stampa-3d\/\">tecnologie di produzione additiva<\/a> per produrre borse uniche. La personalizzazione \u00e8 senza dubbio uno dei motivi per cui sempre pi\u00f9 designer si rivolgono alla stampa 3D: permette di creare oggetti su misura a costi inferiori e in tempi rapidi. Abbiamo gi\u00e0 visto <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-moda-171120219\/\">scarpe o occhiali stampati in 3D<\/a>; questa volta ci rivolgiamo a un accessorio altrettanto utile, la borsa. Abbiamo incontrato Annalisa Nicola, cofondatrice di XYZBAG, per saperne di pi\u00f9 sul ruolo della stampa 3D nello sviluppo delle sue borse e sull&#8217;importanza della personalizzazione nel settore della moda.<\/p>\n<h3 style=\"text-align: justify;\">3DN: Puoi presentarti e raccontarci il tuo primo approccio alla stampa 3D?<\/h3>\n<div id=\"attachment_15249\" style=\"width: 223px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-15249\" class=\" wp-image-15249\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/Annalisa_XYZbag.jpg\" alt=\"\" width=\"213\" height=\"256\" \/><p id=\"caption-attachment-15249\" class=\"wp-caption-text\">Annalisa Nicola<\/p><\/div>\n<p style=\"text-align: justify;\">Ho ereditato una mentalit\u00e0 imprenditoriale da mio padre, cofondatore di un&#8217;azienda italiana di materie plastiche. Dopo essermi laureata in Ecodesign a Torino, negli ultimi 15 anni ho lavorato nel campo del design, dall&#8217;idea al prodotto finito, attraverso la comunicazione B2B. Mi sono occupata soprattutto di materiali e tecnologie plastiche, svolgendo un ruolo di mediazione tra i reparti creativi e i tecnici coinvolti nella creazione di nuovi prodotti. Quando ho iniziato a studiare le tecnologie di stampa 3D, la <a href=\"https:\/\/www.3dnatives.com\/it\/produzione-additiva\/\">produzione additiva<\/a> era gi\u00e0 affermata nel settore commerciale per lo sviluppo di prototipi. Sconosciuta e originale era l&#8217;idea di guardare a queste tecnologie da una prospettiva di produzione.<\/p>\n<p style=\"text-align: justify;\">Ho iniziato ad appassionarmi alla stampa 3D grazie a un libro illuminante: &#8220;Makers: The New Industrial Revolution&#8221; di Chris Anderson. Di solito dico che mi ha aiutato a capire che qualcosa che non esisteva ancora era possibile. Mi \u00e8 piaciuta molto la cultura dei FabLab, negozi digitali open-source in cui esperti moderni ed entusiasti forniscono strumenti e competenze per aiutarvi a realizzare le vostre idee. In questo contesto ho fatto le mie prime prove, con l&#8217;ultima generazione della stampante 3D Sharebot. Il mio primo modello di borsa \u00e8 stato realizzato con la <a href=\"https:\/\/www.3dnatives.com\/it\/modellazione-deposizione-fusa-021120219\/\">tecnologia FDM<\/a>. Sono rimasta totalmente affascinato dal filamento, dall&#8217;incredibile mistero di trasformare un file digitale in qualcosa di fisico in poco tempo. L&#8217;effetto degli &#8220;strati&#8221; tipico di questa tecnologia introduce un&#8217;estetica nuova e interessante ai pezzi. Guardando quel filamento trasformarsi in oggetto ho capito che stava accadendo qualcosa di straordinario.<\/p>\n<h3><\/h3>\n<h3 style=\"text-align: justify;\">3DN: Ci parli di XYZBAG? Qual \u00e8 il vostro obiettivo principale?<\/h3>\n<p style=\"text-align: justify;\">XYZBAG \u00e8 un marchio che vuole unire innovazione, tecnologia e produzione ricodificata (limitata nel tempo) in oggetti fisici &#8220;parlanti&#8221;. Per far fronte all&#8217;emergenza ambientale, creiamo oggetti in plastica di alto valore, prodotti simbolici di nicchia per eventi occasionali, situazioni o regali speciali. Immaginiamo un futuro senza sovrapproduzione e senza sprechi devastanti per l&#8217;ambiente, eliminando le scorte. Il primo modo per non produrre rifiuti \u00e8 non crearli. I clienti sviluppano un legame autentico con il loro prodotto e questo accresce il senso di affetto nei suoi confronti. Vogliamo contribuire a prolungare la vita di un prodotto contro la cultura dell&#8217;usa e getta.<\/p>\n<p style=\"text-align: justify;\">Le nostre borse 3D sono un mezzo per avvicinare pi\u00f9 facilmente le persone al mondo della stampa 3D, attraverso un oggetto alla moda, indossabile e unico. La mia visione \u00e8 un futuro in cui coesisteranno economie di scala e produzioni di pezzi unici: economie di scala per parti prodotte in grandi volumi e produzioni di pezzi unici per prodotti altamente personalizzabili che possono essere costruiti strato per strato. In questo panorama, si creeranno nuove competenze professionali per gestire la complessit\u00e0. Aumentando l&#8217;interazione tra clienti e progettazione, tutte le fasi dello sviluppo del prodotto, dall&#8217;idea alla produzione, richiederanno una mentalit\u00e0 innovativa e collaborativa di livello mai visto prima.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5384 aligncenter\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG2-min.png\" alt=\"XYZBAG\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG2-min.png 700w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG2-min-600x343.png 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG2-min-160x91.png 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3 style=\"text-align: justify;\">3DN: Ci spieghi il processo di produzione di una borsa XYZBAG?<\/h3>\n<p style=\"text-align: justify;\">Ogni progetto che XYZBAG porta avanti \u00e8 unico. Ecco perch\u00e9 iniziamo con un dialogo speciale con il nostro cliente. Le nostre borse 3D sono prodotte <strong>combinando la tradizione artigianale italiana e le tecnologie 3D innovative<\/strong>. Ogni borsa stampata in 3D nasce con un modello digitale, creato attraverso un file CAD (computer-aided design). I nostri clienti possono scegliere tra diverse proposte di design, sulla base di 3 prodotti master (DADA, GRETEL, TRADA) o semplicemente chiederci di generarne uno specifico per loro. Questa, in effetti, \u00e8 la fase pi\u00f9 delicata. <strong>L&#8217;arte della personalizzazione digitale richiede un&#8217;enorme competenza<\/strong> nella creazione di un file adatto alla stampa 3D e la capacit\u00e0 di produrre tutto ci\u00f2 che pu\u00f2 essere immaginato dal cliente, piuttosto che limitare i progetti ai vincoli di produzione.<\/p>\n<p style=\"text-align: justify;\">Il nostro punto di forza \u00e8 la nostra catena di fornitura. Abbiamo sviluppato solidi rapporti con i servizi professionali, focalizzati sul nostro modello di business. Utilizziamo una tecnologia basata sulle polveri. Le nostre ultime creazioni sono state realizzate con <a href=\"https:\/\/www.3dnatives.com\/it\/guida-stampa-3d-multi-jet-fusion-hp-270820229\/\">Multi Jet Fusion di HP<\/a>. Dopo il processo di stampa 3D, le nostre borse vengono dipinte a mano da artigiani professionisti e assemblate con la pelle sintetica o vera all&#8217;interno della borsa. Offriamo una tintura standard di colore nero e colori speciali su richiesta.<\/p>\n<div id=\"attachment_15251\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-15251\" class=\"size-full wp-image-15251\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/XYZbag_2.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-15251\" class=\"wp-caption-text\">XYZBag utilizza la tecnologia MJF di HP. Crediti: XYZBag<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Quali vantaggi porta la produzione additiva alla tua attivit\u00e0?<\/h3>\n<p style=\"text-align: justify;\">La produzione additiva \u00e8 stata l&#8217;espressione della nostra visione. L&#8217;Additive Manufacturing consente livelli completamente nuovi di libert\u00e0 di progettazione, possiamo fabbricare forme difficili, impossibili con altre tecnologie tradizionali. La stampa 3D facilita inoltre la personalizzazione. Seguendo questa strategia, consentiamo ai nostri clienti di acquistare prodotti personalizzati in base alle loro esigenze e alla loro creativit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Inoltre, la stampa 3D elimina la barriera dei costi delle attrezzature tradizionali, consentendo la produzione in modo sperimentale. MJF e <a href=\"https:\/\/www.3dnatives.com\/it\/sinterizzazione-laser-selettiva-301020219\/\">SLS<\/a> sono tecnologie molto utili perch\u00e9 consentono di creare centinaia di parti in un unica stampa. Pertanto, un altro vantaggio \u00e8 che possiamo gestire e personalizzare contemporaneamente lo stesso lotto.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5351 aligncenter\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/xyzbagCAD.jpg\" alt=\"xyzbagCAD\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/xyzbagCAD.jpg 700w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/xyzbagCAD-600x343.jpg 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/xyzbagCAD-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3 style=\"text-align: justify;\">3DN: Secondo te, perch\u00e9 si dovrebbe usare la produzione additiva nel settore moda?<\/h3>\n<p style=\"text-align: justify;\"><strong>Sostenibilit\u00e0 e co-creazione<\/strong> sono alcuni dei punti chiave per il futuro dell&#8217;industria della moda. Sostenibilit\u00e0 non significa solo scegliere il materiale giusto per un prodotto, ma anche creare un modello sostenibile. L&#8217;alternativa alla produzione di stampi comporta costi e risorse energetiche notevoli che possono essere assorbiti solo attraverso la fabbricazione di molti prodotti diversi (produzione industriale).<\/p>\n<p style=\"text-align: justify;\">L&#8217;interazione e la co-creazione con il cliente rappresentano un <strong>valore dirompente in questo settore<\/strong>. Oltre a conferire un&#8217;identit\u00e0 speciale all&#8217;articolo di moda, la produzione additiva porta a una nuova era di personalizzazione in un modo molto esclusivo. Per la prima volta nell&#8217;industria manifatturiera una singola creazione non deve essere replicabile in un gran numero di prodotti identici. <strong>Questo \u00e8 il vero lusso!<\/strong> Inoltre, sono possibili possibilit\u00e0 molto interessanti per accorciare il time to market, al fine di rinnovare le collezioni senza doverle riattrezzare. Nel frattempo, la contaminazione tra digitale e manifattura sar\u00e0 sempre pi\u00f9 affascinante.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5383 aligncenter\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG1.jpg\" alt=\"XYZBAG\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG1.jpg 700w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/XYZBAG1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3 style=\"text-align: justify;\">3DN: Qualche ultima battuta per i nostri lettori?<\/h3>\n<p style=\"text-align: justify;\">La stampa 3D cambier\u00e0 sicuramente il modo di produrre. Ma \u00e8 necessaria la competenza, mantenendo una mente aperta e imparando quanti pi\u00f9 strumenti e processi possibili. C&#8217;\u00e8 ancora un po&#8217; di strada da fare prima che la stampa 3D diventi una tecnologia solida che possa essere considerata un&#8217;alternativa alla produzione tradizionale. Vedere la stampa 3D applicata a un prodotto finito \u00e8 sempre un grande successo per noi! Sono sempre alla ricerca di collaborazioni con team ed esperti che condividono la mia visione di andare oltre i confini di questa affascinante tecnologia.<\/p>\n<p>Pi\u00f9 info su XYZBAG: <a href=\"https:\/\/www.xyzbag.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">QUI<\/a>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/NeKOBKrp-mw\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">Che ne pensi delle borse personalizzate con la stampa 3D di XYZBAG? Lascia un commento sui nostri canali social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_IT\">Twitter,<\/a>\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">Linkedin<\/a> e\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra <a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">Newsletter<\/a> settimanale per ricevere tutte le notizie sulla stampa 3D direttamente nella casella di posta!<\/p>\n<p><em>Crediti per tutte le foto e per la foto di copertina: XYZBAG<\/em><\/p>\n<div class=\"dnati-after-post-leaderboard dnati-entity-placement\" id=\"dnati-2316360673\"><div id=\"dnati-1190056412\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener nofollow\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>XYZBAG \u00e8 un marchio italiano con sede a Torino che ha scelto l&#8217;artigianato digitale: combina metodi di progettazione tradizionali e tecnologie di produzione additiva per produrre borse uniche. La personalizzazione \u00e8 senza dubbio uno dei motivi per cui sempre pi\u00f9&hellip;<\/p>\n","protected":false},"author":6086,"featured_media":5349,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[8,14],"tags":[],"class_list":["post-5318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artedesign","category-interviste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XYZBAG produce borse personalizzate stampate in 3D &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"XYZBAG persoanlizza borse con l&#039;aiuto della tecnologia di produzione additiva. Abbiamo intervistato la fondatrice Annalisa Nicola.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XYZBAG produce borse personalizzate stampate in 3D &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"XYZBAG persoanlizza borse con l&#039;aiuto della tecnologia di produzione additiva. Abbiamo intervistato la fondatrice Annalisa Nicola.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-31T23:01:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-01T12:44:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Untitled-design-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nunzia A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nunzia A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/\"},\"author\":{\"name\":\"Nunzia A.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\"},\"headline\":\"XYZBAG produce borse personalizzate stampate in 3D\",\"datePublished\":\"2023-01-31T23:01:51+00:00\",\"dateModified\":\"2023-02-01T12:44:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/\"},\"wordCount\":1288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/Untitled-design-16.jpg\",\"articleSection\":[\"Arte, Moda e Design\",\"Interviste\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/\",\"name\":\"XYZBAG produce borse personalizzate stampate in 3D &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/Untitled-design-16.jpg\",\"datePublished\":\"2023-01-31T23:01:51+00:00\",\"dateModified\":\"2023-02-01T12:44:14+00:00\",\"description\":\"XYZBAG persoanlizza borse con l'aiuto della tecnologia di produzione additiva. Abbiamo intervistato la fondatrice Annalisa Nicola.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/Untitled-design-16.jpg\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/Untitled-design-16.jpg\",\"width\":850,\"height\":500,\"caption\":\"xyzbag\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/xyzbag-borse-personalizzate-stampa-3d-010220239\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interviste\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/interviste\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"XYZBAG produce borse personalizzate stampate in 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\",\"name\":\"Nunzia A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"caption\":\"Nunzia A.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/nunzia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XYZBAG produce borse personalizzate stampate in 3D &#8211; 3Dnatives","description":"XYZBAG persoanlizza borse con l'aiuto della tecnologia di produzione additiva. Abbiamo intervistato la fondatrice Annalisa Nicola.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/","og_locale":"it_IT","og_type":"article","og_title":"XYZBAG produce borse personalizzate stampate in 3D &#8211; 3Dnatives","og_description":"XYZBAG persoanlizza borse con l'aiuto della tecnologia di produzione additiva. Abbiamo intervistato la fondatrice Annalisa Nicola.","og_url":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2023-01-31T23:01:51+00:00","article_modified_time":"2023-02-01T12:44:14+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Untitled-design-16.jpg","type":"image\/jpeg"}],"author":"Nunzia A.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Nunzia A.","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/"},"author":{"name":"Nunzia A.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714"},"headline":"XYZBAG produce borse personalizzate stampate in 3D","datePublished":"2023-01-31T23:01:51+00:00","dateModified":"2023-02-01T12:44:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/"},"wordCount":1288,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Untitled-design-16.jpg","articleSection":["Arte, Moda e Design","Interviste"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/","url":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/","name":"XYZBAG produce borse personalizzate stampate in 3D &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Untitled-design-16.jpg","datePublished":"2023-01-31T23:01:51+00:00","dateModified":"2023-02-01T12:44:14+00:00","description":"XYZBAG persoanlizza borse con l'aiuto della tecnologia di produzione additiva. Abbiamo intervistato la fondatrice Annalisa Nicola.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Untitled-design-16.jpg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Untitled-design-16.jpg","width":850,"height":500,"caption":"xyzbag"},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/xyzbag-borse-personalizzate-stampa-3d-010220239\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"Interviste","item":"https:\/\/www.3dnatives.com\/it\/category\/interviste\/"},{"@type":"ListItem","position":3,"name":"XYZBAG produce borse personalizzate stampate in 3D"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714","name":"Nunzia A.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","caption":"Nunzia A."},"url":"https:\/\/www.3dnatives.com\/it\/author\/nunzia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/5318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6086"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=5318"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/5318\/revisions"}],"predecessor-version":[{"id":5385,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/5318\/revisions\/5385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/5349"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=5318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=5318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=5318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}