{"id":4594,"date":"2023-01-05T00:02:14","date_gmt":"2023-01-04T23:02:14","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=4594"},"modified":"2023-01-05T14:44:03","modified_gmt":"2023-01-05T13:44:03","slug":"startup3d-poolp-050120239","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/","title":{"rendered":"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">Iniziamo il 2023 con un tema pi\u00f9 che mai attuale nella societ\u00e0 di oggi: l&#8217;impatto ambientale e la salvaguardia del nostro pianeta. Non \u00e8 un segreto che la <a href=\"https:\/\/www.3dnatives.com\/it\/ceramica-tecnica-produzione-additiva-020320229\/\">produzione additiva<\/a> sia uno dei modi per ridurre la quantit\u00e0 di rifiuti prodotti e l&#8217;impronta di carbonio, offrendo al contempo oggetti unici, personalizzati e complessi. Questo \u00e8 il pensiero alla base della nascita della start-up francese POOLP, fondata dopo la crisi sanitaria. La start-up ha sviluppato una micro-fabbrica che utilizza la stampa 3D per dare nuova vita ai rifiuti plastici. Dopo aver vinto il 3D Print Paris 2022 Startup Contest, i cofondatori, Lorenzo Fauvette e Thomas Sicouri, hanno risposto alle nostre domande.<\/p>\n<h3 style=\"text-align: justify;\">3DN: Potete presentarvi e raccontarci del vostro legame con la stampa 3D?<\/h3>\n<p style=\"text-align: justify;\"><strong>Lorenzo e Thomas<\/strong>: Siamo due architetti animati da una vera coscienza ecologica e condividiamo la passione per le nuove tecnologie applicate all&#8217;architettura, all&#8217;arte e al design. Siamo infatti convinti che alcune tecnologie possano migliorare notevolmente le prestazioni ambientali dei nostri modelli di produzione e consumo. Entrambi abbiamo un master in progettazione algoritmica e fabbricazione digitale e robotica per l&#8217;industria delle costruzioni, conseguito presso l&#8217;\u00c9cole Nationale de Ponts et Chauss\u00e9es (ENPC). Stavamo usando la stampa 3D come strumento di prototipazione e ci siamo resi conto che, facendo un salto di scala, la stampa 3D aveva un potenziale dirompente in molti campi.<\/p>\n<div id=\"attachment_74641\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74641\" class=\"size-full wp-image-74641\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2022\/12\/POOL_lorenzo.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-74641\" class=\"wp-caption-text\">Lorenzo \u00e8 uno dei fondatori di POOLP: ha presentato il concept della startup al 3D Print Paris 2022 Startup Contest (photo credits: 3D Print)<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Come \u00e8 nata POOLP?<\/h3>\n<p style=\"text-align: justify;\"><strong>Lorenzo e<\/strong><strong>\u00a0Thomas<\/strong><strong>: <\/strong>POOLP \u00e8 nata dopo il nostro master all&#8217;ENPC. Entrambi volevamo diventare imprenditori e ci siamo resi conto dell&#8217;enorme potenziale della <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-edilizia-240920219\/\">stampa 3D XL nel campo dell&#8217;arte e dell&#8217;architettura<\/a>. Oltre a un nuovo approccio alla progettazione e alla produzione, abbiamo scelto di utilizzare la flessibilit\u00e0 e la compattezza della stampa 3D per farne uno strumento di valorizzazione delle materie plastiche.<\/p>\n<p style=\"text-align: justify;\">Abbiamo quindi iniziato a pensare a un sistema di stampa 3D XL che ci permettesse di sperimentare un gran numero di materiali riciclati e\/o biobased. \u00c8 cos\u00ec che \u00e8 nata POOLP e l&#8217;idea di utilizzare i rifiuti in plastica come materia prima per la stampa 3D.<\/p>\n<p style=\"text-align: justify;\">Il nome POOLP deriva da un gioco di parole basato sul nostro concetto di economia circolare: Plastic LOOP &#8211; scritto al contrario diventa POOL-P&#8230; proprio come l&#8217;economia circolare. In francese si pronuncia come l&#8217;animale &#8220;poulpe&#8221; (polpo) che pu\u00f2 cambiare colore e forma, proprio come la stampa 3D.<\/p>\n<div id=\"attachment_74648\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74648\" class=\"size-full wp-image-74648\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2022\/12\/POOL_plastique.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-74648\" class=\"wp-caption-text\">Il nome della startup si basa sul concetto di economia circolare (crediti: black13kira)<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Potete dirci qualcosa di pi\u00f9 sulla vostra microfabbrica urbana e sulla vostra tecnologia di stampa XXL?<\/h3>\n<p style=\"text-align: justify;\"><strong>Lorenzo<\/strong><strong> e Thomas<\/strong><strong>: <\/strong>Oggi nelle citt\u00e0 sono sempre meno le attivit\u00e0 economiche legate all&#8217;artigianato e alla produzione locale per far posto a bar, ristoranti e abitazioni. La microfabbrica urbana \u00e8 quindi prevista come un modo per insediarsi nel denso tessuto urbano, per rivitalizzare l&#8217;economia e le iniziative locali e per creare sinergie tra i diversi attori del settore dell&#8217;economia circolare. Riciclatori e industriali per le materie prime, artigiani\/designer per lo sviluppo dei progetti e infine i cittadini come utenti finali.<\/p>\n<p style=\"text-align: justify;\">Pensiamo alla nostra microfabbrica urbana come a uno strumento di produzione che opera in un circuito quasi chiuso e che \u00e8 in grado di valorizzare i rifiuti plastici locali prodotti dai territori in cui si trova. Ogni microfabbrica sar\u00e0 composta da diverse unit\u00e0 di produzione additiva in grado di trasformare i rifiuti.<\/p>\n<p style=\"text-align: justify;\">Con questa microfabbrica, POOLP intende promuovere una filosofia di produzione e consumo alternativa. L&#8217;idea \u00e8 quella di utilizzare i rifiuti prodotti dai cittadini o dalle industrie di un determinato territorio per trasformarli in prodotti ad alto valore estetico, sociale e ambientale. Si tratta quindi di sviluppare sia usi funzionali che pezzi artistici che, speriamo, cambieranno il modo di guardare ai rifiuti e gli daranno un valore grazie a uno strumento di produzione capace di produrre un numero infinito di forme. Per questo motivo abbiamo in programma, una volta che la nostra prima microfabbrica urbana sar\u00e0 operativa e redditizia, di sviluppare una vera e propria rete sul territorio francese.<\/p>\n<p style=\"text-align: justify;\">Per sviluppare una tecnologia di stampa 3D facilmente riproducibile e in grado di lavorare con la pi\u00f9 ampia variet\u00e0 di materiali termoplastici di scarto, e per rispettare i nostri impegni ambientali, abbiamo preso macchine industriali gi\u00e0 in uso e le abbiamo modificate e assemblate per creare un&#8217;unit\u00e0 di <a href=\"https:\/\/www.3dnatives.com\/it\/formnext-2022-bilancio-211120229\/\">produzione additiva robotizzata<\/a> in grado di realizzare oggetti di grandi dimensioni da rifiuti plastici.<\/p>\n<p style=\"text-align: justify;\">Il nostro sistema di stampa si basa sul processo FGM (Fused Granulate Modeling), il che significa che \u00e8 in grado di stampare direttamente da granuli e frammenti di plastica e non depositando un filo come avviene con <a href=\"https:\/\/www.3dnatives.com\/it\/modellazione-deposizione-fusa-021120219\/\">FDM\/FFF.<\/a> Questo ci permette di essere pi\u00f9 veloci in termini di tempi di produzione, di ridurre notevolmente i costi delle materie prime e di utilizzare e sperimentare un&#8217;ampia gamma di materiali.<\/p>\n<div id=\"attachment_74643\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74643\" class=\"size-full wp-image-74643\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2022\/12\/POOLP_microusine.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-74643\" class=\"wp-caption-text\">Crediti foto: POOLP<\/p><\/div>\n<p style=\"text-align: justify;\">La nostra unit\u00e0 di produzione additiva \u00e8 composta da un estrusore e da una testina di stampa installata su un robot a 6 assi ABB IRB 6700 che, muovendosi, \u00e8 in grado di trasformare una geometria virtuale pi\u00f9 o meno complessa in un oggetto reale, con precisione e velocit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Per realizzare il nostro primo prototipo di unit\u00e0 di produzione additiva, visti gli elevati costi di investimento, siamo riusciti a stabilire partnership con istituzioni e aziende private che hanno creduto nel progetto. Per questo, vorremmo ringraziare il CNAM di Parigi, ABB Robotics France e La Maison pour Rebondir di SUEZ, che ci hanno sostenuto e aiutato fin dall&#8217;inizio.<\/p>\n<div id=\"attachment_74644\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74644\" class=\"size-full wp-image-74644\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2022\/12\/POOLP.jpg\" alt=\"poolp\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-74644\" class=\"wp-caption-text\">Esempi di strutture stampate in 3D da POOLP (crediti fotografici: POOLP)<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Quali prodotti produce oggi POOLP? Qual \u00e8 il vostro mercato di riferimento?<\/h3>\n<p style=\"text-align: justify;\"><strong>Lorenzo<\/strong><strong> e Thomas<\/strong><strong>:<\/strong>\u00a0Attualmente progettiamo e produciamo principalmente <a href=\"https:\/\/www.3dnatives.com\/it\/mobili-stampati-in-3d-211020219\/\">oggetti di design e d&#8217;arredo<\/a> come sgabelli, tavolini, fioriere e luci. Di recente abbiamo collaborato con un artista, Nicolas Viallard, con il quale abbiamo realizzato una scultura di 70 cm x 70 cm, che \u00e8 stata esposta alla fiera della stampa 3D di Parigi. I nostri prodotti acquistano valore non solo come oggetti, ma anche come manifesto di un cambiamento di paradigma verso una nuova filosofia di produzione e consumo. Al momento, i nostri prodotti sono destinati principalmente alla progettazione di hall aziendali, hotel, ristoranti, negozi, ecc. A lungo termine, speriamo di poter ampliare la nostra gamma di proposte.<\/p>\n<p style=\"text-align: justify;\">Oggi rivolgiamo i nostri servizi di co-progettazione e produzione principalmente ad architetti, designer e artisti che desiderano liberare la loro creativit\u00e0 e che sono consapevoli dell&#8217;urgente <a href=\"https:\/\/www.3dnatives.com\/it\/talk3d-sherri-monroe-amgta-201220229\/\">necessit\u00e0 di ridurre al minimo il loro impatto ambientale<\/a> e di partecipare attivamente alla transizione ecologica.<\/p>\n<h3 style=\"text-align: justify;\">3DN: Secondo voi, in che modo la stampa 3D pu\u00f2 promuovere l&#8217;economia circolare?<\/h3>\n<p style=\"text-align: justify;\"><strong>Lorenzo<\/strong><strong> e Thomas<\/strong><strong>:<\/strong>\u00a0La stampa 3D \u00e8 lo strumento ideale per promuovere l&#8217;economia circolare. Uno dei grandi vantaggi della stampa 3D \u00e8 che consente di produrre geometrie pi\u00f9 o meno complesse ottimizzando la quantit\u00e0 di materiale utilizzato. Nel nostro caso, non produce quasi alcuno scarto di produzione perch\u00e9 possiamo reintegrarli facilmente nel ciclo produttivo. Inoltre, con la stampa 3D XL, possiamo facilmente produrre just-in-time. Ci\u00f2 significa che produciamo solo i pezzi di cui abbiamo bisogno. Nessuna sovrapproduzione e quindi nessun pezzo invenduto. Un altro grande vantaggio \u00e8 che possiamo prendere gli oggetti prodotti, ritrasformarli in materia prima e creare un nuovo oggetto.<\/p>\n<p style=\"text-align: justify;\">Inoltre, il nostro sistema di microfabbriche minimizzerebbe notevolmente i costi di trasporto e le distanze, producendo il pi\u00f9 vicino possibile ai bisogni e con gli scarti prodotti dalle industrie e dagli abitanti del territorio.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-family: Montserrat; font-size: 1.4em; font-weight: 600;\">3DN: Un&#8217;ultima battuta per i nostri lettori?<\/span><\/p>\n<p style=\"text-align: justify;\">Se siete interessati alla nostra avventura e volete saperne di pi\u00f9, contattateci a <span \n                data-original-string='\/rwk2OAsg4PP2q7FNSqUfg==58dcR3+QK03pqO6Wem\/a07SpQ=='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>in<span class=\"apbct-blur\">**<\/span>@<span class=\"apbct-blur\">***<\/span>lp.eu<\/span> e seguiteci su instagram a we_are_poolp e su Linkedin! Saremo lieti di ascoltarvi. IN WASTE WE TRUST!<\/p>\n<p style=\"text-align: justify;\">Cosa ne pensi della startup POOLP? Condividi la tua opinione sui nostri social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_IT\">Twitter<\/a> e <a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">LinkedIn<\/a>. Trovi tutti i nostri video sul nostro canale <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra <a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">Newsletter<\/a> settimanale per ricevere tutte le notizie sulla stampa 3D direttamente nella casella di posta!<\/p>\n<p style=\"text-align: justify;\"><em>*Crediti foto copertina: POOLP<\/em><\/p>\n<div class=\"dnati-after-post-leaderboard dnati-entity-placement\" id=\"dnati-3353173698\"><div id=\"dnati-791444876\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener nofollow\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Iniziamo il 2023 con un tema pi\u00f9 che mai attuale nella societ\u00e0 di oggi: l&#8217;impatto ambientale e la salvaguardia del nostro pianeta. Non \u00e8 un segreto che la produzione additiva sia uno dei modi per ridurre la quantit\u00e0 di rifiuti&hellip;<\/p>\n","protected":false},"author":6086,"featured_media":4629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[14,20],"tags":[],"class_list":["post-4594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviste","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"La start-up francese POOLP ha sviluppato una micro-fabbrica che utilizza la stampa 3D per dare nuova vita ai rifiuti plastici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"La start-up francese POOLP ha sviluppato una micro-fabbrica che utilizza la stampa 3D per dare nuova vita ai rifiuti plastici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-04T23:02:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-05T13:44:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Cover-Startup-Social-Media-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nunzia A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nunzia A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/\"},\"author\":{\"name\":\"Nunzia A.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\"},\"headline\":\"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D\",\"datePublished\":\"2023-01-04T23:02:14+00:00\",\"dateModified\":\"2023-01-05T13:44:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/\"},\"wordCount\":1378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/POOLP_cover.jpeg\",\"articleSection\":[\"Interviste\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/\",\"name\":\"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/POOLP_cover.jpeg\",\"datePublished\":\"2023-01-04T23:02:14+00:00\",\"dateModified\":\"2023-01-05T13:44:03+00:00\",\"description\":\"La start-up francese POOLP ha sviluppato una micro-fabbrica che utilizza la stampa 3D per dare nuova vita ai rifiuti plastici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/POOLP_cover.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/POOLP_cover.jpeg\",\"width\":850,\"height\":500,\"caption\":\"poolp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/startup3d-poolp-050120239\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interviste\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/interviste\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\",\"name\":\"Nunzia A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"caption\":\"Nunzia A.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/nunzia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D &#8211; 3Dnatives","description":"La start-up francese POOLP ha sviluppato una micro-fabbrica che utilizza la stampa 3D per dare nuova vita ai rifiuti plastici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/","og_locale":"it_IT","og_type":"article","og_title":"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D &#8211; 3Dnatives","og_description":"La start-up francese POOLP ha sviluppato una micro-fabbrica che utilizza la stampa 3D per dare nuova vita ai rifiuti plastici.","og_url":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2023-01-04T23:02:14+00:00","article_modified_time":"2023-01-05T13:44:03+00:00","og_image":[{"width":1080,"height":635,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/Cover-Startup-Social-Media-3.jpg","type":"image\/jpeg"}],"author":"Nunzia A.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Nunzia A.","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/"},"author":{"name":"Nunzia A.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714"},"headline":"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D","datePublished":"2023-01-04T23:02:14+00:00","dateModified":"2023-01-05T13:44:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/"},"wordCount":1378,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/POOLP_cover.jpeg","articleSection":["Interviste","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/","url":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/","name":"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/POOLP_cover.jpeg","datePublished":"2023-01-04T23:02:14+00:00","dateModified":"2023-01-05T13:44:03+00:00","description":"La start-up francese POOLP ha sviluppato una micro-fabbrica che utilizza la stampa 3D per dare nuova vita ai rifiuti plastici.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/POOLP_cover.jpeg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/01\/POOLP_cover.jpeg","width":850,"height":500,"caption":"poolp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/startup3d-poolp-050120239\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"Interviste","item":"https:\/\/www.3dnatives.com\/it\/category\/interviste\/"},{"@type":"ListItem","position":3,"name":"#Startup3D: POOLP d\u00e0 nuova vita ai rifiuti in plastica grazie alla stampa 3D"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714","name":"Nunzia A.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","caption":"Nunzia A."},"url":"https:\/\/www.3dnatives.com\/it\/author\/nunzia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/4594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6086"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=4594"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/4594\/revisions"}],"predecessor-version":[{"id":4628,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/4594\/revisions\/4628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/4629"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=4594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=4594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=4594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}