{"id":22475,"date":"2026-07-01T00:00:40","date_gmt":"2026-06-30T22:00:40","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=22475"},"modified":"2026-07-01T06:25:28","modified_gmt":"2026-07-01T04:25:28","slug":"rrreefs-stampata-3d-maldive-01072026","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/","title":{"rendered":"rrreefs installa una barriera corallina stampata in 3D alle Maldive"},"content":{"rendered":"<p style=\"text-align: justify;\">Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D, con l&#8217;obiettivo di restituire un po&#8217; di vita a un ecosistema da anni minacciato dallo sbiancamento dei coralli. Il progetto si chiama <strong><em>Theyra Maa<\/em><\/strong>, &#8220;13 fiori&#8221; in dhivehi, la lingua maldiviana, ed \u00e8 stato realizzato in collaborazione con <strong>rrreefs<\/strong>, un&#8217;azienda svizzera specializzata nel ripristino delle barriere coralline attraverso la produzione additiva su larga scala.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 la prima volta che vediamo argilla stampata in 3D sott&#8217;acqua. Esistono numerosi progetti in tutto il mondo che applicano la <a href=\"https:\/\/www.3dnatives.com\/it\/produzione-additiva\/\">produzione additiva<\/a> al ripristino delle barriere coralline. E non \u00e8 nemmeno la prima volta che l&#8217;azienda svizzera realizza un&#8217;opera di questo livello: dalla sua fondazione nel 2020 ha gi\u00e0 contribuito alla nascita di oltre 15.000 nuovi coralli grazie alle barriere che ha installato.<\/p>\n<div id=\"attachment_86282\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86282\" class=\"wp-image-86282 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/rrreefs-.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-86282\" class=\"wp-caption-text\">Installazione di &#8220;Theyra Maa&#8221; alle Maldive (crediti foto: rrreefs via LinkedIn).<\/p><\/div>\n<p style=\"text-align: justify;\"><em>&#8220;L&#8217;ispirazione alla base di rrreefs nasce da una passione profonda per l&#8217;oceano e dalla determinazione ad agire contro il rapido declino delle barriere coralline, uno dei primi ecosistemi a subire gli effetti del cambiamento climatico&#8221;<\/em>, spiega Josephine Graf, cofondatrice dell&#8217;azienda. Per lei, Theyra Maa dimostra anche come collaborazioni tra settori cos\u00ec diversi possano tradursi in risultati concreti per la <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-ripristino-barriere-coralline-biodiversita-100820239\/\">conservazione degli oceani<\/a>.<\/p>\n<h2>Microcavit\u00e0 pensate per il corallo<\/h2>\n<p style=\"text-align: justify;\">Mauro Bischoff, responsabile della produzione di rrreefs, spiega che il processo di stampa per strati lascia microcavit\u00e0 tra ogni strato di materiale. In questi spazi minuscoli le larve di corallo possono ripararsi dai predatori mentre si fissano al substrato.<\/p>\n<p style=\"text-align: justify;\">Anche la porosit\u00e0 del pezzo viene regolata durante la stampa per favorire la formazione di biofilm, quelle pellicole di microrganismi che rappresentano il primo passo per l&#8217;insediamento del corallo.<\/p>\n<h2>Tredici fiori sott&#8217;acqua<\/h2>\n<p style=\"text-align: justify;\">Le 13 strutture installate sul fondale hanno la forma di un fiore. Questa geometria \u00e8 progettata appositamente per generare piccoli vortici d&#8217;acqua attorno a ciascun modulo. In questo modo le larve di corallo si insediano pi\u00f9 facilmente, anzich\u00e9 essere trascinate dalla corrente. I sommozzatori di rrreefs hanno assemblato le strutture modulo dopo modulo direttamente nella laguna del South Mal\u00e9 Atoll e le hanno fissate al fondale marino, cos\u00ec da resistere al moto ondoso negli anni.<\/p>\n<p style=\"text-align: justify;\">Il progetto \u00e8 sostenuto da Edelweiss Air e dalla fondazione help alliance, entrambe del gruppo Lufthansa, che finanziano l&#8217;installazione nell&#8217;ambito dei loro programmi di turismo responsabile. \u00c8 la prima volta che rrreefs collabora direttamente con una struttura alberghiera, dopo progetti analoghi in diverse zone costiere vulnerabili.<\/p>\n<div id=\"attachment_86283\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86283\" class=\"wp-image-86283 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/rrreefs-flower.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-86283\" class=\"wp-caption-text\">Una delle tredici installazioni floreali di &#8220;Theyra Maa&#8221; (crediti foto: Minor Hotels).<\/p><\/div>\n<p style=\"text-align: justify;\">E voi, cosa ne pensate di questa barriera corallina stampata in 3D alle Maldive? Faccelo sapere lasciando un commento sui nostri social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a> e <a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">LinkedIn<\/a>. Trovi tutti i nostri video sul nostro canale <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra <a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">Newsletter<\/a> settimanale per ricevere tutte le notizie sulla stampa 3D direttamente nella casella di posta!<\/p>\n<p><em>*Crediti foto di copertina: rrreefs<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D, con l&#8217;obiettivo di restituire un po&#8217; di vita a un ecosistema da anni minacciato dallo sbiancamento dei coralli. Il progetto si&hellip;<\/p>\n","protected":false},"author":6110,"featured_media":22476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[4,20],"tags":[],"class_list":["post-22475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>rrreefs installa una barriera corallina stampata in 3D alle Maldive &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rrreefs installa una barriera corallina stampata in 3D alle Maldive &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-30T22:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T04:25:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/rrreefs-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carol S.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carol S.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/\"},\"author\":{\"name\":\"Carol S.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/04221b4afa4161f5e2572ab78657e633\"},\"headline\":\"rrreefs installa una barriera corallina stampata in 3D alle Maldive\",\"datePublished\":\"2026-06-30T22:00:40+00:00\",\"dateModified\":\"2026-07-01T04:25:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/\"},\"wordCount\":506,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/rrreefs-cover.jpg\",\"articleSection\":[\"Architettura e Costruzioni\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/\",\"name\":\"rrreefs installa una barriera corallina stampata in 3D alle Maldive &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/rrreefs-cover.jpg\",\"datePublished\":\"2026-06-30T22:00:40+00:00\",\"dateModified\":\"2026-07-01T04:25:28+00:00\",\"description\":\"Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/rrreefs-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/rrreefs-cover.jpg\",\"width\":850,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rrreefs-stampata-3d-maldive-01072026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Architettura e Costruzioni\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/architettura\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"rrreefs installa una barriera corallina stampata in 3D alle Maldive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/04221b4afa4161f5e2572ab78657e633\",\"name\":\"Carol S.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"caption\":\"Carol S.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/carol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"rrreefs installa una barriera corallina stampata in 3D alle Maldive &#8211; 3Dnatives","description":"Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/","og_locale":"it_IT","og_type":"article","og_title":"rrreefs installa una barriera corallina stampata in 3D alle Maldive &#8211; 3Dnatives","og_description":"Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D.","og_url":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2026-06-30T22:00:40+00:00","article_modified_time":"2026-07-01T04:25:28+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/rrreefs-cover.jpg","type":"image\/jpeg"}],"author":"Carol S.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Carol S.","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/"},"author":{"name":"Carol S.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/04221b4afa4161f5e2572ab78657e633"},"headline":"rrreefs installa una barriera corallina stampata in 3D alle Maldive","datePublished":"2026-06-30T22:00:40+00:00","dateModified":"2026-07-01T04:25:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/"},"wordCount":506,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/rrreefs-cover.jpg","articleSection":["Architettura e Costruzioni","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/","url":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/","name":"rrreefs installa una barriera corallina stampata in 3D alle Maldive &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/rrreefs-cover.jpg","datePublished":"2026-06-30T22:00:40+00:00","dateModified":"2026-07-01T04:25:28+00:00","description":"Il resort Anantara Dhigu ha appena installato nella sua laguna, alle Maldive, 13 strutture in argilla stampate in 3D.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/rrreefs-cover.jpg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/rrreefs-cover.jpg","width":850,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/rrreefs-stampata-3d-maldive-01072026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"Architettura e Costruzioni","item":"https:\/\/www.3dnatives.com\/it\/category\/architettura\/"},{"@type":"ListItem","position":3,"name":"rrreefs installa una barriera corallina stampata in 3D alle Maldive"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/04221b4afa4161f5e2572ab78657e633","name":"Carol S.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","caption":"Carol S."},"url":"https:\/\/www.3dnatives.com\/it\/author\/carol\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/22475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=22475"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/22475\/revisions"}],"predecessor-version":[{"id":22478,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/22475\/revisions\/22478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/22476"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=22475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=22475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=22475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}