{"id":22455,"date":"2026-06-25T11:35:32","date_gmt":"2026-06-25T09:35:32","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=22455"},"modified":"2026-06-25T11:42:59","modified_gmt":"2026-06-25T09:42:59","slug":"exo-1-orologio-parivas-additiva-25062026","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/","title":{"rendered":"Exo.1: il debutto di Parivas nell&#8217;orologeria additiva"},"content":{"rendered":"<p style=\"text-align: justify;\" data-path-to-node=\"2\">C&#8217;\u00e8 un nuovo <a href=\"https:\/\/www.3dnatives.com\/it\/stractra-orologio-titanio-stampato-3d-180820259\/\">orologio realizzato in produzione additiva<\/a> sulla scena: l&#8217;Exo.1 di Parivas. Con sede a Los Angeles, in California, Parivas \u00e8 un&#8217;azienda orologiera la cui missione principale \u00e8 introdurre una nuova categoria nel mondo dell&#8217;orologeria: il design additivo applicato agli orologi. Pur non essendo il primo marchio a integrare la produzione additiva in questo settore, Parivas compie una scelta audace ponendo la tecnologia al centro stesso della propria identit\u00e0 e della propria filosofia di design. Persino il nome dell&#8217;azienda richiama queste origini: Parivas deriva dall&#8217;espressione latina Pario e Pulvis, ovvero <em>&#8220;creato dalla polvere&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\" data-path-to-node=\"3\">L&#8217;Exo.1 \u00e8 la creazione di debutto dell&#8217;azienda, il cui nome rimanda al design simile a un esoscheletro. La sua caratteristica distintiva \u00e8 una cassa in acciaio inossidabile stampata in 3D con un processo a <a href=\"https:\/\/www.3dnatives.com\/it\/laser-powder-bed-fusion-lpbf-050920219\/\">letto di polvere<\/a>. Grazie a questa costruzione monolitica, la lunetta, il corpo, le anse ed i componenti del quadrante sono tutti integrati in un&#8217;unica struttura continua. Questo approccio elimina completamente le tradizionali giunzioni e i punti di raccordo dove generalmente si verificano disallineamenti strutturali o incongruenze estetiche. Per rifinire il pezzo, la cassa \u00e8 sottoposta a un processo di sinterizzazione proprietario che il marchio chiama finitura <em>Solar Dusted<\/em>\u2122. Questa tecnica conferisce una texture simile a un&#8217;impronta digitale, fatta di onde e creste uniche che catturano la luce, garantendo che non esistano due segnatempo perfettamente identici.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70908 aligncenter\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2026\/06\/click-4.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><\/p>\n<p style=\"text-align: justify;\">Chi c&#8217;\u00e8 dietro questa azienda? I fondatori Mickey Brown (CEO) e Justin Chang (COO) vantano oltre 30 anni di esperienza combinata nell&#8217;ingegneria meccanica e nella produzione additiva. Prima che l&#8217;Exo.1 potesse prendere forma, hanno dedicato anni alla progettazione. <em>&#8220;L&#8217;Exo.1 non si \u00e8 adattato alla tecnologia. \u00c8 stata la tecnologia a doversi elevare per raggiungerlo&#8221;,<\/em> afferma Brown.<\/p>\n<h2><span style=\"font-weight: 400;\">L&#8217;Exo.1: animato dalla precisione svizzera<\/span><\/h2>\n<p style=\"text-align: justify;\">L&#8217;Exo.1 \u00e8 animato dal calibro Parivas P1001S: un movimento svizzero automatico scheletrato personalizzato, costruito sull&#8217;architettura Sellita SW300-1SA. L&#8217;orologio \u00e8 certificato secondo lo standard Parivas Chronometer, un programma di precisione sviluppato internamente in collaborazione con la <em>Horological Society of New York<\/em> e concepito per superare gli standard internazionali ISO 3159. Dispone di una riserva di carica di 56 ore, 25 rubini, placcatura in rodio e lavorazione soleil. Ogni orologio sar\u00e0 assemblato a Los Angeles.<\/p>\n<p style=\"text-align: justify;\">Chi desidera acquistare l&#8217;Exo.1 pu\u00f2 iscriversi gi\u00e0 da ora alla lista d&#8217;attesa. Il primo lotto sar\u00e0 composto da soli 30 esemplari, al prezzo di 7.500 dollari ciascuno, con consegna prevista per il primo trimestre del 2027. Per una panoramica completa del processo produttivo, potete guardare i fondatori illustrarlo nel video qui sotto e consultare le specifiche complete dell&#8217;orologio <a href=\"https:\/\/www.prnewswire.com\/news-releases\/parivas-introduces-additive-watchmaking--a-new-category-in-horology-302764868.html\" target=\"_blank\" rel=\"noopener\">QUI<\/a>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/-OHWvfVt8MA?si=rVhH4DmQqBoisG_B\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">E voi, indossereste questo nuovo orologio Exo.1 stampato in 3D? Faccelo sapere lasciando un commento sui nostri social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a> e <a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">LinkedIn<\/a>. Trovi tutti i nostri video sul nostro canale <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra <a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">Newsletter<\/a> settimanale per ricevere tutte le notizie sulla stampa 3D direttamente nella casella di posta!<\/p>\n<p style=\"text-align: justify;\"><em>*Crediti di tutte le foto: Parivas<\/em><\/p>\n<div class=\"dnati-after-post-leaderboard dnati-entity-placement\" id=\"dnati-520648835\"><div id=\"dnati-741948167\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener nofollow\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>C&#8217;\u00e8 un nuovo orologio realizzato in produzione additiva sulla scena: l&#8217;Exo.1 di Parivas. Con sede a Los Angeles, in California, Parivas \u00e8 un&#8217;azienda orologiera la cui missione principale \u00e8 introdurre una nuova categoria nel mondo dell&#8217;orologeria: il design additivo applicato&hellip;<\/p>\n","protected":false},"author":6110,"featured_media":22456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[8,6,20],"tags":[],"class_list":["post-22455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artedesign","category-beni-di-consumo","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Exo.1: il debutto di Parivas nell&#039;orologeria additiva &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"Un orologio la cui cassa \u00e8 stampata in 3D in un unico pezzo, senza giunzioni: \u00e8 l&#039;Exo.1, debutto del nuovo marchio californiano Parivas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exo.1: il debutto di Parivas nell&#039;orologeria additiva &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"Un orologio la cui cassa \u00e8 stampata in 3D in un unico pezzo, senza giunzioni: \u00e8 l&#039;Exo.1, debutto del nuovo marchio californiano Parivas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T09:35:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T09:42:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/parivas-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carol S.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carol S.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/\"},\"author\":{\"name\":\"Carol S.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/04221b4afa4161f5e2572ab78657e633\"},\"headline\":\"Exo.1: il debutto di Parivas nell&#8217;orologeria additiva\",\"datePublished\":\"2026-06-25T09:35:32+00:00\",\"dateModified\":\"2026-06-25T09:42:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/parivas-cover.jpg\",\"articleSection\":[\"Arte, Moda e Design\",\"Beni di consumo\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/\",\"name\":\"Exo.1: il debutto di Parivas nell'orologeria additiva &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/parivas-cover.jpg\",\"datePublished\":\"2026-06-25T09:35:32+00:00\",\"dateModified\":\"2026-06-25T09:42:59+00:00\",\"description\":\"Un orologio la cui cassa \u00e8 stampata in 3D in un unico pezzo, senza giunzioni: \u00e8 l'Exo.1, debutto del nuovo marchio californiano Parivas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/parivas-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/parivas-cover.jpg\",\"width\":850,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/exo-1-orologio-parivas-additiva-25062026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte, Moda e Design\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/artedesign\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exo.1: il debutto di Parivas nell&#8217;orologeria additiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/04221b4afa4161f5e2572ab78657e633\",\"name\":\"Carol S.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=mm&r=g\",\"caption\":\"Carol S.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/carol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Exo.1: il debutto di Parivas nell'orologeria additiva &#8211; 3Dnatives","description":"Un orologio la cui cassa \u00e8 stampata in 3D in un unico pezzo, senza giunzioni: \u00e8 l'Exo.1, debutto del nuovo marchio californiano Parivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/","og_locale":"it_IT","og_type":"article","og_title":"Exo.1: il debutto di Parivas nell'orologeria additiva &#8211; 3Dnatives","og_description":"Un orologio la cui cassa \u00e8 stampata in 3D in un unico pezzo, senza giunzioni: \u00e8 l'Exo.1, debutto del nuovo marchio californiano Parivas.","og_url":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2026-06-25T09:35:32+00:00","article_modified_time":"2026-06-25T09:42:59+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/parivas-cover.jpg","type":"image\/jpeg"}],"author":"Carol S.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Carol S.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/"},"author":{"name":"Carol S.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/04221b4afa4161f5e2572ab78657e633"},"headline":"Exo.1: il debutto di Parivas nell&#8217;orologeria additiva","datePublished":"2026-06-25T09:35:32+00:00","dateModified":"2026-06-25T09:42:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/parivas-cover.jpg","articleSection":["Arte, Moda e Design","Beni di consumo","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/","url":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/","name":"Exo.1: il debutto di Parivas nell'orologeria additiva &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/parivas-cover.jpg","datePublished":"2026-06-25T09:35:32+00:00","dateModified":"2026-06-25T09:42:59+00:00","description":"Un orologio la cui cassa \u00e8 stampata in 3D in un unico pezzo, senza giunzioni: \u00e8 l'Exo.1, debutto del nuovo marchio californiano Parivas.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/parivas-cover.jpg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/parivas-cover.jpg","width":850,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/exo-1-orologio-parivas-additiva-25062026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"Arte, Moda e Design","item":"https:\/\/www.3dnatives.com\/it\/category\/artedesign\/"},{"@type":"ListItem","position":3,"name":"Exo.1: il debutto di Parivas nell&#8217;orologeria additiva"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/04221b4afa4161f5e2572ab78657e633","name":"Carol S.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9cb96c3b61ea500df10b0a86ceb8b879269f47a4dbe4f64fc69b5c98c3b645d?s=96&d=mm&r=g","caption":"Carol S."},"url":"https:\/\/www.3dnatives.com\/it\/author\/carol\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/22455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=22455"}],"version-history":[{"count":1,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/22455\/revisions"}],"predecessor-version":[{"id":22457,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/22455\/revisions\/22457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/22456"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=22455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=22455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=22455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}