{"id":20005,"date":"2025-05-16T00:01:49","date_gmt":"2025-05-15T22:01:49","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=20005"},"modified":"2025-05-15T12:41:54","modified_gmt":"2025-05-15T10:41:54","slug":"airbike-moto-volante-stampata-3d","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/","title":{"rendered":"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea"},"content":{"rendered":"<p style=\"text-align: justify;\">La startup polacca Volonaut ha presentato l&#8217;AirBike, una moto volante. S\u00ec, hai letto bene: questo veicolo \u00e8 in grado di librarsi in aria e di raggiungere una velocit\u00e0 di 200 km\/h. Progettata utilizzando materiali e parti stampate in 3D, l&#8217;AirBike rappresenta una svolta nel campo della mobilit\u00e0 aerea, anche se sono ancora poche le informazioni sulle modalit\u00e0 di commercializzazione.<\/p>\n<p style=\"text-align: justify;\">Volonaut riassume l&#8217;ambizione del progetto con una chiara promessa: <em>\u201cPortare il volo umano a un livello superiore\u201d<\/em>. Questo scooter volante ultraleggero, monoposto e realizzato in fibra di carbonio \u00e8 una perfetta illustrazione dell&#8217;impegno della startup nei confronti delle tecnologie di produzione additiva. Mentre diverse iniziative hanno gi\u00e0 incorporato la <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-automotive-trasporti\/\">stampa 3D in alcune parti di moto<\/a>, l&#8217;AirBike si distingue per la sua natura visionaria.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-81670 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/airbike.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><br \/>\nCosa sappiamo dell&#8217;AirBike?<\/h2>\n<p style=\"text-align: justify;\">Appena uscita dalla fase di sviluppo, l&#8217;AirBike \u00e8 opera di Tomasz Patan, inventore e imprenditore autodidatta polacco con oltre 30 anni di esperienza nella progettazione di droni e aerei. La sua ultima creazione \u00e8 dotata di un sistema di propulsione a getto in grado di spingere fino a 200 km\/h, senza bisogno di eliche visibili. Uno dei principali punti di forza dell&#8217;AirBike \u00e8 l&#8217;utilizzo della produzione additiva combinata con materiali compositi rinforzati con <a href=\"https:\/\/www.3dnatives.com\/it\/fibra-carbonio-stampa-3d-310520239\/\">fibra di carbonio<\/a>. Questa scelta tecnologica ha permesso di progettare un veicolo ultraresistente ed estremamente leggero. Secondo Volonaut, l&#8217;AirBike \u00e8 fino a sette volte pi\u00f9 leggera di una moto tradizionale, grazie a questo approccio minimalista e alla stampa 3D.<\/p>\n<p style=\"text-align: justify;\">A differenza di altri VTOL (veicoli a decollo e atterraggio verticale) progettati per integrare il traffico urbano, l&#8217;AirBike \u00e8 pensata per un&#8217;esperienza coinvolgente e divertente. La startup mette l&#8217;accento sulla guida aperta, sulla visibilit\u00e0 a 360 gradi e sul pilotaggio assistito da computer, dando agli utenti una sensazione di totale libert\u00e0.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/-Fev5M_7Wnw?si=eTZiWnbmbpUbLyTb\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">Ad oggi non sono state rilasciate informazioni sull&#8217;eventuale commercializzazione dell&#8217;AirBike, n\u00e9 sui contesti legali o urbani in cui potrebbe evolvere. Ma una cosa \u00e8 certa: l&#8217;AirBike illustra il potenziale della stampa 3D e dei materiali avanzati per trasformare il settore della <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-automotive-trasporti\/\">mobilit\u00e0<\/a>.<\/p>\n<p style=\"text-align: justify;\">Cosa ne pensi dell&#8217;AirBike? <span data-contrast=\"none\">Se ti interessa l\u2019argomento, non perderti la nostra pagina esclusiva dedicata alla\u00a0<\/span><a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-automotive-trasporti\/\"><span data-contrast=\"none\">stampa 3D nel settore automotive e trasporti<\/span><\/a><span data-contrast=\"none\">. Lascia un commento sui nostri canali\u00a0<\/span><a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\"><span data-contrast=\"none\">Facebook<\/span><\/a><span data-contrast=\"none\">,\u00a0<\/span><a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\"><span data-contrast=\"none\">LinkedIn<\/span><\/a><span data-contrast=\"none\">\u00a0e\u00a0<\/span><a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\"><span data-contrast=\"none\">YouTube<\/span><\/a><span data-contrast=\"none\">. Segui tutte le novit\u00e0 dal mondo della stampa 3D nella nostra\u00a0<\/span><a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\"><span data-contrast=\"none\">Newsletter settimanale<\/span><\/a><span data-contrast=\"none\">!<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:135,&quot;335559739&quot;:135}\">\u00a0<\/span><\/p>\n<p><em>*Tutti i crediti fotografici: Volonaut<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La startup polacca Volonaut ha presentato l&#8217;AirBike, una moto volante. S\u00ec, hai letto bene: questo veicolo \u00e8 in grado di librarsi in aria e di raggiungere una velocit\u00e0 di 200 km\/h. Progettata utilizzando materiali e parti stampate in 3D, l&#8217;AirBike&hellip;<\/p>\n","protected":false},"author":6106,"featured_media":20007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[3,20],"tags":[],"class_list":["post-20005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automotive","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"Una giovane azienda polacca ha presentato la prima moto volante al mondo, con parti stampate in 3D in fibra di carbonio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"Una giovane azienda polacca ha presentato la prima moto volante al mondo, con parti stampate in 3D in fibra di carbonio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T22:01:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea\",\"datePublished\":\"2025-05-15T22:01:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/\"},\"wordCount\":402,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg\",\"articleSection\":[\"Automotive e Trasporti\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/\",\"url\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/\",\"name\":\"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg\",\"datePublished\":\"2025-05-15T22:01:49+00:00\",\"description\":\"Una giovane azienda polacca ha presentato la prima moto volante al mondo, con parti stampate in 3D in fibra di carbonio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage\",\"url\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg\",\"contentUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg\",\"width\":850,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.3dnatives.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Automotive e Trasporti\",\"item\":\"https:\/\/www.3dnatives.com\/it\/category\/automotive\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/#website\",\"url\":\"https:\/\/www.3dnatives.com\/it\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\/\/www.3dnatives.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png\",\"contentUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png\",\"width\":407,\"height\":131,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/3Dnativesit\",\"https:\/\/x.com\/3Dnatives\",\"https:\/\/www.instagram.com\/3d_natives\/\",\"https:\/\/www.linkedin.com\/groups\/12583365\/\",\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.3dnatives.com\/it\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea &#8211; 3Dnatives","description":"Una giovane azienda polacca ha presentato la prima moto volante al mondo, con parti stampate in 3D in fibra di carbonio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/","og_locale":"it_IT","og_type":"article","og_title":"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea &#8211; 3Dnatives","og_description":"Una giovane azienda polacca ha presentato la prima moto volante al mondo, con parti stampate in 3D in fibra di carbonio.","og_url":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2025-05-15T22:01:49+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/"},"author":{"name":"","@id":""},"headline":"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea","datePublished":"2025-05-15T22:01:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/"},"wordCount":402,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg","articleSection":["Automotive e Trasporti","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/","url":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/","name":"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg","datePublished":"2025-05-15T22:01:49+00:00","description":"Una giovane azienda polacca ha presentato la prima moto volante al mondo, con parti stampate in 3D in fibra di carbonio.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/05\/airbike_cover-13.59.17.jpg","width":850,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/airbike-moto-volante-stampata-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"Automotive e Trasporti","item":"https:\/\/www.3dnatives.com\/it\/category\/automotive\/"},{"@type":"ListItem","position":3,"name":"AirBike, la moto volante stampata in 3D che reinventa la mobilit\u00e0 aerea"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png","width":407,"height":131,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"","url":"https:\/\/www.3dnatives.com\/it\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/20005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6106"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=20005"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/20005\/revisions"}],"predecessor-version":[{"id":20022,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/20005\/revisions\/20022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/20007"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=20005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=20005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=20005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}