{"id":18944,"date":"2025-03-14T00:01:29","date_gmt":"2025-03-13T23:01:29","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=18944"},"modified":"2025-03-13T18:04:17","modified_gmt":"2025-03-13T17:04:17","slug":"universita-washington-caffe-funghi-140320259","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/","title":{"rendered":"L&#8217;Universit\u00e0 di Washington usa funghi e fondi di caff\u00e8 stampati in 3D come alternativa alla plastica"},"content":{"rendered":"<p style=\"text-align: justify;\">Tra coloro che bevono il <a href=\"https:\/\/www.3dnatives.com\/it\/gise-caffe-usa-stampa-3d-291120249\/\" target=\"_blank\" rel=\"noopener\">caff\u00e8<\/a> quotidianamente negli Stati Uniti, oltre l&#8217;80% ne beve due o pi\u00f9 tazze al giorno. Come minimo, ci\u00f2 significa 14 tazze di caff\u00e8 a settimana e 728 tazze di caff\u00e8 all&#8217;anno. In totale, ogni anno gli americani buttano via 1,1 miliardi di chili di fondi di caff\u00e8. Come si pu\u00f2 quindi dare ai fondi di caff\u00e8 una seconda vita e riciclarli in modo significativo? Danli Luo, dottoranda in ingegneria presso l&#8217;Universit\u00e0 di Washington, ha visto un&#8217;opportunit\u00e0 scientifica nell&#8217;incontro quotidiano con la macchina del caff\u00e8 e, insieme ai colleghi, ha sviluppato un metodo per dare nuova vita ai <a href=\"https:\/\/www.3dnatives.com\/it\/grano-tavola-caffetteria-mobili-stampati-3d-a-fondi-di-caffe-010720249\/\" target=\"_blank\" rel=\"noopener\">fondi di caff\u00e8<\/a> grazie alla stampa 3D. Questo studio si pone l&#8217;obiettivo di offrire un&#8217;alternativa ecologica alla plastica.<\/p>\n<h3 style=\"text-align: justify;\">Dal chicco alla stampante<\/h3>\n<p style=\"text-align: justify;\">Il caff\u00e8 \u00e8 estremamente ricco di sostanze nutritive e viene sottoposto a un processo di sterilizzazione nel momento in cui viene trattato. Ci\u00f2 rende i fondi di caff\u00e8 un terreno di coltura ideale per i <a href=\"https:\/\/www.3dnatives.com\/it\/batteria-funghi-biodegradabile-stampata-in-3d-210120259\/\" target=\"_blank\" rel=\"noopener\">funghi<\/a>. Quando crescono, formano prima un complesso sistema di radici, il micelio, dotato di un sottile rivestimento miceliare biancastro. Il micelio dei funghi \u00e8 oggi sempre pi\u00f9 utilizzato come materiale di fabbricazione. Numerose aziende, ricercatori e designer lo stanno sperimentando perch\u00e9 \u00e8 leggero, robusto e idrorepellente. Luo e il suo team di ricercatori hanno combinato l&#8217;uso dei fondi di caff\u00e8 con quello delle spore del fungo reishi per sfruttare i vantaggi di entrambi. Hanno inoltre aggiunto farina di riso integrale e gomma xantana. Hanno cos\u00ec ottenuto una pasta stampabile a base di caff\u00e8, che hanno chiamato \u201cMycofluid\u201d e che \u00e8 servita come materiale di stampa per nuove strutture.<\/p>\n<div id=\"attachment_61476\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-61476\" class=\"wp-image-61476 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/printing-coffee.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-61476\" class=\"wp-caption-text\">La pasta dei fondi di caff\u00e8 viene trasformata in nuove strutture grazie alla stampa 3D.<\/p><\/div>\n<p style=\"text-align: justify;\">Per personalizzare la stampante 3D Jubilee del Machine Agency Lab dell&#8217;Universit\u00e0 di Washington, Luo ha anche sviluppato una testina di stampa con una capacit\u00e0 maggiore (1 litro) per la pasta, in modo da poter estrudere vari oggetti. In questo processo, le spore del fungo reishi iniettate nella pasta assicurano la formazione di un micelio dopo la stampa. Perch\u00e9 ci\u00f2 avvenga, le parti devono essere conservate per dieci giorni. A quel punto, \u00a0lo strato di micelio \u00e8 sufficientemente formato e contribuisce alla stabilit\u00e0 dell&#8217;oggetto stampato. Per evitare che il fungo per\u00f2 si espanda sugli oggetti estrusi con il caff\u00e8, i pezzi devono essere asciugati. Non appena sparisce l&#8217;umidit\u00e0, i funghi smettono di crescere.<\/p>\n<h3 style=\"text-align: justify;\">I fondi del caff\u00e8 per un imballaggio sostenibile<\/h3>\n<p style=\"text-align: justify;\">Grazie a questo studio, sono stati ottenuti dei pezzi leggermente pi\u00f9 pesanti rispetto al polistirolo, ma con una densit\u00e0 simile a quella del cartone e una resistenza equivalente a quella del polistirolo. Inoltre, le strutture stampate risultano completamente compostabili e, sebbene teoricamente commestibili, \u00e8 poco probabile che lo siano realmente. La pasta \u00e8 quindi particolarmente adatta per creare dei materiali da imballaggio e rappresenta un&#8217;alternativa ecologica alla plastica e al polistirolo. Ad esempio, il team ha stampato l&#8217;imballaggio di un bicchiere, alcune parti di vaso e due met\u00e0 di una statua Moai.<\/p>\n<div id=\"attachment_61474\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-61474\" class=\"wp-image-61474 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/uw-coffee-object.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-61474\" class=\"wp-caption-text\">La confezione di un barattolo stampato con fondi di caff\u00e8 e ricoperto di micelio.<\/p><\/div>\n<p style=\"text-align: justify;\"><em>\u201cSiamo particolarmente interessati a creare sistemi per persone come i piccoli imprenditori che producono pochi lotti di prodotti, ad esempio piccoli oggetti di vetro delicati che hanno bisogno di un imballaggio resistente per essere spediti\u201d<\/em>, ha detto Luo. <em>\u201cPer questo abbiamo lavorato a nuovi materiali che possono sostituire il polistirolo con qualcosa di pi\u00f9 sostenibile e che pu\u00f2 essere facilmente personalizzato per la produzione su piccola scala\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">In effetti, Luo ha affermato che il processo non \u00e8 destinato alla produzione massificata. Per poter essere scalato, infatti, avrebbe bisogno di grandi quantit\u00e0 di fondi di caff\u00e8 usati lavorati secondo tecniche omogenee e questo non \u00e8 sempre possibile. Per questo motivo, il gruppo di ricerca sta ora lavorando su paste simili a base biologica per la stampa 3D basate su questo approccio.<\/p>\n<p style=\"text-align: justify;\"><em>\u201cSiamo interessati a estendere questo approccio ad altri materiali bioderivati, come altre forme di rifiuti alimentari\u201d<\/em>, ha aggiunto Luo. <em>\u201cVogliamo sostenere ampiamente questo tipo di sviluppo flessibile, non limitandoci a fornire un&#8217;unica soluzione al grave problema dei rifiuti plastici\u201d<\/em>. Lo studio completo, pubblicato su 3D Printing and Additive Manufacturing il 23 gennaio, \u00e8 disponibile\u00a0<a style=\"font-size: 1em;\" href=\"https:\/\/www.liebertpub.com\/doi\/10.1089\/3dp.2023.0342\" target=\"_blank\" rel=\"noopener\">QUI<\/a><span style=\"font-size: 1em;\">.<\/span><\/p>\n<div id=\"attachment_61475\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-61475\" class=\"wp-image-61475 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/mycelium-uw.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-61475\" class=\"wp-caption-text\">La pelle del micelio intorno alla struttura stampata in fondi di caff\u00e8 garantisce la stabilit\u00e0.<\/p><\/div>\n<p style=\"text-align: justify;\">Cosa ne pensi dei fondi di caff\u00e8 a cui viene data nuova vita grazie alla stampa 3D? Faccelo sapere lasciando un commento qui sotto o sui nostri canali social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\">Facebook<\/a><a href=\"https:\/\/twitter.com\/3Dnatives_IT\">,<\/a>\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">Linkedin<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra\u00a0<a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">newsletter settimanale<\/a> per ricevere tutte le notizie sulla stampa 3D direttamente nella casella di posta!<\/p>\n<p style=\"text-align: justify;\"><em>*Crediti per tutte le foto: Luo et al.\/3D Printing and Additive Manufacturing<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra coloro che bevono il caff\u00e8 quotidianamente negli Stati Uniti, oltre l&#8217;80% ne beve due o pi\u00f9 tazze al giorno. Come minimo, ci\u00f2 significa 14 tazze di caff\u00e8 a settimana e 728 tazze di caff\u00e8 all&#8217;anno. In totale, ogni anno&hellip;<\/p>\n","protected":false},"author":6116,"featured_media":18948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[20],"tags":[],"class_list":["post-18944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;Universit\u00e0 di Washington stampa in 3D funghi e fondi di caff\u00e8 &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"I ricercatori dell&#039;Universit\u00e0 di Washington stanno sviluppando materiali ecologici con funghi e fondi di caff\u00e8 utilizzando la stampa 3D.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Universit\u00e0 di Washington usa funghi e fondi di caff\u00e8 stampati in 3D come alternativa alla plastica &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"I ricercatori dell&#039;Universit\u00e0 di Washington stanno sviluppando materiali ecologici con funghi e fondi di caff\u00e8 utilizzando la stampa 3D.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T23:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/03\/stratasys-3d-printing-surgical-model-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisa L.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa L.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/\"},\"author\":{\"name\":\"Elisa L.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/3365fe0239a351187fba61984a282a31\"},\"headline\":\"L&#8217;Universit\u00e0 di Washington usa funghi e fondi di caff\u00e8 stampati in 3D come alternativa alla plastica\",\"datePublished\":\"2025-03-13T23:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/\"},\"wordCount\":811,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/stratasys-3d-printing-surgical-model-2.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/\",\"name\":\"L'Universit\u00e0 di Washington stampa in 3D funghi e fondi di caff\u00e8 &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/stratasys-3d-printing-surgical-model-2.jpg\",\"datePublished\":\"2025-03-13T23:01:29+00:00\",\"description\":\"I ricercatori dell'Universit\u00e0 di Washington stanno sviluppando materiali ecologici con funghi e fondi di caff\u00e8 utilizzando la stampa 3D.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/stratasys-3d-printing-surgical-model-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/stratasys-3d-printing-surgical-model-2.jpg\",\"width\":850,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/universita-washington-caffe-funghi-140320259\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;Universit\u00e0 di Washington usa funghi e fondi di caff\u00e8 stampati in 3D come alternativa alla plastica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/3365fe0239a351187fba61984a282a31\",\"name\":\"Elisa L.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc59e0bc32fc3a824bc137dbf369ef97531fc50d2fcb5d009be57ddb63422381?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc59e0bc32fc3a824bc137dbf369ef97531fc50d2fcb5d009be57ddb63422381?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc59e0bc32fc3a824bc137dbf369ef97531fc50d2fcb5d009be57ddb63422381?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"caption\":\"Elisa L.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'Universit\u00e0 di Washington stampa in 3D funghi e fondi di caff\u00e8 &#8211; 3Dnatives","description":"I ricercatori dell'Universit\u00e0 di Washington stanno sviluppando materiali ecologici con funghi e fondi di caff\u00e8 utilizzando la stampa 3D.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/","og_locale":"it_IT","og_type":"article","og_title":"L'Universit\u00e0 di Washington usa funghi e fondi di caff\u00e8 stampati in 3D come alternativa alla plastica &#8211; 3Dnatives","og_description":"I ricercatori dell'Universit\u00e0 di Washington stanno sviluppando materiali ecologici con funghi e fondi di caff\u00e8 utilizzando la stampa 3D.","og_url":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2025-03-13T23:01:29+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/03\/stratasys-3d-printing-surgical-model-2.jpg","type":"image\/jpeg"}],"author":"Elisa L.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Elisa L.","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/"},"author":{"name":"Elisa L.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/3365fe0239a351187fba61984a282a31"},"headline":"L&#8217;Universit\u00e0 di Washington usa funghi e fondi di caff\u00e8 stampati in 3D come alternativa alla plastica","datePublished":"2025-03-13T23:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/"},"wordCount":811,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/03\/stratasys-3d-printing-surgical-model-2.jpg","articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/","url":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/","name":"L'Universit\u00e0 di Washington stampa in 3D funghi e fondi di caff\u00e8 &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/03\/stratasys-3d-printing-surgical-model-2.jpg","datePublished":"2025-03-13T23:01:29+00:00","description":"I ricercatori dell'Universit\u00e0 di Washington stanno sviluppando materiali ecologici con funghi e fondi di caff\u00e8 utilizzando la stampa 3D.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/03\/stratasys-3d-printing-surgical-model-2.jpg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2025\/03\/stratasys-3d-printing-surgical-model-2.jpg","width":850,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/universita-washington-caffe-funghi-140320259\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.3dnatives.com\/it\/category\/news\/"},{"@type":"ListItem","position":3,"name":"L&#8217;Universit\u00e0 di Washington usa funghi e fondi di caff\u00e8 stampati in 3D come alternativa alla plastica"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/3365fe0239a351187fba61984a282a31","name":"Elisa L.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cc59e0bc32fc3a824bc137dbf369ef97531fc50d2fcb5d009be57ddb63422381?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc59e0bc32fc3a824bc137dbf369ef97531fc50d2fcb5d009be57ddb63422381?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc59e0bc32fc3a824bc137dbf369ef97531fc50d2fcb5d009be57ddb63422381?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","caption":"Elisa L."},"url":"https:\/\/www.3dnatives.com\/it\/author\/elisa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/18944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6116"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=18944"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/18944\/revisions"}],"predecessor-version":[{"id":18949,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/18944\/revisions\/18949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/18948"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=18944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=18944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=18944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}