{"id":1752,"date":"2021-12-31T09:11:16","date_gmt":"2021-12-31T08:11:16","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=1752"},"modified":"2023-01-13T16:49:16","modified_gmt":"2023-01-13T15:49:16","slug":"rapporto-2021-tendenze-stampa-3d-311220219","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/","title":{"rendered":"Il rapporto 2021 sulle tendenze della stampa 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">Il 2021 \u00e8 stato certamente un anno interessante per il settore della produzione additiva, anche perch\u00e9 si \u00e8 iniziata a vedere la luce alla fine del tunnel, nonostante la pandemia globale in corso. Quest&#8217;anno, gli eventi fisici sono tornati con grande successo: al Formnext 2021, c&#8217;erano 17.859 partecipanti da 75 nazioni diverse e pi\u00f9 di 600 espositori provenienti da 36 paesi, di cui <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-italia-formnext-2021-01122021\/\">circa 30 italiani<\/a>. Insieme a questi, abbiamo visto un numero sorprendente anche di eventi ibridi come Formnext Digital Days, che ha avuto luogo dopo l&#8217;evento fisico. Ci\u00f2 significa che, anche se gli event fisici erano possibili, gli eventi online hanno continuato ad essere molto seguiti, dimostrando che sono probabilmente destinati a rimanere. I risultati ottenuti dai nostri eventi <a href=\"https:\/\/www.additiv.events\/\">ADDITIV<\/a> ne sono un&#8217;ulteriore prova. Quest&#8217;anno, per la prima volta, \u00e8 stato evidente l&#8217;impatto del COVID-19 sull&#8217;industria. Nel <a href=\"https:\/\/wohlersassociates.com\/2021report.htm\" target=\"_blank\" rel=\"noopener\">Wohlers Report 2021<\/a> \u00e8 stato mostrato che, sebbene il settore sia cresciuto rispetto al 2020, la crescita \u00e8 stata significativamente inferiore agli anni precedenti (il 7,5% rispetto a una media del 27,4%).<\/p>\n<p style=\"text-align: justify;\">Questo si spiega anche considerando che molti settori serviti dalla stampa 3D sono stati duramente colpiti dalla pandemia. Il settore aerospaziale e in particolare l&#8217;aviazione commerciale sono stati particolarmente danneggiati, in quanto i viaggi aerei sono stati per lungo tempo sospesi. Questo a sua volta ha avuto un impatto sul mercato della produzione additiva dei <a href=\"https:\/\/www.3dnatives.com\/it\/guida-metalli-stampa-3d-120920219\/\">metalli<\/a>, colpito pi\u00f9 di quello dei <a href=\"https:\/\/www.3dnatives.com\/it\/plastiche-stampa-3d-090920219\/\">polimeri<\/a>. Quest&#8217;anno, con la ripresa dei viaggi, questi settori hanno visto una leggera ripresa. Ma quali sono state esattamente le tendenze della stampa 3D nel 2021? E come sta cambiando \u2013 se sta cambiando \u2013 la produzione additiva? Abbiamo riassunto le tendenze principali che hanno segnato il settore nel 2021.<\/p>\n<div id=\"attachment_2225\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2225\" class=\"size-full wp-image-2225\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/formnext2021.jpg\" alt=\"formnext2021\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/formnext2021.jpg 700w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/formnext2021-600x343.jpg 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/formnext2021-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-2225\" class=\"wp-caption-text\">Gli eventi fisici sono ritornati nel 2021 (Crediti foto: Formnext)<\/p><\/div>\n<h3 style=\"text-align: justify;\">Un mercato in piena evoluzione<\/h3>\n<p style=\"text-align: justify;\">Una tendenza evidente durante il 2021 \u00e8 stato il consolidamento delle aziende produttrici, cos\u00ec come l&#8217;ingresso di un maggior numero di societ\u00e0 in borsa. Forse l&#8217;esempio pi\u00f9 notevole \u00e8 <a href=\"https:\/\/www.3dnatives.com\/it\/directory-stampa-3d\/desktop-metal\/\">Desktop Metal<\/a> che \u00e8 passata in pochi anni dall&#8217;essere una start-up a diventare uno dei principali attori del mercato AM. Quest&#8217;anno l&#8217;azienda ha acquisito a febbraio EnvisionTEC, societ\u00e0 leader nella tecnologia di stampa 3D DLP, mostrando la sua determinazione a entrare nel mercato dei polimeri e dei metalli; Aerosint a luglio, mostrando anche l&#8217;interesse nel mercato multi-materiale e nella <a href=\"https:\/\/www.3dnatives.com\/it\/laser-powder-bed-fusion-lpbf-050920219\/\">tecnologia di fusione a letto di polvere<\/a>; infine, a sorpresa, ha acquistato in agosto il suo concorrente ExOne, il principale produttore di stampanti 3D <a href=\"https:\/\/www.3dnatives.com\/it\/binder-jetting-stampa-3d-060920219\/\">Binder Jetting<\/a> sul mercato.<\/p>\n<p style=\"text-align: justify;\">Desktop Metal non \u00e8 stata l&#8217;unica azienda ad espandersi. Ci sono state altre importanti acquisizioni nel corso dell&#8217;anno, come Protolabs che ha acquisito 3D Hubs con un affare da 280 milioni di dollari all&#8217;inizio dell&#8217;anno e Materialise che ha acquisito Link3D con un affare da 33,5 milioni di dollari a novembre. Inoltre, pi\u00f9 aziende hanno annunciato la loro intenzione di quotarsi in borsa, tra cui VELO3D, Markforged, Xometry, Shapeways e Essentium. Il mercato della produzione additiva, dunque, da questo punto di vista sembra pi\u00f9 maturo e comincia a popolarsi non pi\u00f9 soltanto di start-up, ma di aziende pi\u00f9 grandi capaci di una produzione pi\u00f9 di massa.<\/p>\n<div id=\"attachment_35513\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-35513\" class=\"wp-image-35513 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2021\/12\/dm.png\" alt=\"tendenze della stampa 3D\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-35513\" class=\"wp-caption-text\">Aidro, pioniere nella produzione additiva a metallo di sistemi idraulici di nuova generazione, \u00e8 stata una delle aziende acquisite da Desktop Metal quest&#8217;anno (crediti: Business Wire)<\/p><\/div>\n<p style=\"text-align: justify;\">Il mercato \u00e8 anche guidato dagli investimenti, che secondo i rapporti stanno cominciando a dare i loro frutti. Tra gli altri: DyeMansion il produttore di soluzioni di post-processing, ha raccolto 14 milioni di dollari per la produzione di parti finite; ICON ha ricevuto 207 milioni di dollari in finanziamenti di serie B e Fabric8Labs 19,3 milioni di dollari in finanziamenti di serie A. Sar\u00e0 interessante vedere come il mercato continuer\u00e0 a maturare e crescere nel 2022, ma certamente ci aspettiamo grandi cose dopo questo anno produttivo.<\/p>\n<h3 style=\"text-align: justify;\">La sostenibilit\u00e0: una forte tendenza nella stampa 3D del 2021<\/h3>\n<p style=\"text-align: justify;\">Nel mercato della stampa 3D, come negli altri, si riflettono anche tendenze globali. Per esempio, nel 2021 pi\u00f9 che mai abbiamo visto aziende e governi che hanno cercato di passare a soluzioni pi\u00f9 rispettose dell&#8217;ambiente, per combattere la crisi climatica. La NASA ha evidenziato che gli ultimi sette anni sono stati i pi\u00f9 caldi mai registrati e, secondo l&#8217;Intergovernmental Panel on Climate Change (IPCC) delle Nazioni Unite, entro i prossimi due decenni \u00e8 probabile che le temperature aumentino di 1,5 gradi centigradi. L&#8217;AM \u00e8 stata una delle tecnologie in prima linea grazie alla sua capacit\u00e0 di limitare lo spreco di materiale rispetto ai metodi di produzione tradizionali. Quest&#8217;anno, dunque, <a href=\"https:\/\/www.3dnatives.com\/it\/produzione-additiva-sostenibilita-241120219\/\">la sostenibilit\u00e0 \u00e8 stata un tema centrale<\/a> anche nella comunit\u00e0 AM.<\/p>\n<p style=\"text-align: justify;\">Una prova di questa tendenza \u00e8 la crescita dell&#8217;AMGTA o Additive Manufacturer Green Trade Association, un&#8217;organizzazione creata per promuovere i benefici ambientali della produzione additiva. Gi\u00e0 38 aziende, tra cui Stratasys, ExOne, EOS, BASF, Siemens, 3D Systems e GE Additive ne fanno parte. A Formnext quest&#8217;anno hanno tenuto una serie di conferenze, invitando le aziende ad affrontare i punti deboli lungo l&#8217;intera catena del valore additivo per identificare le azioni da intraprendere in termini di sostenibilit\u00e0.<\/p>\n<p><center><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/YIaC_FFpra0\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/center><\/p>\n<p style=\"text-align: justify;\">Il cambiamento sembra essere in arrivo. Quest&#8217;anno, ci sono stati numerosi progressi nella produzione di materiali pi\u00f9 sostenibili. Alcuni produttori hanno creato materiali a partire dai rifiuti o da altri materiali riciclati, favorendo un&#8217;economia pi\u00f9 circolare. NonOilen di Fillamentum \u00e8 stato il primo filamento biodegradabile al 100% per la stampa 3D.<\/p>\n<h3 style=\"text-align: justify;\"><b>FDM non solo per i polimeri<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Una delle altre tendenze del 2021 \u00e8 stata la continua democratizzazione della stampa 3D, in particolare per materiali non polimerici. Nello specifico, pensiamo alla crescente attenzione all\u2019<a href=\"https:\/\/www.3dnatives.com\/it\/modellazione-deposizione-fusa-021120219\/\">FDM<\/a> per materiali come la <a href=\"https:\/\/www.3dnatives.com\/it\/produzione-additiva-ceramica-131020219\/\">ceramica<\/a> e i metalli, entrambi ambiti nell&#8217;AM in quanto possono essere utilizzati per parti, anche di uso finale, in molti settori importanti come quello aerospaziale e medico. Tuttavia, le macchine che possono stampare con questi materiali non sono molte. Ora, con l&#8217;aumento delle stampanti desktop FDM che possono stampare metalli e ceramiche, la tecnologia sta diventando pi\u00f9 accessibile, economica e facile da usare.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Quest&#8217;anno un certo numero di aziende ha introdotto le proprie soluzioni FDM a metallo, tra cui i ben noti produttori di polimeri FDM BCN3D, Ultimaker e Makerbot. Queste opzioni permetteranno agli utenti di aggiungere la nuova funzione alle loro stampanti, dando loro un&#8217;opzione a basso costo per la <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-metallo\/\">stampa 3D a metallo<\/a>.\u00a0<\/span><\/p>\n<div id=\"attachment_35514\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-35514\" class=\"wp-image-35514 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2021\/12\/markforged.jpg\" alt=\"tendenze della stampa 3D 2021\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-35514\" class=\"wp-caption-text\">Soluzione FDM desktop per materiali non polimerici (crediti foto: Markforged)<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si prevede comunque l\u2019introduzione di soluzioni pi\u00f9 complete: Raise3D e 3DGence hanno gi\u00e0 annunciato che lanceranno stampanti FDM a metallo nel 2022.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><b>Stampa 3D per l\u2019edilizia: forte crescita nel 2021<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">L&#8217;idea di usare la stampa 3D per le costruzioni non \u00e8 nuova, ma ci\u00f2 che ha stupito quest&#8217;anno \u00e8 stata la quantit\u00e0 di progetti diversi realizzati. ICON ha annunciato numerosi progetti in Texas: dalla loro prima casa stampata nel marzo 2018, ora hanno progettato un intero quartiere stampato in 3D con 20 edifici.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La stampa 3D, inoltre, inizia ad essere vista come una risorsa per affrontare importanti questioni umanitarie, in particolare quelle relative alle crisi abitative. Habitat for Humanity ha iniziato a lavorare su una casa unifamiliare stampata in 3D con tre camere da letto e due bagni in Arizona per aiutare con la crisi degli alloggi nello Stato. Sempre pi\u00f9 aziende stanno svelando i piani per quartieri stampati in 3D, soprattutto con abitazioni a basso costo. Un esempio, \u00e8 stato il piano di Twente Additive Manufactring (TAM) e World Housing per la creazione di un villaggio stampato in 3D in Canada, per porre fine al fenomeno dei senzatetto nella comunit\u00e0. Infine, <a href=\"https:\/\/www.3dnatives.com\/it\/tecla-wasp-210420219\/\">il progetto TECLA di WASP<\/a> \u00e8 stato terminato quest&#8217;anno, spianando la strada per alloggi sostenibili con le loro abitazioni stampate in terra cruda.<\/span><\/p>\n<div id=\"attachment_35515\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-35515\" class=\"wp-image-35515 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2021\/12\/tecla.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-35515\" class=\"wp-caption-text\">TECLA \u00e8 stata stampata da WASP a Massa Lombarda, in Italia (crediti foto: WASP)<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Oltre a questi progetti, questo \u00e8 stato anche l&#8217;anno in cui abbiamo visto per la prima volta le case stampate in 3D messe in vendita. A febbraio, SQ4D ha messo sul mercato la prima casa stampata in 3D per 299.999 dollari a Long Island. La famosa Fibonacci House di TAM \u00e8 invece diventata ufficialmente la prima casa stampata in 3D ad essere inserita su Airbnb, disponibile per viaggiatori e appassionati di stampa 3D che vorrebbero prenotare una notte in questa abitazione unica. <\/span><span style=\"font-weight: 400;\">Nel 2022, ci aspettiamo di vedere progetti ancora pi\u00f9 innovativi da parte delle aziende che stanno investendo nella produzione additiva per l\u2019edilizia.<\/span><\/p>\n<p style=\"text-align: justify;\">Cosa ne pensi delle tendenze della stampa 3D nel 2021? Hai qualche previsione per le tendenze nel 2022? Faccelo sapere nei commenti qui sotto o sui nostri canali social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_IT\">Twitter,<\/a>\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">Linkedin<\/a> e\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra <a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">Newsletter<\/a> settimanale per ricevere tutte le notizie sulla stampa 3D direttamente nella tua casella di posta!<\/p>\n<p style=\"text-align: justify;\"><em>*Crediti foto copertina: Pro beam<\/em><\/p>\n<div class=\"dnati-after-post-leaderboard dnati-entity-placement\" id=\"dnati-2939903140\"><div id=\"dnati-2098293386\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener nofollow\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Il 2021 \u00e8 stato certamente un anno interessante per il settore della produzione additiva, anche perch\u00e9 si \u00e8 iniziata a vedere la luce alla fine del tunnel, nonostante la pandemia globale in corso. Quest&#8217;anno, gli eventi fisici sono tornati con&hellip;<\/p>\n","protected":false},"author":6086,"featured_media":1764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[17,20],"tags":[],"class_list":["post-1752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercato-stampa-3d","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il rapporto 2021 sulle tendenze della stampa 3D &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"Quali sono state le tendenze della stampa 3D nel 2021? Come sta cambiando la produzione additiva? Il nostro report 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il rapporto 2021 sulle tendenze della stampa 3D &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"Quali sono state le tendenze della stampa 3D nel 2021? Come sta cambiando la produzione additiva? Il nostro report 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-31T08:11:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-13T15:49:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/Trends.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nunzia A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nunzia A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/\"},\"author\":{\"name\":\"Nunzia A.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\"},\"headline\":\"Il rapporto 2021 sulle tendenze della stampa 3D\",\"datePublished\":\"2021-12-31T08:11:16+00:00\",\"dateModified\":\"2023-01-13T15:49:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/\"},\"wordCount\":1466,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/12\\\/Trends.jpeg\",\"articleSection\":[\"Mercato Stampa 3D\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/\",\"name\":\"Il rapporto 2021 sulle tendenze della stampa 3D &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/12\\\/Trends.jpeg\",\"datePublished\":\"2021-12-31T08:11:16+00:00\",\"dateModified\":\"2023-01-13T15:49:16+00:00\",\"description\":\"Quali sono state le tendenze della stampa 3D nel 2021? Come sta cambiando la produzione additiva? Il nostro report 2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/12\\\/Trends.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/12\\\/Trends.jpeg\",\"width\":850,\"height\":500,\"caption\":\"tendenze stampa 3d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/rapporto-2021-tendenze-stampa-3d-311220219\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercato Stampa 3D\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/mercato-stampa-3d\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il rapporto 2021 sulle tendenze della stampa 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\",\"name\":\"Nunzia A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g\",\"caption\":\"Nunzia A.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/nunzia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il rapporto 2021 sulle tendenze della stampa 3D &#8211; 3Dnatives","description":"Quali sono state le tendenze della stampa 3D nel 2021? Come sta cambiando la produzione additiva? Il nostro report 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/","og_locale":"it_IT","og_type":"article","og_title":"Il rapporto 2021 sulle tendenze della stampa 3D &#8211; 3Dnatives","og_description":"Quali sono state le tendenze della stampa 3D nel 2021? Come sta cambiando la produzione additiva? Il nostro report 2021.","og_url":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2021-12-31T08:11:16+00:00","article_modified_time":"2023-01-13T15:49:16+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/Trends.jpeg","type":"image\/jpeg"}],"author":"Nunzia A.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Nunzia A.","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/"},"author":{"name":"Nunzia A.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714"},"headline":"Il rapporto 2021 sulle tendenze della stampa 3D","datePublished":"2021-12-31T08:11:16+00:00","dateModified":"2023-01-13T15:49:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/"},"wordCount":1466,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/Trends.jpeg","articleSection":["Mercato Stampa 3D","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/","url":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/","name":"Il rapporto 2021 sulle tendenze della stampa 3D &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/Trends.jpeg","datePublished":"2021-12-31T08:11:16+00:00","dateModified":"2023-01-13T15:49:16+00:00","description":"Quali sono state le tendenze della stampa 3D nel 2021? Come sta cambiando la produzione additiva? Il nostro report 2021.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/Trends.jpeg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/12\/Trends.jpeg","width":850,"height":500,"caption":"tendenze stampa 3d"},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/rapporto-2021-tendenze-stampa-3d-311220219\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"Mercato Stampa 3D","item":"https:\/\/www.3dnatives.com\/it\/category\/mercato-stampa-3d\/"},{"@type":"ListItem","position":3,"name":"Il rapporto 2021 sulle tendenze della stampa 3D"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714","name":"Nunzia A.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=mm&r=g","caption":"Nunzia A."},"url":"https:\/\/www.3dnatives.com\/it\/author\/nunzia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/1752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6086"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=1752"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/1752\/revisions"}],"predecessor-version":[{"id":4903,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/1752\/revisions\/4903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/1764"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=1752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=1752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=1752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}