{"id":15144,"date":"2024-10-16T00:01:08","date_gmt":"2024-10-15T22:01:08","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=15144"},"modified":"2024-10-15T17:38:22","modified_gmt":"2024-10-15T15:38:22","slug":"medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/","title":{"rendered":"MedScan3D utilizza la stampa 3D per creare modelli anatomici personalizzati"},"content":{"rendered":"<p style=\"text-align: justify;\">La pianificazione chirurgica ha fatto molta strada negli ultimi anni, grazie alle nuove tecnologie utilizzate nel <a href=\"https:\/\/www.3dnatives.com\/it\/stampa-3d-medicale-dentale\/\">settore medico<\/a>. I medici possono ora contare su strumenti digitali per visualizzare le patologie in 3D, il tutto in modo personalizzato per facilitare le operazioni. Oltre a questi strumenti, possiamo citare la produzione additiva, che svolge un ruolo fondamentale nel settore medico, e pi\u00f9 specificamente nella pianificazione. Consente di progettare modelli anatomici personalizzati a partire dalla scansione del paziente, in modo che il chirurgo possa visualizzare, toccare e allenarsi. Una delle aziende che progetta questi modelli \u00e8 MedScan3D. Offre un&#8217;ampia gamma di prodotti stampati in 3D per migliorare le procedure chirurgiche e formare gli operatori sanitari e i futuri medici. Abbiamo incontrato la fondatrice e CEO Jacqui O&#8217;Connor per saperne di pi\u00f9 su questi dispositivi e su come viene utilizzata la produzione additiva.<\/p>\n<h3 style=\"text-align: justify;\">3DN: Ciao, puoi presentarti?<\/h3>\n<p style=\"text-align: justify;\">Mi chiamo Jacqui O&#8217;Connor e sono la fondatrice e CEO di MedScan3D. Ho una Laurea in Chimica e un Master in Ingegneria biomedica. Sono specializzata nella ricerca e nello sviluppo di biomateriali e dispositivi medici e ho una vasta esperienza clinica nel settore sanitario. Sono membro della rete irlandese e mi occupo di sostenere le donne nelle discipline STEM. In MedScan3D utilizziamo la produzione additiva per creare modelli anatomici specifici per il paziente e clinicamente rilevanti per la pianificazione chirurgica.<\/p>\n<div id=\"attachment_85407\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85407\" class=\"size-full wp-image-85407\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/07\/Medscan3D_Jacqui.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-85407\" class=\"wp-caption-text\">Jacqui O&#8217;Connor<\/p><\/div>\n<h3>3DN: Che cos&#8217;\u00e8 MedScan3D?<\/h3>\n<p style=\"text-align: justify;\">MedScan3D \u00e8 specializzata nella stampa 3D di modelli anatomici 3D altamente precisi e specifici per il paziente, ricavati da scansioni CT, MRI e CBCT. Ci rivolgiamo a tutti i professionisti della sanit\u00e0, come cardiologi, oncologi e chirurghi. Mettere l&#8217;anatomia reale nelle mani degli operatori sanitari riduce i rischi per il paziente e si traduce in un risultato pi\u00f9 soddisfacente, con meno problemi imprevisti in sala operatoria.<\/p>\n<p style=\"text-align: justify;\">I nostri modelli non sono utilizzati solo per la pianificazione chirurgica, ma anche dagli ingegneri ricercatori per fornire modelli di prova per i loro dispositivi medici. Questi modelli possono essere prodotti in una variet\u00e0 di materiali per applicazioni di prototipazione e test di dispositivi. I modelli medici personalizzabili sono adattati a un settore specifico, consentendo di ottimizzare le procedure di prova in tutte le fasi di sviluppo del dispositivo. Lo sviluppo del giusto modello di prova \u00e8 della massima importanza per portare un impianto alla sua fase ottimale. In questo modo il chirurgo avr\u00e0 a disposizione il dispositivo migliore per il trattamento del paziente.<\/p>\n<div id=\"attachment_85405\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85405\" class=\"wp-image-85405 size-full\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/07\/Medscan3D_1.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-85405\" class=\"wp-caption-text\">Questo modello \u00e8 stato progettato per la colangiopancreatografia retrograda endoscopica.<\/p><\/div>\n<p style=\"text-align: justify;\">MedScan3D semplifica quello che normalmente \u00e8 un processo complicato e fornisce una soluzione \u201cchiavi in mano\u201d, interamente in-house. Ci\u00f2 consente di ottenere modelli rapidi, personalizzabili e senza limiti, in grado di soddisfare le esigenze dei team di ricerca e sviluppo.<\/p>\n<h3 style=\"text-align: justify;\">3DN: Quali sono i processi di stampa 3D e i materiali utilizzati?<\/h3>\n<p style=\"text-align: justify;\">In MedScan3D utilizziamo la tecnologia <a href=\"https:\/\/www.3dnatives.com\/it\/material-jetting-polyjet-stampa-3d-110920219\/\">Material Jetting<\/a>, in cui gocce di resina liquida vengono spruzzate su una piattaforma e polimerizzate sotto la luce UV dopo ogni strato. In termini di materiali, utilizziamo diversi tipi di resina:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Materiali che simulano le propriet\u00e0 meccaniche dei tessuti molli.<\/li>\n<li style=\"text-align: justify;\">Materiali siliconici di diversa durezza shore.<\/li>\n<li>Per i dispositivi rigidi, <a href=\"https:\/\/www.3dnatives.com\/it\/policarbonato-stampa-3d-170220239\/\">policarbonato<\/a> o materiali simili all&#8217;acrilico.<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">3DN: Quali sono i principali vantaggi dell&#8217;utilizzo della produzione additiva nel settore medicale, e pi\u00f9 specificamente per MedScan3D?<\/h3>\n<p>Vedo diversi vantaggi nell&#8217;utilizzo della produzione additiva:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Consente la ricostruzione fisica delle scansioni del paziente per fornire un vero modello 3D, anzich\u00e9 basarsi esclusivamente sulle immagini.<\/li>\n<li style=\"text-align: justify;\">Offre soluzioni di prototipazione rapida per determinare i dispositivi e gli impianti appropriati prima di iniziare una procedura.<\/li>\n<li>Migliora la pianificazione della procedura grazie all&#8217;uso di modelli specifici per il paziente.<\/li>\n<li style=\"text-align: justify;\">Facilita la comunicazione con i pazienti.<\/li>\n<\/ul>\n<div id=\"attachment_85406\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85406\" class=\"wp-image-85406 size-full\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/07\/MedScan3D.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-85406\" class=\"wp-caption-text\">Vari modelli di valvola aortica stampati in 3D.<\/p><\/div>\n<h3>3DN: Come vedi lo sviluppo della produzione additiva sel settore medicale nei prossimi 10 anni?<\/h3>\n<p style=\"text-align: justify;\">Ritengo che il campo di applicazione della stampa 3D nel settore medico sia ampio e non sfruttato. Noi di MedScan3D vogliamo essere parte del quadro generale quando si tratta di testare i dispositivi su modelli anatomici. Ora siamo in grado di fornire dati specifici sul paziente per i test al banco, consentendo ai chirurghi di ottenere un feedback reale sul dispositivo che utilizzeranno su un paziente specifico. I progressi del <a href=\"https:\/\/www.3dnatives.com\/it\/3d-bioprinting-medicina-220920219\/\">bioprinting<\/a> sono interessanti, come la possibilit\u00e0 di sostituire le parti in alluminio con parti stampate in 3D con le stesse prestazioni.<\/p>\n<h3>3DN: Qualche ultima parola per i nostri lettori?<\/h3>\n<p style=\"text-align: justify;\">Come donna in un settore dominato dagli uomini, vorrei incoraggiare le giovani donne a interessarsi alle STEM fin dalla pi\u00f9 tenera et\u00e0, mostrando loro che si tratta di un settore appagante in cui \u00e8 possibile combinare la matematica logica con il design creativo. Sebbene l&#8217;industria della produzione additiva sia attualmente un settore molto dominato dagli uomini, questo non pu\u00f2 che incoraggiare le donne nelle STEM a essere all&#8217;avanguardia e a definire gli standard per la prossima generazione. Cerca sempre di entrare in contatto con altre donne che ti ispireranno e ti supporteranno lungo il tuo cammino. Avere un gruppo di sostegno ti incoragger\u00e0 a continuare il tuo percorso verso il successo, e non permettere mai a nessuno di dirti che non puoi realizzare tutto ci\u00f2 che hai deciso di fare! Puoi trovare maggiori informazioni su MedScan3D <a href=\"https:\/\/www.medscan3d.ie\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a>.<\/p>\n<p style=\"text-align: justify;\">Cosa ne pensi di MedScan? \u00a0Condividi la tua opinione sui nostri social\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">LinkedIn<\/a>. Trovi tutti i nostri video sul nostro canale\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra\u00a0<a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/#!\">Newsletter<\/a>\u00a0settimanale per ricevere tutte le notizie sulla stampa 3D direttamente nella casella di posta!<\/p>\n<p><em>*Crediti per tutte le foto: MedScan3D<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pianificazione chirurgica ha fatto molta strada negli ultimi anni, grazie alle nuove tecnologie utilizzate nel settore medico. I medici possono ora contare su strumenti digitali per visualizzare le patologie in 3D, il tutto in modo personalizzato per facilitare le&hellip;<\/p>\n","protected":false},"author":6106,"featured_media":15150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[14,11,20],"tags":[],"class_list":["post-15144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviste","category-medicale","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MedScan3D crea modelli anatomici personalizzati con la stampa 3D &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"MedScan3D \u00e8 un&#039;azienda che produce dispositivi medici utilizzando la produzione additiva: li abbiamo intervistati!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MedScan3D utilizza la stampa 3D per creare modelli anatomici personalizzati &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"MedScan3D \u00e8 un&#039;azienda che produce dispositivi medici utilizzando la produzione additiva: li abbiamo intervistati!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T22:01:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"MedScan3D utilizza la stampa 3D per creare modelli anatomici personalizzati\",\"datePublished\":\"2024-10-15T22:01:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/\"},\"wordCount\":959,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg\",\"articleSection\":[\"Interviste\",\"Medicale e Dentale\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/\",\"url\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/\",\"name\":\"MedScan3D crea modelli anatomici personalizzati con la stampa 3D &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg\",\"datePublished\":\"2024-10-15T22:01:08+00:00\",\"description\":\"MedScan3D \u00e8 un'azienda che produce dispositivi medici utilizzando la produzione additiva: li abbiamo intervistati!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage\",\"url\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg\",\"contentUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg\",\"width\":850,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.3dnatives.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.3dnatives.com\/it\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MedScan3D utilizza la stampa 3D per creare modelli anatomici personalizzati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/#website\",\"url\":\"https:\/\/www.3dnatives.com\/it\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\/\/www.3dnatives.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png\",\"contentUrl\":\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png\",\"width\":407,\"height\":131,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/3Dnativesit\",\"https:\/\/x.com\/3Dnatives\",\"https:\/\/www.instagram.com\/3d_natives\/\",\"https:\/\/www.linkedin.com\/groups\/12583365\/\",\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.3dnatives.com\/it\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MedScan3D crea modelli anatomici personalizzati con la stampa 3D &#8211; 3Dnatives","description":"MedScan3D \u00e8 un'azienda che produce dispositivi medici utilizzando la produzione additiva: li abbiamo intervistati!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/","og_locale":"it_IT","og_type":"article","og_title":"MedScan3D utilizza la stampa 3D per creare modelli anatomici personalizzati &#8211; 3Dnatives","og_description":"MedScan3D \u00e8 un'azienda che produce dispositivi medici utilizzando la produzione additiva: li abbiamo intervistati!","og_url":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2024-10-15T22:01:08+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/"},"author":{"name":"","@id":""},"headline":"MedScan3D utilizza la stampa 3D per creare modelli anatomici personalizzati","datePublished":"2024-10-15T22:01:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/"},"wordCount":959,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg","articleSection":["Interviste","Medicale e Dentale","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/","url":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/","name":"MedScan3D crea modelli anatomici personalizzati con la stampa 3D &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg","datePublished":"2024-10-15T22:01:08+00:00","description":"MedScan3D \u00e8 un'azienda che produce dispositivi medici utilizzando la produzione additiva: li abbiamo intervistati!","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2024\/10\/Medscan3D_cover.jpg","width":850,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/medscan3d-stampa-3d-modelli-anatomici-personalizzati-161020249\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.3dnatives.com\/it\/category\/news\/"},{"@type":"ListItem","position":3,"name":"MedScan3D utilizza la stampa 3D per creare modelli anatomici personalizzati"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2021\/11\/logo_3Dnatives_IT_grey.png","width":407,"height":131,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"","url":"https:\/\/www.3dnatives.com\/it\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/15144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6106"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=15144"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/15144\/revisions"}],"predecessor-version":[{"id":15177,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/15144\/revisions\/15177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/15150"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=15144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=15144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=15144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}