{"id":10719,"date":"2023-12-12T00:01:17","date_gmt":"2023-12-11T23:01:17","guid":{"rendered":"https:\/\/www.3dnatives.com\/it\/?p=10719"},"modified":"2023-11-29T17:29:28","modified_gmt":"2023-11-29T16:29:28","slug":"working3d-esaminatrice-brevetti-stampa-3d-121220239","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/","title":{"rendered":"#Working3D: sei domande a un&#8217;esaminatrice di brevetti di stampa 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">Per la nostra serie di articoli #Working3D, in cui analizziamo le diverse professioni del settore della <a href=\"https:\/\/www.3dnatives.com\/it\/produzione-additiva\/\">produzione additiva<\/a>, abbiamo avuto l&#8217;opportunit\u00e0 di indagare in modo pi\u00f9 approfondito l&#8217;ambito lavorativo connesso ai brevetti di stampa 3D. In particolare, abbiamo intervistato Monica Lozza, rappresentante dell&#8217;European Patent Office (EPO) che ci ha raccontato in cosa consiste la sua professione di <strong>esaminatrice di brevetti di stampa 3D<\/strong>. Le abbiamo chiesto di raccontarci com\u2019\u00e8 strutturato il suo lavoro quotidiano, quali sono le qualifiche che le hanno permesso di raggiungere questo ruolo e di dare un consiglio a chi desidera intraprendere la stessa professione. Da non perdere!<\/p>\n<h3 style=\"text-align: justify;\">3DN: Ciao, puoi presentarti e dirci di pi\u00f9 sull&#8217;attivit\u00e0 dell&#8217;EPO?<\/h3>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10730 alignleft\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozzapic.jpg\" alt=\"\" width=\"250\" height=\"250\" srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozzapic.jpg 250w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozzapic-160x160.jpg 160w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>Ciao, mi chiamo Monica Lozza e lavoro come esaminatrice di brevetti presso l&#8217;ufficio europeo dei brevetti dell&#8217;Aia, l\u2019<strong>EPO (European Patent Office)<\/strong>. L&#8217;EPO \u00e8 l&#8217;autorit\u00e0 che concede brevetti per l&#8217;Europa ad inventori, ricercatori e aziende di tutto il mondo. Si tratta di una delle pi\u00f9 grandi organizzazioni di servizio pubblico in Europa, con circa 6300 dipendenti, tra cui oltre 4000 scienziati e ingegneri che lavorano come esaminatori di brevetti.<\/p>\n<p style=\"text-align: justify;\">Lavoriamo in tutti i campi della tecnologia ed io lavoro in un team con dieci colleghi focalizzati sulla <a href=\"https:\/\/www.3dnatives.com\/it\/plastiche-stampa-3d-090920219\/\">stampa 3D delle materie plastiche.<\/a> La mia area di competenza \u00e8 rappresentata dalle macchine e dai processi di stampa 3D delle materie plastiche, quindi mi occupo specificamente delle domande di brevetto presentate presso il nostro ufficio in questo campo. In altri team, altri colleghi si concentrano sulla <a href=\"https:\/\/www.3dnatives.com\/it\/guida-metalli-stampa-3d-120920219\/\">stampa 3D dei metalli<\/a>, altri sugli aspetti digitali della tecnologia e altri ancora sui materiali (polimeri, biomateriali, etc.).<\/p>\n<h3 style=\"text-align: justify;\">3DN: Qual \u00e8 la giornata tipo di un&#8217;esaminatrice di brevetti nel campo della stampa 3D?<\/h3>\n<p style=\"text-align: justify;\">Ogni domanda di brevetto \u00e8 diversa e quindi ogni giorno \u00e8 diverso. Le domande di brevetto sono testi e disegni che descrivono un&#8217;invenzione. Iniziamo con un controllo formale e poi eseguiamo una ricerca nei nostri database, perch\u00e9 dobbiamo determinare se la presunta invenzione \u00e8 davvero nuova o se esiste gi\u00e0 da qualche altra parte nel mondo. I brevetti vengono concessi solo per invenzioni tecniche nuove, non ovvie e applicabili industrialmente. Il nostro lavoro quotidiano combina cos\u00ec le competenze scientifiche con la ricerca analitica e un occhio per gli aspetti giuridici della propriet\u00e0 intellettuale. Per garantire la massima qualit\u00e0, ogni domanda di brevetto presso l&#8217;EPO viene esaminata da un <strong>team di tre esaminatori<\/strong>. Inoltre, se occorre, consultiamo colleghi che potrebbero avere informazioni da altre aree di competenza e comunichiamo con i richiedenti per allineare la loro domanda ai requisiti legali per un brevetto europeo.<\/p>\n<div id=\"attachment_10726\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10726\" class=\"wp-image-10726 size-full\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza.jpg 700w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza-600x343.jpg 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-10726\" class=\"wp-caption-text\">Monica Lozza con il suo team di lavoro.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Quali sono i titoli di studio richiesti per ricoprire questo ruolo?<\/h3>\n<p style=\"text-align: justify;\">Per diventare un esaminatore di brevetti, occorre una laurea in una materia scientifica o in ingegneria, il requisito minimo \u00e8 la laurea magistrale. La laurea dovrebbe essere pertinente al campo tecnico in cui si desidera lavorare. Per esempio, io mi sono laureata in Ingegneria Chimica al Politecnico di Milano. Occorrono inoltre eccellenti competenze linguistiche, poich\u00e9 lavoriamo in tre lingue ufficiali: inglese, francese e tedesco.<\/p>\n<h3 style=\"text-align: justify;\">3DN: Qual \u00e8 il tuo punto di vista sulla situazione attuale nel mercato dei brevetti per stampa 3D in Europa e nel mondo?<\/h3>\n<p style=\"text-align: justify;\">L\u2019EPO ha appena pubblicato<a href=\"https:\/\/www.3dnatives.com\/it\/litalia-secondo-posto-europa-sistemi-industriali-stampa-3d-200920239\/\"> uno studio sulle tendenze mondiali nell&#8217;innovazione della stampa 3D<\/a>, che rileva che l&#8217;Europa e gli Stati Uniti sono in testa alla corsa globale nell&#8217;innovazione in questa tecnologia. Abbiamo osservato un grande e rapido <strong>aumento del numero di domande di brevetto<\/strong> depositate presso l\u2019EPO. Ci sono molte invenzioni provenienti da grandi aziende, ma anche universit\u00e0, istituti pubblici di ricerca e startup.<\/p>\n<p style=\"text-align: justify;\">A titolo personale, posso certamente confermare questa forte crescita di domande di brevetto nel campo. Quando sono entrata a far parte dell&#8217;EPO 15 anni fa, dopo l&#8217;universit\u00e0 e dopo un periodo di lavoro nel settore industriale, ero una dei tre soli esaminatori di brevetti nel campo della stampa 3D. All\u2019epoca, non si chiamava neppure &#8220;stampa 3D&#8221; o &#8220;manifattura additiva&#8221;, ma &#8220;prototipazione rapida&#8221;. Questo dimostra il cambiamento di focus della tecnologia. Oggi siamo pi\u00f9 di dieci colleghi nel mio team e molti altri esaminatori trattano domande in altri ambiti dello stesso campo.<\/p>\n<h3 style=\"text-align: justify;\">3DN: Quali sono le maggiori sfide che si incontrano in questo lavoro?<\/h3>\n<p style=\"text-align: justify;\">Lavorando come esaminatore di brevetti \u00e8 necessario essere sempre aggiornati sugli ultimi sviluppi. Nel campo della stampa 3D abbiamo visto progressi incredibili, e dobbiamo tenere conto di una forte crescita nella \u201cprior art\u201d (tutte le informazioni disponibili al pubblico prima della data di registrazione della domanda di brevetto), che pu\u00f2 essere in qualsiasi lingua tra cui giapponese, cinese e coreano. A tale scopo, l&#8217;EPO dispone di ampi database e strumenti di traduzione che consentono di effettuare ricerche complete e accurate. Dobbiamo inoltre essere coerenti nell&#8217;applicazione del diritto europeo in materia di brevetti a tutte le domande, perch\u00e9 l\u2019esito del nostro lavoro deve essere prevedibile affinch\u00e9 i brevetti siano utili alle aziende e alla societ\u00e0.<\/p>\n<div id=\"attachment_10727\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10727\" class=\"wp-image-10727 size-full\" src=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza2.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza2.jpg 700w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza2-600x343.jpg 600w, https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/monicalozza2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-10727\" class=\"wp-caption-text\">Esaminare brevetti di stampa 3D richiede competenze trasversali e lavoro in team.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Che consiglio daresti a chi vuole intraprendere la tua professione?<\/h3>\n<p style=\"text-align: justify;\">Oltre ai requisiti minimi a cui accennavo in precedenza (laurea magistrale scientifica\/tecnica e conoscenza delle lingue), occorre avere occhio per il <strong>dettaglio<\/strong> e interesse nell\u2019<strong>innovazione<\/strong>. \u00c8 necessario sentirsi a proprio agio con altre lingue e comunicare con chiarezza. Nel mio caso l\u2019esperienza lavorativa mi \u00e8 sicuramente servita per aggiungere conoscenze pratiche alla mia preparazione universitaria, ma tanti colleghi hanno iniziato a lavorare per l\u2019EPO subito dopo l\u2019universit\u00e0. L\u2019ambiente lavorativo \u00e8 molto internazionale, stimolante ed inclusivo: le ragazze interessate alla scienza e alla tecnologia dovrebbero prendere in considerazione di candidarsi all\u2019EPO!<\/p>\n<p style=\"text-align: justify;\">Cosa ne pensi di questa professione di stampa 3D? Faccelo sapere lasciando un commento sui nostri canali social <a href=\"https:\/\/www.facebook.com\/3Dnativesit\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a><a href=\"https:\/\/twitter.com\/3Dnatives_IT\">,<\/a>\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/12583365\/\">Linkedin<\/a> e\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\">YouTube<\/a>! Non dimenticare di iscriverti alla nostra <a href=\"https:\/\/www.3dnatives.com\/it\/newsletter-stampa-3d\/\">Newsletter<\/a> per ricevere tutte le notizie dall&#8217;evento direttamente nella tua casella di posta!<\/p>\n<p><em>Crediti per tutte le foto: \u201cCopyright European Patent Office\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per la nostra serie di articoli #Working3D, in cui analizziamo le diverse professioni del settore della produzione additiva, abbiamo avuto l&#8217;opportunit\u00e0 di indagare in modo pi\u00f9 approfondito l&#8217;ambito lavorativo connesso ai brevetti di stampa 3D. In particolare, abbiamo intervistato Monica&hellip;<\/p>\n","protected":false},"author":6086,"featured_media":10744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[14,20],"tags":[],"class_list":["post-10719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviste","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>#Working3D: sei domande a un&#039;esaminatrice di brevetti di stampa 3D &#8211; 3Dnatives<\/title>\n<meta name=\"description\" content=\"Per la serie #Working3D, abbiamo intervistato Monica Lozza, esaminatrice di brevetti di stampa 3D presso l&#039;EPO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Working3D: sei domande a un&#039;esaminatrice di brevetti di stampa 3D &#8211; 3Dnatives\" \/>\n<meta property=\"og:description\" content=\"Per la serie #Working3D, abbiamo intervistato Monica Lozza, esaminatrice di brevetti di stampa 3D presso l&#039;EPO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/\" \/>\n<meta property=\"og:site_name\" content=\"3Dnatives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/3Dnativesit\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-11T23:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/MicrosoftTeams-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nunzia A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:site\" content=\"@3Dnatives\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nunzia A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/\"},\"author\":{\"name\":\"Nunzia A.\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\"},\"headline\":\"#Working3D: sei domande a un&#8217;esaminatrice di brevetti di stampa 3D\",\"datePublished\":\"2023-12-11T23:01:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/\"},\"wordCount\":1016,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/11\\\/MicrosoftTeams-image.png\",\"articleSection\":[\"Interviste\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/\",\"name\":\"#Working3D: sei domande a un'esaminatrice di brevetti di stampa 3D &#8211; 3Dnatives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/11\\\/MicrosoftTeams-image.png\",\"datePublished\":\"2023-12-11T23:01:17+00:00\",\"description\":\"Per la serie #Working3D, abbiamo intervistato Monica Lozza, esaminatrice di brevetti di stampa 3D presso l'EPO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/11\\\/MicrosoftTeams-image.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/11\\\/MicrosoftTeams-image.png\",\"width\":850,\"height\":500,\"caption\":\"monica lozza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/working3d-esaminatrice-brevetti-stampa-3d-121220239\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interviste\",\"item\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/category\\\/interviste\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#Working3D: sei domande a un&#8217;esaminatrice di brevetti di stampa 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"name\":\"3Dnatives\",\"description\":\"Il sito web della stampa 3D\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#organization\",\"name\":\"3Dnatives\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/social-logo.png\",\"width\":696,\"height\":696,\"caption\":\"3Dnatives\"},\"image\":{\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3Dnativesit\",\"https:\\\/\\\/x.com\\\/3Dnatives\",\"https:\\\/\\\/www.instagram.com\\\/3d_natives\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/12583365\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMWrNpdLOXa7BffRKXZoaZw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/#\\\/schema\\\/person\\\/f948b97628d47e0ac15f66df6679a714\",\"name\":\"Nunzia A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g\",\"caption\":\"Nunzia A.\"},\"url\":\"https:\\\/\\\/www.3dnatives.com\\\/it\\\/author\\\/nunzia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#Working3D: sei domande a un'esaminatrice di brevetti di stampa 3D &#8211; 3Dnatives","description":"Per la serie #Working3D, abbiamo intervistato Monica Lozza, esaminatrice di brevetti di stampa 3D presso l'EPO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/","og_locale":"it_IT","og_type":"article","og_title":"#Working3D: sei domande a un'esaminatrice di brevetti di stampa 3D &#8211; 3Dnatives","og_description":"Per la serie #Working3D, abbiamo intervistato Monica Lozza, esaminatrice di brevetti di stampa 3D presso l'EPO.","og_url":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/","og_site_name":"3Dnatives","article_publisher":"https:\/\/www.facebook.com\/3Dnativesit","article_published_time":"2023-12-11T23:01:17+00:00","og_image":[{"width":850,"height":500,"url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/MicrosoftTeams-image.png","type":"image\/png"}],"author":"Nunzia A.","twitter_card":"summary_large_image","twitter_creator":"@3Dnatives","twitter_site":"@3Dnatives","twitter_misc":{"Scritto da":"Nunzia A.","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#article","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/"},"author":{"name":"Nunzia A.","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714"},"headline":"#Working3D: sei domande a un&#8217;esaminatrice di brevetti di stampa 3D","datePublished":"2023-12-11T23:01:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/"},"wordCount":1016,"commentCount":0,"publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/MicrosoftTeams-image.png","articleSection":["Interviste","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/","url":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/","name":"#Working3D: sei domande a un'esaminatrice di brevetti di stampa 3D &#8211; 3Dnatives","isPartOf":{"@id":"https:\/\/www.3dnatives.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#primaryimage"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#primaryimage"},"thumbnailUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/MicrosoftTeams-image.png","datePublished":"2023-12-11T23:01:17+00:00","description":"Per la serie #Working3D, abbiamo intervistato Monica Lozza, esaminatrice di brevetti di stampa 3D presso l'EPO.","breadcrumb":{"@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#primaryimage","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/MicrosoftTeams-image.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2023\/11\/MicrosoftTeams-image.png","width":850,"height":500,"caption":"monica lozza"},{"@type":"BreadcrumbList","@id":"https:\/\/www.3dnatives.com\/it\/working3d-esaminatrice-brevetti-stampa-3d-121220239\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.3dnatives.com\/it\/"},{"@type":"ListItem","position":2,"name":"Interviste","item":"https:\/\/www.3dnatives.com\/it\/category\/interviste\/"},{"@type":"ListItem","position":3,"name":"#Working3D: sei domande a un&#8217;esaminatrice di brevetti di stampa 3D"}]},{"@type":"WebSite","@id":"https:\/\/www.3dnatives.com\/it\/#website","url":"https:\/\/www.3dnatives.com\/it\/","name":"3Dnatives","description":"Il sito web della stampa 3D","publisher":{"@id":"https:\/\/www.3dnatives.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3dnatives.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.3dnatives.com\/it\/#organization","name":"3Dnatives","url":"https:\/\/www.3dnatives.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","contentUrl":"https:\/\/www.3dnatives.com\/it\/wp-content\/uploads\/sites\/5\/2026\/06\/social-logo.png","width":696,"height":696,"caption":"3Dnatives"},"image":{"@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3Dnativesit","https:\/\/x.com\/3Dnatives","https:\/\/www.instagram.com\/3d_natives\/","https:\/\/www.linkedin.com\/groups\/12583365\/","https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw"]},{"@type":"Person","@id":"https:\/\/www.3dnatives.com\/it\/#\/schema\/person\/f948b97628d47e0ac15f66df6679a714","name":"Nunzia A.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af384137a5f75fdd0d850dee89e9f631de6198debad513b04ac8777900a8109b?s=96&d=https%3A%2F%2Fwww.3dnatives.com%2Fit%2Fwp-content%2Fthemes%2F3dnatives%2Fassets%2Fimg%2F3dn-gravatar.png&r=g","caption":"Nunzia A."},"url":"https:\/\/www.3dnatives.com\/it\/author\/nunzia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/10719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/users\/6086"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/comments?post=10719"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/10719\/revisions"}],"predecessor-version":[{"id":10735,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/posts\/10719\/revisions\/10735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media\/10744"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/media?parent=10719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/categories?post=10719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/it\/wp-json\/wp\/v2\/tags?post=10719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}