{"id":8941,"date":"2017-07-26T00:04:01","date_gmt":"2017-07-25T22:04:01","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=8941"},"modified":"2017-09-05T15:36:09","modified_gmt":"2017-09-05T13:36:09","slug":"test-ultimaker-3-260720172","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/test-ultimaker-3-260720172\/","title":{"rendered":"Lab 3Dnatives: Test de la impresora 3D Ultimaker 3"},"content":{"rendered":"<p style=\"text-align: justify;\">Presentada de manera sorpresa hace poco m\u00e1s de seis meses, la impresora 3D Ultimaker 3 es la \u00faltima m\u00e1quina desarrollada por el fabricante holand\u00e9s. Uno de los fabricantes de impresoras de escritorio decidi\u00f3 innovar <strong>introduciendo en su cat\u00e1logo un primer modelo equipado con dos extrusores<\/strong> que combinan m\u00faltiples materiales y colores.<\/p>\n<p style=\"text-align: justify;\">Para averiguar las verdaderas innovaciones de la m\u00e1quina hemos recibido la Ultimaker 3 en el laboratorio de 3Dnatives y en <a href=\"https:\/\/www.3dnatives.com\/es\/3D-compare\/imprimante\/ultimaker-3\" target=\"_blank\" rel=\"noopener noreferrer\">nuestro comparador<\/a>. Una oportunidad para ver si el fabricante sigue posicion\u00e1ndose como uno de los l\u00edderes de la industria. Entre las cuestiones planteadas hablamos de: \u00bf la fiabilidad de la m\u00e1quina?, \u00bfla calidad de las piezas ha mejorado? \u00bfC\u00f3mo funciona la mezcla de materiales? Para responder a estas y a muchas preguntas m\u00e1s no te pierdas el Test de la Ultimaker 3 a continuaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8954\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-14.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-14.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-14-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-14-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">1. Desembalaje de la Ultimaker 3<\/span><\/h3>\n<p style=\"text-align: justify;\">Despu\u00e9s de varios tests de impresoras de la marcar Ultimaker llegamos a <a href=\"https:\/\/www.3dnatives.com\/es\/ultimaker-3-nueva-generacion-18102016\/\">esta tercera generaci\u00f3n<\/a>, hemos notado en esta \u00faltima un esfuerzo de su parte por fortalecer, pero a la vez simplificar el embalaje de la impresora 3D. Sigue manteni\u00e9ndose bajo la misma l\u00ednea de calidad, la impresora presenta un paquete compacto y de gran resistencia al da\u00f1o para aguantar el viaje.<\/p><div class=\"dnati-inside_content dnati-entity-placement\" id=\"dnati-3830380312\"><div id=\"dnati-760163321\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"NPE2027_Feathr Ads_850x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Desde un punto de vista est\u00e9tico, Ultimaker 3 es similar en todos los aspectos a su hermana mayor con su poco convencional fuente de alimentaci\u00f3n y sus marcas blancas. La presencia de un segundo extrusor, es realmente lo que la aleja de las semejanzas. La Ultimaker 3 tiene ahora un volumen de impresi\u00f3n ligeramente menor de 215 x 215 x 200 mm contra 223 x 223 x 205 mm de la Ultimaker \u00a02+ (pero m\u00e1s de 197 x 215 x 200 mm si vas m\u00e9todo de extrusi\u00f3n dual ). Adem\u00e1s, <strong>Wi-Fi y un puerto USB<\/strong> est\u00e1n reemplazando la tarjeta SD de la versi\u00f3n anterior.<\/span><\/p>\n<div id=\"attachment_8944\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8944\" class=\"wp-image-8944 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-4.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-4.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-4-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-4-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><p id=\"caption-attachment-8944\" class=\"wp-caption-text\">La impresora 3D viene provista de una bobina PLA y una bobina soluble de PVA<\/p><\/div>\n<p style=\"text-align: justify;\">Entre los elementos que se incluyen con la m\u00e1quina, nos encontramos con una amplia gama de accesorios: una bandeja de vidrio, cubierta de cables, un soporte de bobina, dos filamentos gu\u00edas, una bobina de filamento PLA (350 g) y una bobina de filamento medio PVA (350g) de la marca Ultimaker, un cable Ethernet, una memoria USB, una barra de pegamento, aceite para la X \/ Y, grasa para las barras del eje Z, un destornillador, hoja de calibraci\u00f3n XY , tarjeta de calibraci\u00f3n Z, gu\u00eda de inicio r\u00e1pido, cables de alimentaci\u00f3n, y tambi\u00e9n una prueba de impresi\u00f3n para la m\u00e1quina.<\/p>\n<p style=\"text-align: justify;\">La otra gran novedad de la Ultimaker 3 son sus nuevos componentes Print Core, que es <strong>la capacidad de adaptaci\u00f3n de los extrusores de la impresora a diferentes filamentos<\/strong>, lo que reduce el riesgo de obstrucci\u00f3n de las boquillas y asegura un f\u00e1cil mantenimiento de la m\u00e1quina. As\u00ed nos encontramos con dos Print \u00a0Core de 0.4mm, el primero llamado \u00abAA\u00bb dedicada a la impresi\u00f3n de filamentos convencionales tales como PLA o ABS (ya instalado en la m\u00e1quina) y un n\u00facleo de 0,4 mm de impresi\u00f3n el \u00abBB\u00bb para la impresi\u00f3n de materiales de soporte (PVA-instalaci\u00f3n al \u00a0momento).<\/p>\n<p style=\"text-align: justify;\">Otras mejoras en la impresora 3D ,que hay que tener en cuenta, es la presencia de una c\u00e1mara de vigilancia, sistema de ventilaci\u00f3n optimizado, indicador para alertar al usuario de posibles anomal\u00edas.<\/p>\n<div id=\"attachment_8942\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8942\" class=\"wp-image-8942 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-2.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-2.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-2-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-2-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><p id=\"caption-attachment-8942\" class=\"wp-caption-text\">La impresora y todo los accesorio incluidos al adquirirla<\/p><\/div>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">2.Instalaci\u00f3n <\/span><\/h3>\n<p style=\"text-align: justify;\">Ya puesta fuera de su empaque, la instalaci\u00f3n de los diferentes elementos de la impresora nos llevar\u00e1 tan s\u00f3lo diez minutos. Debes conectar el soporte de la bobina, que ahora se rastrea con <strong>un chip NFC, que registra la cantidad restante de filamento<\/strong>, a\u00f1adir la cubierta del cable, inserta la tapa de cristal, y finalmente conectar el cable de alimentaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Una pantalla se encender\u00e1 en la Ultimaker 3, sigue siendo similar a las pantallas de generaciones anteriores, mientras que una pantalla LCD a color habr\u00eda sido muy apreciado, como una Form 2 de Formlabs o una N2 Dual de Raise3D.<\/p>\n<div id=\"attachment_8943\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8943\" class=\"wp-image-8943 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-3.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-3.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-3-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-3-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><p id=\"caption-attachment-8943\" class=\"wp-caption-text\">Los Print Core AA y BB, los nuevos componentes de la Ultimaker 3<\/p><\/div>\n<p style=\"text-align: justify;\">El siguiente paso colocar el Print Core en el cabezal de impresi\u00f3n, luego se cargan los filamentos deseados. Punto a destacar, es que tendr\u00e1s que cargar los dos filamentos en la impresora cada vez que desees poner en marcha una sola impresi\u00f3n. Y aunque esta etapa sigue siendo en gran medida similar a la antigua Ultimaker, lo har\u00e1s muy \u00a0f\u00e1cilmente guiado a trav\u00e9s del panel de control de la m\u00e1quina. El sistema de chip NFC es bastante eficaz, reconoce cada etapa de bobinas de carga adecuadas dependiendo del Print Core de impresi\u00f3n instalado.<\/p>\n<p style=\"text-align: justify;\">Un \u00faltimo paso importante est\u00e1 relacionado con la placa de calibraci\u00f3n y el desplazamiento XY. Para la mesa de impresi\u00f3n, es aconsejable comenzar con un manual tradicional de calibraci\u00f3n. Tambi\u00e9n tendr\u00e1s acceso a un nuevo procedimiento llamado \u00abnivelaci\u00f3n activo\u00bb. Esta funci\u00f3n permite calibrar la bandeja mediante la comprobaci\u00f3n y el reajuste de 3 puntos de referencia en \u00e9l, y permite imprimir autom\u00e1ticamente compensando los errores de calibraci\u00f3n al elevar o bajar la bandeja. Un procedimiento bastante r\u00e1pido (aproximadamente 2-3 minutos) que se puede realizar antes de cada tiempo de impresi\u00f3n. En nuestro caso, hemos tenido algunas preocupaciones relacionadas con la calibraci\u00f3n, debido al tornillo de ajuste, pero nada serio.<\/p>\n<div id=\"attachment_8955\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8955\" class=\"wp-image-8955 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><p id=\"caption-attachment-8955\" class=\"wp-caption-text\">Pantalla que controla la impresora 3D<\/p><\/div>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">3. Software Cura<\/span><\/h3>\n<p style=\"text-align: justify;\">Hablando del software es por supuesto, Cura, el famoso programa de c\u00f3digo abierto desarrollado por Ultimaker. Para la Ultimaker 3, tienes que descargar la versi\u00f3n 2.3 o alguno m\u00e1s reciente. Una vez instalado, el primer paso es conectar la impresora 3D en unos pocos pasos simples con tu red Wi-Fi, algo que llev\u00e1bamos tiempo esperando. Tambi\u00e9n podr\u00e1s conectar \u00a0la impresora mediante un cable Ethernet o un USB.<\/p>\n<p style=\"text-align: justify;\">Al abrir Cura, uno se da cuenta de que<strong> el software reconoce autom\u00e1ticamente los materiales y los colores<\/strong> de la m\u00e1quina, una novedad que ofrece la presencia de chips NFC, que simplifican la experiencia del usuario.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Muchas opciones han surgido en los \u00faltimos meses en el software de Cura, algunos relacionados con el m\u00e9todo de extrusi\u00f3n doble propuesto para la Ultimaker 3. Al realizar tus primeras impresiones, es muy probable que pases tiempo probando y optimizando estos par\u00e1metros, algunos todav\u00eda en versi\u00f3n Beta.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8946\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-6.jpg\" alt=\"\" width=\"620\" height=\"363\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-6.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-6-300x176.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-6-160x94.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">4. Las primeras impresiones 3D<\/span><\/h3>\n<p style=\"text-align: justify;\">Algunos dir\u00e1n que la presencia de los chips NFC cierra un poco la impresora a otras marcas; Ultimaker sin embargo asegur\u00f3 permitir a los usuarios la posibilidad de utilizar otras marcas de carretes, aunque \u00e9stos no ser\u00e1n reconocidos por Cura. Por ahora, la marca todav\u00eda aconsejan utilizar el modo extrusi\u00f3n dual con los siguientes pares de filamentos: PLA-PVA, Nylon-PVA-PLA PLA, ABS-ABS y CPE-CPE (co-poli\u00e9ster). Como parte de la prueba, se limita sin embargo a la impresi\u00f3n \u00fanica PLA, sino tambi\u00e9n a las parejas PLA-PLA y PLA-PVA.<\/p>\n<p style=\"text-align: justify;\">Una de las debilidades observadas en las impresiones no es tanto la calidad de los modelos, est\u00e1 m\u00e1s relacionado con la velocidad de impresi\u00f3n. Est\u00e1 bastante claro que <strong>la impresi\u00f3n en dos colores y dos materiales aumenta el tiempo de producci\u00f3n<\/strong>. Sin embargo, la velocidad puede ser optimizado cambiando algunos ajustes en Cura. Se pueden ganar preciosos minutos jugando con un par\u00e1metro tal como montajes c\u00f3nicos (para reducir el tama\u00f1o de los medios de base) o el relleno de malla que proporcionar\u00e1n un relleno m\u00e1s o menos denso en diferentes niveles del modelo.<\/p>\n<p style=\"text-align: justify;\">El uso de los materiales de Ultimaker asegura una impresi\u00f3n fiable y tener los par\u00e1metros correctos asociados. A continuaci\u00f3n encontrar\u00e1s una serie de monedas impresas en 3D en la Ultimaker 3. Los resultados hablan por s\u00ed mismos, la calidad no se ha perdido a pesar de la complejidad de algunas partes. La extrusi\u00f3n de modo dual, mezcla los filamentos y se mantiene limpio debido a la impresi\u00f3n simult\u00e1nea de una Prime Tower para purgar los inyectores.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8947\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-7.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-7.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-7-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-7-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8948\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-8.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-8.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-8-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-8-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8951\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-11.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-11.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-11-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-11-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8949\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-9.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-9.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-9-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-9-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8950\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-10.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-10.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-10-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-10-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8952\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-12.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-12.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-12-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-12-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8953\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-13.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-13.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-13-300x169.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/test_ultimaker3-13-160x90.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.3dnatives.com\/es\/archivo-tests\/tests-de-impresoras-3d\/\"><strong>Encuentra m\u00e1s tests de\u00a0impresoras 3D en nuestro\u00a0Lab 3Dnatives<\/strong><\/a><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-1539825674\"><div id=\"dnati-89376264\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Presentada de manera sorpresa hace poco m\u00e1s de seis meses, la impresora 3D Ultimaker 3 es la \u00faltima m\u00e1quina desarrollada por el fabricante holand\u00e9s. Uno de los fabricantes de impresoras de escritorio decidi\u00f3 innovar introduciendo en su cat\u00e1logo un primer&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":8945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,17],"tags":[],"class_list":["post-8941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-tests"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/8941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=8941"}],"version-history":[{"count":1,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/8941\/revisions"}],"predecessor-version":[{"id":30728,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/8941\/revisions\/30728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/8945"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=8941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=8941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=8941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}