{"id":85246,"date":"2026-01-28T00:00:55","date_gmt":"2026-01-27T23:00:55","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=85246"},"modified":"2026-01-28T07:23:34","modified_gmt":"2026-01-28T06:23:34","slug":"extrudex-transformar-residuos-filamentos-28012026","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/extrudex-transformar-residuos-filamentos-28012026\/","title":{"rendered":"ExtrudeX, una m\u00e1quina DIY para transformar tus residuos pl\u00e1sticos en filamentos de impresi\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">Aunque la impresi\u00f3n 3D permite ahorrar material al depositarlo solo donde es necesario, no deja de generar residuos. \u00bfQu\u00e9 hacer con las impresiones fallidas, los restos de filamento o, simplemente, las piezas que se quieren tirar? La joven empresa Creative3DP, dirigida por Priyank Pal, ha ideado <strong>ExtrudeX<\/strong>, una m\u00e1quina accesible y f\u00e1cil de usar para remediar este problema. La idea es poder <strong>transformar todos estos residuos pl\u00e1sticos en filamentos reutilizables<\/strong>, directamente desde tu taller o desde casa. Lanzado y financiado en Kickstarter, este proyecto, que se puede imprimir en 3D en casa, ha tenido un gran \u00e9xito, lo que demuestra que es posible cerrar el ciclo.<\/p>\n<p style=\"text-align: justify;\">La idea de una m\u00e1quina de este tipo no es nueva y nos vienen a la mente algunos nombres, como la empresa holandesa <a href=\"https:\/\/www.3dnatives.com\/es\/startup-3devo-reciclaje-plasticos-filamentos-070820192\/\">3devo<\/a>. Hay que decir que este tipo de soluciones son muy interesantes, ya que favorecen el reciclaje, la econom\u00eda circular y los circuitos locales cortos que permiten trabajar con total autonom\u00eda. Pero entonces, \u00bfen qu\u00e9 se diferencia ExtrudeX?<\/p>\n<div id=\"attachment_92335\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-92335\" class=\"size-full wp-image-92335\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2026\/01\/extrudex_machine.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-92335\" class=\"wp-caption-text\">La m\u00e1quina ExtrudeX pretende ser f\u00e1cil de usar y accesible.<\/p><\/div>\n<hr \/>\n<h2 style=\"text-align: justify;\">Caracter\u00edsticas clave de ExtrudeX<\/h2>\n<p style=\"text-align: justify;\">Seg\u00fan su creador, se trata ante todo de ofrecer una m\u00e1quina m\u00e1s compacta y ligera, adecuada para los makers y el uso dom\u00e9stico. ExtrudeX mide <strong>65 cm<\/strong> de largo, por lo que la puedes colocar f\u00e1cilmente sobre una mesa junto a tu impresora FDM, por ejemplo. Dotada de un asa lateral, tambi\u00e9n es <strong>f\u00e1cilmente transportable<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Pero lo que resulta especialmente interesante es que <strong>se construye directamente en casa<\/strong>. Se compone de varias piezas impresas en 3D, como el chasis y el sistema de extracci\u00f3n. Su fabricaci\u00f3n es econ\u00f3mica y se puede reparar f\u00e1cilmente si se rompe o se desgasta alg\u00fan componente. En cuanto a las dem\u00e1s piezas, como el motor y los componentes electr\u00f3nicos, se pueden comprar f\u00e1cilmente en tiendas locales. La ventaja de una m\u00e1quina DIY es que se entiende mucho mejor c\u00f3mo funciona, lo que facilita su uso diario.<\/p>\n<p style=\"text-align: justify;\">En cuanto a los materiales, la ExtrudeX puede procesar materiales de soporte, impresiones fallidas, pellets limpios: todo los puedes mezclar para crear un filamento de impresi\u00f3n. Cabe se\u00f1alar que, por el momento, solo son compatibles el <a href=\"https:\/\/www.3dnatives.com\/es\/guia-filamento-pla-en-la-impresion-3d-190820192\/\">PLA<\/a>, el <a href=\"https:\/\/www.3dnatives.com\/es\/filamento-de-abs-impresion-3d-06062019\/\">ABS<\/a> y el <a href=\"https:\/\/www.3dnatives.com\/es\/el-plastico-petg-en-la-impresion-3d-181220192\/\">PETG<\/a>.<\/p>\n<div id=\"attachment_92336\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-92336\" class=\"size-full wp-image-92336\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2026\/01\/extrudex_parameters.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-92336\" class=\"wp-caption-text\">Ajusta la m\u00e1quina f\u00e1cilmente en funci\u00f3n del pl\u00e1stico que deseas transformar.<\/p><\/div>\n<hr \/>\n<h2 style=\"text-align: justify;\">\u00bfC\u00f3mo funciona?<\/h2>\n<p style=\"text-align: justify;\">En concreto, \u00bfc\u00f3mo funciona la Extruder? Debes seguir seis pasos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Corta los residuos pl\u00e1sticos: puedes utilizar una trituradora o unas tijeras.<\/li>\n<li>Calienta la ExtrudeX en funci\u00f3n del pl\u00e1stico utilizado.<\/li>\n<li>Coloca el pl\u00e1stico cortado en la tolva.<\/li>\n<li>Pon en marcha el motor.<\/li>\n<li>Inserta el hilo extruido en el mecanismo de extracci\u00f3n.<\/li>\n<li>Espera a que se enfr\u00ede y recupera el filamento.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Creative3DP recomienda mezclar un 40 % de residuos triturados con un 60 % de pellets de pl\u00e1stico virgen y siempre con el mismo material, por lo que debes utilizar restos de PLA con <a href=\"https:\/\/www.3dnatives.com\/es\/impresion-3d-pellets-proceso-fabricacion-161220212\/\">pellets<\/a> de PLA.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/TvjR2JvBCVo?si=pTEA8zJeuCFWXZSB\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">La campa\u00f1a de Kickstarter ya ha finalizado y la m\u00e1quina se puede comprar en la p\u00e1gina web de Creative3DP por algo m\u00e1s de 200 euros. Te invitamos a visitar la p\u00e1gina <a href=\"https:\/\/creative3dp.com\/products\/extrudex-diy-filament-recycling-machine\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a> para obtener m\u00e1s informaci\u00f3n. Por el momento, est\u00e1 agotada.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 opinas de la m\u00e1quina ExtrudeX? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener\u00a0noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/groups\/8516968\/\" target=\"_blank\" rel=\"noopener\u00a0noreferrer\">LinkedIn<\/a> y <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\" target=\"_blank\" rel=\"noopener\u00a0noreferrer\">Youtube<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener\u00a0noreferrer\">Newsletter\u00a0semanal<\/a>.<\/p>\n<p style=\"text-align: justify;\"><em>*Cr\u00e9ditos de todas las fotos: Creative3DP<\/em><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-4223849308\"><div id=\"dnati-596891216\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Aunque la impresi\u00f3n 3D permite ahorrar material al depositarlo solo donde es necesario, no deja de generar residuos. \u00bfQu\u00e9 hacer con las impresiones fallidas, los restos de filamento o, simplemente, las piezas que se quieren tirar? La joven empresa Creative3DP,&hellip;<\/p>\n","protected":false},"author":6110,"featured_media":85247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,9],"tags":[],"class_list":["post-85246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-impresoras-3d"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/85246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=85246"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/85246\/revisions"}],"predecessor-version":[{"id":85250,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/85246\/revisions\/85250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/85247"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=85246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=85246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=85246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}