{"id":82823,"date":"2025-07-10T00:02:27","date_gmt":"2025-07-09T22:02:27","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=82823"},"modified":"2025-07-07T10:29:14","modified_gmt":"2025-07-07T08:29:14","slug":"qr3d-casa-cuatro-plantas-impresa-3d-100720252","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/qr3d-casa-cuatro-plantas-impresa-3d-100720252\/","title":{"rendered":"QR3D, la casa de cuatro plantas impresa en 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">La <a href=\"https:\/\/www.3dnatives.com\/es\/fundamentos-fabricacion-aditiva\/\">fabricaci\u00f3n aditiva<\/a> ha vuelto a demostrar toda su agilidad en el sector de la construcci\u00f3n, \u00a1esta vez en Singapur! El pa\u00eds ha inaugurado recientemente una casa de varios pisos con paredes impresas en 3D. Bautizada como QR3D, ha sido dise\u00f1ada por el estudio de arquitectura Park + Associates e integra un vac\u00edo escult\u00f3rico en su centro. Construida en colaboraci\u00f3n con la empresa CES_InnovFab, la casa est\u00e1 compuesta en m\u00e1s de un 90% por materiales impresos en 3D. Adem\u00e1s, cuenta con un total de cuatro plantas y 570 metros cuadrados; toda una proeza para la fabricaci\u00f3n aditiva.<\/p>\n<p style=\"text-align: justify;\">La impresi\u00f3n 3D de hormig\u00f3n ofrece m\u00faltiples ventajas al <a href=\"https:\/\/www.3dnatives.com\/es\/infografia-impresion-3d-construccion-110520232\/\">sector de la construcci\u00f3n<\/a> y los proyectos de viviendas que utilizan esta tecnolog\u00eda no dejan de multiplicarse. Esta t\u00e9cnica permite acortar los plazos de construcci\u00f3n, reducir la dureza del trabajo, disminuir los costes y dise\u00f1ar formas nunca antes vistas. A\u00fan no hemos llegado al punto de ver <a href=\"https:\/\/www.3dnatives.com\/es\/funcionamiento-impresora-3d-hormigon-120720212\/\">impresoras 3D de hormig\u00f3n<\/a> por todas partes, pero el futuro es muy prometedor y la industria de la construcci\u00f3n lo ha comprendido bien. En cualquier caso, en Singapur, la casa QR3D es sin duda el ejemplo perfecto de lo que se puede lograr.<\/p>\n<div id=\"attachment_90248\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-90248\" class=\"size-full wp-image-90248\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2025\/07\/Q3RD_bathroom.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-90248\" class=\"wp-caption-text\">Uno de los ba\u00f1os de la casa. (Cr\u00e9ditos: STUDIOWONGS)<\/p><\/div>\n<h2>El interior de la casa QR3D<\/h2>\n<p style=\"text-align: justify;\">Se trata de una casa de m\u00e1s de <strong>570 metros cuadrados<\/strong> que cuenta con <strong>7 habitaciones<\/strong> distribuidas en <strong>4 plantas<\/strong>, dise\u00f1ada para Lim Koon Park, fundador y arquitecto del estudio Park + Associates. \u00c9l mismo explica: <em>\u201cQuer\u00edamos crear algo que fuera m\u00e1s all\u00e1 de una demostraci\u00f3n tecnol\u00f3gica. La arquitectura centrada en la tecnolog\u00eda suele producir una eficiencia uniforme o formas experimentales que carecen de habitabilidad. Quer\u00edamos algo m\u00e1s matizado\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Parte de la casa se imprimi\u00f3 en 3D in situ, y el equipo se asegur\u00f3 de proteger bien la m\u00e1quina de las inclemencias del tiempo y del clima tropical de Singapur. Otros elementos se crearon directamente en f\u00e1brica. Lo que m\u00e1s llama la atenci\u00f3n de la casa QR3D es la integraci\u00f3n de un <strong>\u00f3culo,<\/strong> es decir, una abertura redonda, que atraviesa las cuatro plantas y confiere al comedor un ambiente \u00fanico. Sirve tanto como sistema de refrigeraci\u00f3n como de aut\u00e9ntico pozo de luz. Este \u00f3culo est\u00e1 compuesto por diferentes ladrillos impresos en 3D que luego se ensamblaron. En concreto, esta parte supuso un reto importante en el proyecto debido a su inclinaci\u00f3n. El hormig\u00f3n tend\u00eda a hundirse en algunos puntos, por lo que el equipo prefiri\u00f3 crear componentes m\u00e1s peque\u00f1os que pudieran ensamblarse f\u00e1cilmente.<\/p>\n<div id=\"attachment_90247\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-90247\" class=\"size-full wp-image-90247\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2025\/07\/QR3D.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-90247\" class=\"wp-caption-text\">El \u00f3culo atraviesa las cuatro plantas y proporciona luz y refrigeraci\u00f3n. (Cr\u00e9ditos, de izquierda a derecha: STUDIOWONGS; Derek Swalwell; STUDIOWONGS)<\/p><\/div>\n<p style=\"text-align: justify;\">Los materiales que se utilizaron pueden inscribirse en una l\u00f3gica medioambiental, ya que la mayor\u00eda son reciclados. De hecho, esta era una preocupaci\u00f3n importante para el estudio de arquitectura. A\u00f1aden: <em>\u201cLa impresi\u00f3n 3D para la construcci\u00f3n en Singapur no es nueva, pero se utiliza principalmente a peque\u00f1a escala y con fines utilitarios, como muros decorativos, maceteros y ba\u00f1os prefabricados para proyectos multiresidenciales\u201d<\/em>. Se trata de la primera casa de varios pisos impresa en 3D y muestra claramente c\u00f3mo la fabricaci\u00f3n aditiva puede transformar el paisaje urbano. Haz clic AQU\u00cd para obtener m\u00e1s informaci\u00f3n y ver m\u00e1s fotos del proyecto.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la casa QR3D? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/groups\/8516968\/\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a> y <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<p><em>*Cr\u00e9ditos foto de portada: STUDIOWONGS<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fabricaci\u00f3n aditiva ha vuelto a demostrar toda su agilidad en el sector de la construcci\u00f3n, \u00a1esta vez en Singapur! El pa\u00eds ha inaugurado recientemente una casa de varios pisos con paredes impresas en 3D. Bautizada como QR3D, ha sido&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":82824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,297],"tags":[],"class_list":["post-82823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-arquitectura"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/82823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=82823"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/82823\/revisions"}],"predecessor-version":[{"id":82828,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/82823\/revisions\/82828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/82824"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=82823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=82823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=82823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}