{"id":77914,"date":"2024-10-14T15:00:11","date_gmt":"2024-10-14T13:00:11","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=77914"},"modified":"2024-10-17T10:30:27","modified_gmt":"2024-10-17T08:30:27","slug":"acoplasticos-industria-plastico-mediante-la-manufactura-aditiva-141020242","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/acoplasticos-industria-plastico-mediante-la-manufactura-aditiva-141020242\/","title":{"rendered":"Acopl\u00e1sticos impulsa la innovaci\u00f3n en la industria del pl\u00e1stico mediante la manufactura aditiva"},"content":{"rendered":"<p style=\"text-align: justify;\">La industria del pl\u00e1stico en <a href=\"https:\/\/www.3dnatives.com\/es\/la-impresion-3d-en-latinoamerica-140120212\/\">Am\u00e9rica Latina<\/a> est\u00e1 experimentando una transformaci\u00f3n profunda con la adopci\u00f3n de tecnolog\u00edas avanzadas como la impresi\u00f3n 3D. En ese sentido, Acopl\u00e1sticos juega un rol importante en la promoci\u00f3n de las tecnolog\u00edas 3D entre las principales empresas del pl\u00e1stico en Colombia. A trav\u00e9s de su divisi\u00f3n <strong>ACO3D<\/strong>, la organizaci\u00f3n ha liderado iniciativas como el 3DFEST y la creaci\u00f3n de alianzas estrat\u00e9gicas con instituciones como el SENA (Servicio Nacional de Aprendizaje), promoviendo la manufactura aditiva y facilitando el desarrollo de competencias en la industria. Hablamos con el presidente Acopl\u00e1sticos, Daniel Mitchell, para saber m\u00e1s sobre la organizaci\u00f3n, su labor para impulsar la impresi\u00f3n 3D y su impacto en el sector del <a href=\"https:\/\/www.3dnatives.com\/es\/plasticos-impresion-3d-22072015\/\">pl\u00e1stico<\/a>.<\/p>\n<h3>\u00bfPodr\u00eda presentarse y contarnos qu\u00e9 es Acopl\u00e1sticos?<\/h3>\n<p style=\"text-align: justify;\">Mi nombre es Daniel Mitchell y soy el presidente de Acopl\u00e1sticos. Acopl\u00e1sticos es una asociaci\u00f3n fundada en 1961 que re\u00fane y representa a las industrias de materiales y productos pl\u00e1sticos, reciclaje de pl\u00e1sticos, pinturas, caucho, tintas, fibras y sectores relacionados en Colombia.<\/p>\n<h3>\u00bfC\u00f3mo surgi\u00f3 Aco3D y cu\u00e1les son sus objetivos?<\/h3>\n<p style=\"text-align: justify;\">ACO3D surge en el a\u00f1o 2019, cuando Acopl\u00e1sticos toma la iniciativa de acercarse a los emprendedores y empresarios de este sector en Colombia, con el fin de conformar un grupo s\u00f3lido de empresas con las cuales trabajar en pro de esa industria. El primer gran paso se dio en el marco de una alianza con el Hub de Innovaci\u00f3n del SENA Medell\u00edn, con quien se cre\u00f3 y lanz\u00f3 <em>\u201c3DFEST: la primera impresi\u00f3n vale por tres\u201d<\/em>. Este fue el primer festival de impresi\u00f3n 3D del pa\u00eds destinado a promover la transferencia de conocimientos, la innovaci\u00f3n y la generaci\u00f3n de alianzas estrat\u00e9gicas, brindando herramientas tecnol\u00f3gicas en \u00e1reas afines a la manufactura aditiva, la fabricaci\u00f3n digital, la realidad virtual y aumentada, la animaci\u00f3n y la impresi\u00f3n 3D.<\/p>\n<p style=\"text-align: justify;\">Tras ese primer hito, ACOPL\u00c1STICOS continu\u00f3 fortaleciendo el relacionamiento con las empresas del sector, lo que llev\u00f3 a que se realizara una segunda edici\u00f3n del 3DFEST en 2022, esta vez en el marco de la feria ColombiaPlast. En esta edici\u00f3n, un grupo de empresas de impresi\u00f3n 3D y manufactura aditiva exhibieron su oferta de bienes y servicios ante los casi 40.000 visitantes que tuvo la feria.<\/p>\n<p style=\"text-align: justify;\">Con el \u00e9xito de las primeras dos ediciones del 3DFEST, ACOPL\u00c1STICOS tom\u00f3 la decisi\u00f3n de formalizar este proyecto con la creaci\u00f3n del cap\u00edtulo sectorial <strong>ACO3D<\/strong>, mediante el cual se trabaja para impulsar el crecimiento y el desarrollo sostenible de la impresi\u00f3n 3D y la fabricaci\u00f3n digital. Nuestros objetivos incluyen; desarrollar iniciativas colectivas y fomentar sinergias con las empresas de los sectores representados a trav\u00e9s de proyectos, campa\u00f1as, eventos, ferias y otras acciones que contribuyan a la competitividad y el crecimiento del sector; promocionar el desarrollo de la impresi\u00f3n 3D y la fabricaci\u00f3n digital en todos los \u00e1mbitos, econ\u00f3mico, comercial e internacional, tecnol\u00f3gico y educativo y ser el m\u00e1s importante referente colombiano en lo concerniente al grupo de tecnolog\u00edas de impresi\u00f3n 3D y fabricaciones digitales.<\/p>\n<div id=\"attachment_77918\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-77918\" class=\"wp-image-77918 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DMitchel-acoplasticos.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DMitchel-acoplasticos.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DMitchel-acoplasticos-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DMitchel-acoplasticos-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-77918\" class=\"wp-caption-text\">El presidente de Acopl\u00e1sticos, Daniel Mitchell. (Cr\u00e9ditos: Acopl\u00e1sticos)<\/p><\/div>\n<p style=\"text-align: justify;\">Este a\u00f1o, del 23 al 27 de septiembre se llev\u00f3 a cabo la tercera edici\u00f3n del 3DFEST, nuevamente en el marco de la feria COLOMBIAPLAST y con el apoyo del Hub de Innovaci\u00f3n del Sena en Medell\u00edn. Adem\u00e1s de la exhibic\u00f3n comercial, se crearon unos retos de innovaci\u00f3n abierta en soluci\u00f3n de impresi\u00f3n 3D. El primer reto fue con estudiantes de 9\u00ba, 10\u00b0 y 11\u00b0 para desarrollar habilidades en modelado 3D, dise\u00f1o param\u00e9trico e impresi\u00f3n 3D, donde exploraron formas geom\u00e9tricas para la creaci\u00f3n de elementos lum\u00ednicos (l\u00e1mparas) que generen productos disruptivos para hogares con estilos de vida modernos. El segundo reto fue resuelto por estudiantes de la Universidad Nacional de Colombia y se desarroll\u00f3 a trav\u00e9s de una alianza con Yamaha y la empresa EPLUS 3D\/Centro 3D, con quienes se trabaj\u00f3 en la impresi\u00f3n en 3D met\u00e1lica de accesorios para moto y una turbina e\u00f3lica.<\/p>\n<h3>\u00bfC\u00f3mo cree que evolucionar\u00e1 la industria del pl\u00e1stico con la implementaci\u00f3n de la impresi\u00f3n 3D en Am\u00e9rica Latina?<\/h3>\n<p style=\"text-align: justify;\">La impresi\u00f3n 3D ya est\u00e1 transformando a la industria del pl\u00e1stico en Am\u00e9rica Latina y se espera que en los pr\u00f3ximos a\u00f1os contin\u00fae adopt\u00e1ndose cada vez m\u00e1s en el sector como una tecnolog\u00eda de apoyo. La impresi\u00f3n 3D tiene la capacidad de revolucionar los procesos productivos, impulsar la innovaci\u00f3n y la eficiencia, facilitar la diversificaci\u00f3n de aplicaciones, eliminar etapas intermedias, ayudar a responder al reto de la sostenibilidad, disminuir los tiempos y costos en la producci\u00f3n de piezas e impulsar el desarrollo de tecnolog\u00eda local. Aspectos que a su vez permiten a las empresas responder de manera m\u00e1s \u00e1gil a las fluctuaciones del mercado e impulsar su competitividad.<\/p>\n<p style=\"text-align: justify;\">Por ejemplo, con el prototipado r\u00e1pido, las empresas pueden desarrollar y probar nuevos productos en menor tiempo y a menores costos, comparado con los m\u00e9todos tradicionales de inyecci\u00f3n. Tambi\u00e9n se pueden fabricar moldes con impresi\u00f3n 3D para desarrollo de productos y prototipos en <a href=\"https:\/\/www.3dnatives.com\/es\/impresion-3d-vs-moldeo-inyeccion-110720242\/\">procesos de inyecci\u00f3n<\/a> de pl\u00e1sticos. Novedades como estas tienen un gran potencial en los productos pl\u00e1sticos para sectores como el automotriz, el aeron\u00e1utico, bienes de consumo y salud, construcci\u00f3n, partes de aparatos el\u00e9ctricos y electr\u00f3nicos, entre otros.<\/p>\n<div id=\"attachment_77917\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-77917\" class=\"wp-image-77917 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Aco3DFest.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Aco3DFest.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Aco3DFest-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Aco3DFest-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-77917\" class=\"wp-caption-text\">Presentaci\u00f3n durante el 3DFEST 2024. (Cr\u00e9ditos: Acopl\u00e1sticos)<\/p><\/div>\n<h3>\u00bfPodr\u00eda decirnos c\u00f3mo abordan el tema de la sostenibilidad?<\/h3>\n<p style=\"text-align: justify;\">Acopl\u00e1sticos est\u00e1 comprometido con la sostenibilidad y el crecimiento responsable de la industria del pl\u00e1stico en Colombia. En esta l\u00ednea, aborda la soluci\u00f3n al reto de los residuos pl\u00e1sticos a trav\u00e9s de cuatro pilares verticales (ecodise\u00f1o, cultura ciudadana, regulaci\u00f3n y mercados de econom\u00eda circular), y un pilar horizontal (informaci\u00f3n), todo ello con el prop\u00f3sito de dinamizar los mercados del posconsumo del pl\u00e1stico y avanzar con firmeza hacia la econom\u00eda circular. Para el desarrollo de estos cinco pilares, contamos con los sellos loop de ecodise\u00f1o del ICIPC, la campa\u00f1a de sensibilizaci\u00f3n <em>\u201cDale Vida al Pl\u00e1stico\u201d<\/em>, el plan de gesti\u00f3n de residuos de empaques y envases ACOREP y el proyecto GoPl\u00e1stic para dinamizar los mercados del reciclaje a trav\u00e9s de acceso a financiamiento, capital, mercados y nuevas tecnolog\u00edas.<\/p>\n<div id=\"attachment_77916\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-77916\" class=\"wp-image-77916 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3DFest.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3DFest.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3DFest-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3DFest-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-77916\" class=\"wp-caption-text\">(Cr\u00e9ditos: Acopl\u00e1sticos)<\/p><\/div>\n<h3>\u00bfUnas \u00faltimas palabras para nuestros lectores?<\/h3>\n<p style=\"text-align: justify;\">La implementaci\u00f3n de la impresi\u00f3n 3D a\u00fan es muy incipiente en muchos pa\u00edses de Am\u00e9rica Latina, incluyendo Colombia, y enfrenta varios desaf\u00edos como el desconocimiento generalizado sobre c\u00f3mo utilizarla de manera adecuada e implementarla como tecnolog\u00eda de apoyo en los procesos de producci\u00f3n tradicionales. En esta l\u00ednea, es muy importante priorizar el trabajo conjunto entre sector privado, sector p\u00fablico y academia para promover la capacitaci\u00f3n y la inclusi\u00f3n de la impresi\u00f3n 3D en los sistemas educativos, as\u00ed como brindar incentivos a la inversi\u00f3n y mejores condiciones de cr\u00e9dito o programas de financiamiento para impulsar el acceso a esta tecnolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">Acopl\u00e1sticos, como el gremio que representa a la industria de la manufactura aditiva en Colombia, a trav\u00e9s de su cap\u00edtulo ACO3D, est\u00e1 comprometido con su posicionamiento y desarrollo competitivo. Es por esto que, de la mano de aliados estrat\u00e9gicos a nivel nacional e internacional, desde Acopl\u00e1sticos promovemos, de manera constante, la difusi\u00f3n del conocimiento a trav\u00e9s de webinars, eventos como el 3DFEST y los retos de innovaci\u00f3n abierta desarrollados de la mano de actores como el Hub de Innovaci\u00f3n del SENA en Medell\u00edn, colegios, c\u00e1maras de comercio, empresas, entre otros, con el prop\u00f3sito de cerrar las brechas y potenciar las grandes oportunidades de este sector.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 opinas de la labor de Acopl\u00e1sticos y su proyecto Aco3D? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/groups\/8516968\/\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a> y <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-3791771435\"><div id=\"dnati-3159263416\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La industria del pl\u00e1stico en Am\u00e9rica Latina est\u00e1 experimentando una transformaci\u00f3n profunda con la adopci\u00f3n de tecnolog\u00edas avanzadas como la impresi\u00f3n 3D. En ese sentido, Acopl\u00e1sticos juega un rol importante en la promoci\u00f3n de las tecnolog\u00edas 3D entre las principales&hellip;<\/p>\n","protected":false},"author":6110,"featured_media":77934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,10,12],"tags":[],"class_list":["post-77914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-entrevistas","category-materiales"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=77914"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77914\/revisions"}],"predecessor-version":[{"id":77933,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77914\/revisions\/77933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/77934"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=77914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=77914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=77914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}