{"id":77430,"date":"2024-09-18T00:02:26","date_gmt":"2024-09-17T22:02:26","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=77430"},"modified":"2024-09-18T10:32:33","modified_gmt":"2024-09-18T08:32:33","slug":"aplicacion-material-3d-injertos-oseos-180920242","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/aplicacion-material-3d-injertos-oseos-180920242\/","title":{"rendered":"Aplicaci\u00f3n del mes: un nuevo material de impresi\u00f3n 3D para crear injertos \u00f3seos"},"content":{"rendered":"<p style=\"text-align: justify;\">A medida que la investigaci\u00f3n en materiales para impresi\u00f3n 3D avanza, cada vez surgen m\u00e1s proyectos innovadores en multitud de industrias. En esta ocasi\u00f3n, destacamos una aplicaci\u00f3n m\u00e9dica relacionada con la fabricaci\u00f3n aditiva y llevada a cabo por investigadores en la Universidad de Waterloo. El equipo ha creado un innovador material que imita las propiedades del <a href=\"https:\/\/www.3dnatives.com\/es\/proyectos-bioimpresion-organos-tejidos-impresos-3d-070420202\/\">tejido<\/a> \u00f3seo y promete revolucionar el tratamiento de pacientes sometidos a cirug\u00edas reconstructivas y de reparaci\u00f3n \u00f3sea. Este nuevo material, un nanocompuesto de biopol\u00edmeros, puede utilizarse en impresoras 3D de resina para fabricar injertos \u00f3seos personalizados, adaptados espec\u00edficamente a las necesidades de cada paciente.<\/p>\n<p style=\"text-align: justify;\">Actualmente, las reconstrucciones quir\u00fargicas mayores dependen de <a href=\"https:\/\/www.3dnatives.com\/es\/top-implantes-impresos-en-3d-150720192\/\">implantes<\/a> de metal y hueso donado. Sin embargo, a menudo \u00e9stos no se ajustan perfectamente a la anatom\u00eda del paciente y pueden ser rechazados por el organismo receptor. Es por ello, que muchos centros m\u00e9dicos y hospitales est\u00e1n recurriendo a las nuevas tecnolog\u00edas. La capacidad de este nuevo material para ser impreso en 3D ofrece una alternativa que podr\u00eda reducir la necesidad de implantes met\u00e1licos, disminuir el riesgo de infecciones y mejorar la aceptaci\u00f3n del injerto por parte del cuerpo del paciente.<\/p>\n<div id=\"attachment_77432\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-77432\" class=\"wp-image-77432 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-77432\" class=\"wp-caption-text\">La Dra. Maud Gorbet observando los osteoclastos (c\u00e9lulas que se comen el hueso y lo reabsorben) en un material nanocompuesto impreso en 3D.<\/p><\/div>\n<h3 style=\"text-align: justify;\">Injertos \u00f3seos mejorados mediante impresi\u00f3n 3D<\/h3>\n<p style=\"text-align: justify;\">El material desarrollado por los investigadores incorpora nanopart\u00edculas que simulan la composici\u00f3n mineral del hueso, reforzando as\u00ed el biopol\u00edmero. La meta final es que las c\u00e9lulas \u00f3seas del paciente crezcan y reemplacen el nanocompuesto con hueso nuevo, permitiendo que el material se elimine naturalmente del cuerpo. Elizabeth Diederichs, doctorada de Waterloo, explica: <em>\u201cNuestro trabajo se centra actualmente en mejorar la solidez funcional de nuestro nanocompuesto de biopol\u00edmero como implante y su capacidad para ser sustituido por hueso vivo con el paso del tiempo. El objetivo es que este material reduzca la necesidad del paciente de someterse a operaciones repetidas tras someterse a una cirug\u00eda de reconstrucci\u00f3n \u00f3sea\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Para ello, utilizaron la impresora 3D de resina Sonic XL 4K, del fabricante Phrozen. Basada en la tecnolog\u00eda <a href=\"https:\/\/www.3dnatives.com\/es\/diferencias-impresion-3d-sla-msla-280720222\/\">mSLA<\/a> (Masked Stereolithography Apparatus), esta m\u00e1quina permiti\u00f3 crear modelos m\u00e9dicos con una altura de capa de 50\u2009\u03bcm. Una vez terminado el proceso de fabricaci\u00f3n, las piezas de biopol\u00edmero se enjuagaron con etanol y postratadas en una estaci\u00f3n de curado UV. Con respecto a la t\u00e9cnica utilizada, los investigadores intentaron utilizar la impresi\u00f3n por extrusi\u00f3n (escritura directa de tinta), pero no obtuvieron los resultados deseados. Afirman que, en comparaci\u00f3n con otros procesos de fabricaci\u00f3n, la tecnolog\u00eda mSLA es mucho m\u00e1s r\u00e1pida, permitiendo la producci\u00f3n de piezas con muchos menos defectos y una mayor fidelidad.<\/p>\n<div id=\"attachment_77433\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-77433\" class=\"wp-image-77433 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-2.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-2-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-77433\" class=\"wp-caption-text\">El equipo de investigaci\u00f3n, de izquierda a derecha: Dr. Dibakar Mondal, Elizabeth Diederichs, Dra. Maud Gorbet y Dr. Thomas Willett.<\/p><\/div>\n<p style=\"text-align: justify;\">Las pruebas iniciales de compatibilidad entre el hueso y las c\u00e9lulas se realizaron con \u00e9xito en colaboraci\u00f3n con la Dra. Maud Gorbet, profesora de Ingenier\u00eda y directora del programa de licenciatura en ingenier\u00eda biom\u00e9dica de Waterloo. <em>\u201cCualquier material implantado en el cuerpo provoca una respuesta\u201d<\/em>, afirma Gorbet. <em>\u201cNuestras pruebas demuestran que la respuesta biol\u00f3gica de las c\u00e9lulas \u00f3seas a nuestro nanocompuesto de biopol\u00edmero supera la de los m\u00e9todos tradicionales. Se adhieren, proliferan y mantienen su comportamiento, lo cual es muy emocionante\u201d<\/em>.<\/p>\n<h4>Un futuro prometedor<\/h4>\n<p style=\"text-align: justify;\">Este avance forma parte de la iniciativa Health Futures de la Universidad de Waterloo, que busca mejorar la salud y el bienestar a trav\u00e9s de avances tecnol\u00f3gicos, atenci\u00f3n virtual y aplicaciones de datos sanitarios. Con este nuevo material, los investigadores siguen empujando los l\u00edmites de la <a href=\"https:\/\/www.3dnatives.com\/es\/infografia-impresion3d-en-medicina15072015\/\">tecnolog\u00eda m\u00e9dica<\/a> y, m\u00e1s concretamente, del potencial de la impresi\u00f3n 3D. El Dr. Thomas Willett, investigador principal, concluye: <em>\u00abHemos creado un material resistente, imprimible en 3D y compatible con el potencial de convertirse en nuevo tejido \u00f3seo. Con esta tecnolog\u00eda, podemos conseguir la geometr\u00eda espec\u00edfica del paciente necesaria para reconstruir defectos \u00f3seos con mayor \u00e9xito\u00bb<\/em>. El equipo ahora busca financiamiento para llevar a cabo ensayos adicionales y obtener las aprobaciones normativas necesarias para introducir esta tecnolog\u00eda en el \u00e1mbito cl\u00ednico. A continuaci\u00f3n te dejamos una tabla con la informaci\u00f3n m\u00e1s relevante de esta aplicaci\u00f3n. A\u00fan as\u00ed, puedes obtener m\u00e1s informaci\u00f3n sobre la investigaci\u00f3n, <a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/jbm.a.37719\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<div id=\"attachment_77435\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-77435\" class=\"wp-image-77435 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-table.png\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-table.png 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-table-600x343.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MedicalApplication-table-160x91.png 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-77435\" class=\"wp-caption-text\">Cr\u00e9ditos: 3Dnatives<\/p><\/div>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de este nuevo material de impresi\u00f3n 3D para crear injertos \u00f3seos? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/groups\/8516968\/\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a> y\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<p style=\"text-align: justify;\"><em>*Cr\u00e9ditos de todas las fotos: Universidad de Waterloo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que la investigaci\u00f3n en materiales para impresi\u00f3n 3D avanza, cada vez surgen m\u00e1s proyectos innovadores en multitud de industrias. En esta ocasi\u00f3n, destacamos una aplicaci\u00f3n m\u00e9dica relacionada con la fabricaci\u00f3n aditiva y llevada a cabo por investigadores en&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":77434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,13,284],"tags":[],"class_list":["post-77430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-investigacion","category-medico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=77430"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77430\/revisions"}],"predecessor-version":[{"id":77456,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77430\/revisions\/77456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/77434"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=77430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=77430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=77430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}