{"id":77381,"date":"2024-09-17T00:02:34","date_gmt":"2024-09-16T22:02:34","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=77381"},"modified":"2024-09-12T14:21:47","modified_gmt":"2024-09-12T12:21:47","slug":"startup3d-amfree-impresion-xxl-metal-170920242","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/startup3d-amfree-impresion-xxl-metal-170920242\/","title":{"rendered":"#Startup3D: AMFREE supera las limitaciones de la impresi\u00f3n 3D XXL de metal"},"content":{"rendered":"<p style=\"text-align: justify;\">Aunque la fabricaci\u00f3n aditiva de metal crece a\u00f1o tras a\u00f1o, persisten ciertos retos en el mercado, sobre todo cuando se trata de producir piezas de <a href=\"https:\/\/www.3dnatives.com\/es\/adoptar-impresion-3d-de-gran-formato-090420205\/\">gran formato<\/a> o de repararlas. Las soluciones disponibles en el mercado son a menudo poco fiables, y las piezas producidas no cumplen las normas o son demasiado caras. Este es el contexto de la startup francesa AMFREE, que desarrolla <a href=\"https:\/\/www.3dnatives.com\/es\/impresoras-3d-hibridas-mercado-030820202\/\">m\u00e1quinas h\u00edbridas<\/a> XXL de impresi\u00f3n 3D de metal. La meta es facilitar el trabajo del operador y garantizar resultados de alta calidad. En concreto, se basa en la inteligencia artificial para corregir errores y detectar cualquier problema de fabricaci\u00f3n. Hemos tenido la oportunidad de reunirnos con Nicolas Villedary, CEO de la empresa, para saber m\u00e1s sobre la tecnolog\u00eda utilizada, los sectores a los que se dirige y los planes de futuro de esta ambiciosa startup.<\/p>\n<h3>3DN: \u00bfPodr\u00edas presentarte y contar tu relaci\u00f3n con la fabricaci\u00f3n aditiva?<\/h3>\n<p style=\"text-align: justify;\">Me llamo Nicolas Villedary y soy el CEO de AMFREE, una empresa dedicada a comercializar impresoras 3D de metal que facilitan la producci\u00f3n y reparaci\u00f3n de piezas de gran tama\u00f1o (hasta 5 metros). Estas m\u00e1quinas se distribuyen como un ecosistema completo (m\u00e1quina, software, servicios asociados) que garantiza la calidad de los productos y la facilidad de uso.<\/p>\n<div id=\"attachment_86023\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86023\" class=\"size-full wp-image-86023\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/08\/AMFREE_team-e1725283696606.jpg\" alt=\"\" width=\"700\" height=\"266\" \/><p id=\"caption-attachment-86023\" class=\"wp-caption-text\">Los equipos de AMFREE e IREPA LASER junto a una pieza de metal XXL impresa en 3D.<\/p><\/div>\n<h3>3DN: \u00bfQu\u00e9 es AMFREE? \u00bfC\u00f3mo se desarroll\u00f3 la idea?<\/h3>\n<p style=\"text-align: justify;\">Fundada en agosto de 2023 y con sede en Illkirch-Graffenstaden (Alsacia), AMFREE busca hacer que la fabricaci\u00f3n aditiva de metal de piezas grandes sea m\u00e1s r\u00e1pida y accesible. La tecnolog\u00eda naci\u00f3 en 2019 en el CRT (Centro de Recursos Tecnol\u00f3gicos) alsaciano IREPA LASER. Se ha puesto en marcha una l\u00ednea piloto que ya se est\u00e1 utilizando para cualificar y producir piezas industriales. En esta misma l\u00ednea, AMFREE contin\u00faa su I+D para desarrollar nuevas funcionalidades (escaneado 3D, mecanizado, control de procesos, sensores inteligentes, etc.), la IA de sus m\u00e1quinas y su infraestructura digital y de servicios.<\/p>\n<p style=\"text-align: justify;\">Hemos desarrollado AMFREE partiendo de la constataci\u00f3n de que los distintos procesos de fabricaci\u00f3n aditiva tienen sus l\u00edmites en t\u00e9rminos de productividad y competitividad. Aunque algunos son cada vez m\u00e1s precisos, como los procesos de fusi\u00f3n l\u00e1ser de polvo (PBF) para fabricar piezas complejas, actualmente solo son adecuados para dise\u00f1ar piezas de unas pocas decenas de cent\u00edmetros de longitud o di\u00e1metro. Estas tecnolog\u00edas no son adecuadas para la fabricaci\u00f3n de piezas XXL que pueden medir varios metros.<\/p>\n<p style=\"text-align: justify;\">Hoy en d\u00eda, la fabricaci\u00f3n de piezas grandes se asemeja m\u00e1s a la artesan\u00eda. Las instalaciones de producci\u00f3n suelen ser m\u00e1quinas especiales o \u00abde la casa\u00bb con resultados variables, de un operario a otro, de una f\u00e1brica a otra, o de una m\u00e1quina a otra. Las piezas XXL suelen ser cr\u00edticas con un alto valor a\u00f1adido, o exponen a sus usuarios a importantes perjuicios econ\u00f3micos cuando dejan de funcionar. Como no son f\u00e1cilmente sustituibles era necesario desarrollar m\u00e1quinas est\u00e1ndar, sencillas, asequibles y econ\u00f3micas, capaces de producir piezas m\u00e1s r\u00e1pidamente (reduciendo el plazo de entrega) o de ponerlas de nuevo en servicio (econom\u00eda circular, ecorresponsabilidad, preservando los recursos y la energ\u00eda).<\/p>\n<div id=\"attachment_86117\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86117\" class=\"size-full wp-image-86117\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/09\/AMFREE_technologie.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-86117\" class=\"wp-caption-text\">La m\u00e1quina se basa en la tecnolog\u00eda DED l\u00e1ser multihilo, que permite una gesti\u00f3n din\u00e1mica de la energ\u00eda.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bfQu\u00e9 retos plantea la impresi\u00f3n 3D de grandes piezas met\u00e1licas? \u00bfC\u00f3mo los solvent\u00e1is?<\/h3>\n<p style=\"text-align: justify;\">En el caso de las piezas grandes, el reto es producirlas bien a la primera. Las piezas son grandes y las no conformidades suelen ser costosas. Adem\u00e1s, pueden minar la competitividad de la fabricaci\u00f3n aditiva l\u00f3gica.<\/p>\n<p style=\"text-align: justify;\">Para lograrlo, AMFREE ha optado por ofrecer una soluci\u00f3n completa y precalificada. De este modo, los usuarios tienen la garant\u00eda de disponer de todo el equipo y el software que necesitan para fabricar piezas XXL en condiciones adecuadas, validadas y perfectamente \u00f3ptimas. Al adquirir una m\u00e1quina, los usuarios obtienen todo lo que necesitan, sin costes a\u00f1adidos, y 60 meses de asistencia profesional por parte de expertos en materiales y procesos. Las m\u00e1quinas AMFREE est\u00e1n equipadas con diversas herramientas de IA especializadas que mejoramos cada d\u00eda. Como resultado, todas nuestras m\u00e1quinas se benefician de nuevas habilidades que les ayudan a controlar su trabajo y evitar la falta de calidad. AMFREE trabaja actualmente en el perfeccionamiento del control de procesos de sus m\u00e1quinas.<\/p>\n<p style=\"text-align: justify;\">El centro de servicios de AMFREE trabaja para cualificar nuevos materiales y su IA asociada. Todo ello se destina a aplicaciones industriales en numerosos sectores (aeron\u00e1utica, espacio, defensa, industria, ferrocarril, utillaje, O&amp;G, nuclear, hidr\u00e1ulica, etc.), en colaboraci\u00f3n con diversos fabricantes de hilo de soldadura. Gracias a ello, es posible garantizar las propiedades de las fabricaciones\/reparaciones realizadas con la tecnolog\u00eda de AMFREE. \u00c9sta permite el desarrollo de nuevos materiales y aleaciones innovadores para nuevas aplicaciones (como el sector de petr\u00f3leo y gas), mediante la fusi\u00f3n simult\u00e1nea y controlada de varios hilos de diferentes tipos.<\/p>\n<div id=\"attachment_86118\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86118\" class=\"size-full wp-image-86118\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/09\/AMFREE_3Dpieces.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-86118\" class=\"wp-caption-text\">Ejemplo de piezas impresas en 3D por AMFREE.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bfPuedes hablarnos m\u00e1s de vuestra m\u00e1quina?<\/h3>\n<p style=\"text-align: justify;\">AMFREE opt\u00f3 por la <a href=\"https:\/\/www.3dnatives.com\/es\/guia-deposicion-de-energia-directa-100920192\/\">tecnolog\u00eda DED<\/a> porque el uso de un l\u00e1ser ofrece la posibilidad de controlar con precisi\u00f3n la cantidad de energ\u00eda aplicada y de obtener densidades de energ\u00eda muy elevadas de forma r\u00e1pida y local. Para ir a\u00fan m\u00e1s lejos, hemos desarrollado una tecnolog\u00eda innovadora que nos permite alcanzar altas velocidades de deposici\u00f3n del hilo controlando al mismo tiempo las caracter\u00edsticas geom\u00e9tricas de los dep\u00f3sitos y garantizando una calidad metal\u00fargica extrema (a menudo buscada para piezas de alto valor a\u00f1adido).<\/p>\n<p style=\"text-align: justify;\">Nuestras m\u00e1quinas tambi\u00e9n utilizan la <a href=\"https:\/\/www.3dnatives.com\/es\/proyectos-que-combinan-impresion-3d-e-inteligencia-artificial-ia-220220242\/\">inteligencia artificial<\/a> para predecir y corregir fen\u00f3menos imprevisibles. Para supervisar el proceso se utilizan sensores inteligentes desarrollados por nuestros equipos. Estos datos son procesados por las IA, que utilizan todos los datos producidos por la m\u00e1quina para corregir cualquier desviaci\u00f3n antes de que provoque un incumplimiento. En \u00faltima instancia, permite anticiparse a ellas con el fin de tomar medidas preventivas y evitar que se produzcan en primer lugar.<\/p>\n<p style=\"text-align: justify;\">En su configuraci\u00f3n est\u00e1ndar, una m\u00e1quina AMFREE consiste en un robot sobre un eje lineal, que lleva una boquilla l\u00e1ser multihilo. Es adaptable bajo pedido y su envolvente inicial de fabricaci\u00f3n es de 5 x 2,5 x 2,5 m.<\/p>\n<div id=\"attachment_86028\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86028\" class=\"size-full wp-image-86028\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/09\/AMFree_machine.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-86028\" class=\"wp-caption-text\">La m\u00e1quina AMFREE est\u00e1ndar consta de un robot sobre un eje lineal.<\/p><\/div>\n<p style=\"text-align: justify;\">Como opci\u00f3n, se puede a\u00f1adir un posicionador (para fabricaci\u00f3n multieje continua), un cabezal deslizante (para piezas cil\u00edndricas) y un robot adicional para incorporar opciones de escaneado 3D o mecanizado para uso multiproceso. La idea es colocar la pieza dentro de la m\u00e1quina y trabajar en torno a ella (inspecci\u00f3n dimensional, preparaci\u00f3n de superficies, fabricaci\u00f3n aditiva, mecanizado de zonas inaccesibles tras la fabricaci\u00f3n, ensayos no destructivos). Estas m\u00e1quinas permiten refabricar piezas cercanas a sus dimensiones finales a partir de simples bobinas (o tambores) de hilo met\u00e1lico. Adem\u00e1s, tambi\u00e9n permiten a los fabricantes que las explotan ampliar su cuota de mercado al mundo de las reparaciones y adoptar as\u00ed un enfoque circular, virtuoso y lucrativo de la fabricaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Estas m\u00e1quinas est\u00e1n equipadas con los \u00faltimos controles num\u00e9ricos Siemens Sinumerik ONE. Heredan todas las funcionalidades del mundo del <a href=\"https:\/\/www.3dnatives.com\/es\/impresion-3d-o-mecanizado-cnc-160420182\/\">mecanizado<\/a>. Est\u00e1n totalmente instrumentadas y adaptadas a nuevos usos (m\u00e1quinas comunicantes, 4.0, actualizables, aumentadas por IA, etc).<\/p>\n<h3>3DN: \u00bfCu\u00e1les son los sectores objetivo? \u00bfQu\u00e9 futuros proyectos ten\u00e9is?<\/h3>\n<p style=\"text-align: justify;\">En Europa, nos dirigimos a los usuarios industriales, de piezas forjadas o fundidas y a las empresas de mantenimiento. Con el apoyo del gobierno franc\u00e9s (BPI) y de la regi\u00f3n de Grand Est, estamos acelerando los desarrollos digitales en torno al proceso (sensores inteligentes, gesti\u00f3n din\u00e1mica de la energ\u00eda) y a la infraestructura digital y de servicios anexa a las m\u00e1quinas, dise\u00f1ada para soportar las futuras mejoras desarrolladas por el centro de servicios AMFREE. Tambi\u00e9n se est\u00e1 trabajando para cualificar el rendimiento de las opciones disponibles para nuestras m\u00e1quinas (escaneado 3D, mecanizado) y para simplificar el uso de la fabricaci\u00f3n aditiva XXL en todas sus formas.<\/p>\n<div id=\"attachment_86031\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86031\" class=\"size-full wp-image-86031\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2024\/09\/AMFREE_scan.jpg\" alt=\"amfree\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-86031\" class=\"wp-caption-text\">La m\u00e1quina tiene la opci\u00f3n de equiparse con un esc\u00e1ner 3D o un husillo de mecanizado.<\/p><\/div>\n<p style=\"text-align: justify;\">En breve recaudaremos 2,5 millones de euros para reforzar nuestra plantilla, seguir simplificando la arquitectura de nuestras m\u00e1quinas y sus usos, y promover intensamente en Europa esta nueva tecnolog\u00eda altamente productiva. Sin duda tiene un potencial a\u00fan desconocido para la industria y hasta ahora inesperado para las grandes dimensiones. Por \u00faltimo, tenemos previsto vender nuestra primera m\u00e1quina en 2024, con vistas a vender unas diez unidades de aqu\u00ed a 2026. Estar\u00e1n dirigidas a sectores como el aeroespacial, la energ\u00eda, la industria, petr\u00f3leo y la defensa.<\/p>\n<h3>3DN: \u00bfUnas palabras finales para nuestros lectores?<\/h3>\n<p style=\"text-align: justify;\">Estamos intentando forjar alianzas estrat\u00e9gicas con varios fabricantes y centros t\u00e9cnicos europeos para popularizar la tecnolog\u00eda y promover sus ventajas, que a\u00fan son muy desconocidas. Puedes visitar nuestro sitio web <a href=\"https:\/\/amfree.eu\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a> para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la tecnolog\u00eda desarrollada por AMFREE? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/groups\/8516968\/\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a> y\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<p style=\"text-align: justify;\"><em>*Cr\u00e9ditos de todas las fotos: AMFREE<\/em><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-3489891347\"><div id=\"dnati-2726517977\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Aunque la fabricaci\u00f3n aditiva de metal crece a\u00f1o tras a\u00f1o, persisten ciertos retos en el mercado, sobre todo cuando se trata de producir piezas de gran formato o de repararlas. Las soluciones disponibles en el mercado son a menudo poco&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":77384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,10,9],"tags":[],"class_list":["post-77381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-entrevistas","category-impresoras-3d"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=77381"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77381\/revisions"}],"predecessor-version":[{"id":77418,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77381\/revisions\/77418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/77384"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=77381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=77381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=77381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}