{"id":77255,"date":"2024-09-02T00:02:38","date_gmt":"2024-09-01T22:02:38","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=77255"},"modified":"2024-09-03T10:02:51","modified_gmt":"2024-09-03T08:02:51","slug":"matriz-zinc-impresa-3d-defectos-oseos-020920242","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/matriz-zinc-impresa-3d-defectos-oseos-020920242\/","title":{"rendered":"Una matriz de zinc impresa en 3D podr\u00eda tratar defectos \u00f3seos"},"content":{"rendered":"<p style=\"text-align: justify;\">Los defectos \u00f3seos pueden ser cong\u00e9nitos o deberse a accidentes, y requieren distintos enfoques de tratamiento seg\u00fan la causa. Un posible m\u00e9todo de curaci\u00f3n es una matriz de zinc impresa en 3D. Ideada por expertos chinos de la Universidad de Beihang, el Hospital Renji, la Universidad Jiao Tong de Shanghai, la Universidad Tsinghua y la Universidad de Pek\u00edn, la <a href=\"https:\/\/www.3dnatives.com\/es\/category\/investigacion\/\">investigaci\u00f3n<\/a> podr\u00eda tratar defectos \u00f3seos. El proyecto cuenta con el apoyo de la empresa china Bright Laser Technologies (BLT) y sus m\u00e1quinas y sistemas de impresi\u00f3n 3D.<\/p>\n<p style=\"text-align: justify;\">Estas estructuras de zinc poroso impresas en 3D ofrecen un enfoque innovador para reparar defectos \u00f3seos mediante regeneraci\u00f3n. Sin embargo, uno de los principales retos hasta la fecha ha sido la r\u00e1pida degradaci\u00f3n de las estructuras de zinc, que provocan toxicidad. Por este motivo, ahora se ha optimizado la composici\u00f3n de la aleaci\u00f3n, la estructura de la superficie y la geometr\u00eda de los poros de las matrices.<\/p>\n<div id=\"attachment_58226\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58226\" class=\"wp-image-58226 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Degardationsverhalten.jpg\" alt=\"3D-gedrucktes Zinkger\u00fcst \" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-58226\" class=\"wp-caption-text\">Comportamiento de degradaci\u00f3n de las matrices de zinc impresas en 3D en f\u00e9mur de rata al cabo de tres d\u00edas y tres meses (Cr\u00e9ditos: Li, S., Yang, H., Qu, X. et al.)<\/p><\/div>\n<p style=\"text-align: justify;\">En los \u00faltimos tres a\u00f1os, los investigadores han trabajado en el desarrollo de nuevas aleaciones de zinc biodegradables (Zn-Li) que pueden utilizarse para imprimir en 3D las estructuras. Las aleaciones Zn-Li (0,8% Li en peso) ofrecen propiedades mec\u00e1nicas y un buen equilibrio entre resistencia, plasticidad y comportamiento frente a la corrosi\u00f3n. Las matrices se fabricaron con el <a href=\"https:\/\/www.3dnatives.com\/es\/sinterizado-directo-de-metal-por-laser-les-explicamos-todo\/\">sistema L-PBF<\/a> de BLT, que permite dise\u00f1os precisos y estructuras complejas.<\/p>\n<p style=\"text-align: justify;\">Tras la impresi\u00f3n 3D, se realizaron diversos tratamientos superficiales, como el tratamiento ultras\u00f3nico, el grabado \u00e1cido y el pulido electroqu\u00edmico, para optimizar la rugosidad de la superficie y favorecer la interacci\u00f3n celular. Estos tratamientos dieron lugar a un micromecanizado espec\u00edfico de la superficie que mejora tanto la adhesi\u00f3n como la propagaci\u00f3n celular, lo cual es importante para la regeneraci\u00f3n \u00f3sea.<\/p>\n<div id=\"attachment_58224\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58224\" class=\"wp-image-58224 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Zinkgeruest.jpg\" alt=\"3D-gedrucktes Zinkger\u00fcst \" width=\"700\" height=\"300\" \/><p id=\"caption-attachment-58224\" class=\"wp-caption-text\">Dise\u00f1o de matrices biodegradables y porosas con base de zinc impresas en 3D (Cr\u00e9ditos: Li, S., Yang, H., Qu, X. et al.)<\/p><\/div>\n<p style=\"text-align: justify;\">Adem\u00e1s, las estructuras especiales de la superficie favorecen la interacci\u00f3n con los macr\u00f3fagos (los gl\u00f3bulos blancos). A su vez, pueden mejorar la respuesta inmunitaria, es decir, la reacci\u00f3n del sistema inmunitario ante organismos potencialmente da\u00f1inos, lo que en \u00faltima instancia favorece la regeneraci\u00f3n \u00f3sea. Adem\u00e1s, la matriz de zinc impresa en 3D muestra una degradaci\u00f3n controlada en el organismo, que est\u00e1 asociada a la regeneraci\u00f3n \u00f3sea. Esta propiedad es crucial para crear un entorno \u00f3ptimo para la regeneraci\u00f3n e integraci\u00f3n del implante.<\/p>\n<p style=\"text-align: justify;\">En general, el uso de matrices impresas en 3D conduce a una mejora eficiente de la regeneraci\u00f3n \u00f3sea en comparaci\u00f3n con los implantes convencionales, ya que las propiedades estructurales y qu\u00edmicas de las matrices promueven la formaci\u00f3n de hueso nuevo. El uso de la impresi\u00f3n 3D para producir matrices de Zn-Li ofrece un gran potencial, ya que permite un control preciso de la estructura y la porosidad de los implantes, lo cual es crucial para la regeneraci\u00f3n del hueso. Puedes encontrar m\u00e1s informaci\u00f3n sobre la investigaci\u00f3n, <a href=\"https:\/\/www.nature.com\/articles\/s41467-024-47189-5\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<div id=\"attachment_58225\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58225\" class=\"wp-image-58225 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Zinkgeruest-2.jpg\" alt=\"3D-gedrucktes Zinkger\u00fcst \" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-58225\" class=\"wp-caption-text\">Morfolog\u00eda superficial y propiedades de la matriz de Zn-0,8Li tras tratamiento ultras\u00f3nico, grabado \u00e1cido y pulido electroqu\u00edmico (EC) (Cr\u00e9ditos de la imagen: Li, S., Yang, H., Qu, X. et al.)<\/p><\/div>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la matriz de zinc impresa en 3D? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/groups\/8516968\/\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a> y\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los defectos \u00f3seos pueden ser cong\u00e9nitos o deberse a accidentes, y requieren distintos enfoques de tratamiento seg\u00fan la causa. Un posible m\u00e9todo de curaci\u00f3n es una matriz de zinc impresa en 3D. Ideada por expertos chinos de la Universidad de&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":77258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,13,284],"tags":[],"class_list":["post-77255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-investigacion","category-medico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=77255"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77255\/revisions"}],"predecessor-version":[{"id":77262,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/77255\/revisions\/77262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/77258"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=77255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=77255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=77255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}