{"id":71719,"date":"2024-01-08T00:02:49","date_gmt":"2024-01-07T23:02:49","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=71719"},"modified":"2025-03-03T22:25:33","modified_gmt":"2025-03-03T21:25:33","slug":"guia-impresion-3d-cold-metal-fusion-080120242","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/guia-impresion-3d-cold-metal-fusion-080120242\/","title":{"rendered":"Gu\u00eda completa: la impresi\u00f3n 3D por Cold Metal Fusion, \u00a1te explicamos todo!"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoy en d\u00eda, estamos observando una tendencia en la industria manufacturera hacia soluciones de <a href=\"https:\/\/www.3dnatives.com\/es\/guia-impresion-3d-metal\/\">fabricaci\u00f3n aditiva de metal<\/a>. Sin embargo, en muchas ocasiones estas m\u00e1quinas pueden llegar a ser caras para muchas empresas que se est\u00e1n iniciando en este campo. As\u00ed, los costes de las impresoras 3D de metal pueden suponer una gran barrera de entrada en el mercado. A su vez, se est\u00e1n desarrollando soluciones de fabricaci\u00f3n aditiva de pol\u00edmeros basadas en polvo a precios cada vez m\u00e1s bajos. Esto convierte a la tecnolog\u00eda de <a href=\"https:\/\/www.3dnatives.com\/es\/sinterizado-selectivo-por-laser-les-explicamos-todo\/\">sinterizado selectivo por l\u00e1ser<\/a> (SLS) como una buena alternativa para la creaci\u00f3n de piezas finales polim\u00e9ricas en multitud de aplicaciones. Pero, \u00bfy si se pudieran combinar los beneficios de la impresi\u00f3n 3D de metal con las soluciones de bajo coste de la fabricaci\u00f3n por SLS? Ahora esto se puede conseguir gracias a la tecnolog\u00eda Cold Metal Fusion (fusi\u00f3n de metal en fr\u00edo).<\/p>\n<p style=\"text-align: justify;\">Desarrollada por la empresa alemana Headmade Materials, la impresi\u00f3n 3D por <strong>Cold Metal Fusion (CMF)<\/strong> consiste en un m\u00e9todo de fabricaci\u00f3n indirecto de metales. En concreto, la compa\u00f1\u00eda desarrolla los materiales en polvo compatibles con este sistema, pero no las impresoras 3D, o al menos por el momento. Dicha materia prima est\u00e1 compuesta de part\u00edculas de metal en el interior y un recubrimiento de aglutinante polim\u00e9rico. Basado en un proceso de lecho de polvo, el sistema CMF permite crear piezas finales de metal a quienes cuentan con <a href=\"https:\/\/www.3dnatives.com\/es\/impresoras-3d-sls-220320182\/\">m\u00e1quinas SLS<\/a>. Conozcamos ahora las propiedades de esta tecnolog\u00eda y que avances supone para la industria de fabricaci\u00f3n aditiva.<\/p>\n<div id=\"attachment_71770\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-71770\" class=\"wp-image-71770 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-71770\" class=\"wp-caption-text\">Pieza de titanio impresa en 3D mediante tecnolog\u00eda Cold Metal Fusion.<\/p><\/div>\n<h3>Funcionamiento de la tecnolog\u00eda Cold Metal Fusion<\/h3>\n<p style=\"text-align: justify;\">Como cada proceso de impresi\u00f3n 3D, todo comienza con el dise\u00f1o de los modelos en un software CAD. Un aspecto importante a tener en cuenta al dise\u00f1ar las piezas para CMF (y en general para cualquier proceso basado en la sinterizaci\u00f3n), es el hecho de que \u00e9stas pueden encoger durante la fabricaci\u00f3n. En CMF, las piezas alcanzan una alta densidad que reduce la contracci\u00f3n necesaria durante el proceso de sinterizaci\u00f3n. Al utilizar polvo de metal como materia prima, las piezas se pueden contraer uniformemente en todas las direcciones (X-Y-Z) en torno al 14%. Por tanto, habr\u00e1 que tener en cuenta estos pocos mil\u00edmetros que pueden encoger. Despu\u00e9s, el archivo digital se enviar\u00e1 al programa de corte o slicer para laminar la pieza y configurar los par\u00e1metros de fabricaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Una vez abordados el dise\u00f1o y laminado, pasamos a la creaci\u00f3n de las piezas. Los materiales compatibles con esta tecnolog\u00eda incluyen el acero inoxidable 316L, cromo-cobalto, <a href=\"https:\/\/www.3dnatives.com\/es\/titanio-aleacion-ti6al4v-020220212\/\">titanio Ti6Al4V<\/a> y tungsteno. Adem\u00e1s, hay otros en fase de desarrollo, como el Inconel, el aluminio o el acero para herramientas y utillaje<span class=\"TextRun SCXW135743826 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW135743826 BCX0\">, entre otros<\/span><\/span>. En cuanto a la impresi\u00f3n en 3D, una de las preguntas que nos puede venir a la cabeza al pensar en la tecnolog\u00eda CMF es: \u00bfc\u00f3mo es posible que sea un m\u00e9todo \u201cen fr\u00edo\u201d y requiera un sinterizado de calor? Esto se debe a que, durante la impresi\u00f3n, el aglutinante de pl\u00e1stico se funde a baja temperatura (a tan solo 50\u00baC), lo cual se consigue con el rango de potencia de los sistemas de sinterizado de pol\u00edmeros de baja potencia. De ah\u00ed que se considere un proceso en fr\u00edo.<\/p>\n<p style=\"text-align: justify;\">Como todo proceso de impresi\u00f3n 3D SLS, un l\u00e1ser sinteriza capa a capa las part\u00edculas de polvo depositadas en la placa de fabricaci\u00f3n. Adem\u00e1s, al tratarse de un m\u00e9todo basado en lecho de polvo, no se requieren <a href=\"https:\/\/www.3dnatives.com\/es\/guia-soportes-de-impresion-3d-200920222\/\">soportes de impresi\u00f3n<\/a>, ya que el propio polvo actual como soporte. Este tambi\u00e9n permite el llamado \u201c<em>stacking<\/em>\u201d o apilamiento de varias piezas, unas encima de otras, en un mismo proceso de fabricaci\u00f3n. En este caso, dado que las part\u00edculas de metal est\u00e1n protegidas por las de pol\u00edmero, no se encuentran expuestas al aire y, por lo tanto, no se produce la oxidaci\u00f3n del metal. Por otra parte, el proceso en fr\u00edo no tiene ning\u00fan impacto t\u00e9rmico en el polvo no sinterizado, por lo que ser\u00e1 posible reutilizarlo en futuras impresiones.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-71771 aligncenter\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-process.jpg\" alt=\"\" width=\"700\" height=\"230\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-process.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-process-600x197.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-process-160x53.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h4>La importancia del postratamiento<\/h4>\n<p style=\"text-align: justify;\">En la impresi\u00f3n 3D por Cold Metal Fusion, el post-procesamiento es una etapa clave. Tras retirar las piezas \u201cverdes\u201d de la impresora SLS, se realiza <a href=\"https:\/\/www.3dnatives.com\/es\/limpieza-piezas-postratamiento-impresion-3d-200220232\/\">la limpieza<\/a> de la bandeja de fabricaci\u00f3n, eliminando el polvo no sinterizado. Esta etapa puede completarse mediante el uso de aire a presi\u00f3n o un chorro de agua gracias a la gran estabilidad de dichas piezas verdes. Tras ello, se realiza el despegado o desaglomerado, un proceso en el que los modelos se sumergen en disolvente para eliminar el pl\u00e1stico sinterizado de la estructura met\u00e1lica. Las piezas obtenidas se denominan \u201cmarrones\u201d y al salir del desaglomerado est\u00e1n listas para la etapa final: la sinterizaci\u00f3n real del metal.<\/p>\n<p style=\"text-align: justify;\">En este \u00faltimo paso, se introducen las piezas marrones en un horno que las calienta y elimina cualquier resto de aglutinante que haya en su interior. De esta forma, las part\u00edculas restantes de metal se sinterizan dando lugar a las piezas finales met\u00e1licas. Cabe destacar que, para esta etapa final, se requiere un horno especializado que sea capaz de alcanzar temperaturas de sinterizado para <a href=\"https:\/\/www.3dnatives.com\/es\/descubriendo-los-metales-de-la-impresion-3d\/\">metales<\/a>.<\/p>\n<h3>Beneficios y aplicaciones en la industria<\/h3>\n<p style=\"text-align: justify;\">Como vemos, la principal ventaja de la tecnolog\u00eda Cold Metal Fusion es la capacidad de crear piezas finales de metal utilizando impresoras 3D SLS. Estas m\u00e1quinas para pol\u00edmeros est\u00e1n ampliamente disponibles en el mercado y suelen tener un coste generalmente muy inferior al de las soluciones de <a href=\"https:\/\/www.3dnatives.com\/es\/sinterizado-directo-de-metal-por-laser-les-explicamos-todo\/\">fusi\u00f3n l\u00e1ser por lecho de polvo<\/a> (LPBF) de metal. De hecho, la impresi\u00f3n 3D por CMF puede realizarse en m\u00e1quinas SLS b\u00e1sicas como las de Sintratec, reduciendo a\u00fan m\u00e1s el coste de inversi\u00f3n inicial para las empresas. En el sitio web de Headmade Materials a\u00f1aden: <em>\u201cEs el coste de inversi\u00f3n m\u00e1s bajo de todos los procesos de impresi\u00f3n 3D de metal para la producci\u00f3n en serie de hasta 100.000 piezas\u201d<\/em>. Esta cifra significa que la impresi\u00f3n 3D por CMF ser\u00eda una opci\u00f3n m\u00e1s adecuada a nivel econ\u00f3mico que los procesos MIM (Metal Injection Molding) o la fundici\u00f3n a alta presi\u00f3n.<\/p>\n<div id=\"attachment_71778\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-71778\" class=\"wp-image-71778 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part-2.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part-2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part-2-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/CMF-part-2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-71778\" class=\"wp-caption-text\">Dos ejemplos de piezas creadas por CMF.<\/p><\/div>\n<p style=\"text-align: justify;\">Este m\u00e9todo de fabricaci\u00f3n tambi\u00e9n es una alternativa a la impresi\u00f3n 3D por inyecci\u00f3n aglutinante, capaz de crear igualmente piezas de metal. Por ello, muchas de las aplicaciones ser\u00e1n similares a las de las tecnolog\u00edas LPBF y binder jetting. Los sectores que m\u00e1s se pueden beneficiar de este m\u00e9todo de fabricaci\u00f3n incluyen el <a href=\"https:\/\/www.3dnatives.com\/es\/infografia-impresion-3d-automocion-181020222\/\">automotriz<\/a>, aeroespacial, m\u00e9dico y de bienes de consumo, entre otros.<\/p>\n<p style=\"text-align: justify;\">Por mencionar algunos ejemplos, la empresa Sturdy Cycles cambi\u00f3 su producci\u00f3n de piezas de titanio a la impresi\u00f3n 3D por CMF. Esto ofreci\u00f3 una mayor eficiencia en el desarrollo del equipamiento deportivo, reduciendo costes y permitiendo la fabricaci\u00f3n in situ. Otro caso de \u00e9xito lo encontramos en la competici\u00f3n internacional Formula Student, donde Headmade Materials patrocin\u00f3 a uno de los participantes. En concreto, el equipo representando a la Universidad de Ciencias Aplicadas de Esslingen (Alemania) recibi\u00f3 un separador de aire y aceite creado mediante Cold Metal Fusion. El componente, fabricado con la aleaci\u00f3n de titanio Ti6Al4V, contaba con optimizaci\u00f3n del peso y una gran capacidad de carga. Por \u00faltimo, otro uso de CMF lo realiz\u00f3 el fabricante alem\u00e1n de herramientas Utilis AG. Desarroll\u00f3 un portaherramientas de corte en acero con un exclusivo canal interior de refrigerante capaz de aumentar el rendimiento de la herramienta de corte en un 185%.<\/p>\n<h3>El futuro de la impresi\u00f3n 3D por CMF<\/h3>\n<p style=\"text-align: justify;\">Aunque la tecnolog\u00eda Cold Metal Fusion es relativamente nueva, su uso se est\u00e1 democratizando a pasos agigantados. La idea de un proceso sinterizado selectivo l\u00e1ser de metal se est\u00e1 haciendo cada vez m\u00e1s popular en el mercado, y muchas empresas ya est\u00e1n plante\u00e1ndose su adopci\u00f3n. Adem\u00e1s, este sistema de fabricaci\u00f3n se est\u00e1 impulsando gracias a la llamada \u201c<strong>ColdMetalFusion Alliance<\/strong>\u201d. Se trata de una iniciativa promovida por Headmade Materials despu\u00e9s de que la startup surgiera como parte del fondo de capital riesgo AM Ventures, propiedad de <a href=\"https:\/\/www.3dnatives.com\/es\/inside-3d-tour-fabricacion-aditiva-eos-alemania-171020232\/\">la empresa EOS<\/a>. A esta alianza se han unido varias empresas industriales, como mimPlus, Element22 y Miba, pero tambi\u00e9n fabricantes de impresoras 3D como Farsoon Technologies (desarrollador de soluciones SLS).<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/r828X7o7RKo?si=pkSR9sbtk5Rwlioj\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">La meta de la ColdMetalFusion Alliance es industrializar la tecnolog\u00eda a trav\u00e9s de est\u00e1ndares comunes entre la sinterizaci\u00f3n y la fabricaci\u00f3n aditiva. Las empresas miembros no s\u00f3lo comparten normas, sino tambi\u00e9n una cultura y una forma de pensar similar. Los continuos avances de este sistema y los materiales compatibles que est\u00e1n por venir permitir\u00e1n a esta tecnolog\u00eda llegar a muchos m\u00e1s sectores y aplicaciones.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la gu\u00eda sobre la impresi\u00f3n 3D por Cold Metal Fusion? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/groups\/8516968\/\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a> y <a href=\"https:\/\/www.youtube.com\/channel\/UCMWrNpdLOXa7BffRKXZoaZw\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<p style=\"text-align: justify;\"><em>*Cr\u00e9ditos de todas las fotos: Headmade Materials<\/em><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-2530325639\"><div id=\"dnati-3456536400\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda, estamos observando una tendencia en la industria manufacturera hacia soluciones de fabricaci\u00f3n aditiva de metal. Sin embargo, en muchas ocasiones estas m\u00e1quinas pueden llegar a ser caras para muchas empresas que se est\u00e1n iniciando en este campo.&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":71720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,12,282],"tags":[],"class_list":["post-71719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-materiales","category-tecnologias-3d"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/71719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=71719"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/71719\/revisions"}],"predecessor-version":[{"id":80558,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/71719\/revisions\/80558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/71720"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=71719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=71719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=71719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}