{"id":54008,"date":"2021-09-29T00:02:54","date_gmt":"2021-09-28T22:02:54","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=54008"},"modified":"2021-09-28T13:22:34","modified_gmt":"2021-09-28T11:22:34","slug":"paises-bajos-puente-3d-ciclistas-290929212","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/paises-bajos-puente-3d-ciclistas-290929212\/","title":{"rendered":"Inauguran en los Pa\u00edses Bajos el puente para ciclistas m\u00e1s largo impreso en 3D"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Despu\u00e9s de varios meses de trabajo, la ciudad de Nijmegen ubicada en los Pa\u00edses Bajos, ahora cuenta con un puente para ciclistas impreso en 3D que ser\u00eda uno de los m\u00e1s largos hasta la fecha. Inaugurado a principios de septiembre, el puente mide 29 metros y fue fabricado en el centro de impresi\u00f3n 3D de Saint-Gobain Weber Beamix, que incorpora varios brazos rob\u00f3ticos BAM. Lo llamativo de esta estructura es la forma en que fue dise\u00f1ada. Se basaron en un software de dise\u00f1o param\u00e9trico que permite optimizar el material o el tiempo de impresi\u00f3n, entre otras cosas, siempre teniendo en cuenta las cargas aplicadas (n\u00famero de bicicletas, peatones, peso, etc).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ya dimos a conocer este proyecto el <a href=\"https:\/\/www.3dnatives.com\/es\/the-project-bridge-construccion-050420212\/\">pasado mes de abril<\/a> y despu\u00e9s de seguir su progreso, \u00a1por fin ha sido terminado! Al igual que el <a href=\"https:\/\/www.3dnatives.com\/es\/puente-3d-metal-amsterdam-260720212\/\">puente de MX3D<\/a> instalado en \u00c1msterdam, el de Nijmegen se inaugur\u00f3 hace apenas unas semanas. Detr\u00e1s de la estructura, hay un trabajo de colaboraci\u00f3n entre varios socios, incluida la Universidad Tecnol\u00f3gica de Eindhoven (UTE) o el arquitecto Michiel van der Kley. Los equipos dividieron el puente en varios bloques impresos en 3D, ensamblados directamente en el sitio para mantener la simplicidad. Bert Velthuis, del Ayuntamiento de Nijmegen, coment\u00f3: <\/span><i><span style=\"font-weight: 400;\">\u201cLa ciudad de Nijmegen se siente muy honrada de incorporar este innovador puente impreso en 3D. Somos una ciudad llena de puentes, y esta estructura especial e innovadora es una maravillosa noticia. El puente es pura conexi\u00f3n: en la fase de dise\u00f1o y construcci\u00f3n, uni\u00f3 a los diferentes socios y, a partir de ahora, el puente conecta a nuestros ciudadanos\u201d<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<div id=\"attachment_65632\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-65632\" class=\"wp-image-65632 size-full\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2021\/09\/pont_bloc.jpg\" alt=\"puente 3D Pa\u00edses Bajos\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-65632\" class=\"wp-caption-text\">El puente est\u00e1 formado por varios bloques impresos en 3D. | Cr\u00e9ditos: Ciudad de Nijmegen\/Michiel van der Kley<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El puente de 29 metros de largo se integra a la perfecci\u00f3n con el entorno, pues el arquitecto ha querido darle formas redondas y naturales. Estos patrones no se pudieron obtener con otra tecnolog\u00eda aparte de la impresi\u00f3n 3D. Los diversos miembros del equipo esperan llevar m\u00e1s all\u00e1 la <a href=\"https:\/\/www.3dnatives.com\/es\/funcionamiento-impresora-3d-hormigon-120720212\/\">fabricaci\u00f3n aditiva de hormig\u00f3n<\/a> y ofrecer m\u00e1s construcciones impresas en 3D. Theo Salet, profesor de estructuras de hormig\u00f3n en la UTE, concluye: <\/span><i><span style=\"font-weight: 400;\">\u201cLa impresi\u00f3n 3D de hormig\u00f3n tiene un enorme potencial de crecimiento. Usamos menos materias primas porque la m\u00e1quina solo agrega el hormig\u00f3n necesario para la construcci\u00f3n. Tambi\u00e9n podemos aumentar significativamente la velocidad de fabricaci\u00f3n. En el futuro, queremos hacer que el hormig\u00f3n sea m\u00e1s duradero y poder reutilizarlo. A\u00fan as\u00ed, queda mucho por hacer. Tambi\u00e9n estoy orgulloso de que el conocimiento que desarroll\u00e9 se abri\u00f3 camino en la industria tan r\u00e1pidamente\u201d<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p><div class=\"dnati-inside_content dnati-entity-placement\" id=\"dnati-1635088298\"><div id=\"dnati-279491035\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"NPE2027_Feathr Ads_850x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\">Puedes encontrar m\u00e1s informaci\u00f3n del proyecto <a href=\"https:\/\/www.tue.nl\/en\/news-and-events\/news-overview\/01-01-1970-nijmegen-has-the-longest-3d-printed-concrete-bicycle-bridge-in-the-world\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>. \u00bfQu\u00e9 piensas del puente 3D instalado en los Pa\u00edses Bajos? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCo9ZtHB24te-z7AMWTL92MA\/featured\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a> y <a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<p><em>*Cr\u00e9ditos foto de portada: Ville de Nim\u00e8gue\/Michiel van der Kley<\/em><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-605080258\"><div id=\"dnati-1086845956\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de varios meses de trabajo, la ciudad de Nijmegen ubicada en los Pa\u00edses Bajos, ahora cuenta con un puente para ciclistas impreso en 3D que ser\u00eda uno de los m\u00e1s largos hasta la fecha. Inaugurado a principios de septiembre,&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":54009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,297,132],"tags":[],"class_list":["post-54008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-arquitectura","category-diseno"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/54008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=54008"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/54008\/revisions"}],"predecessor-version":[{"id":54011,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/54008\/revisions\/54011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/54009"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=54008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=54008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=54008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}