{"id":53988,"date":"2021-09-28T00:02:59","date_gmt":"2021-09-27T22:02:59","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=53988"},"modified":"2021-09-27T10:52:07","modified_gmt":"2021-09-27T08:52:07","slug":"hyperion-robotics-fabricacion-aditiva-construccion-280920212","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/hyperion-robotics-fabricacion-aditiva-construccion-280920212\/","title":{"rendered":"Hyperion Robotics y su visi\u00f3n de la fabricaci\u00f3n aditiva en la construcci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El sector de la construcci\u00f3n ha estado explorando el potencial de la <a href=\"https:\/\/www.3dnatives.com\/es\/fundamentos-fabricacion-aditiva\/\">fabricaci\u00f3n aditiva<\/a> durante los \u00faltimos a\u00f1os. Hoy en d\u00eda, la idea de una casa impresa en 3D ya no es algo nuevo en el mercado, ya que hemos visto multitud de edificios impresos en 3D. De hecho, cada vez m\u00e1s empresas deciden adoptar la fabricaci\u00f3n aditiva en la <a href=\"https:\/\/www.3dnatives.com\/es\/futuro-impresion-3d-sector-construccion-260120212\/\">construcci\u00f3n<\/a>. Una de ellas es la startup finlandesa Hyperion Robotics. Fundada en 2019, la empresa apareci\u00f3 en las noticias internacionales en el verano de 2020, cuando se asoci\u00f3 con una organizaci\u00f3n estadounidense sin \u00e1nimo de lucro para un proyecto de lo m\u00e1s interesante. Quer\u00eda crear escuelas impresas en 3D en Madagascar para hacer que la educaci\u00f3n sea m\u00e1s accesible para la poblaci\u00f3n africana en v\u00edas de desarrollo. Tuvimos curiosidad por saber m\u00e1s sobre los futuros proyectos de Hyperion Robotics, por lo que hablamos con su director de dise\u00f1o, el Dr. Ashish Mohite.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfPuedes presentarte y contarnos m\u00e1s sobre Hyperion Robotics?<\/h3>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24186 alignleft\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2020\/09\/Ashish-Hyperion-Robot.jpeg\" alt=\"\" width=\"282\" height=\"188\" \/><span style=\"font-weight: 400;\">Mi nombre es Ashish Mohite, soy arquitecto y doctorado en investigaci\u00f3n por la Universidad Aalto en Finlandia y he estado trabajando con impresi\u00f3n 3D durante los \u00faltimos 9 a\u00f1os. Soy cofundador y director de dise\u00f1o de Hyperion Robotics, donde estamos desarrollando tecnolog\u00eda de automatizaci\u00f3n, rob\u00f3tica e impresi\u00f3n 3D para hacer que la industria de la construcci\u00f3n sea m\u00e1s eficiente y sostenible. La compa\u00f1\u00eda se lanz\u00f3 oficialmente en Finlandia en 2019 cuando me un\u00ed a mi cofundador Fernando de los R\u00edos (CEO de Hyperion). Aport\u00e9 mi experiencia en impresi\u00f3n y arquitectura 3D, para resolver un problema que yo mismo hab\u00eda sufrido en la construcci\u00f3n y construcci\u00f3n de viviendas en India y en Europa. Tambi\u00e9n quer\u00eda tener un impacto significativo en la industria menos automatizada del mundo.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfQu\u00e9 tecnolog\u00edas de impresi\u00f3n 3D us\u00e1is en vuestra actividad?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nuestro sistema de impresi\u00f3n 3D se basa en <a href=\"https:\/\/www.3dnatives.com\/es\/funcionamiento-impresora-3d-hormigon-120720212\/\">brazos rob\u00f3ticos industriales<\/a>. Actualmente utilizamos robots Kuka en nuestros proyectos, pero somos \u201cindependientes de los robots\u201d. Esto quiere decir que podemos integrar nuestro software patentado para ser utilizado por cualquier persona sin conocimientos t\u00e9cnicos, y equipos de impresi\u00f3n 3D en diferentes tipos de sistemas. En t\u00e9rminos de materiales, usamos una mezcla especial de hormig\u00f3n que cuenta con una cantidad reducida de cemento gracias a desechos reciclados, y adem\u00e1s est\u00e1 optimizada para diferentes aplicaciones y entornos. Estamos trabajando con nuestros socios industriales para desarrollar mezclas m\u00e1s sostenibles y de alto rendimiento para la impresi\u00f3n 3D. Tambi\u00e9n disponemos de un m\u00e9todo muy especial para incorporar refuerzo en el proceso. Ofrecemos nuestra tecnolog\u00eda como una soluci\u00f3n integral a nuestros clientes, tal y como las empresas constructoras y los promotores est\u00e1n acostumbrados a trabajar con subcontratistas. Somos capaces de adaptar nuestra oferta en funci\u00f3n de todas las necesidades.<\/span><\/p>\n<div id=\"attachment_24196\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-24196\" class=\"wp-image-24196 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2020\/09\/Untitled-22.jpg\" alt=\"hyperion robotics\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-24196\" class=\"wp-caption-text\">Un robot industrial Kuka que imprime en 3D una gran pieza de hormig\u00f3n.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bfEn qu\u00e9 tipo de proyectos hab\u00e9is estado involucrados hasta ahora?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Siempre intentamos involucrarnos en proyectos muy interesantes. Por ejemplo, acabamos de terminar la llamada \u201cCreate Summer School\u201d mediante impresi\u00f3n 3D de hormig\u00f3n junto a nuestro socio acad\u00e9mico CREATE Group de la Universidad del Sur de Dinamarca en Odense. All\u00ed realizamos talleres de impresi\u00f3n 3D y experimentos con hormig\u00f3n junto a estudiantes de diferentes or\u00edgenes. Este es uno de los primeros proyectos con CREATE, que est\u00e1 dirigido por el profesor Roberto Naboni, donde buscamos ampliar los l\u00edmites de la impresi\u00f3n 3D en el entorno arquitect\u00f3nico. Tambi\u00e9n queremos reducir la huella de carbono de la industria, aprovechando las instalaciones de prueba de vanguardia en la Universidad. Otro proyecto muy interesante es el de Thinking Huts, una ONG estadounidense que pretende imprimir escuelas en 3D para pa\u00edses africanos donde casi no hay acceso a la educaci\u00f3n para la mayor\u00eda de la poblaci\u00f3n infantil.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfPuedes contarnos m\u00e1s sobre la colaboraci\u00f3n con Thinking Huts?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El proyecto <a href=\"https:\/\/www.3dnatives.com\/es\/thinking-huts-acceso-educacion-030620212\/\">Thinking Huts<\/a> nos entusiasma mucho porque combina innovaci\u00f3n, sostenibilidad y un aspecto de gran impacto social. Los ni\u00f1os de Madagascar y \u00c1frica tienen muchas limitaciones para acceder a la educaci\u00f3n, por lo que hemos decidido unir fuerzas con Maggie Grout y su equipo para ser su socio tecnol\u00f3gico. Estamos aportando nuestros sistemas rob\u00f3ticos y nuestro know-how en impresi\u00f3n y construcci\u00f3n 3D para poder construir la primera escuela en Madagascar. Una vez que este proyecto se haya construido con \u00e9xito, ser\u00e1 el trampol\u00edn para permitir que Thinking Huts aumente el acceso global a la educaci\u00f3n. Despu\u00e9s de eso, desplegaremos m\u00e1s robots para ayudar a construir escuelas a mayor escala, para decenas de miles de ni\u00f1os.<\/span><\/p>\n<div id=\"attachment_24189\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-24189\" class=\"wp-image-24189 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2020\/09\/Untitled-20.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-24189\" class=\"wp-caption-text\">Una ilustraci\u00f3n de una escuela impresa en 3D en Madagascar para el proyecto Thinking Huts.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bfCu\u00e1les son los futuros proyectos de Hyperion Robotics?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Imaginamos un futuro en el que la construcci\u00f3n estar\u00e1 completamente automatizada por robots y queremos ser la fuerza que impulse esta revoluci\u00f3n. Actualmente estamos implementando sistemas de impresi\u00f3n 3D a nivel mundial, por lo que nuestro objetivo es brindar a nuestros clientes la mejor experiencia y soporte, solidificar estas relaciones y llegar a nuevos mercados. As\u00ed, queremos atraer nuevos clientes que est\u00e9n convencidos de que la arquitectura y la industria de la construcci\u00f3n necesita cambiar para tener un impacto en el mundo.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfC\u00f3mo ves el estado actual de la impresi\u00f3n 3D en la construcci\u00f3n y la arquitectura?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Estamos muy entusiasmados con la forma en que la industria de la impresi\u00f3n 3D en la construcci\u00f3n est\u00e1 evolucionando y creciendo. Como sabemos, este m\u00e9todo productivo ha existido durante un par de d\u00e9cadas y, como la mayor\u00eda de las nuevas tecnolog\u00edas, ha tardado bastante en madurar. Estamos viendo algunos cambios exponenciales en proyectos a gran escala, como viviendas e infraestructura para personas necesitadas. Incluso las empresas m\u00e1s antiguas y conservadoras est\u00e1n comenzando a darse cuenta de que hay una necesidad de cambio y est\u00e1n comenzando a invertir grandes cantidades para formar parte de esta revoluci\u00f3n. Esperamos que el inter\u00e9s y el crecimiento contin\u00faen y que comencemos a ver nuevos tipos de proyectos, materiales y aplicaciones en todo el mundo.<\/span><\/p>\n<div id=\"attachment_24190\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-24190\" class=\"wp-image-24190 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2020\/09\/Untitled-21.jpg\" alt=\"hyperion robotics\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-24190\" class=\"wp-caption-text\">Plano detalle del resultado obtenido mediante la impresi\u00f3n 3D de hormig\u00f3n.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bfAlgo m\u00e1s que decir a los lectores?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Tenemos la misi\u00f3n de hacer que la industria de la construcci\u00f3n sea m\u00e1s sostenible y automatizada. Para lograrlo, necesitamos la contribuci\u00f3n de todas las partes involucradas, desde actores industriales y acad\u00e9micos hasta individuos y gobiernos de todo el mundo. Siempre estamos buscando personas, empresas e instituciones apasionadas por la forma en que la tecnolog\u00eda de vanguardia influye en la forma en que construimos. Puedes obtener m\u00e1s informaci\u00f3n sobre nuestros proyectos a trav\u00e9s de <a href=\"https:\/\/www.hyperionrobotics.com\/\">este enlace<\/a>.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la entrevista realizada al equipo de Hyperion Robotics? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCo9ZtHB24te-z7AMWTL92MA\/featured\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a> y <a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-2983108115\"><div id=\"dnati-473840828\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El sector de la construcci\u00f3n ha estado explorando el potencial de la fabricaci\u00f3n aditiva durante los \u00faltimos a\u00f1os. Hoy en d\u00eda, la idea de una casa impresa en 3D ya no es algo nuevo en el mercado, ya que hemos&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":53992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,297,10],"tags":[],"class_list":["post-53988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-arquitectura","category-entrevistas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/53988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=53988"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/53988\/revisions"}],"predecessor-version":[{"id":54001,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/53988\/revisions\/54001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/53992"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=53988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=53988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=53988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}