{"id":53595,"date":"2021-08-30T00:02:41","date_gmt":"2021-08-29T22:02:41","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=53595"},"modified":"2021-08-27T09:38:15","modified_gmt":"2021-08-27T07:38:15","slug":"divedesign-protesis-3d-animales-300820212","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/divedesign-protesis-3d-animales-300820212\/","title":{"rendered":"DiveDesign y el desarrollo de pr\u00f3tesis 3D para mejorar la vida de los animales"},"content":{"rendered":"<p style=\"text-align: justify;\">Los grandes avances de la tecnolog\u00eda 3D han permitido utilizar la <a href=\"https:\/\/www.3dnatives.com\/es\/animales-impresion-3d-240520172\/\">impresi\u00f3n 3D para ayudar animales<\/a>, concretamente para mejorar su calidad de vida. Muchos de ellos son rescatados, pero sus malas condiciones no les permiten ser independientes. Es por eso que muchas empresas han recurrido a la fabricaci\u00f3n aditiva y a la digitalizaci\u00f3n 3D para el desarrollo de prototipos que solucionen este problema. DiveDesign, una empresa estadounidense con sede en Nueva Jersey, ha trabajado con algunas de estas compa\u00f1\u00edas para ayudar a producir pr\u00f3tesis y \u00f3rtesis 3D adaptadas a cada animal. Hemos hablado con Adam <span style=\"font-weight: 400;\">Hecht, del equipo de DiveDesign, para conocer m\u00e1s su relaci\u00f3n con estos proyectos y el desarrollo de dispositivos para animales utilizando la fabricaci\u00f3n aditiva.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfPodr\u00edas presentarte y contar tu conexi\u00f3n con la impresi\u00f3n 3D?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Mi nombre es Adam, junto con mi socio fund\u00e9 DiveDesign LLC. A trav\u00e9s de varios proyectos e iniciativas internas, hemos adoptado y utilizado la impresi\u00f3n 3D de muchas formas diferentes para ayudar a satisfacer mejor las necesidades de nuestros clientes y contrarrestar la fabricaci\u00f3n tradicional.<\/span><\/p>\n<div id=\"attachment_53600\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-53600\" class=\"size-full wp-image-53600\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/700x400-min.jpg\" alt=\"DiveDesign\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/700x400-min.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/700x400-min-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/700x400-min-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-53600\" class=\"wp-caption-text\">El equipo de DiveDesign. A la derecha, <span style=\"font-weight: 400;\">Adam Hecht.<\/span><\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bfQu\u00e9 es Dive Design y c\u00f3mo se fund\u00f3? \u00bfCu\u00e1ndo empezaste a trabajar con animales?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">DiveDesign es una empresa de dise\u00f1o y desarrollo de productos que se asocia estrat\u00e9gicamente y desarrolla relaciones duraderas con marcas visionarias. Probamos nuevas ideas y creamos soluciones que son el catalizador del cambio en toda la industria. DiveDesign fue fundada por Alex Tholl y Adam Hecht con la necesidad de expandir el creciente trabajo independiente en dise\u00f1o industrial. En los \u00faltimos a\u00f1os, hemos construido un equipo talentoso que sirve a una variedad de industrias que necesitan un desarrollo continuo de productos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Comenzamos a trabajar con animales cuando nuestro cliente y amigo Derrick Campana (propietario de Bionic Pets y Wizard Of Paws) nos hizo saber que estaba luchando por mantenerse al d\u00eda con la demanda de pr\u00f3tesis para patas de perros. Ten\u00eda los pedidos, pero el proceso de fabricaci\u00f3n era demasiado lento para entregarlas a tiempo. Ayudamos a dise\u00f1ar una herramienta digital y, junto con el <a href=\"https:\/\/www.3dnatives.com\/es\/integrar-tecnologia-escaneado-3d-211220202\/\">escaneo 3D<\/a>, pudimos imprimir en 3D estas nuevas pr\u00f3tesis para \u00e9l.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfPodr\u00edas hablar sobre las tecnolog\u00edas 3D que utiliz\u00e1is en vuestros proyectos?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Utilizamos muchas <a href=\"https:\/\/www.3dnatives.com\/es\/tipos-impresoras-3d-fdm-190620172\/\">m\u00e1quinas de impresi\u00f3n 3D FDM<\/a> para crear prototipos de baja y alta fidelidad para los proyectos de nuestros clientes, tambi\u00e9n utilizamos la extrusi\u00f3n de material para construir las pr\u00f3tesis de animales ya mencionadas. La tecnolog\u00eda de escaneo 3D tambi\u00e9n juega un papel muy importante en estas pr\u00f3tesis, y en algunos otros trabajos no relacionados, ya que permite adaptar los modelos al cuerpo del animal.<\/span><\/p>\n<div id=\"attachment_53599\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-53599\" class=\"wp-image-53599 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/2-min.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/2-min.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/2-min-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/2-min-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-53599\" class=\"wp-caption-text\">Tammy, un cerdito rescatado con una pr\u00f3tesis para las patas traseras. | Cr\u00e9ditos: DiveDesign<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bfPor qu\u00e9 optaste por esta tecnolog\u00eda para ayudar a los animales? \u00bfCu\u00e1les son los beneficios obtenidos?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La barrera de entrada con FDM es extremadamente baja, f\u00e1cilmente modificable y tiene miles de opciones de materiales. Est\u00e1bamos buscando una m\u00e1quina con un mayor volumen de construcci\u00f3n y que fuera compatible con materiales flexibles. Uno de los mayores beneficios es la producci\u00f3n en masa de piezas personalizadas. Cada pr\u00f3tesis es muy diferente, pero podemos satisfacer la creciente demanda porque las m\u00e1quinas funcionan las 24 horas del d\u00eda. Adem\u00e1s, podemos asignar ese tiempo restante para desarrollar nuevos tipos de articulaciones prot\u00e9sicas, carros y adaptadores que promueven los avances en el \u00e1mbito de las mascotas.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfCu\u00e1l es vuestra visi\u00f3n como empresa? \u00bfQu\u00e9 futuros proyectos est\u00e1n por venir?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nuestra visi\u00f3n es continuar creciendo y trabajando con clientes que desean innovar, traspasar los l\u00edmites del dise\u00f1o tradicional y ser l\u00edderes en sus industrias. En DiveDesign nos gustar\u00eda continuar haciendo crecer nuestro talentoso equipo, <a href=\"https:\/\/www.3dnatives.com\/es\/3D-compare\">comprar m\u00e1s impresoras 3D<\/a> y expandir a\u00fan m\u00e1s nuestras capacidades de los prototipos r\u00e1pidos. <\/span><span style=\"font-weight: 400;\">Estamos desarrollando un dispositivo de entrenamiento que podr\u00eda cambiar la forma en que interactuamos con las m\u00e1quinas tradicionales en el hogar y en el gimnasio, dise\u00f1ando y creando prototipos de nuevos sistemas de carritos para perros con problemas de movilidad y viajando a algunas ferias comerciales, lo cual es muy emocionante despu\u00e9s de estar limitados a causa de la crisis sanitaria.<\/span><\/p>\n<div id=\"attachment_53598\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-53598\" class=\"wp-image-53598 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/1-min.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/1-min.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/1-min-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/1-min-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-53598\" class=\"wp-caption-text\">Cr\u00e9ditos: DiveDesign<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: \u00bf\u00daltimas palabras para los lectores?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Puedes ponerte en contacto con nosotros a trav\u00e9s de nuestro <a href=\"https:\/\/www.divedesignco.com\/\" target=\"_blank\" rel=\"noopener\">sitio web<\/a>. Te contaremos c\u00f3mo podemos ser una buena opci\u00f3n para ayudar a tu empresa a optimizar los flujos de trabajo, dinamizar una l\u00ednea de productos y mucho m\u00e1s.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de DiveDesign y su utilizaci\u00f3n de la tecnolog\u00eda 3D para ayudar a los animales? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCo9ZtHB24te-z7AMWTL92MA\/featured\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a> y <a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los grandes avances de la tecnolog\u00eda 3D han permitido utilizar la impresi\u00f3n 3D para ayudar animales, concretamente para mejorar su calidad de vida. Muchos de ellos son rescatados, pero sus malas condiciones no les permiten ser independientes. Es por eso&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":53601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,10],"tags":[],"class_list":["post-53595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-entrevistas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/53595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=53595"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/53595\/revisions"}],"predecessor-version":[{"id":53606,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/53595\/revisions\/53606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/53601"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=53595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=53595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=53595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}