{"id":48551,"date":"2020-10-01T15:00:57","date_gmt":"2020-10-01T13:00:57","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=48551"},"modified":"2024-02-20T18:07:39","modified_gmt":"2024-02-20T17:07:39","slug":"mambo-barco-fibra-de-vidrio-011020202","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/mambo-barco-fibra-de-vidrio-011020202\/","title":{"rendered":"MAMBO, el barco de fibra de vidrio impreso en 3D, finalmente despega"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfRecuerdas este barco impreso en 3D que os presentamos en los pasillos de <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=GrBW5mAdDaQ&amp;t=93s\"><span style=\"font-weight: 400;\">Formnext 2019<\/span><\/a><span style=\"font-weight: 400;\">? Fue dise\u00f1ado por Moi Composites en colaboraci\u00f3n con Autodesk, Catmarine, Micad y Owens Corning, y \u00a1finalmente se ha hecho a la mar! Llamado MAMBO (Barco de fabricaci\u00f3n aditiva por motor), parece ser el primer barco de fibra de vidrio impreso en 3D que navegar\u00e1 por aguas italianas en el sal\u00f3n n\u00e1utico de G\u00e9nova a partir de ma\u00f1ana. Mide 6,5 metros de largo por 2,5 metros de ancho, pesa alrededor de 800 kg y est\u00e1 equipado con un sistema de navegaci\u00f3n real, suelo de corcho, asientos de cuero blanco y un motor de 115 CV. \u00a1Una verdadera primicia para el sector mar\u00edtimo!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Est\u00e1 claro que la fabricaci\u00f3n aditiva es tan efectiva en el aire como en el agua. Las <a href=\"https:\/\/www.3dnatives.com\/es\/top-10-aplicaciones-maritimas-la-impresion-3d-230820172\/\">aplicaciones al servicio del mar<\/a> se multiplican, ya sea para preservar el medio ambiente, dise\u00f1ar dispositivos m\u00e1s eficientes o simplemente dise\u00f1ar repuestos para todo tipo de barcos. En cuanto a la fabricaci\u00f3n de embarcaciones, las tecnolog\u00edas 3D han comenzado a demostrar su val\u00eda, como en el caso del <\/span><a href=\"https:\/\/www.3dnatives.com\/es\/3dirigo-barco-impreso-en-3d-181020192\/\"><span style=\"font-weight: 400;\">barco 3Dirigo<\/span><\/a><span style=\"font-weight: 400;\">, desarrollado por la Universidad de Maine, que bati\u00f3 r\u00e9cords mundiales. Los dise\u00f1adores confiaron en la tecnolog\u00eda de gran formato para crear todo el barco de una vez. En el caso del fabricante italiano Moi Composites, es m\u00e1s el material utilizado el que conviene destacar, ya que MAMBO est\u00e1 hecho de un compuesto a base de fibra de vidrio.<\/span><\/p>\n<div id=\"attachment_48556\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48556\" class=\"size-full wp-image-48556\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MAMBO.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MAMBO.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MAMBO-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/MAMBO-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-48556\" class=\"wp-caption-text\">MAMBO es un barco a motor impreso en 3D en fibras de vidrio continuas. | Cr\u00e9ditos: Autodesk<\/p><\/div>\n<h3 style=\"text-align: justify;\">Impresi\u00f3n 3D compuesta para dise\u00f1ar MAMBO<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Moi Composites se bas\u00f3 en la tecnolog\u00eda Continuous Fiber Manufacturing, un m\u00e9todo de <a href=\"https:\/\/www.3dnatives.com\/es\/guia-completa-impresion-3d-composites-280120202\/\">impresi\u00f3n 3D\u00a0 de materiales compuestos<\/a> de fibra continua. Un robot Kuka guiado por un algoritmo deposita un pl\u00e1stico termoendurecible cargado con fibras continuas (en este caso vidrio), que por lo tanto, se endurece con una fuente de luz UV. El sistema permite desarrollar piezas m\u00e1s ligeras, m\u00e1s resistentes y m\u00e1s duraderas, sin necesidad de crear moldes inaccesibles y limitar el desperdicio de material. La startup italiana ha llevado a cabo varios proyectos para demostrar las capacidades de esta tecnolog\u00eda, todo comenz\u00f3 con su robot Atropos. El barco MAMBO es sin duda uno de los ejemplos m\u00e1s llamativos.<\/span><\/p><div class=\"dnati-inside_content dnati-entity-placement\" id=\"dnati-687425937\"><div id=\"dnati-3132358513\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"NPE2027_Feathr Ads_850x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Con el apoyo de varias empresas, incluida Autodesk, Moi Composites imagin\u00f3 una lancha de 6,5 metros de largo y 2,5 metros de ancho, con un casco en forma de Y inspirado en el Arcidiavolo dise\u00f1ado por Sonny Levi. Los equipos explican que la estructura monocasco con formas org\u00e1nicas y asim\u00e9tricas se construy\u00f3 sobre esta base. Por fin tenemos la sensaci\u00f3n de que las formas imaginadas contin\u00faan, un poco como la corriente del agua. Gabriele Natale, CEO y cofundador de Moi Composites, agrega: <\/span><i><span style=\"font-weight: 400;\">\u201cParticipamos en el sal\u00f3n n\u00e1utico de G\u00e9nova en 2017, y fue durante este evento que tuvimos la idea de fabricar el MAMBO. Primero vimos tomar forma el proyecto, luego le dimos vida, y finalmente lleg\u00f3 el MAMBO al mar. Imprimimos un barco en 3D, reforzando el concepto de personalizaci\u00f3n con un dise\u00f1o \u00fanico creado y adaptado en la mente del propietario, para que todos tengan la oportunidad de comprender y experimentar el mar a su manera. Todo esto no hubiera sucedido sin el apoyo de nuestros socios, que creyeron con nosotros en este ambicioso proyecto\u201d<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<div id=\"attachment_48557\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48557\" class=\"size-full wp-image-48557\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/mambo1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/mambo1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/mambo1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/mambo1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-48557\" class=\"wp-caption-text\">Despu\u00e9s de la impresi\u00f3n, el barco se pint\u00f3 de azul.<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se utilizaron dos robots para imprimir la lancha. Cada secci\u00f3n individual fue laminada, integrando la resina de poli\u00e9ster con las fibras de vidrio, luego ensamblada con las otras. M\u00e1s tarde, el MAMBO se pint\u00f3 de azul para su presentaci\u00f3n en el Sal\u00f3n N\u00e1utico de G\u00e9nova. En cualquier caso, es un buen ejemplo de las posibilidades de la fabricaci\u00f3n aditiva en el sector mar\u00edtimo y esperamos que inspire a m\u00e1s de un fabricante de barcos. Puedes encontrar m\u00e1s informaci\u00f3n en el sitio web de Moi Composites, <a href=\"https:\/\/www.moi.am\/#home\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a>.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas del barco MAMBO impreso en 3D? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCo9ZtHB24te-z7AMWTL92MA\/featured\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS<\/a>.\u00a0Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-1163221337\"><div id=\"dnati-1151706152\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfRecuerdas este barco impreso en 3D que os presentamos en los pasillos de Formnext 2019? Fue dise\u00f1ado por Moi Composites en colaboraci\u00f3n con Autodesk, Catmarine, Micad y Owens Corning, y \u00a1finalmente se ha hecho a la mar! Llamado MAMBO (Barco&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":48555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,354,296],"tags":[],"class_list":["post-48551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-automocion","category-transportes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/48551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=48551"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/48551\/revisions"}],"predecessor-version":[{"id":48558,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/48551\/revisions\/48558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/48555"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=48551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=48551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=48551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}