{"id":44875,"date":"2020-08-28T00:02:49","date_gmt":"2020-08-27T22:02:49","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=44875"},"modified":"2023-08-28T09:33:12","modified_gmt":"2023-08-28T07:33:12","slug":"impresion-3d-a-microescala-170420202","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/impresion-3d-a-microescala-170420202\/","title":{"rendered":"\u00bfCu\u00e1l es el estado actual de la impresi\u00f3n 3D a microescala?"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La microfabricaci\u00f3n es el proceso de creaci\u00f3n de estructuras en miniatura a escalas microm\u00e9tricas. Hist\u00f3ricamente, la microfabricaci\u00f3n se utiliz\u00f3 por primera vez en la industria electr\u00f3nica para miniaturizar el tama\u00f1o de los dispositivos. De hecho, a lo largo de los a\u00f1os, los dispositivos electr\u00f3nicos se han vuelto m\u00e1s peque\u00f1os y elegantes. Los tama\u00f1os de los componentes que estaban en decenas de micr\u00f3metros se convirtieron en micr\u00f3metros de un solo d\u00edgito, y luego en cientos de nan\u00f3metros, y luego se redujeron a unas pocas decenas de nan\u00f3metros, donde se encuentran hoy. Como resultado, lo que sol\u00eda llamarse microfabricaci\u00f3n se renombr\u00f3 como nanofabricaci\u00f3n, aunque los principios rectores se han mantenido esencialmente igual. Para enfrentar el desaf\u00edo de reducir el tama\u00f1o de los componentes en la industria electr\u00f3nica, continuamente se desarrollan nuevas herramientas y t\u00e9cnicas. Una de estas t\u00e9cnicas es la impresi\u00f3n 3D a microescala. Entonces, \u00bfqu\u00e9 aplicaciones est\u00e1n habilitadas por la <a href=\"https:\/\/www.3dnatives.com\/es\/tecnologias-3d\/\">fabricaci\u00f3n aditiva<\/a> a microescala? Y, en general, \u00bfcu\u00e1les son los beneficios de esta tecnolog\u00eda?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En primer lugar, debemos tener en cuenta que en el mundo de la fabricaci\u00f3n aditiva, la industria electr\u00f3nica es una de las menos conocedoras de la tecnolog\u00eda. Si consideramos que el sector aeroespacial fue uno de los primeros sectores en adoptar y desarrollar la impresi\u00f3n 3D, la electr\u00f3nica es esencialmente lo contrario. Sin embargo, la fabricaci\u00f3n aditiva puede aportar beneficios y nuevas capacidades a este sector, al permitir un nuevo nivel de personalizaci\u00f3n para componentes de micro y nanoescala&#8230;<\/span><\/p>\n<div id=\"attachment_44881\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44881\" class=\"wp-image-44881 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_1-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-44881\" class=\"wp-caption-text\">Para enfrentar el desaf\u00edo de reducir el tama\u00f1o de los componentes en microelectr\u00f3nica, continuamente se desarrollan nuevas herramientas y t\u00e9cnicas. El principal impulsor de esta tecnolog\u00eda son los circuitos integrados, como este.<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">De hecho, la fabricaci\u00f3n aditiva a microescala se desarroll\u00f3 por primera vez para beneficiar a la industria electr\u00f3nica, pero actualmente la tecnolog\u00eda se est\u00e1 moviendo m\u00e1s all\u00e1 de este campo. Por ejemplo, la t\u00e9cnica podr\u00eda usarse para aplicaciones m\u00e9dicas, donde los componentes de tama\u00f1o nanom\u00e9trico podr\u00edan insertarse al cuerpo para curar enfermedades. En el siguiente apartado, analizamos m\u00faltiples \u00e1ngulos de la relaci\u00f3n entre la fabricaci\u00f3n aditiva y la fabricaci\u00f3n micro \/ nano para brindar una visi\u00f3n general del estado actual de esta tecnolog\u00eda y sus aplicaciones en los sectores electr\u00f3nicos y m\u00e1s all\u00e1.<\/span><\/p>\n<h3 style=\"text-align: justify;\">La tecnolog\u00eda detr\u00e1s de la impresi\u00f3n 3D a microescala<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En primer lugar, consideremos la tecnolog\u00eda principal detr\u00e1s de la impresi\u00f3n 3D a microescala, tambi\u00e9n conocida como microstereolitograf\u00eda. Esta se basa en un principio de fabricaci\u00f3n muy similar al de la <a href=\"https:\/\/www.3dnatives.com\/es\/impresion-3d-por-estereolitografia-les-explicamos-todo\/\">estereolitograf\u00eda<\/a> (SLA), la primera tecnolog\u00eda de impresi\u00f3n 3D patentada. Sin embargo, implementa mejoras de proceso que resultan en una resoluci\u00f3n mucho mejor (hasta un par de micr\u00f3metros). Se basa en la polimerizaci\u00f3n de un material fotosensible por luz ultravioleta.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En el segmento de la electr\u00f3nica, la tecnolog\u00eda debe ser capaz de crear estructuras conductoras y aislantes al mismo tiempo, lo cual es un gran desaf\u00edo. <a href=\"https:\/\/www.3dnatives.com\/es\/nano-dimension-290320172\/\">Nano Dimension<\/a>, uno de los principales fabricantes de componentes electr\u00f3nicos impresos en 3D, ha introducido una tecnolog\u00eda de impresi\u00f3n 3D basada en la inyecci\u00f3n de tinta que utiliza nanoenlaces. Tambi\u00e9n trabaja con fotopolimerizaci\u00f3n, mediante un cabezal de impresi\u00f3n que deposita nanopart\u00edculas diel\u00e9ctricas, nanopart\u00edculas conductoras y pol\u00edmeros en la placa de construcci\u00f3n, curandose con luz UV entre deposiciones sucesivas. Por otro lado, Optomec, otra empresa l\u00edder en electr\u00f3nica impresa en 3D, ha desarrollado la impresi\u00f3n 3D Aerosol Jet, que funciona mediante la deposici\u00f3n de un flujo reducido de tintas electr\u00f3nicas tan peque\u00f1as como 10 \u00b5m.<\/span><\/p>\n<div id=\"attachment_44882\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44882\" class=\"size-full wp-image-44882\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_2.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_2-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-44882\" class=\"wp-caption-text\">Hay una gran demanda de placas de circuito impreso (PCB) para ser m\u00e1s densas y complejas. El siguiente PCB es multicapa, lo que significa que contiene m\u00faltiples capas de trazas conductoras en lugar de contener solo 1 | Cr\u00e9ditos: Nano Dimension<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cuando se trata de <a href=\"https:\/\/www.3dnatives.com\/es\/descubriendo-los-metales-de-la-impresion-3d\/\">metales<\/a>, la microstereolitograf\u00eda ya no es el m\u00e9todo m\u00e1s adecuado. La microsinterizaci\u00f3n por l\u00e1ser es una tecnolog\u00eda similar a la <a href=\"https:\/\/www.3dnatives.com\/es\/sinterizado-selectivo-por-laser-les-explicamos-todo\/\">sinterizaci\u00f3n selectiva por l\u00e1ser<\/a> (SLS). Este sistema se ha desarrollado para crear microestructuras impresas en 3D en metal, y es utilizada por actores como <a href=\"https:\/\/www.3dnatives.com\/es\/3d-microprint-microescala-160120182\/\">3D MicroPrint<\/a>, con sede en Alemania. Exaddon, por otro lado, se basa en un proceso que podr\u00eda compararse con la <a href=\"https:\/\/www.3dnatives.com\/es\/guia-deposicion-de-energia-directa-100920192\/\">deposici\u00f3n de energ\u00eda directa<\/a>, al que denominan deposici\u00f3n electroqu\u00edmica. Una boquilla de micro tama\u00f1o deposita un l\u00edquido de iones met\u00e1licos, que se transforman mediante un proceso electrol\u00edtico (carga el\u00e9ctrica) en \u00e1tomos s\u00f3lidos.<\/span><\/p>\n<div id=\"attachment_44884\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44884\" class=\"wp-image-44884 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_4.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_4.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_4-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_4-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-44884\" class=\"wp-caption-text\">La fabricaci\u00f3n de bobinas con un di\u00e1metro inferior a 300 micr\u00f3metros es un desaf\u00edo complejo que apenas se aborda con m\u00e9todos convencionales. Estas bobinas de cobre han sido impresas en 3D por Exaddon en colaboraci\u00f3n con la Harvard Medical School | Cr\u00e9ditos: Exaddon<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En cuanto a la impresi\u00f3n 3D a nanoescala, la tecnolog\u00eda se llama litograf\u00eda multifot\u00f3n (MPL), m\u00e1s com\u00fanmente conocida como polimerizaci\u00f3n de dos fotones (2PP). Utiliza, como su nombre lo indica, la absorci\u00f3n de dos fotones de los l\u00e1seres de alta intensidad, como la luz infrarroja cercana (NIR). Estos l\u00e1seres de alta intensidad pueden crear resoluciones de hasta 50 nm (0.05 \u00b5m). Las partes son tan peque\u00f1as que en realidad tardan m\u00e1s en crearse de lo que uno podr\u00eda esperar. Es un proceso largo porque polimeriza varias \u00e1reas peque\u00f1as a la vez, y por esta raz\u00f3n es dif\u00edcil de ampliar. Para hacernos una idea, a simple vista podemos ver objetos tan peque\u00f1os como 0.1 mm, que ser\u00edan unos 100 micr\u00f3metros (\u00b5m). Por lo tanto, no podremos ver muchas de las estructuras que la polimerizaci\u00f3n de dos fotones (2PP) es capaz de crear.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">De hecho, los investigadores en m\u00faltiples universidades de todo el mundo est\u00e1n estudiando las capacidades de la tecnolog\u00eda 2PP. Recientemente, en la Universidad China de Hong Kong (CUHK), en colaboraci\u00f3n con el Laboratorio Nacional Lawrence Livermore, los investigadores han estado trabajando para mejorarla. Sourabh Saha, l\u00edder de este proyecto de investigaci\u00f3n, explica: <\/span><i><span style=\"font-weight: 400;\">\u201cTradicionalmente, hay compensaciones entre velocidad y resoluci\u00f3n. Si deseamos un proceso m\u00e1s r\u00e1pido, se perder\u00e1 resoluci\u00f3n. Hemos roto esta compensaci\u00f3n de ingenier\u00eda, lo que nos permite imprimir mil veces m\u00e1s r\u00e1pido con las caracter\u00edsticas m\u00e1s peque\u00f1as\u201d<\/span><\/i><span style=\"font-weight: 400;\">. Esencialmente, los investigadores est\u00e1n reemplazando el singular l\u00e1ser de alta intensidad con un campo de luz para acelerar el proceso.<\/span><\/p>\n<div id=\"attachment_44883\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44883\" class=\"size-full wp-image-44883\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_3.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_3.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_3-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_3-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-44883\" class=\"wp-caption-text\">Este castillo mide 230 \u00b5m x 250 \u00b5m x 360 \u00b5m, y ha sido impreso en 3D sobre un l\u00e1piz usando 2PP | Cr\u00e9ditos: TU Wien<\/p><\/div>\n<h3 style=\"text-align: justify;\">Las aplicaciones de la impresi\u00f3n 3D a microescala<\/h3>\n<h4 style=\"text-align: justify;\">Industria electr\u00f3nica<\/h4>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Como se mencion\u00f3, en el campo de la electr\u00f3nica, la impresi\u00f3n 3D a microescala puede mejorar el rendimiento, la funcionalidad y aumentar la miniaturizaci\u00f3n de los dispositivos. Para los ingenieros, uno de los desaf\u00edos de innovar en este campo a menudo es crear prototipos para probar la forma o la integraci\u00f3n de la electr\u00f3nica en el dise\u00f1os de productos. Mediante la creaci\u00f3n de prototipos internamente en lugar de la subcontrataci\u00f3n, los fabricantes pueden beneficiarse de plazos de entrega m\u00e1s cortos, flexibilidad de dise\u00f1o, personalizaci\u00f3n y una cadena de suministro simplificada. La impresi\u00f3n 3D a microescala se puede utilizar para crear nuevos dise\u00f1os para dispositivos electr\u00f3nicos integrados, electroimanes, MIDS (dispositivos de interconexi\u00f3n moldeados), antenas, sensores y PCB de m\u00faltiples capas (placas de circuito impreso).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El CEO de Nano Dimension, Amit Dror, explica que muchos sectores se beneficiar\u00e1n de esta tecnolog\u00eda m\u00e1s all\u00e1 de las aplicaciones de creaci\u00f3n de prototipos. Seg\u00fan \u00e9l: <\/span><i><span style=\"font-weight: 400;\">\u201choy en d\u00eda, la necesidad m\u00e1s fuerte de soluciones AME (electr\u00f3nica de fabricaci\u00f3n aditiva) proviene de las industrias aeroespacial y de defensa. Mirando hacia el horizonte, podemos esperar que la producci\u00f3n a escala industrial provenga de la industria automotriz y de los bienes de consumo electr\u00f3nicos\u201d<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<div id=\"attachment_44886\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44886\" class=\"size-full wp-image-44886\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_6.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_6.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_6-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_6-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-44886\" class=\"wp-caption-text\">El prototipo de PCB impreso en 3D de precisi\u00f3n de Nano Dimension producido en DragonFly Pro | Cr\u00e9ditos: Nano Dimension<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La electr\u00f3nica de impresi\u00f3n 3D tiene una alta probabilidad de seguir el mismo camino en adoptar la microfabricaci\u00f3n. A medida que esta tecnolog\u00eda madura y los nuevos jugadores ingresan al mercado, la impresi\u00f3n 3D de productos electr\u00f3nicos podr\u00eda eventualmente pasar de ser una herramienta de creaci\u00f3n de prototipos a un proceso de producci\u00f3n en masa. Optomec, la otra compa\u00f1\u00eda l\u00edder en este segmento de fabricaci\u00f3n aditiva, explica que su tecnolog\u00eda Aerosol Jet es capaz de imprimir en 3D 5,000 circuitos integrados de 25 a 50 \u00b5m por hora, y la producci\u00f3n se puede escalar hasta 10,000 por hora con la introducci\u00f3n de una boquilla adicional. En otras palabras, la compa\u00f1\u00eda ya promete que su tecnolog\u00eda es escalable para soportar la producci\u00f3n de grandes cantidades.<\/span><\/p>\n<h4 style=\"text-align: justify;\">Otras aplicaciones<\/h4>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Por supuesto, hay otros beneficios colaterales de poder imprimir estructuras tan peque\u00f1as. M\u00faltiples startups como <a href=\"https:\/\/www.3dnatives.com\/es\/nanofabrica-microimpresion-3d-26032019\/\">Nanofabrica<\/a>, Nanoscribe, Boston Micro Fabrication o MicroLight3D han desarrollado micro tecnolog\u00edas que pueden usarse para producir dispositivos m\u00e9dicos, como por ejemplo, <a href=\"https:\/\/www.3dnatives.com\/es\/microagujas-impresas-4d-inyecciones-160420202\/\">microagujas<\/a>. Para los profesionales de este sector, es prioritario minimizar la cantidad de da\u00f1o tisular colateral durante una operaci\u00f3n. Por lo tanto, miniaturizar dispositivos m\u00e9dicos es clave. Todav\u00eda en el sector m\u00e9dico, Nanoscribe explica que los usuarios pueden fabricar andamios 3D para estudiar el crecimiento celular, la migraci\u00f3n o la diferenciaci\u00f3n de c\u00e9lulas madre en estructuras biomim\u00e9ticas utilizando su tecnolog\u00eda 2PP. La startup tambi\u00e9n usa 2PP para una variedad de otras aplicaciones como refractiva, difractiva y micro \u00f3ptica.<\/span><\/p>\n<div id=\"attachment_44885\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44885\" class=\"size-full wp-image-44885\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_5.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_5.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_5-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FS_5-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-44885\" class=\"wp-caption-text\">Herramientas impresas en 3D que muestran precisi\u00f3n microm\u00e9trica utilizando impresi\u00f3n micro 3D en metal | Cr\u00e9ditos: Microfabrica<\/p><\/div>\n<h3 style=\"text-align: justify;\">\u00bfQu\u00e9 depara el futuro para este sector de impresi\u00f3n 3D?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En el futuro, las posibles aplicaciones incluir\u00e1n la producci\u00f3n de sensores port\u00e1tiles o integrados para el monitoreo de la salud en tiempo real. Adem\u00e1s, los sensores impresos en 3D podr\u00edan integrarse en lentes para permitir aplicaciones de realidad aumentada. Por otra parte, la electr\u00f3nica integrada impresa en 3D podr\u00eda verse en objetos desde tel\u00e9fonos inteligentes a autom\u00f3viles, agregando funcionalidad y haci\u00e9ndolos m\u00e1s ligeros. Las limitaciones actuales se refieren al software para desarrollar los modelos de una fabricaci\u00f3n tan peque\u00f1a, pero tambi\u00e9n para expandir los materiales disponibles para este proceso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Para concluir, es bastante evidente que la adopci\u00f3n m\u00e1s amplia de la impresi\u00f3n 3D a microescala enfrentar\u00e1 los mismos obst\u00e1culos que otras tecnolog\u00edas de fabricaci\u00f3n aditiva. John Kawola, CEO de Boston Micro Fabrication, afirma: <\/span><i><span style=\"font-weight: 400;\">\u201cNo creemos que los desaf\u00edos de una adopci\u00f3n m\u00e1s amplia de la impresi\u00f3n 3D a microescala sean diferentes de los desaf\u00edos de la impresi\u00f3n 3D en general. La fabricaci\u00f3n aditiva en todos los tama\u00f1os seguir\u00e1 siendo valiosa para la ingenier\u00eda y el dise\u00f1o de prototipos. La tecnolog\u00eda a microescala ofrece nuevas herramientas a los ingenieros que anteriormente no pod\u00edan crear prototipos de manera efectiva a ese tama\u00f1o. Adem\u00e1s, la producci\u00f3n de piezas de microescala suele ser bastante costosa, lo que aumenta el valor de considerar la impresi\u00f3n 3D para la producci\u00f3n de piezas de uso final\u201d<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la impresi\u00f3n 3D a microescala? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a>, <a href=\"https:\/\/www.youtube.com\/channel\/UCo9ZtHB24te-z7AMWTL92MA\/featured\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a> y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS<\/a>. Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra <a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal<\/a>.<\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-3279893239\"><div id=\"dnati-2986796146\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La microfabricaci\u00f3n es el proceso de creaci\u00f3n de estructuras en miniatura a escalas microm\u00e9tricas. Hist\u00f3ricamente, la microfabricaci\u00f3n se utiliz\u00f3 por primera vez en la industria electr\u00f3nica para miniaturizar el tama\u00f1o de los dispositivos. De hecho, a lo largo de los&hellip;<\/p>\n","protected":false},"author":6070,"featured_media":44880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,282],"tags":[],"class_list":["post-44875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-tecnologias-3d"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/44875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6070"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=44875"}],"version-history":[{"count":3,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/44875\/revisions"}],"predecessor-version":[{"id":44897,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/44875\/revisions\/44897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/44880"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=44875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=44875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=44875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}