{"id":41575,"date":"2019-11-21T00:03:11","date_gmt":"2019-11-20T23:03:11","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=41575"},"modified":"2019-11-19T09:51:58","modified_gmt":"2019-11-19T08:51:58","slug":"complementan-tecnologias-fff-y-sla-201120192","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/complementan-tecnologias-fff-y-sla-201120192\/","title":{"rendered":"\u00bfC\u00f3mo se complementan las tecnolog\u00edas FFF y SLA?"},"content":{"rendered":"<p style=\"text-align: justify;\">La mayor\u00eda de los usuarios de impresi\u00f3n 3D no creen que <strong>FFF y SLA puedan ser tecnolog\u00edas complementarias<\/strong>, pero cuando se usan en conjunto, pueden ser muy beneficiosas para cualquier tipo de proyecto. En el desarrollo de productos, la impresi\u00f3n 3D SLA es ideal para modelos conceptuales detallados o prototipos funcionales. En la fabricaci\u00f3n, ambas tecnolog\u00edas se pueden usar para crear plantillas, accesorios y otras herramientas. Generalmente se prefiere FFF para piezas m\u00e1s grandes y relativamente simples, mientras que SLA es m\u00e1s adecuada para componentes m\u00e1s complejos y herramientas de alta precisi\u00f3n. Para las empresas, comprender las diferencias entre estas dos tecnolog\u00edas en t\u00e9rminos de calidad de impresi\u00f3n, materiales, aplicaciones, flujo de trabajo, velocidad y costo es esencial para optimizar sus proyectos.<\/p>\n<h3>Diferencias entre FFF y SLA<\/h3>\n<p style=\"text-align: justify;\">Desde el punto de vista del p\u00fablico en general, la impresi\u00f3n 3D FFF sigue siendo la tecnolog\u00eda m\u00e1s utilizada. Como recordatorio, las <a href=\"https:\/\/www.3dnatives.com\/es\/modelado-por-deposicion-fundida29072015\/\">impresoras 3D FFF\/FDM funcionan extruyendo filamentos termopl\u00e1sticos<\/a> capa por capa en la plancha de impresi\u00f3n hasta la producci\u00f3n de la pieza. Por otro lado, la <a href=\"https:\/\/www.3dnatives.com\/es\/impresion-3d-por-estereolitografia-les-explicamos-todo\/\">estereolitograf\u00eda<\/a> se usa m\u00e1s ampliamente en los sectores profesionales. Utiliza un l\u00e1ser para polimerizar la resina en una parte de pl\u00e1stico duro, un proceso llamado fotopolimerizaci\u00f3n. Mientras que la FDM crea un enlace mec\u00e1nico entre las capas, SLA crea enlaces qu\u00edmicos mediante la reticulaci\u00f3n de fotopol\u00edmeros en cada capa. El resultado es una pieza totalmente densa y herm\u00e9tica, ideal para muchas aplicaciones de ingenier\u00eda y fabricaci\u00f3n donde las propiedades de los materiales son importantes. Las piezas SLA tambi\u00e9n ofrecen una alta resistencia lateral, lo que da como resultado piezas isotr\u00f3picas. En t\u00e9rminos de precisi\u00f3n y exactitud, la tecnolog\u00eda FFF todav\u00eda tiene que lidiar con la falta de detalles muy finos, especialmente para piezas complejas.<\/p>\n<div id=\"attachment_41580\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-41580\" class=\"size-full wp-image-41580\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Formlabs_1.jpg\" alt=\"FFF y SLA\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Formlabs_1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Formlabs_1-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Formlabs_1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-41580\" class=\"wp-caption-text\">Una pieza impresa con el FFF (izquierda) y una pieza impresa con el SLA (derecha). El nivel de detalle es mayor con SLA (Cr\u00e9ditos: Formlabs)<\/p><\/div>\n<p style=\"text-align: justify;\">Una vez que la pieza se imprime en 3D, el \u00faltimo paso del proceso de impresi\u00f3n en 3D es <a href=\"https:\/\/www.3dnatives.com\/es\/postratamiento-de-piezas-impresas-en-3d-210320192\/\">el posprocesamiento<\/a>. Las piezas SLA siempre deben enjuagarse con alcohol isoprop\u00edlico (IPA) u otro solvente para eliminar cualquier resina no polimerizada de su superficie. Algunos tambi\u00e9n requieren curado en caliente, lo que le da a la pieza una resistencia y estabilidad superiores. El proceso FFF no requiere limpieza. Adem\u00e1s, <strong>las piezas FFF y SLA pueden mecanizarse, imprimarse, pintarse y ensamblarse<\/strong> para aplicaciones o acabados espec\u00edficos.<\/p>\n<p style=\"text-align: justify;\">Desde el punto de vista de la inversi\u00f3n, es innegable que las <a href=\"https:\/\/www.3dnatives.com\/es\/top-10-impresoras-low-cost-27072016\/\">impresoras 3D FDM son m\u00e1s asequibles<\/a> que las impresoras SLA, las primeras pueden estar disponibles a partir cien euros. Esto es muy atractivo para los fabricantes, aficionados o peque\u00f1as empresas que pueden probar la tecnolog\u00eda a un precio m\u00e1s accesible. Por supuesto, hay impresoras profesionales FFF y los precios son mucho m\u00e1s altos, entre 2.000 y 8.000 euros, sin mencionar las m\u00e1quinas industriales m\u00e1s caras. Estas m\u00e1quinas profesionales compiten directamente con las impresoras 3D SLA, que cuestan alrededor de 3.000 euros. Por ejemplo, <a href=\"https:\/\/www.3dnatives.com\/es\/form-3-y-form-3l-formlabs-020420192\/\">Formlabs ofrece su Form 3L<\/a>, una gran impresora 3D SLA, a un precio asequible, por menos de 10.000 euros. Han surgido algunas impresoras 3D SLA igualmente accesibles, pero est\u00e1n limitadas por su peque\u00f1o volumen de impresi\u00f3n; esta es tambi\u00e9n una de las limitaciones de la estereolitograf\u00eda actual, aunque <strong>algunas m\u00e1quinas est\u00e1n comenzando a ofrecer vol\u00famenes m\u00e1s generosos<\/strong>, como la\u00a0 <a href=\"https:\/\/www.3dnatives.com\/es\/3D-compare\/imprimante\/form-3l\">Form 3L de Formlabs<\/a>, con sus 300 x 335 x 200 mm.<\/p>\n<div id=\"attachment_41579\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-41579\" class=\"size-full wp-image-41579\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FDMvsSLA_2.jpg\" alt=\"FFF y SLA\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FDMvsSLA_2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FDMvsSLA_2-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/FDMvsSLA_2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-41579\" class=\"wp-caption-text\">La Form 3L ofrece un gran volumen de impresi\u00f3n en 3D (Cr\u00e9ditos: Formlabs)<\/p><\/div>\n<h3>\u00bfC\u00f3mo aprovechar estas dos tecnolog\u00edas?<\/h3>\n<p style=\"text-align: justify;\">Las impresoras 3D FFF y SLA tienen caracter\u00edsticas similares y a menudo complementarias. Muchas compa\u00f1\u00edas invierten en ambas tecnolog\u00edas, lo que demuestra que no siempre est\u00e1n compitiendo, en contra de la creencia popular. La inversi\u00f3n en estas dos tecnolog\u00edas se debe a que puede beneficiarse de lo mejor de ambas: prototipos r\u00e1pidos de bajo costo combinados con componentes funcionales de alta calidad para una amplia gama de aplicaciones.<\/p>\n<p style=\"text-align: justify;\">Un ejemplo concreto es el proyecto <a href=\"https:\/\/www.3dnatives.com\/es\/third-thumb-protesis-todos-210720172\/\">Third Thumb<\/a>, creado por Dani Clode en colaboraci\u00f3n con The Plasticity Lab del Instituto de Neurociencia Cognitiva de la University College London (UCL). El proyecto consiste en una pr\u00f3tesis de pulgar controlada por el pie del usuario, cuyo objetivo es mejorar la facilidad de uso y el control de las pr\u00f3tesis. El pulgar est\u00e1 hecho de piezas impresas en SLA y FDM. Dani Clode explica: <em>\u00abEl pulgar en s\u00ed est\u00e1 hecho de poliuretano termopl\u00e1stico flexible, impreso en FDM, con un relleno bajo. Es dif\u00edcil trabajar con un material flexible FDM, pero es la mejor opci\u00f3n para el pulgar en este momento. Tambi\u00e9n lo hace ligero y fuerte. Los dedos se imprimieron en SLA en una impresora Formlabs, porque necesitaba un material flexible de alta resoluci\u00f3n que pudiera imprimirse finamente, tener una buena forma y adherirse bien. Me gusta el hecho de que se adhiere f\u00e1cilmente a otros materiales, a diferencia de la silicona. El SLA es el \u00fanico m\u00e9todo de impresi\u00f3n que puede manejar todas las conexiones internas complejas para controlar el pulgar. \u00ab<\/em><\/p>\n<div id=\"attachment_41578\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-41578\" class=\"size-full wp-image-41578\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DaniClode.jpg\" alt=\"SLA y FDM\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DaniClode.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DaniClode-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/DaniClode-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-41578\" class=\"wp-caption-text\">Dani Clode con el Third Thumb.<\/p><\/div>\n<p style=\"text-align: justify;\">Por lo tanto, puedes ampliar las posibilidades de la impresi\u00f3n 3D combinando varias tecnolog\u00edas, incluidos los beneficios de <a href=\"https:\/\/www.3dnatives.com\/es\/fdm-o-sla-impresion-3d-131220172\/\">FDM y SLA<\/a>. Si eres un usuario de tecnolog\u00edas de deposici\u00f3n fundida y deseas cambiar a estereolitograf\u00eda, no dudes en ponerse en contacto con Formlabs, experto en SLA durante varios a\u00f1os. Para obtener m\u00e1s informaci\u00f3n, <a href=\"https:\/\/formlabs.com\/eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">haz clic aqu\u00ed<\/a>.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la utilizaci\u00f3n en conjunto de las tecnolog\u00edas FFF y SLA? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>,<a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0Twitter<\/a>,\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCo9ZtHB24te-z7AMWTL92MA\/featured\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS.<\/a>\u00a0Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor\u00eda de los usuarios de impresi\u00f3n 3D no creen que FFF y SLA puedan ser tecnolog\u00edas complementarias, pero cuando se usan en conjunto, pueden ser muy beneficiosas para cualquier tipo de proyecto. En el desarrollo de productos, la impresi\u00f3n&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":41581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,282],"tags":[],"class_list":["post-41575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-tecnologias-3d"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/41575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=41575"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/41575\/revisions"}],"predecessor-version":[{"id":41582,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/41575\/revisions\/41582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/41581"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=41575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=41575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=41575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}