{"id":40480,"date":"2019-08-23T00:08:06","date_gmt":"2019-08-22T22:08:06","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=40480"},"modified":"2019-08-22T15:30:41","modified_gmt":"2019-08-22T13:30:41","slug":"zapatos-ecologicos-impresos-en-3d-230820192","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/zapatos-ecologicos-impresos-en-3d-230820192\/","title":{"rendered":"ORGANIC, la colecci\u00f3n de zapatos ecol\u00f3gicos impresos en 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">La colecci\u00f3n de zapatos ORGANIC es una colaboraci\u00f3n entre Lucie Trejtnarov\u00e1, estudiante de posgrado en la Universidad Tomas Bata en Zlin, Rep\u00fablica Checa; el fabricante de materiales, Fillamentum, y el estudio de dise\u00f1o, Malai Design &amp; Materials. Como su nombre lo indica, son zapatos ecol\u00f3gicos impresos en 3D: <strong>este calzado es reciclable y compostable.<\/strong><\/p>\n<p style=\"text-align: justify;\">La fabricaci\u00f3n aditiva se ha convertido en un muy buen compa\u00f1ero de los proyectos ecol\u00f3gicos, y ahora tambi\u00e9n de la moda y el dise\u00f1o. Recordamos proyectos como la nueva <a href=\"https:\/\/www.3dnatives.com\/es\/una-falda-impresa-en-3d-310520192\/\">falda impresa en 3D \u00abCero Desechos\u00bb<\/a> o las <a href=\"https:\/\/www.3dnatives.com\/es\/fick-zapatillas-impresas-3d-051220182\/\">zapatillas Fick, <\/a>creadas por un grupo de j\u00f3venes espa\u00f1oles. El proyecto ORGANIC, es otro ejemplo de c\u00f3mo la impresi\u00f3n 3D abre el camino para el desarrollo de <a href=\"https:\/\/www.3dnatives.com\/es\/top-10-de-iniciativas-que-combinan-la-impresion-3d-y-la-ecologia-19012016\/\">proyectos sostenibles<\/a>.<\/p>\n<h3>Desarrollo de los zapatos ecol\u00f3gicos<\/h3>\n<p style=\"text-align: justify;\">En primer lugar, las sandalias muestran una suela exterior impresa en 3D, hecha de Flexfill 98A basado en TPU e impresa en una impresora 3D Ultimaker 3. El <a href=\"https:\/\/www.3dnatives.com\/es\/plasticos-impresion-3d-22072015\/\">pl\u00e1stico de impresi\u00f3n 3D<\/a> Flexfill 98A de Fillamentum ofrece una gran capacidad de procesamiento y propiedades mec\u00e1nicas muy espec\u00edficas. El fabricante de filamentos ofrece dos grados de Flexfill, el 98A y el 92A. En el caso de este proyecto, se eligi\u00f3 el 98A porque es m\u00e1s resistente y es el m\u00e1s apropiado para el calzado. Esta <strong>suela impresa en 3D es completamente reciclable<\/strong> gracias a sus propiedades de procesabilidad. Algo que Lucie Trejtnarov\u00e1 buscaba a la hora de elegir el material de impresi\u00f3n.<\/p><div class=\"dnati-inside_content dnati-entity-placement\" id=\"dnati-1255267869\"><div id=\"dnati-1552274844\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"NPE2027_Feathr Ads_850x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_40482\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-40482\" class=\"size-full wp-image-40482\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_1.jpg\" alt=\"zapatos impresos en 3D\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_1-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-40482\" class=\"wp-caption-text\">El proceso detr\u00e1s del dise\u00f1o y la impresi\u00f3n 3D del zapato | Cr\u00e9ditos: Lucie Trejtnarov\u00e1<\/p><\/div>\n<p style=\"text-align: justify;\">La parte superior est\u00e1 hecha de Malai (tambi\u00e9n conocido como cuero de coco) y Pi\u00f1atrex, hecho de hojas de pi\u00f1a. El cuero de coco, al igual que el cuero real, es flexible, duradero y resistente al agua. <strong>El Malai se produce a partir de celulosa bacteriana totalmente org\u00e1nica y sostenible<\/strong>, cultivado a partir de residuos procedentes de la industria del coco en el sur de la India.<\/p>\n<p style=\"text-align: justify;\">Lucie Trejtnarov\u00e1 explic\u00f3: \u201cSomos responsables de cada uno de nuestros pasos. Los zapatos ecol\u00f3gicos de la colecci\u00f3n ORGANIC se basan en un principio simple: al final de su vida, puede dividirse en varias partes, la parte superior en algo compostable y la suela en algo reciclable para volver a usarla \u00ab.<\/p>\n<div id=\"attachment_40483\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-40483\" class=\"size-full wp-image-40483\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_2.jpg\" alt=\"zapatos ecol\u00f3gicos\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_2-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/3Dprintedshoe_2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-40483\" class=\"wp-caption-text\">La suela impresa en 3D con material Flexfill 98A | Cr\u00e9ditos: Silvia Leitmannova<\/p><\/div>\n<p style=\"text-align: justify;\">Lucie Trejtnarov\u00e1 tambi\u00e9n explic\u00f3 que el concepto de ORGANIC comenz\u00f3 cuando estaba haciendo su tesis sobre \u00abExtravagancia 3D\u00bb en la Universidad Tomas Bata. \u00abPrimero me puse en contacto con la creaci\u00f3n de modelos 3D y el uso de impresoras 3D en la Universidad, [lo cual] fue un desaf\u00edo completamente nuevo para m\u00ed\u00bb. Para aprender el modelado 3D, \u00abContinu\u00e9 en la Academia de Artes y Dise\u00f1o de Bezalel en Jerusal\u00e9n con un curso de SOLIDWORKS\u00bb, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">Para comprender c\u00f3mo se hizo realidad esta colecci\u00f3n, puedes ver el siguiente video:<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/RVsHw67OMnw\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de la creaci\u00f3n de zapatos ecol\u00f3gicos con impresi\u00f3n 3D? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>,<a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0Twitter<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS.<\/a>\u00a0Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal.<\/a><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-1991035130\"><div id=\"dnati-3430431422\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La colecci\u00f3n de zapatos ORGANIC es una colaboraci\u00f3n entre Lucie Trejtnarov\u00e1, estudiante de posgrado en la Universidad Tomas Bata en Zlin, Rep\u00fablica Checa; el fabricante de materiales, Fillamentum, y el estudio de dise\u00f1o, Malai Design &amp; Materials. Como su nombre&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":40484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,132],"tags":[],"class_list":["post-40480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-diseno"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/40480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=40480"}],"version-history":[{"count":1,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/40480\/revisions"}],"predecessor-version":[{"id":40485,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/40480\/revisions\/40485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/40484"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=40480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=40480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=40480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}