{"id":39848,"date":"2019-07-02T00:07:28","date_gmt":"2019-07-01T22:07:28","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=39848"},"modified":"2019-07-01T12:12:02","modified_gmt":"2019-07-01T10:12:02","slug":"impresion-3d-caida-del-cabello-020720192","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/impresion-3d-caida-del-cabello-020720192\/","title":{"rendered":"La impresi\u00f3n 3D para evitar la ca\u00edda del cabello"},"content":{"rendered":"<p style=\"text-align: justify;\">En la Universidad de Columbia en los Estados Unidos, un equipo de investigadores utiliz\u00f3 la impresi\u00f3n 3D combatir la ca\u00edda del cabello. La <a href=\"https:\/\/www.3dnatives.com\/es\/tecnologias-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">tecnolog\u00eda de fabricaci\u00f3n aditiva<\/a> les permiti\u00f3 crear f\u00e1cilmente moldes\/bases de pl\u00e1stico que posteriormente fueron utilizados para hacer crecer los fol\u00edculos pilosos. Una innovaci\u00f3n importante para el sector m\u00e9dico. Ya que hasta ahora es muy complicado conseguir con \u00e9xito el crecimiento de cabello en condiciones de laboratorio.<\/p>\n<p style=\"text-align: justify;\">En 2016 se comenz\u00f3 a hablar de proyectos relacionados con la <a href=\"https:\/\/www.3dnatives.com\/es\/por-que-la-impresion-3d-230720182\/\">impresi\u00f3n 3D<\/a> y el cabello. Recordamos la asociaci\u00f3n entre el grupo franc\u00e9s Poietis y el grupo L&#8217;Or\u00e9al, que comenz\u00f3 la investigaci\u00f3n para <a href=\"https:\/\/www.3dnatives.com\/es\/loreal-biompresion-de-cabello-29092016\/\">bioimprimir cabello<\/a> y ofrecer una soluci\u00f3n para todos aquellos que sufran de alopecia. La meta de este nuevo estudio es similiar, paliar la ca\u00edda del cabello, sin embargo, con un enfoque ligeramente diferente, ya que no imprimen c\u00e9lulas, sino simplemente los moldes que facilitar\u00e1n y fomentar\u00e1n el crecimiento de los fol\u00edculos pilosos.<\/p>\n<div id=\"attachment_39850\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39850\" class=\"size-full wp-image-39850\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux.jpg\" alt=\"impresi\u00f3n 3D Ca\u00edda del cabello\" width=\"700\" height=\"500\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux-300x214.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux-160x114.jpg 160w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux-100x70.jpg 100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-39850\" class=\"wp-caption-text\">Secci\u00f3n transversal de un fol\u00edculo piloso (cr\u00e9ditos: Angela Christiano \/ Columbia Irving Medical Center)<\/p><\/div>\n<h3>Desarrollo de moldes 3D para evitar la ca\u00edda del cabello<\/h3>\n<p style=\"text-align: justify;\">Varios investiadores incluidos los de la Universidad de Columbia, han descubierto que las c\u00e9lulas del ser humano tomadas de la base del cuero cabelludo no crecen al ser cultivadas en laboratorio. Algo que no ocurre con el pelo animal como el de los ratones, estos por el encontrario al crecer en condiciones de laboratorio se hacen demasiado resistendes limitanto su injerci\u00f3n. Para solucionar el problema al que se enfrentan m\u00e9dicos y cient\u00edficos desarrollaron este molde de pl\u00e1stico que sirve como base destinado a reproduci\u00f3n un entorno micro-natural que tiene todos los elementos para estimular el crecimiento del fol\u00edculo piloso. Cuenta con peque\u00f1as fol\u00edculos pl\u00e1sticos de medio milimetro de ancho en donde son cultivan las c\u00e9lulas.\u00bbLas t\u00e9cnicas de fabricaci\u00f3n tradicionales no pudieron crear tales estructuras finas. Por lo tanto, este trabajo se ha facilitado enormemente con las innovaciones de la tecnolog\u00eda de impresi\u00f3n 3D \u00ab, dijo Angela Christiano, autora del estudio.<\/p>\n<p style=\"text-align: justify;\">El equipo de investigadores explic\u00f3 que ha colocado c\u00e9lulas de los fol\u00edculos pilosos alrededor de estos conductores pl\u00e1sticos, y luego sobre las c\u00e9lulas que producen queratina, la prote\u00edna a partir de la cual se forma el cabello. Despu\u00e9s de un per\u00edodo de cultivo de tres semanas, el cabello comienza a crecer. Los moldes se imprimieron en 3D en una <a href=\"https:\/\/www.3dnatives.com\/es\/modelado-por-deposicion-fundida29072015\/\">impresora 3D de escritorio FDM<\/a>, concretamente la Sindoh 3DWOX.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_39852\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39852\" class=\"size-full wp-image-39852\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux2.jpg\" alt=\"pelo 3D\" width=\"700\" height=\"450\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux2-300x193.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/cheveux2-160x103.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-39852\" class=\"wp-caption-text\">Angela Christiano lidera la investigaci\u00f3n.<\/p><\/div>\n<h3>Desarrollo de una granja capilar con impresi\u00f3n 3D<\/h3>\n<p style=\"text-align: justify;\">\u00abPodemos crear una especie de granja capilar, es decir, una red de cabello adecuadamente dise\u00f1ada y modelada para que pueda ser trasplantada en el cuero cabelludo del mismo paciente. La restauraci\u00f3n capilar se vuelve mucho m\u00e1s accesible para todos los pacientes, hombres o mujeres. Ya no estaremos limitados por la cantidad de donantes de cabello; en general, se necesitan unos 2000 fol\u00edculos sanos para que el trasplante tenga \u00e9xito \u00abmencion\u00f3Angela Christiano. La industria farmac\u00e9utica tambi\u00e9n podr\u00eda utilizar los fol\u00edculos artificiales para desarrollar nuevos medicamentos para evitar la ca\u00edda del cabello. Puedes encontrar m\u00e1s informaci\u00f3n sobre el estudio en la web oficial <a href=\"https:\/\/www.cuimc.columbia.edu\/news\/studies-uncover-new-approaches-combat-hair-loss-men-and-women\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/B39H6R1ZjMo\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas del proyecto para evitar la ca\u00edda del cabello? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>,<a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0Twitter<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS.<\/a>\u00a0Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal.<\/a><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-873604510\"><div id=\"dnati-1213683373\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>En la Universidad de Columbia en los Estados Unidos, un equipo de investigadores utiliz\u00f3 la impresi\u00f3n 3D combatir la ca\u00edda del cabello. La tecnolog\u00eda de fabricaci\u00f3n aditiva les permiti\u00f3 crear f\u00e1cilmente moldes\/bases de pl\u00e1stico que posteriormente fueron utilizados para hacer&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":39851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,13],"tags":[],"class_list":["post-39848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-investigacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/39848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=39848"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/39848\/revisions"}],"predecessor-version":[{"id":39854,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/39848\/revisions\/39854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/39851"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=39848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=39848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=39848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}