{"id":39833,"date":"2019-07-01T00:04:16","date_gmt":"2019-06-30T22:04:16","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=39833"},"modified":"2019-07-01T10:51:20","modified_gmt":"2019-07-01T08:51:20","slug":"rostros-fabricacion-aditiva-gil-lavi-010720192","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/rostros-fabricacion-aditiva-gil-lavi-010720192\/","title":{"rendered":"Los rostros de la fabricaci\u00f3n aditiva: Gil Lavi, un pionero en la industria 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">Despu\u00e9s de <a href=\"https:\/\/www.3dnatives.com\/es\/rostros-am-avi-reichental-200320192\/\">Avi Reichenta<\/a>l y <a href=\"https:\/\/www.3dnatives.com\/es\/rostros-fabricacion-aditiva-hanan-gothait-130520192\/\">Hanan Gothait<\/a>, continuamos con nuestros encuentros con grandes personalidades de la fabricaci\u00f3n aditiva, este mes ha sido Gil Lavi, un pionero en la industria, como uno de nuestros Rostros de la Fabricaci\u00f3n Aditiva. Gil tiene una larga carrera en la industria comenz\u00f3 en la d\u00e9cada de 2000 dentro del fabricante Objet (ahora Stratasys), ha pasado por grandes nombres de la industria como Makerbot, Roboze o BigRep, antes de embarcarse en su propia aventura empresarial. \u00bfC\u00f3mo ha experimentado Gil Lavi los r\u00e1pidos cambios en el mercado en los \u00faltimos a\u00f1os? \u00bfCu\u00e1les son las oportunidades y los desaf\u00edos que a\u00fan existen en el mercado? 3Dnatives se ha encontrado con \u00e9l para tener las respuestas.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-39837 alignleft\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi3.jpg\" alt=\"Gil Lavi\" width=\"211\" height=\"191\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi3.jpg 500w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi3-300x272.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi3-160x145.jpg 160w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/h3>\n<h3>3DN: Has recorrido un largo camino en la industria de fabricaci\u00f3n aditiva, \u00bfpodr\u00edas contarle a nuestros lectores tus experiencias anteriores?<\/h3>\n<p style=\"text-align: justify;\">Me un\u00ed a la industria hace 13 a\u00f1os cuando empec\u00e9 en Objet Geometries cuando era una empresa \u00fanica en el panorama de la industria. En ese momento, no hab\u00eda m\u00e1s de una docena de empresas de impresi\u00f3n 3D en la industria, por lo que fue un momento de creer en en el futuro. Pas\u00e9 10 a\u00f1os en la empresa, incluidos tres a\u00f1os despu\u00e9s de la fusi\u00f3n con Stratasys, la creaci\u00f3n y gesti\u00f3n de los socios de ventas de la empresa en Europa y, posteriormente, las cuentas estrat\u00e9gicas de la empresa en EMEA. En 2015, dej\u00e9 la compa\u00f1\u00eda en busca de empresas innovadoras que los ayudaran a construir su estrategia de lanzamiento al mercado y desplegar sus redes de canales globales.<\/p>\n<h3 style=\"text-align: justify;\">3DN: \u00bfQu\u00e9 nos puedes contar de tu trabajo actual en la industria de la aabricai\u00f3n aditiva?<\/h3>\n<p style=\"text-align: justify;\">A lo largo de los a\u00f1os, conoc\u00ed a muchos distribuidores en la impresi\u00f3n 3D que buscaban productos prometedores para vender, pero ten\u00edan recursos limitados para filtrar y elegir los productos correctos. Por otro lado, conoc\u00ed a docenas de compa\u00f1\u00edas de inicio de impresi\u00f3n 3D que buscaban construir sus redes globales, pero carec\u00edan de la experiencia y el alcance de los socios de ventas profesionales.<\/p>\n<p style=\"text-align: justify;\">As\u00ed que en Formnext 2018, fund\u00e9 3D Alliances, que es una compa\u00f1\u00eda de consultor\u00eda que llena este vac\u00edo exacto. Formamos alianzas comerciales con las principales compa\u00f1\u00edas de impresi\u00f3n 3D de hardware y software para ayudarles a implementar y administrar su red de canales global. A partir de hoy, hay tres compa\u00f1\u00edas \u00fanicas en nuestro portafolio: <a href=\"https:\/\/www.3dnatives.com\/es\/xjet-impresora-3d-metal-02112016\/\">XJET3D<\/a> de Israel con su incre\u00edble tecnolog\u00eda NanoParticle Jetting \u2122 de metal y cer\u00e1mica; Essentium3D de Texas, EE.UU., el desarrollador de las plataformas de extrusi\u00f3n m\u00e1s r\u00e1pidas del mundo, y ParaMatters de California, EE. UU., que forma parte de XponentialWorks Innovation Lab, el desarrollador de uno de los programas de optimizaci\u00f3n de topol\u00f3gica m\u00e1s potentes de la industria. Todas son compa\u00f1\u00edas prometedoras y bien financiadas que ofrecen soluciones \u00fanicas. Esperamos poder firmar nuevos acuerdos de alianzas comerciales en los pr\u00f3ximos meses.<\/p>\n<div id=\"attachment_39836\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39836\" class=\"size-full wp-image-39836\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi2.jpg\" alt=\"Essentium\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi2-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-39836\" class=\"wp-caption-text\">Gil Lavi con el equipo de Essentium<\/p><\/div>\n<p style=\"text-align: justify;\">A partir de hoy, hemos logrado construir una red de m\u00e1s de 1,200 distribuidores activos de impresi\u00f3n 3D\/Fabricaci\u00f3n Aditiva en 72 pa\u00edses, que de hecho es el m\u00e1s grande en la industria. Utilizamos esta red para encontrar y reclutar a los socios de ventas adecuados para cada compa\u00f1\u00eda con la que trabajamos.<br \/>\nAdem\u00e1s de esta actividad, recientemente lanzamos un nuevo servicio para <a href=\"https:\/\/www.3dnatives.com\/es\/directorio-impresion-3d\/categories\/revendedores-de-impresoras-3d-industriales\">distribuidores de impresi\u00f3n 3D<\/a>: informes generales sobre empresas emergentes interesantes en la industria. Estos informes incluyen informaci\u00f3n que ayuda a los distribuidores a conocer nuevas empresas y evaluar sus productos.<\/p>\n<h3>3DN: \u00bfC\u00f3mo ha cambiado la industria desde que Gil Lavi dio su primer paso en la industria 3D?<\/h3>\n<p>Hubo muchos cambios en los \u00faltimos 13 a\u00f1os, pero creo que los m\u00e1s significativos fueron los siguientes tres:<\/p>\n<ol>\n<li style=\"text-align: justify;\">La cantidad de empresas de impresi\u00f3n 3D creci\u00f3 significativamente debido a la caducidad de las patentes, las nuevas inversiones y la llegada de una nueva generaci\u00f3n de empresarios.<\/li>\n<li style=\"text-align: justify;\">La nueva visi\u00f3n de la industria se basa en la idea de implementar <a href=\"https:\/\/www.3dnatives.com\/es\/tecnologias-3d\/\">tecnolog\u00edas de impresi\u00f3n 3D<\/a> en la fabricaci\u00f3n en lugar de solo en crear prototipos.<\/li>\n<li style=\"text-align: justify;\">Uno de los cambios m\u00e1s importantes: la impresi\u00f3n 3D ha sido reconocida como una revoluci\u00f3n en el camino. Se van a hacer las cosas. Es por esto que vemos una variedad de industrias que desarrollan soluciones innovadoras para imprimir\/fabricar alimentos, partes del cuerpo, casas, tableros de circuitos, muebles, art\u00edculos de moda y m\u00e1s. No tengo dudas de que veremos en los pr\u00f3ximos a\u00f1os la aceleraci\u00f3n de m\u00e1s desarrollos especiales.<\/li>\n<\/ol>\n<div id=\"attachment_39838\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39838\" class=\"size-full wp-image-39838\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi4.jpg\" alt=\"Paramatters\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi4.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi4-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/interview_gillavi4-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-39838\" class=\"wp-caption-text\">Gil Lavi trabaja con ParaMatters, una soluci\u00f3n software 3D con sede en EE.UU.<\/p><\/div>\n<h3>3DN: \u00bfQu\u00e9 novedades o empresa de la industria dela fabricaci\u00f3n aditiva han llamado tu atenci\u00f3n en los \u00faltimos meses?<\/h3>\n<p style=\"text-align: justify;\">Lo que me llam\u00f3 la atenci\u00f3n no es una compa\u00f1\u00eda o tecnolog\u00eda espec\u00edfica, sino m\u00e1s bien la comprensi\u00f3n de qu\u00e9 deber\u00eda hacer la sinergia entre la variedad de hardware industrial y las soluciones de software, y por qu\u00e9 es importante adaptarlas juntas en un solo ecosistema en el futuro. El segundo es el resultado, es decir, los diferentes tipos de tecnolog\u00edas de impresi\u00f3n 3D que rompen las barreras de velocidad, variedad de materiales y resistencia. El \u00faltimo es el procesamiento posterior, que ser\u00e1 m\u00e1s importante en el futuro.<br \/>\nSi lo mira desde el lado de los usuarios industriales pesados, podr\u00e1n trabajar en una soluci\u00f3n completa de extremo a extremo.<\/p>\n<div id=\"attachment_39839\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39839\" class=\"size-full wp-image-39839\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/xjet-2.jpg\" alt=\"Gil Lavi\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/xjet-2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/xjet-2-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/xjet-2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-39839\" class=\"wp-caption-text\">3D Alliances trabaja con el fabricante israel\u00ed XJet<\/p><\/div>\n<h3>3DN: \u00bfCu\u00e1les cree que son los desaf\u00edos pendientes para la adopci\u00f3n global de la fabricaci\u00f3n aditiva en toda la industria?<\/h3>\n<p style=\"text-align: justify;\">En este momento, parece que hay muchas tecnolog\u00edas\/soluciones de impresi\u00f3n 3D en la industria que tienen el potencial de revolucionar la forma en que se hacen las cosas. Sin embargo, en muchos casos, todav\u00eda hay brechas entre lo que pueden hacer las tecnolog\u00edas, para implementarlas verdaderamente en el proceso de fabricaci\u00f3n est\u00e1ndar completo.<br \/>\nAdem\u00e1s de las brechas de rendimiento que incluyen la velocidad, la resistencia y la variedad de materiales, creo que uno de los principales desaf\u00edos ser\u00e1 la automatizaci\u00f3n. Para revolucionar verdaderamente la fabricaci\u00f3n, necesitar\u00e1 soluciones autom\u00e1ticas y suaves con una intervenci\u00f3n m\u00ednima en el trabajo, desde el dise\u00f1o hasta la impresi\u00f3n y el procesamiento posterior, cuando el resultado final es una parte final de uso final. Aunque puedes encontrar grandes soluciones en la industria hoy en d\u00eda, la mayor\u00eda de ellas todav\u00eda est\u00e1n separadas una de la otra. Adaptarlos a un solo ecosistema ser\u00e1 la clave para aumentar la adopci\u00f3n en muchas industrias.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas del encuentro con Gil Lavi? Deja tus comentarios en nuestras redes sociales: <a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>,<a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0Twitter<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener noreferrer\">RSS.<\/a>\u00a0Sigue toda la informaci\u00f3n sobre impresi\u00f3n 3D en nuestra\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/newsletter-impresion-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter semanal.<\/a><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-1259184855\"><div id=\"dnati-674760681\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de Avi Reichental y Hanan Gothait, continuamos con nuestros encuentros con grandes personalidades de la fabricaci\u00f3n aditiva, este mes ha sido Gil Lavi, un pionero en la industria, como uno de nuestros Rostros de la Fabricaci\u00f3n Aditiva. Gil tiene&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":39847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,10],"tags":[],"class_list":["post-39833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-entrevistas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/39833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=39833"}],"version-history":[{"count":1,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/39833\/revisions"}],"predecessor-version":[{"id":39840,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/39833\/revisions\/39840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/39847"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=39833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=39833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=39833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}