{"id":36587,"date":"2018-10-29T00:05:56","date_gmt":"2018-10-28T23:05:56","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=36587"},"modified":"2018-10-26T11:52:14","modified_gmt":"2018-10-26T09:52:14","slug":"solidez-aluminio-impreso-en-3d-291020182","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/solidez-aluminio-impreso-en-3d-291020182\/","title":{"rendered":"Consiguen duplicar la solidez del aluminio impreso en 3D"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La<a href=\"https:\/\/www.3dnatives.com\/es\/guia-impresion-3d-metal\/\" target=\"_blank\" rel=\"noopener\"> impresi\u00f3n 3D de metal<\/a> ha crecido exponencialmente en los \u00faltimos meses. De acuerdo al informe Wohlers 2018, tan solo <a href=\"https:\/\/www.3dnatives.com\/es\/informe-wohlers-2018-020420182\/\" target=\"_blank\" rel=\"noopener\">en 2017 creci\u00f3 un 80%<\/a>, y se espera que esto siga en aumento. En los \u00faltimos a\u00f1os han crecido las investigaciones sobre tecnolog\u00edas y materiales, que fomentan a\u00fan m\u00e1s su crecimiento. Uno de los \u00faltimos desarrollos fue hecho por la Universidad Nacional de Ciencia y Tecnolog\u00eda (NUST MISIS), en Rusia, que present\u00f3 su desarrollo para duplicar la solidez del aluminio impreso en 3D. Gracias a esto ser\u00eda posible <strong>obtener un componente con una resistencia cercana a la del titanio<\/strong>, algo muy apreciado dentro la industria aeron\u00e1utica por su relaci\u00f3n peso\/resistencia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Una grandes innovaciones que han llegado con las tecnolog\u00edas de fabricaci\u00f3n aditiva es la capacidad de optimizar piezas con geometr\u00edas m\u00e1s complejas, reduciendo peso y costes. Dentro de las industrias automotriz, aeroespacial y m\u00e9dica el ahorro en peso y material es primordial, sobretodo hablando de metales como el titanio, el aluminio y el acero. Por su parte, el aluminio es un metal mucho m\u00e1s ligero que es f\u00e1cilmente moldeable, sin embargo no es lo suficientemente resistente. En la mayor\u00eda de las aplicaciones se prefiere el titanio por tener una resistencia 6 veces mayor. Por ello los investigadores rusos han trabajado con un aluminio de alta pureza para aumentar su resistencia y proponer un nuevo m\u00e9todo de producci\u00f3n de polvo.<\/span><\/p>\n<div id=\"attachment_36593\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36593\" class=\"size-full wp-image-36593\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_Aluminium1.jpg\" alt=\"aluminio impreso en 3D\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_Aluminium1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_Aluminium1-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_Aluminium1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-36593\" class=\"wp-caption-text\">Piezas de aluminio impreso en 3D<\/p><\/div>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Aluminio impreso en 3D, una fabricaci\u00f3n m\u00e1s sencilla <\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Para el desarrollo del aluminio impreso en 3D con de mayor resistencia, <strong>se utilizan gr\u00e1nulos de aluminio con una pureza de 99.7%<\/strong>. Gracias a la oxidaci\u00f3n, el tratamiento alcalino y \u00e1cido y calcinaci\u00f3n t\u00e9rmica a 1450 \u00b0 C, los gr\u00e1nulos se convierten en hidr\u00f3xido de aluminio. En cada etapa del proceso, los investigadores verifican las impurezas del \u00f3xido, especialmente las de hierro y potasio, que han demostrado ser las m\u00e1s problem\u00e1ticas. Con estos datos, el equipo modifica los tratamientos qu\u00edmicos, el lavado y la calcinaci\u00f3n, dando un UHPA con una pureza de 99.99% y 99.999%.<\/span><\/p>\n<div id=\"attachment_36591\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36591\" class=\"size-full wp-image-36591\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium1.jpg\" alt=\"aluminio impreso en 3D\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium1-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-36591\" class=\"wp-caption-text\">El aluminio se quema durante la etapa de purificaci\u00f3n del polvo(cr\u00e9ditos: NUST MISIS)<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Aunque a\u00fan no se han determinado las condiciones \u00f3ptimas de procesamiento del polvo, el equipo de NUST MISiS explica que ya est\u00e1 utilizando este material para desarrollar prototipos de aluminio impreso en 3D utilizando la <a href=\"https:\/\/www.3dnatives.com\/es\/sinterizado-directo-de-metal-por-laser-les-explicamos-todo\/\" target=\"_blank\" rel=\"noopener\">sinterizaci\u00f3n selectiva por l\u00e1ser<\/a>. Obteniendo exitosamente partes con un tercio de la resistencia del titanio. El profesor Alexander Gromov afirma: \u00ab<strong>Hemos desarrollado una tecnolog\u00eda para reforzar los materiales compuestos<\/strong> de matriz de aluminio impresos en 3D. Hemos obtenido modificadores innovadores al quemar polvos de aluminio. Las propiedades especiales y la estructura de la superficie permiten que las part\u00edculas se adhieran firmemente a la matriz de aluminio. Por lo tanto, dupliquen la resistencia de los compuestos resultantes \u00ab.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Una de las principales ventajas de este m\u00e9todo de producci\u00f3n de polvo UHPA es su bajo costo, que permite mantener una alta rentabilidad durante la aplicaci\u00f3n del material. Puedes encontrar toda la investigaci\u00f3n <a href=\"http:\/\/en.misis.ru\/university\/news\/science\/2018-10\/5609\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/span><\/p>\n<div id=\"attachment_36592\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36592\" class=\"size-full wp-image-36592\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium2.jpg\" alt=\"aluminio impreso en 3D\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium2-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/aluminium2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-36592\" class=\"wp-caption-text\">Alguna piezas impresas en 3D con el polvo UHPA (cr\u00e9ditos: NUST MISIS)<\/p><\/div>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de los nuevos desarrollos del aluminio impreso en 3D? Danos tu opini\u00f3n en nuestros canales de<strong>\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativeses?fref=nf\">Facebook<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/twitter.com\/3Dnatives_ES\">Twitter<\/a><\/strong>\u00a0y\u00a0<strong><a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\">RSS<\/a>.<\/strong><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-1597377528\"><div id=\"dnati-3708245496\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La impresi\u00f3n 3D de metal ha crecido exponencialmente en los \u00faltimos meses. De acuerdo al informe Wohlers 2018, tan solo en 2017 creci\u00f3 un 80%, y se espera que esto siga en aumento. En los \u00faltimos a\u00f1os han crecido las&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":36590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,13],"tags":[],"class_list":["post-36587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-investigacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/36587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=36587"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/36587\/revisions"}],"predecessor-version":[{"id":36595,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/36587\/revisions\/36595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/36590"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=36587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=36587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=36587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}