{"id":35453,"date":"2018-08-12T00:05:38","date_gmt":"2018-08-11T22:05:38","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=35453"},"modified":"2018-08-10T11:53:35","modified_gmt":"2018-08-10T09:53:35","slug":"videos-nasa-y-la-impresion-3d-120820182","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/videos-nasa-y-la-impresion-3d-120820182\/","title":{"rendered":"V\u00eddeos 3D: NASA y la impresi\u00f3n 3D para la conquista del espacio&#8230;."},"content":{"rendered":"<p style=\"text-align: justify;\">A pesar de estos d\u00edas de calor las novedades sobre impresi\u00f3n 3D no han parado. Esta semana te presentamos diferentes novedades que no hemos podido incluir en nuestros art\u00edculos diarios. No te pierdas las desarrollos de la NASA y la impresi\u00f3n 3D para desarrollar habitats en el espacio, la recuperaci\u00f3n de una pagado china o lo usos militares de las tecnolog\u00edas de fabricaci\u00f3n aditiva.<\/p>\n<p style=\"text-align: justify;\"><strong>TOP 1 &#8211; Un l\u00e1piz 3D para crear:<\/strong> En el siguiente v\u00eddeo se presenta el Lix Pen, un l\u00e1piz 3D capaz de ser utilizado por artistas, una oferta un poco menos profesional que el <a href=\"https:\/\/www.3dnatives.com\/es\/3doodler-pro-02092016\/\" target=\"_blank\" rel=\"noopener\">Doodler Pro<\/a>. En el siguiente v\u00eddeo se muestras la diferentes creaciones que se pueden conseguir con una herramienta como esta que imprime en 3D sin ninguna limitaci\u00f3n.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ju9r5JSv2p0\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>TOP 2 &#8211; Alaba estudia la impresi\u00f3n 3D para tener usos militares:<\/strong> La Universidad de Alabama present\u00f3 un proyecto de <a href=\"https:\/\/www.3dnatives.com\/es\/top-10-aplicaciones-militares-3d-05102016\/\" target=\"_blank\" rel=\"noopener\">impresi\u00f3n 3D para que sea utilizada dentro del campo militar<\/a>. Esta es una de las m\u00faltiples aplicaciones de las tecnolog\u00edas de fabricaci\u00f3n aditiva en el campo militar. Hace algunos meses tambi\u00e9n te contamos de la inversi\u00f3n del gobierno estadounidense para comenzar a desarrollar <a href=\"https:\/\/www.3dnatives.com\/es\/ee-uu-explosivos-impresos-en-3d-230420182\/\" target=\"_blank\" rel=\"noopener\">explosivos con impresi\u00f3n 3D.<\/a><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/neaG-S2GU68\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>TOP 3 &#8211; La impresi\u00f3n 3D recupera un patrimonio de la humanidad:<\/strong> Gracias a las tecnolog\u00edas 3D fue posible recuperar la\u00bbGran Pagoda\u00bb del Centro del Patrimonio Mundial de la UNESCO en Kew Gardens.\u00a0 Con ayuda de <a href=\"https:\/\/www.3dnatives.com\/es\/top-10-escaneres-3d-low-cost-19102016\/\" target=\"_blank\" rel=\"noopener\">esc\u00e1neres 3D<\/a> y posteriormente t\u00e9cnicas de sinterizado selectivo, se consigui\u00f3 recrear a los dragones que decoraban los techos del monumento.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/5KU6hbbZai4\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>TOP 4 &#8211; La NASA y la impresi\u00f3n 3D:<\/strong> La NASA en colaboraci\u00f3n con Austodesk han desarrollado un proyecto para enviar robots que impriman en 3D a la Luna para el desarrollo de habitats. Esta no es la primera vez que hablamos de la NASA y la impresi\u00f3n 3D, hace unos d\u00edas se dieron a conocer los ganadores de la creaci\u00f3n de <a href=\"https:\/\/www.3dnatives.com\/es\/vivienda-3d-habitar-en-marte-030820182\/\" target=\"_blank\" rel=\"noopener\">habitats impresos en 3D para Marte<\/a>.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/iH6Un45kQxg\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>TOP 5 &#8211; 3DMP, la impresi\u00f3n 3D de metal:<\/strong> La nueva tecnolog\u00eda 3DMP de la empresa GEFERTEC es pera ser una de las tecnolog\u00edas de impresi\u00f3n 3D m\u00e1s revolucionarias de la industria. En un a\u00f1o en el que la impresi\u00f3n de metal creaci\u00f3n casi un 80% de acuerdo al <a href=\"https:\/\/www.3dnatives.com\/es\/informe-wohlers-2018-020420182\/\" target=\"_blank\" rel=\"noopener\">estudio Wohler<\/a> llegan cada d\u00eda m\u00e1s actores y tecnolog\u00edas al sector.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/LAOiMOh5680\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 piensas de los desarrollos de la NASA y la impresi\u00f3n 3D?\u00a0Deja tus comentarios en nuestras redes sociales\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativeses\/?ref=hl\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>,<a href=\"https:\/\/twitter.com\/3Dnatives_ES\" target=\"_blank\" rel=\"noopener\">\u00a0Twitter<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\" target=\"_blank\" rel=\"noopener\">RSS.<\/a><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-1537015063\"><div id=\"dnati-1899065797\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A pesar de estos d\u00edas de calor las novedades sobre impresi\u00f3n 3D no han parado. Esta semana te presentamos diferentes novedades que no hemos podido incluir en nuestros art\u00edculos diarios. No te pierdas las desarrollos de la NASA y la&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":35462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,15],"tags":[],"class_list":["post-35453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-videos"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/35453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=35453"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/35453\/revisions"}],"predecessor-version":[{"id":35463,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/35453\/revisions\/35463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/35462"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=35453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=35453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=35453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}