{"id":32164,"date":"2017-12-19T00:06:28","date_gmt":"2017-12-18T23:06:28","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=32164"},"modified":"2017-12-19T11:34:07","modified_gmt":"2017-12-19T10:34:07","slug":"departamentos-de-impresion-3d-19122017","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/departamentos-de-impresion-3d-19122017\/","title":{"rendered":"Proponen introducir departamentos de impresi\u00f3n 3D en los hospitales espa\u00f1oles"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Las tecnolog\u00edas de fabricaci\u00f3n aditiva han supuesto grandes avances en diversos sectores m\u00e9dicos. Han conseguido ayudar con m\u00faltiples <a href=\"https:\/\/www.3dnatives.com\/es\/12-aplicaciones-discapacitados-11012017\/\">aplicaciones para personas discapacitadas<\/a>, el desarrollo de pr\u00f3tesis a medida, y por supuesto, <a href=\"https:\/\/www.3dnatives.com\/es\/bioimpresion-futuro-medicina-180520172\/\">la bioimpresi\u00f3n<\/a>. Por estos beneficios el Grupo Parlamentario Popular espa\u00f1ol hizo <strong>una proposici\u00f3n al Congreso de diputados para introducir departamentos de impresi\u00f3n 3D en los hospitales p\u00fablicos. <\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El principal impulsor de esta propuesta es Teodoro Garc\u00eda que habl\u00f3 de los beneficios en tiempo que se pueden tener en una operaci\u00f3n con la utilizaci\u00f3n de r\u00e9plicas de \u00f3rganos impresas en 3D. Inicialmente la implementaci\u00f3n de estos departamentos se centrar\u00e1 principalmente en la impresi\u00f3n de r\u00e9plicas de \u00f3rganos de los pacientes para aumentar el \u00e9xito de las cirug\u00edas, as\u00ed como la utilizaci\u00f3n en pr\u00f3tesis personalizadas. Sobre la utilizaci\u00f3n de estas tecnolog\u00edas en comparaci\u00f3n con las tradicionales \u201cE<\/span><span style=\"font-weight: 400;\">stas tecnolog\u00edas reducen los procesos intermedios de fabricaci\u00f3n y lo hace hasta un 90% m\u00e1s r\u00e1pido\u00bb, coment\u00f3 \u00a0Garc\u00eda a Europa Press.<\/span><\/p>\n<div id=\"attachment_32168\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32168\" class=\"wp-image-32168 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw2.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw2.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw2-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-32168\" class=\"wp-caption-text\">Miembros del Grupo Parlamentario Popular con modelos m\u00e9dicos impresos en 3D. Europa Press<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Las ventajas de la fabricaci\u00f3n aditiva es que ni la complejidad de un modelos, ni las diferentes personalizaciones de este supondr\u00e1n un aumento de precio. Lo cual lo hace muy f\u00e1cilmente aplicable dentro de los hospitales espa\u00f1oles. <\/span><span style=\"font-weight: 400;\">\u00abEstas caracter\u00edsticas s<strong>uponen una verdadera revoluci\u00f3n en el \u00e1mbito del dise\u00f1o de los productos sanitarios<\/strong> y una amplia libertad creativa para fabricar cualquier objeto creado por la imaginaci\u00f3n humana\u00bb, tal y como refleja el PP en su Proposici\u00f3n no de Ley.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">No es la primera vez que hablamos del \u00e9xito y la buena aceptaci\u00f3n que tiene la impresi\u00f3n 3d dentro de los hospitales. Hace unas semanas el gigante de la impresi\u00f3n 3D dio a conocer su <a href=\"https:\/\/www.3dnatives.com\/es\/biomimics-modelado-anatomico-011220172\/\">plataforma BioMimics<\/a>, para que los diferentes hospitales en el mundo cuenten con el software e infraestructura necesaria para la reproducci\u00f3n de \u00f3rganos de pacientes. <\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 se espera de estos departamentos de impresi\u00f3n 3D en los hospitales?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Espa\u00f1a ya se encuentra trabajando en diferentes propuestas para incorporar la impresi\u00f3n 3D en el sector m\u00e9dico, hace unos meses Abax Innovation Technologies firm\u00f3 un acuerdo con el Hospital Universitario de la Paz para comenzar la aplicaci\u00f3n de las tecnolog\u00edas de fabricaci\u00f3n aditiva.<\/span><\/p>\n<div id=\"attachment_32169\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32169\" class=\"wp-image-32169 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw1.jpg 700w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw1-300x171.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/Article_3DLaw1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-32169\" class=\"wp-caption-text\">Pr\u00f3tesis 3D personalizadas<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Dentro de la proposici\u00f3n de no Ley del Parlamentario Popular se insta al gobierno espa\u00f1ola a promover las medidas necesarias para impulsar las tecnolog\u00edas de impresi\u00f3n 3D dentro del sector sanitario.<\/span><span style=\"font-weight: 400;\"> \u00abSe necesita un mayor impulso para superar todos los obst\u00e1culos que permitan avanzar en su completa aplicaci\u00f3n en el sector sanitario\u00bb, coment\u00f3 Garc\u00eda. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La propuesta<strong> insta al Estado a la promoci\u00f3n de empresas relacionadas con las tecnolog\u00edas 3D,<\/strong> as\u00ed como servicios internos dentro de los hospitales relacionados con esta tecnolog\u00edas. Finalmente solicita la formaci\u00f3n de ingenieros expertos en fabricaci\u00f3n aditiva para que sean incorporados en el nuevo servicios de departamentos de impresi\u00f3n 3D en los hospitales del pa\u00eds.<\/span><\/p>\n<p>\u00bfTe gusta el mundo de la impresi\u00f3n 3D y quieres saber m\u00e1s?\u00a0S\u00edguenos en<strong>\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativeses?fref=nf\">Facebook<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/twitter.com\/3Dnatives_ES\">Twitter<\/a><\/strong>\u00a0y\u00a0<strong><a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\">RSS<\/a>.<\/strong><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-3265371481\"><div id=\"dnati-2756783606\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Las tecnolog\u00edas de fabricaci\u00f3n aditiva han supuesto grandes avances en diversos sectores m\u00e9dicos. Han conseguido ayudar con m\u00faltiples aplicaciones para personas discapacitadas, el desarrollo de pr\u00f3tesis a medida, y por supuesto, la bioimpresi\u00f3n. Por estos beneficios el Grupo Parlamentario Popular&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":32167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,13,284],"tags":[],"class_list":["post-32164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-investigacion","category-medico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/32164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=32164"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/32164\/revisions"}],"predecessor-version":[{"id":32224,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/32164\/revisions\/32224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/32167"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=32164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=32164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=32164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}