{"id":2839,"date":"2016-02-09T03:06:12","date_gmt":"2016-02-09T01:06:12","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?p=2839"},"modified":"2016-02-09T03:06:12","modified_gmt":"2016-02-09T01:06:12","slug":"siemens-invierte-20-millones-en-impresion-3d-de-metal-09022016","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/es\/siemens-invierte-20-millones-en-impresion-3d-de-metal-09022016\/","title":{"rendered":"Siemens invierte 20 millones en impresi\u00f3n 3D de metal"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Siemens anunci\u00f3 en un reciente comunicado de prensa la inversi\u00f3n de aproximadamente 21,3 millones de euros que hizo para la<strong> apertura de un centro de producci\u00f3n especializado en fabricaci\u00f3n aditiva de metal<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La multinacional alemana piensa fijar esta primera planta en Finspang, Suecia. Ser\u00e1 la primera de su tipo en el pa\u00eds y tendr\u00e1 la responsabilidad de fabricar y reparar componentes met\u00e1licos para el sector energ\u00e9tico. La plantilla inicial de esta planta ser\u00e1 de aproximadamente 20 empleados que ser\u00e1n profesionales t\u00e9cnicos y de ingenier\u00eda relacionados con las tecnolog\u00edas 3D.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00abSiemens es una empresa l\u00edder en Suecia, m\u00e1s generalmente en la fabricaci\u00f3n de aditivos de componentes met\u00e1licos para la industria de la energ\u00eda. Este es un paso m\u00e1s en nuestra inversi\u00f3n a largo plazo en esta \u00e1rea, donde todav\u00eda no hemos visto todas las posibilidades. Con esta inversi\u00f3n, queremos construir las habilidades y experiencias del ma\u00f1ana que conducir\u00e1 al desarrollo futuro del sector \u00ab, dice Hans Holmstr\u00f6m, CEO de Siemens Industrial Turbomachine.<\/span><\/p>\n<div id=\"attachment_2841\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2841\" class=\"wp-image-2841 size-full\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/article_siemens2.jpg\" alt=\"article_siemens2\" width=\"620\" height=\"330\" srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/article_siemens2.jpg 620w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/article_siemens2-300x160.jpg 300w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/article_siemens2-160x85.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><p id=\"caption-attachment-2841\" class=\"wp-caption-text\">Tendr\u00e1 la responsabilidad de fabricar y reparar componentes met\u00e1licos para el sector energ\u00e9tico<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><strong>Siemens es otra de las grandes empresas que apuestan por las fabricaci\u00f3n aditiva<\/strong> y la creaci\u00f3n a partir de impresi\u00f3n 3D, el a\u00f1o pasado grandes marcas como <a href=\"https:\/\/www.3dnatives.com\/es\/thales-planta-de-impresion-3d-18122015\/\">Thales<\/a>, General Electric o\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/michelin-se-lanza-a-la-impresion-3d-en-metal-14092015\/\">Michelin<\/a>\u00a0 formaron parte de la lista de <a href=\"https:\/\/www.3dnatives.com\/es\/top-10-de-empresas-que-marcaron-el-2015-22122015\/\">empresas presentes en las nuevas tecnolog\u00edas<\/a>, abriendo instalaciones similares para aumentar su capacidad de producci\u00f3n y creando tambi\u00e9n nuevos m\u00e9todos de fabricaci\u00f3n de piezas de alto valor.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00abCon esta inversi\u00f3n, podemos desarrollar nuevos m\u00e9todos de fabricaci\u00f3n y reparaci\u00f3n de componentes, tales como quemadores de combusti\u00f3n para nuestras turbinas de gas industriales, mucho m\u00e1s r\u00e1pidamente. Con este enfoque innovador, podemos reducir nuestros tiempos de reparaci\u00f3n de varios meses a unas pocas semanas. Este es un paso importante en nuestra capacidad de satisfacer las necesidades de nuestros clientes \u00ab, dice Thorbjorn Fors, Director de Negocios Globales de Siemens.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Hace unos meses, Siemens dio a conocer un v\u00eddeo en su uso de la fabricaci\u00f3n aditiva:<\/span><\/p>\n<p class=\"wpview-selection-before\">\n<div class=\"wpview-body\" contenteditable=\"false\">\n<div class=\"wpview-content wpview-type-embedURL\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/VyEgbyNg0Q8?feature=oembed\" width=\"620\" height=\"349\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<div class=\"wpview-overlay\"><\/div>\n<\/div>\n<\/div>\n<p class=\"wpview-selection-after\">\n<p style=\"text-align: justify;\">\u00bfInteresado en\u00a0el mundo de la impresi\u00f3n 3D y quieres saber m\u00e1s?\u00a0S\u00edguenos en<strong>\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativeses?fref=nf\">Facebook<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/twitter.com\/3Dnatives_ES\">Twitter<\/a><\/strong>\u00a0y\u00a0<strong><a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\">RSS<\/a>.<\/strong><\/p>\n<div class=\"dnati-under_article dnati-entity-placement\" id=\"dnati-3024734954\"><div id=\"dnati-3567638051\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/es\/wp-content\/uploads\/sites\/4\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Siemens anunci\u00f3 en un reciente comunicado de prensa la inversi\u00f3n de aproximadamente 21,3 millones de euros que hizo para la apertura de un centro de producci\u00f3n especializado en fabricaci\u00f3n aditiva de metal. La multinacional alemana piensa fijar esta primera planta&hellip;<\/p>\n","protected":false},"author":6026,"featured_media":2840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,8],"tags":[57,212,155,211],"class_list":["post-2839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-negocios","tag-impresion-3d","tag-inversion","tag-negocios","tag-siemens"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/2839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/users\/6026"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/comments?post=2839"}],"version-history":[{"count":1,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/2839\/revisions"}],"predecessor-version":[{"id":2842,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/posts\/2839\/revisions\/2842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/2840"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=2839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/categories?post=2839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/tags?post=2839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}