{"id":5650,"date":"2016-10-25T18:00:49","date_gmt":"2016-10-25T16:00:49","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?post_type=tribe_events&#038;p=5650"},"modified":"2020-06-17T15:12:43","modified_gmt":"2020-06-17T13:12:43","slug":"3d-industry-tour","status":"publish","type":"ntv_events","link":"https:\/\/www.3dnatives.com\/es\/eventos\/3d-industry-tour\/","title":{"rendered":"3D Industry Tour"},"content":{"rendered":"<p style=\"text-align: justify\">Jornada informativa en la que HP dar\u00e1 a conocer las caracter\u00edsticas y las aplicaciones industriales y profesionales de su nueva y exclusiva tecnolog\u00eda de impresi\u00f3n 3D, denominada MultiJet Fusion. As\u00ed mismo, expertos en tecnolog\u00eda 3D de Grupo Sicnova y centros tecnol\u00f3gicos espa\u00f1oles dar\u00e1n el contexto necesario, explicando en qu\u00e9 consisten las distintas tecnolog\u00edas de fabricaci\u00f3n aditiva y de digitalizaci\u00f3n 3D existentes en la actualidad, y cu\u00e1l es su papel dentro de la llamada \u201cIndustria 4.0\u201d.<\/p>\n<p style=\"text-align: justify\"><strong>\u00bfA QUI\u00c9N EST\u00c1 DIRIGIDO?<\/strong><\/p>\n<p style=\"text-align: justify\">A profesionales e industrias de diversos \u00e1mbitos que quieran mejorar sus procesos actuales de fabricaci\u00f3n, prototipado, dise\u00f1o de producto, fabricaci\u00f3n de utillaje, etc.<\/p>\n<p style=\"text-align: justify\">De especial inter\u00e9s para profesionales de sectores como automoci\u00f3n, aeron\u00e1utica, arquitectura, energ\u00eda, medicina, joyer\u00eda, patrimonio, ingenier\u00eda civil, defensa\u2026<\/p>\n<p style=\"text-align: justify\">[3D Industry Tour]<br \/>\n[3D Industry Tour]<\/p>\n<p style=\"text-align: justify\"><strong>\u00bfD\u00d3NDE Y CU\u00c1NDO?<\/strong><\/p>\n<p style=\"text-align: justify\">3D INDUSTRY TOUR se celebrar\u00e1 en 9 puntos de la geograf\u00eda espa\u00f1ola durante los meses de octubre y noviembre:<\/p>\n<p style=\"text-align: justify\">19 de octubre: Madrid<br \/>\n20 de octubre: Valencia<br \/>\n21 de octubre: Alicante<br \/>\n25 de octubre: Elgoibar (Gipuzkoa) \u2013 Instituto de M\u00e1quina Herramienta<br \/>\n26 de octubre: Pamplona<br \/>\n27 de octubre: Valladolid<br \/>\n3 de noviembre: Ja\u00e9n<br \/>\n4 de noviembre: Sevilla<br \/>\n8 de noviembre: Sant Cugat del Vall\u00e8s (Barcelona) \u2013 Hewlett Packard<\/p>\n<p style=\"text-align: justify\"><strong>\u00bfC\u00d3MO INSCRIBIRSE?<\/strong><\/p>\n<div class=\"views-field views-field-body-1\">\n<div class=\"field-content\">\n<p style=\"text-align: justify\">Rellena el formulario de contacto para tramitar tu inscripci\u00f3n de forma gratuita y recibir\u00e1s un correo electr\u00f3nico con la confirmaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Si tienes dudas o necesitas m\u00e1s informaci\u00f3n sobre las jornadas, puedes enviar un correo electr\u00f3nico a <a href=\"mailto:in**@************ur.com\" data-original-string=\"g1znh\/jjP6aPZIo8U4uJCg==58dgwz\/hHazwJZvRbs6X+7khC2LqmbJ6143zqGJt4T38X8=\" title=\"Este contacto ha sido codificado por Anti-Spam by CleanTalk. Haz clic para decodificar. Para finalizar la decodificaci\u00f3n, aseg\u00farate de que JavaScript est\u00e1 activado en tu navegador.\"><span \n                data-original-string='J6NTPwm9VgkXqn9i2QZUAQ==58dIH1HDm2pVeIMhWE7JaAXsAQCJu\/gkfK232PiixC7JpI='\n                class='apbct-email-encoder'\n                title='Este contacto ha sido codificado por Anti-Spam by CleanTalk. Haz clic para decodificar. Para finalizar la decodificaci\u00f3n, aseg\u00farate de que JavaScript est\u00e1 activado en tu navegador.'>in<span class=\"apbct-blur\">**<\/span>@<span class=\"apbct-blur\">************<\/span>ur.com<\/span><\/a><\/p>\n<p style=\"text-align: justify\">Ent\u00e9rate de muchas m\u00e1s\u00a0noticias\u00a0sobre impresi\u00f3n 3D con nosotros\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativeses?fref=nf\">Facebook<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/3Dnatives_ES\">Twitter<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.3dnatives.com\/es\/feed\/\">RSS<\/a>.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jornada informativa en la que HP dar\u00e1 a conocer las caracter\u00edsticas y las aplicaciones industriales y profesionales de su nueva y exclusiva tecnolog\u00eda de impresi\u00f3n 3D, denominada MultiJet Fusion. As\u00ed mismo, expertos en tecnolog\u00eda 3D de Grupo Sicnova y centros&hellip;<\/p>\n","protected":false},"featured_media":5651,"template":"","ntv_event_cat":[20,27],"ntv_organizer":[],"class_list":["post-5650","ntv_events","type-ntv_events","status-publish","has-post-thumbnail","hentry","ntv_event_cat-exposicion","ntv_event_cat-seminario"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_events\/5650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_events"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/ntv_events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/5651"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=5650"}],"wp:term":[{"taxonomy":"ntv_event_cat","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_event_cat?post=5650"},{"taxonomy":"ntv_organizer","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_organizer?post=5650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}