{"id":1835,"date":"2015-11-16T01:07:41","date_gmt":"2015-11-15T23:07:41","guid":{"rendered":"https:\/\/www.3dnatives.com\/es\/?post_type=tribe_events&#038;p=1835"},"modified":"2020-06-17T15:12:45","modified_gmt":"2020-06-17T13:12:45","slug":"bilbao-maker-faire","status":"publish","type":"ntv_events","link":"https:\/\/www.3dnatives.com\/es\/eventos\/bilbao-maker-faire\/","title":{"rendered":"Bilbao Maker Faire"},"content":{"rendered":"<p style=\"text-align: justify\">Maker Faire es la mayor feria de creadores e inventores, que ya ha celebrado m\u00e1s de 100 ediciones a lo largo y ancho del planeta y vuelve a Bilbao. M\u00e1s de un centenar de actividades Do-It-Yourself para familias, ni\u00f1os, creadores y tecn\u00f3logos de todas las edades. La entrad<span class=\"text_exposed_show\">a es Libre y Gratuita.<\/span><\/p>\n<p style=\"text-align: justify\">Esta edici\u00f3n ser\u00e1 hermana de las ediciones, con el mismo t\u00edtulo y concepto, que se celebran en Nueva York, California o Roma. En esta edici\u00f3n los organizadores han abierto un \u00abCall for Makers\u00bb para todas las personas que quieran participar en este evento mostrnado sus creaciones y productos, La inscripci\u00f3n est\u00e1 abierta a exhibidores, y a quienes quieran realizar una presentaci\u00f3n, taller o colaborar como voluntarios.<\/p>\n<p style=\"text-align: justify\">Durante tres d\u00edas en el barrio de Zorrozaurre, en la Antigua F\u00e1brica de Galletas Artiach, el publico disfrutar\u00e1 de un ambiente creativo, proyectos d robots, drones, y obviamente \u00a1Impresoras 3D!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maker Faire es la mayor feria de creadores e inventores, que ya ha celebrado m\u00e1s de 100 ediciones a lo largo y ancho del planeta y vuelve a Bilbao. M\u00e1s de un centenar de actividades Do-It-Yourself para familias, ni\u00f1os, creadores&hellip;<\/p>\n","protected":false},"featured_media":1836,"template":"","ntv_event_cat":[20,21,18],"ntv_organizer":[],"class_list":["post-1835","ntv_events","type-ntv_events","status-publish","has-post-thumbnail","hentry","ntv_event_cat-exposicion","ntv_event_cat-formacion","ntv_event_cat-maker-faire"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_events\/1835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_events"}],"about":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/types\/ntv_events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media\/1836"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/media?parent=1835"}],"wp:term":[{"taxonomy":"ntv_event_cat","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_event_cat?post=1835"},{"taxonomy":"ntv_organizer","embeddable":true,"href":"https:\/\/www.3dnatives.com\/es\/wp-json\/wp\/v2\/ntv_organizer?post=1835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}