{"id":61316,"date":"2025-02-17T15:00:22","date_gmt":"2025-02-17T14:00:22","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=61316"},"modified":"2025-02-12T10:57:13","modified_gmt":"2025-02-12T09:57:13","slug":"raf-flugzeuge-zu-metallpulvern-recycelt-flugzeugteile-3d-drucken-rolls-royce-170220251","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/raf-flugzeuge-zu-metallpulvern-recycelt-flugzeugteile-3d-drucken-rolls-royce-170220251\/","title":{"rendered":"RAF-Flugzeuge werden zu Metallpulvern recycelt, um neue Flugzeugteile in 3D zu drucken"},"content":{"rendered":"<p style=\"text-align: justify;\">Die Royal Air Force, die Luftwaffe der britischen Armee, hat eine interessante Partnerschaft mit Rolls-Royce bekannt gegeben, bei der <a href=\"https:\/\/www.3dnatives.com\/de\/additive-fertigung\/\">additive Fertigungsverfahren<\/a> zum Einsatz kommen. Gemeinsam haben sie am Programm Tornado 2 Tempest teilgenommen, bei dem Ersatzteile von veralteten Kampfflugzeugen recycelt und zu 3D-druckbarem Pulver verarbeitet werden. Nach einem Reinigungs- und Zerst\u00e4ubungsprozess kann das Pulver dann f\u00fcr die Konstruktion von Komponenten des neuen Orpheus-Triebwerks verwendet werden, das Teil des Programms Future Combat Air System (FCAS) ist. Die recycelten Teile wurden aufgrund ihres Gehalts an Titan ausgew\u00e4hlt, einem <a href=\"https:\/\/www.3dnatives.com\/de\/3d-metalldruck\/\">Metall<\/a>, das in der <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-in-luft-und-raumfahrt-und-verteidigung\/\">Luft- und Raumfahrtindustrie<\/a> aufgrund seines geringen Gewichts, seiner Festigkeit, seiner geringen Toxizit\u00e4t und seiner hohen Korrosionsbest\u00e4ndigkeit besonders gefragt ist.<\/p>\n<p style=\"text-align: justify;\">Viele Branchen versuchen, ihren <a href=\"https:\/\/www.3dnatives.com\/de\/10-gruende-warum-der-3d-druck-als-nachhaltiger-gilt-300720241\/\">\u00f6kologischen Fu\u00dfabdruck<\/a> und ihre Abh\u00e4ngigkeit von komplexen Lieferketten zu verringern. Die additive Fertigung scheint ein perfektes Werkzeug zu sein, um einige dieser Herausforderungen zu bew\u00e4ltigen, da sie eine lokale und bedarfsorientierte Produktion erm\u00f6glicht und gleichzeitig die Menge an anfallendem Abfall reduziert. Dar\u00fcber hinaus kann die Technologie auch das Gewicht der geplanten Teile verringern, w\u00e4hrend sie gleichzeitig die Festigkeit erh\u00f6ht und die Endkosten senkt. Auf dem Papier scheint sie also die perfekte Technik zu sein, um die Flugzeuge von morgen zu entwerfen. In der Praxis ist es komplizierter, aber die Entwicklungen sind vielversprechend.<\/p>\n<div id=\"attachment_88406\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-88406\" class=\"wp-image-88406 size-full\" src=\"https:\/\/www.3dnatives.com\/wp-content\/uploads\/2025\/02\/Rolls-Royce-powder.jpg\" alt=\"rolls-royce\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-88406\" class=\"wp-caption-text\">Einige Komponenten des Tornado-Kampfjets werden zu Metallpulvern zerst\u00e4ubt, die f\u00fcr die additive Fertigung geeignet sind.<\/p><\/div>\n<h3 style=\"text-align: justify;\">Rolls-Royce setzt bei der Entwicklung von Orpheus auf die Vorteile der additiven Fertigung<\/h3>\n<p style=\"text-align: justify;\">Seit einiger Zeit arbeitet Rolls-Royce nun schon an seiner Orpheus-Reihe: Es handelt sich um kleine, relativ erschwingliche Zweistromtriebwerke f\u00fcr den Verteidigungsmarkt. Dieses Projekt hat vor allem dazu beigetragen, neue Arbeitspraktiken einzuf\u00fchren und andere Produktionsmethoden, wie die additive Fertigung, zu testen. Die bereits von dem britischen Unternehmen durchgef\u00fchrten Tests wurden an Triebwerken durchgef\u00fchrt, die 3D-gedruckte Teile enthielten. Das langfristige Ziel ist es, alle wichtigen Komponenten mithilfe der additiven Fertigung zu konstruieren.<\/p>\n<p style=\"text-align: justify;\">Und die Teilnahme am Projekt Tornado 2 Tempest stellt einen weiteren Schritt in diesem Bestreben dar. Die Grundidee besteht darin, auf kaputte Ersatzteile und Komponenten des britischen Verteidigungsministeriums zur\u00fcckzugreifen und die Metalle, aus denen sie bestehen, wiederzuverwerten. Dabei handelt es sich haupts\u00e4chlich um <a href=\"https:\/\/www.3dnatives.com\/de\/leitfaden-aluminium-3d-druck-131220231\/\">Aluminium<\/a>, <a href=\"https:\/\/www.3dnatives.com\/de\/leitfaden-3d-druck-mit-stahl-160720241\/\">Stahl<\/a> und <a href=\"https:\/\/www.3dnatives.com\/de\/titan-aluminium-3d-druck-160520231\/\">Titan<\/a>. Indem sie diese Teile zu Pulvern zerst\u00e4ubten, konnten die Teams Materialien f\u00fcr die additive Metallfertigung gewinnen. So stellte Rolls-Royce einen Nasenkonus (oder astronautische Kappe) und Kompressorbl\u00e4tter aus alten Kompressorschaufeln von D\u00fcsentriebwerken her.<\/p>\n<p style=\"text-align: justify;\">Thomas Powell, DRDT&#8217;s Strategic &amp; Submarine Recycling Senior Commercial Manager, kommt zu dem Schluss: &#8222;<em>Diese L\u00f6sung reduziert nicht nur die Kosten und den Aufwand f\u00fcr die Beschaffung kritischer und hochwertiger Metalle, sondern erm\u00f6glicht auch die Herstellung leichterer, st\u00e4rkerer und haltbarerer Komponenten als die mit herk\u00f6mmlichen Schmiedetechniken hergestellten, wodurch die Nachhaltigkeit und Effizienz des Verteidigungsministeriums insgesamt verbessert wird.&#8220;<\/em><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/ezIwB_-3ujs?si=77UsKo88jg6e8ZLB\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">Die Projektteams &#8211; insgesamt 80 Personen &#8211; haben den 3D-gedruckten Konus in einen Testmotor eingebaut und die Ergebnisse waren sehr positiv. Sie haben bewiesen, dass das Bauteil sicher und zuverl\u00e4ssig ist. Nun bleibt abzuwarten, ob auch andere Komponenten des Motors aus recyceltem Pulver in 3D gedruckt werden. In der Zwischenzeit k\u00f6nnen Sie <a href=\"https:\/\/www.rolls-royce.com\/media\/press-releases\/2025\/05-02-2025-tornado-2-tempest-recycling-project-off-to-flying-start.aspx\" target=\"_blank\" rel=\"noopener\">HIER<\/a> weitere Informationen finden.<\/p>\n<p style=\"text-align: justify;\">Was halten Sie von dem Projekt von Rolls-Royce? \u00a0Lassen Sie uns dazu einen Kommentar da, oder teilen Sie es uns auf\u00a0<a id=\"menur3js\" class=\"fui-Link ___1q1shib f2hkw1w f3rmtva f1ewtqcl fyind8e f1k6fduh f1w7gpdv fk6fouc fjoy568 figsok6 f1s184ao f1mk8lai fnbmjn9 f1o700av f13mvf36 f1cmlufx f9n3di6 f1ids18y f1tx3yz7 f1deo86v f1eh06m1 f1iescvh fhgqx19 f1olyrje f1p93eir f1nev41a f1h8hb77 f1lqvz6u f10aw75t fsle3fq f17ae5zn\" title=\"https:\/\/www.facebook.com\/3dnativesde\/\" href=\"https:\/\/www.facebook.com\/3Dnativesde\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Link Facebook\">Facebook<\/a>\u00a0oder\u00a0<a id=\"menur3ju\" class=\"fui-Link ___1q1shib f2hkw1w f3rmtva f1ewtqcl fyind8e f1k6fduh f1w7gpdv fk6fouc fjoy568 figsok6 f1s184ao f1mk8lai fnbmjn9 f1o700av f13mvf36 f1cmlufx f9n3di6 f1ids18y f1tx3yz7 f1deo86v f1eh06m1 f1iescvh fhgqx19 f1olyrje f1p93eir f1nev41a f1h8hb77 f1lqvz6u f10aw75t fsle3fq f17ae5zn\" title=\"https:\/\/www.linkedin.com\/groups\/13502336\/\" href=\"https:\/\/www.linkedin.com\/groups\/13502336\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Link LinkedIN\">LinkedIN<\/a>\u00a0mit. Wenn Sie mehr zum 3D-Druck in der Luft- und Raumfahrt lesen m\u00f6chten, schauen Sie auf unserer\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-in-luft-und-raumfahrt-und-verteidigung\/\">Landing Page<\/a>\u00a0vorbei. M\u00f6chten Sie au\u00dferdem eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach erhalten? Dann registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a id=\"menur3k0\" class=\"fui-Link ___1q1shib f2hkw1w f3rmtva f1ewtqcl fyind8e f1k6fduh f1w7gpdv fk6fouc fjoy568 figsok6 f1s184ao f1mk8lai fnbmjn9 f1o700av f13mvf36 f1cmlufx f9n3di6 f1ids18y f1tx3yz7 f1deo86v f1eh06m1 f1iescvh fhgqx19 f1olyrje f1p93eir f1nev41a f1h8hb77 f1lqvz6u f10aw75t fsle3fq f17ae5zn\" title=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\" href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Link w\u00f6chentlichen Newsletter\">w\u00f6chentlichen Newsletter<\/a>.<\/p>\n<p><em>*Alle Bildnachweise: Royal Air Force<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Royal Air Force, die Luftwaffe der britischen Armee, hat eine interessante Partnerschaft mit Rolls-Royce bekannt gegeben, bei der additive Fertigungsverfahren zum Einsatz kommen. Gemeinsam haben sie am Programm Tornado 2 Tempest teilgenommen, bei dem Ersatzteile von veralteten Kampfflugzeugen recycelt&hellip;<\/p>\n","protected":false},"author":6112,"featured_media":61317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,153],"tags":[],"class_list":["post-61316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-luft-und-raumfahrt"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/61316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6112"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=61316"}],"version-history":[{"count":1,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/61316\/revisions"}],"predecessor-version":[{"id":61318,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/61316\/revisions\/61318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/61317"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=61316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=61316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=61316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}