{"id":60628,"date":"2025-01-06T00:01:12","date_gmt":"2025-01-05T23:01:12","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=60628"},"modified":"2025-01-07T17:24:34","modified_gmt":"2025-01-07T16:24:34","slug":"milchfieber-erkennen-tiergesundheit-landwirtschaft-3d-druck-060120251","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/milchfieber-erkennen-tiergesundheit-landwirtschaft-3d-druck-060120251\/","title":{"rendered":"Milchfieber fr\u00fchzeitig erkennen: Durchbruch f\u00fcr Tiergesundheit und Landwirtschaft dank 3D-Druck"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ein weitverbreitetes Problem in der <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-in-der-landwirtschaft-061120241\/\">Landwirtschaft<\/a>, das erhebliche wirtschaftliche und gesundheitliche Folgen f\u00fcr K\u00fche und Betriebe haben kann, ist das Milchfieber. <\/span><span style=\"font-weight: 400;\">Insgesamt betrifft dieses rund 80 % der K\u00fche und 25 % der Erstkalbinnen und ist auch bekannt als Hypokalz\u00e4mie. Hierbei handelt es sich um eine Stoffwechselkrankheit, welche vor allem bei laktierenden K\u00fchen auftritt und zur Reduzierung des Calciumspiegels im Blut der K\u00fche f\u00fchrt, wodurch lebenswichtige Funktionen wie die Muskel- und Nervenaktivit\u00e4t beeintr\u00e4chtigt werden. Aber auch die Milchproduktion wird verringert, wodurch die Krankheit wirtschaftliche Verluste von bis zu 290 US-Dollar pro Milchkuh verursachen kann. F\u00fcr Landwirte war es bisher schwierig, Milchfieber zu diagnostizieren, da oftmals keine typischen Symptome erkennbar sind. Das soll sich nun aber \u00e4ndern, da ein Wissenschaftlerteam der Virginia Tech mittels <a href=\"https:\/\/www.3dnatives.com\/de\/additive-fertigung\/\">additiver Fertigung<\/a> einen Sensor entwickelt hat, der Milchfieber in nur zehn Sekunden erkennen soll \u2013 eine <a href=\"https:\/\/www.3dnatives.com\/de\/10-gruende-warum-der-3d-druck-als-nachhaltiger-gilt-300720241\/\">nachhaltige L\u00f6sung<\/a> f\u00fcr die Landwirtschaft und die Gesundheit der Tiere.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Die Aufgabe des Sensors ist es, die Konzentration von Calcium und Phosphat in Milchproben der K\u00fche zu messen. Hergestellt wurde dieser hierf\u00fcr mittels der <a href=\"https:\/\/www.3dnatives.com\/de\/alles-ueber-harz-3d-druck-030120241\/\">Polymerharz-3D-Drucktechnologie<\/a>, die aufgrund kosteng\u00fcnstiger Produktion und Flexibilit\u00e4t gew\u00e4hlt wurde. Der Produktionsprozess umfasste das Schicht-f\u00fcr-Schicht-Drucken, UV-Aush\u00e4rtung zur Bildung mikroskopischer Oberfl\u00e4chenstrukturen und eine Goldbeschichtung mittels e-Beam-Verdampfung. Die mikroskopisch gewellte Oberfl\u00e4che erm\u00f6glicht eine hohe Empfindlichkeit, und die Sensorstruktur umfasst insgesamt drei Elektroden, von denen zwei als Arbeitselektroden dienen. Diese wurden mit ionenselektiven Membranen f\u00fcr Calcium und Phosphat beschichtet. Besonders wichtig ist, dass der Sensor die Ionen-Konzentration im attomolaren Bereich, also 38 aM f\u00fcr Calcium, erfassen kann. Das erm\u00f6glicht, bereits geringe Anzeichen von Milchfieber zu erkennen, bevor st\u00e4rkere Symptome auftreten k\u00f6nnen.\u00a0<\/span><\/p>\n<div id=\"attachment_60632\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-60632\" class=\"wp-image-60632 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Milchfieber_3D-Sensor_3Dnatives.jpg\" alt=\"3d-druck Milchfieber\" width=\"700\" height=\"300\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Milchfieber_3D-Sensor_3Dnatives.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Milchfieber_3D-Sensor_3Dnatives-600x257.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Milchfieber_3D-Sensor_3Dnatives-160x69.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-60632\" class=\"wp-caption-text\">Der 3D-gedruckte Sensor kann problemlos in Melksysteme integriert werden und bietet eine schnelle sowie genaue Analyse von Calcium- und Phosphatwerten in Milchproben, um Milchfieber fr\u00fchzeitig zu erkennen. (Bild: School of Animal Sciences, Virginia Tech, Blacksburg, USA)<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Zusammenfassend bringt der 3D-gedruckte Sensor viele Vorteile mit sich, darunter vor allem sein Preis, denn traditionelle Diagnosel\u00f6sungen sind oft teuer und kompliziert in der Handhabung. Der neue Sensor kann hingegen in nur zwei Stunden mit minimalem Ressourceneinsatz produziert werden, und bei seiner Verwendung sind keine Fachkenntnisse n\u00f6tig. Au\u00dferdem tr\u00e4gt er zu einer nachhaltigen Tierhaltung bei, da er die Gesundheits\u00fcberwachung von K\u00fchen f\u00f6rdert und so schnelle und pr\u00e4zise Diagnosen vor Ort erm\u00f6glicht. Gleichzeitig werden nat\u00fcrlich auch wirtschaftliche Verluste minimiert und dar\u00fcber hinaus bietet der Sensor die M\u00f6glichkeit zur Erweiterung, beispielsweise zur Messung unterschiedlicher Biomarker in Milchproben, um auch andere Tierkrankheiten feststellen zu k\u00f6nnen. Mehr \u00fcber das Projekt erfahren Sie <a href=\"https:\/\/www.nature.com\/articles\/s41467-024-55535-w\" target=\"_blank\" rel=\"noopener\">HIER<\/a>.<\/span><\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-4263135891\"><div id=\"dnati-2007014203\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\">Was halten Sie von der Anwendung des 3D-Drucks bei der Herstellung des Sensors? Denken Sie, dass dieser zuk\u00fcnftig in der Landwirtschaft verwendet wird? Lassen Sie uns dazu einen Kommentar da, oder teilen Sie es uns auf <a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>\u00a0oder\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\/\">LinkedIN<\/a>\u00a0mit. M\u00f6chten Sie au\u00dferdem eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach erhalten? Dann registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein weitverbreitetes Problem in der Landwirtschaft, das erhebliche wirtschaftliche und gesundheitliche Folgen f\u00fcr K\u00fche und Betriebe haben kann, ist das Milchfieber. Insgesamt betrifft dieses rund 80 % der K\u00fche und 25 % der Erstkalbinnen und ist auch bekannt als Hypokalz\u00e4mie.&hellip;<\/p>\n","protected":false},"author":6112,"featured_media":60631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,256],"tags":[],"class_list":["post-60628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-projekte"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/60628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6112"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=60628"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/60628\/revisions"}],"predecessor-version":[{"id":60675,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/60628\/revisions\/60675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/60631"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=60628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=60628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=60628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}