{"id":58390,"date":"2026-04-08T04:00:48","date_gmt":"2026-04-08T02:00:48","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=58390"},"modified":"2026-04-08T09:29:07","modified_gmt":"2026-04-08T07:29:07","slug":"3d-druck-im-entwicklungsprozess-von-raketen-und-raumfahrzeugen-290820241","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/3d-druck-im-entwicklungsprozess-von-raketen-und-raumfahrzeugen-290820241\/","title":{"rendered":"3D-Druck im Entwicklungsprozess von Raketen und Raumfahrzeugen"},"content":{"rendered":"<p style=\"text-align: justify;\">Seit der <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-in-luft-und-raumfahrt-und-verteidigung\/\">Mondlandung<\/a> im Jahr 1969 hat die Menschheit nie aufgeh\u00f6rt, nach den Sternen zu greifen. Was sich jedoch ge\u00e4ndert hat, sind die Mittel, um dorthin zu gelangen. Seit Apollo 11 haben sich die Raketen stark ver\u00e4ndert. Innovation ist das Gebot der Stunde, und in den letzten Jahren hat dies die <a href=\"https:\/\/www.3dnatives.com\/de\/additive-fertigung\/\">additive Fertigung<\/a> hervorgebracht. Immer h\u00e4ufiger sehen wir 3D-gedruckte Raketen, sowohl solche, die in der Entwicklung sind, als auch solche, die bereits ins All geschickt wurden. In der folgenden Auflistung (in keiner bestimmten Reihenfolge) haben wir einen Blick auf einige der aufregendsten Projekte geworfen, darunter alles von vollst\u00e4ndig 3D-gedruckten Raketen bis hin zu Triebwerken und anderen Teilen, die mithilfe der additiven Fertigung hergestellt und optimiert wurden.<\/p>\n<h3>Agnibaan von Angikul Cosmos<\/h3>\n<p style=\"text-align: justify;\">Agnibaan ist eines der j\u00fcngsten 3D-gedruckten Raketenprojekte. Es stammt direkt von Agnikul Cosmos, einem indischen Luft- und Raumfahrtunternehmen, das der Meinung ist, dass der Weg ins All f\u00fcr jeden erreichbar sein sollte. Aus diesem Grund hat sich das Unternehmen dem <a href=\"https:\/\/www.3dnatives.com\/de\/3d-technologies\/\">3D-Druck<\/a> zugewandt. Agnibaan (was in Sanskrit \u201eFeuerpfeil\u201c bedeutet) ist nach Angaben des Unternehmens die weltweit erste Rakete mit einem aus einem St\u00fcck gedruckten 3D-Triebwerk, obwohl Agnikul nicht bekannt gegeben hat, welche Technologien f\u00fcr das Projekt verwendet wurden. Der erfolgreiche Start von Agnibaan am 30. Mai um 7:15 Uhr markiert einen gro\u00dfen Schritt nach vorn f\u00fcr die additive Fertigung in der indischen Raumfahrtindustrie.<\/p>\n<div id=\"attachment_58408\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58408\" class=\"wp-image-58408 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/agnibaan.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/agnibaan.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/agnibaan-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/agnibaan-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58408\" class=\"wp-caption-text\">(Bild: Agnikul Cosmos)<\/p><\/div>\n<h3><b>Das E-2-Raketentriebwerk von Launcher<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.3dnatives.com\/de\/launcher-feiert-ersten-erfolgreichen-test-seines-e-2-raketentriebwerks\/\">Launcher<\/a> ist ein 2017 gegr\u00fcndetes Unternehmen, welches in einer Partnerschaft mit der US Space Force, der US Air Force und der <a href=\"https:\/\/www.3dnatives.com\/de\/sensoren-fuer-kuenftige-nasa-missionen-sollen-mit-additiver-technologie-hergestellt-werden-290520241\/\">NASA<\/a> an der Entwicklung von Hochleistungsraketen und Orbitaltransferfahrzeugen arbeitete. Durch die Integration modernster Fl\u00fcssigkeitsantriebstechnologie und den Einsatz von 3D-Druck entstand das E-2-Fl\u00fcssigkeitsraketentriebwerk. Es handelt sich dabei um ein geschlossenes Verbrennungstriebwerk, dessen Brennkammer aus einer Kupfer-Chrom-Zirkon-Legierung besteht, welche die Kosten sowie die Abh\u00e4ngigkeit von Lieferketten reduziert. Launcher ist damit das erste Unternehmen im Bereich der Tr\u00e4gerraketen, das 3D-gedruckte Kupferlegierungen zur Herstellung der Brennkammer eines Raketentriebwerks verwendet. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Au\u00dferdem verf\u00fcgt die Brennkammer \u00fcber integrierte K\u00fchlkan\u00e4le, die die thermische Effizienz steigern sollen. Gemeinsam mit AMCM entwickelte Launcher den AMCM M 4K <a href=\"https:\/\/www.3dnatives.com\/de\/beliebte-3d-drucker-040720171\/\">3D-Drucker<\/a>, mit dem die Brennkammer dann gedruckt wurde. Der koaxiale Injektor des E-2-Triebwerks wurde auf einem Velo3D Sapphire 3D-Drucker produziert. Im April 2022 erreichte das 3D-gedruckte E-2-Triebwerk bei Tests im NASA Stennis Space Center seine volle Schubkraft, woraufhin Launcher den erfolgreichen Abschluss des Testlaufs bekanntgab.<\/span><\/p>\n<div id=\"attachment_58392\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58392\" class=\"wp-image-58392 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/E-2-LAUNCHER.jpg\" alt=\"3D-gedruckte Raketen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/E-2-LAUNCHER.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/E-2-LAUNCHER-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/E-2-LAUNCHER-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58392\" class=\"wp-caption-text\">(Bild: Launcher)<\/p><\/div>\n<h3>Ariane 6<\/h3>\n<p style=\"text-align: justify;\">Die <a href=\"https:\/\/www.3dnatives.com\/de\/berta-triebwerk-esa-260220191\/\">ArianeGroup<\/a> ist ein Gemeinschaftsunternehmen von der Airbus Group und Safran. Mit der Ariane 6 stellte die ArianeGroup Europas neueste Schwerlast-Tr\u00e4gerrakete her, die im Juli 2024 erfolgreich ihren Erststart hinlegte. Die Ariane 6 ist flexibel aufgebaut und kann sehr gro\u00dfe Lasten transportieren. Bei der Herstellung der Ariane 6 setzte die ArianeGroup auch auf den industriellen 3D-Druck. Zahlreiche Komponenten des Triebwerks wurden so additiv gefertigt, was zu einer Senkung der Kosten f\u00fchrte und Produktionszyklen minimierte. Die Brennkammer wurde in Deutschland entwickelt und hergestellt. Die Ummantelung des Liners wurde etwa im <a href=\"https:\/\/www.3dnatives.com\/de\/kaltgasspritzen-cold-spray-120420231\/\">Kaltgasspritzverfahren<\/a> aufgedruckt und der Monoblock-Einspritzkopf wurde per <a href=\"https:\/\/www.3dnatives.com\/de\/selektives-lasersintern\/\">Lasersinter-Verfahren<\/a> gedruckt. Dieser Einspritzkopf mit all seinen Einspritzelementen wurde von EOS gefertigt.<\/p>\n<div id=\"attachment_58401\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58401\" class=\"wp-image-58401 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/ariane-6-rocket-arianegroup.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/ariane-6-rocket-arianegroup.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/ariane-6-rocket-arianegroup-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/ariane-6-rocket-arianegroup-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58401\" class=\"wp-caption-text\">(Bild: ArianeGroup)<\/p><\/div>\n<h3><strong>Skyroot Aerospace und sein 3D-gedrucktes Triebwerk<\/strong><\/h3>\n<p style=\"text-align: justify;\">Das 2018 gegr\u00fcndete indische Unternehmen <a href=\"https:\/\/www.3dnatives.com\/de\/skyroot-aerospace-3d-gedrucktes-kryo-triebwerk-140420231\/\">Skyroot Aerospace<\/a> hat es sich zum Ziel gesetzt, den Weltraum f\u00fcr alle zu \u00f6ffnen, indem es schnelle, pr\u00e4zise und erschwingliche Tr\u00e4gerraketen f\u00fcr den Weltraum anbietet. Sie hat unter ihrer Vikram-Reihe mehrere Modelle entwickelt. Was uns jedoch besonders interessiert, sind die Triebwerke dieser Raketen. Es tr\u00e4gt den Namen Dhawan und ist ein 3D-gedrucktes Teil. Es handelt sich um ein kryogenes Triebwerk, das sowohl fl\u00fcssiges Erdgas als auch fl\u00fcssigen Sauerstoff verwendet. Beide Treibstoffe ben\u00f6tigen Temperaturen von unter -150 \u00b0C, um gelagert und betrieben werden zu k\u00f6nnen. Sowohl beim Dhawan-I als auch bei der zweiten Version wurde daher die <a href=\"https:\/\/www.3dnatives.com\/de\/3d-metalldruck\/\">metallbasierte additive Fertigung<\/a> gew\u00e4hlt. Beide Triebwerke wurden erfolgreich getestet. Der Dhawan-II-Motor soll in die Vikram-II-Rakete eingebaut werden, die Ende des Jahres abheben soll.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/bjDIE-XV5VY?si=hnnpo2ibueXyczlt\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h3>Das 3D-gedruckte Hadley-Triebwerk von Ursa Major<\/h3>\n<p style=\"text-align: justify;\">Ursa Major ist ein weiteres amerikanisches Startup-Unternehmen, das durch seine Arbeit an 3D-gedruckten Raketen Aufmerksamkeit erregt hat. Zuletzt gab das Unternehmen im M\u00e4rz 2024 bekannt, dass sein teilweise 3D-gedrucktes Hadley-Triebwerk erfolgreich geflogen ist und sich Mach 5 gen\u00e4hert hat. Auch wenn nicht klar ist, welche Technologien und Materialien bei der Entwicklung des Hadley-Triebwerks zum Einsatz kamen, so wissen wir doch, dass der 3D-Druck eine wichtige Rolle spielte und dass wahrscheinlich Kupfer und <a href=\"https:\/\/www.3dnatives.com\/de\/metall-3d-drucker-deutschland-dach-hersteller-180520211\/\">Metall<\/a> im 3D-Druckverfahren hergestellt wurden, h\u00f6chstwahrscheinlich mit dem <a href=\"https:\/\/www.3dnatives.com\/de\/3ddruck-laserschmelzen\/\">Laser-Pulverbett-Verfahren<\/a>, da das Unternehmen bereits in der Vergangenheit mit EOS gearbeitet hat. Ein gro\u00dfer Meilenstein in der Nutzung des 3D-Drucks zur Herstellung von Triebwerken f\u00fcr den privaten Raumfahrtsektor!<\/p>\n<div id=\"attachment_58406\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58406\" class=\"wp-image-58406 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/hadley_fire_test.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/hadley_fire_test.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/hadley_fire_test-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/hadley_fire_test-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58406\" class=\"wp-caption-text\">Ein Hei\u00dftest des Hadley-Triebwerks (Bild: Ursa Major)<\/p><\/div>\n<h3><b>Das Detonationsraketentriebwerk <\/b><strong>(<\/strong><b>RDRE) der NASA<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Als f\u00fchrende Institution in der Raumfahrt und Flugwissenschaft setzt die NASA, welche 1958 gegr\u00fcndet wurde, immer wieder neue Ma\u00dfst\u00e4be in der Antriebstechnologie. So hat die NASA das erste rotierende Detonationsraketentriebwerk (Rotating Detonation Rocket Engine, RDRE) in Originalgr\u00f6\u00dfe mithilfe von 3D-Druck hergestellt. Zuk\u00fcnftig k\u00f6nnte das Triebwerk die Bauweise von Antriebssystemen neu definieren. Das RDRE verwendet ein fortschrittliches Antriebskonzept, bei dem Schub durch das Ph\u00e4nomen der \u00dcberschallverbrennung hergestellt wird. Dadurch kann dann eine h\u00f6here Leistung bei gleichzeitig geringerem Kraftstoffverbrauch erzielt werden. Hergestellt wurde das Triebwerk mittels <a href=\"https:\/\/www.3dnatives.com\/de\/3ddruck-laserschmelzen\/\">Powder Bed Fusion<\/a>, wobei die von der NASA entwickelte Kupferlegierung GRCop-42 zum Einsatz kam, die es dem Motor erm\u00f6glicht, auch unter extremen Bedingungen \u00fcber l\u00e4ngere Zeitr\u00e4ume hinweg zu funktionieren. Im Herbst 2023 f\u00fchrte die NASA im Marshall Space Flight Center eine Reihe von Tests durch, um zu \u00fcberpr\u00fcfen, ob der Motor den extremen Temperaturen und den typischen Anforderungen, wie der Integration einer Lambdasonde, standh\u00e4lt. Die Tests wurden erfolgreich abgeschlossen und das RDRE bietet damit das Potential, zuk\u00fcnftige Missionen zum Mond oder Mars zu unterst\u00fctzen.<\/span><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/jBWUim-rppQ?si=vo8TfeisKb491UQG\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h3>EOS und Hyperganic drucken Aerospike-Raketentriebwerk<\/h3>\n<p style=\"text-align: justify;\">2022 machten\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/eos-hyperganic-antriebskomponenten-raumfahrt-160520221\/#!\" target=\"_blank\" rel=\"noopener\">EOS und Hyperganic<\/a>\u00a0Schlagzeilen, weil es ihnen gelungen ist, mithilfe von K\u00fcnstlicher Intelligenz und 3D-Druck ein Aerospike-Raketentriebwerk mit besonders komplexem Design zu fertigen. Hyperganic, ein 2015 gegr\u00fcndetes deutsches Unternehmen, machte es mit seiner algorithmischen Konstruktionssoftware m\u00f6glich, ein von der Natur inspiriertes Design nachzubilden. Das Aerospike-Raketentriebwerk besticht daher durch sein au\u00dfergew\u00f6hnliches und hochkomplexes Design. In einem ersten Schritt wurde das Triebwerk aus einer Nickellegierung in 3D gedruckt, dabei kam die EOS M 400-4-Maschine zum Einsatz und die Legierung NickelAlloy IN718. In einem weiteren Schritt wurde das Triebwerk in gr\u00f6\u00dferem Ma\u00dfstab aus Kupfer gefertigt.<\/p>\n<div id=\"attachment_58402\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58402\" class=\"wp-image-58402 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/eos-rocket.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/eos-rocket.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/eos-rocket-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/eos-rocket-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58402\" class=\"wp-caption-text\">(Bild: EOS)<\/p><\/div>\n<h3><b>KI und 3D-Druck f\u00fcr TKL-5-Fl\u00fcssigtreibstoff-Raketenantrieb<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Durch den Einsatz von Computational Engineering und additiver Fertigung hat <a href=\"https:\/\/www.3dnatives.com\/de\/anwendung-des-monats-leap-71-raketenantrieb-100720241\/\">LEAP 71<\/a>, ein in Dubai ans\u00e4ssiges Unternehmen, bedeutende Fortschritte in der Raumfahrttechnologie erzielt. Denn das Unternehmen hat mittels der KI-basierten Software Noyron ein Raketentriebwerk entwickelt. Ziel des Projekts war es, die F\u00e4higkeiten der Noyron-Software zu demonstrieren, welche es erm\u00f6glichte, das TKL-5-Raketentriebwerk vollst\u00e4ndig digital und ohne menschlichen Eingriff zu entwerfen und zu produzieren. Aufgrund der <a href=\"https:\/\/www.3dnatives.com\/de\/projekte-3d-druck-und-ki-220220241\/\">KI-Algorithmen<\/a> war keine <a href=\"https:\/\/www.3dnatives.com\/de\/top-10-cad-software-fuer-jedes-niveau\/\">CAD<\/a>-Konstruktion erforderlich, was die gesamte Produktion des Triebwerks auf nur zwei Wochen optimierte. Produziert wurde das Triebwerk von AMCM auf einem EOS M290 3D-Drucker aus Kupfer, was in Kombination mit aktiver K\u00fchlung zu einem leistungsf\u00e4higen Antrieb f\u00fchrte. Anschlie\u00dfend erfolgte die Nachbearbeitung durch das &#8222;Race to Space&#8220;-Team der Universit\u00e4t Sheffield und erfolgreich getestet wurde das Triebwerk auf dem Gel\u00e4nde von Airborne Engineering. Dort erreichte es eine Schubkraft von 20.000 PS und eignet sich somit ideal f\u00fcr den Einsatz in Orbitalraketen. LEAP 71 sieht in diesem 3D-gedruckten Raketenantrieb das Potential, das Innovationstempo in der Raumfahrt zu beschleunigen sowie die bessere Erreichbarkeit des Weltraums.<\/span><\/p>\n<div id=\"attachment_58393\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58393\" class=\"wp-image-58393 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/LEAP-71-engine.jpg\" alt=\"3D-gedruckte Raketen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/LEAP-71-engine.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/LEAP-71-engine-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/LEAP-71-engine-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58393\" class=\"wp-caption-text\">(Bild: LEAP 71)<\/p><\/div>\n<h3 style=\"text-align: justify;\"><strong>Die Rakete Orbex Prime<\/strong><\/h3>\n<p style=\"text-align: justify;\">Das britische Luft- und Raumfahrtunternehmen Orbex hat die kohlenstoffarme und leistungsstarke Rakete Orbex Prime entwickelt. Die Rakete wurde mit dem SLM800 <a href=\"https:\/\/www.3dnatives.com\/de\/ubersicht-hersteller-metall-3d-druck\/\">Metall-3D-Drucker<\/a> von Nikon SLM Solutions hergestellt. Prime wird mit einem zu 100 % erneuerbaren Treibstoff, Biopropan, betrieben, der die CO2-Emissionen um 90 % reduzieren kann. Dar\u00fcber hinaus ist die Rakete so konzipiert, dass sie wiederverwendbar ist, indem sie ein R\u00fcckholsystem enth\u00e4lt, das ebenfalls so programmiert ist, dass keine Tr\u00fcmmer in der Erdumlaufbahn zur\u00fcckbleiben. Prime wurde 2022 im Vereinigten K\u00f6nigreich zum ersten Mal der \u00d6ffentlichkeit vorgestellt.<\/p>\n<div id=\"attachment_58394\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58394\" class=\"wp-image-58394 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/orbex.jpg\" alt=\"3D-gedruckte Raketen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/orbex.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/orbex-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/orbex-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58394\" class=\"wp-caption-text\">(Bild: Orbex)<\/p><\/div>\n<h3>Die Terran 1 und Terran R 3D-gedruckte Raketen von Relativity Space<\/h3>\n<p style=\"text-align: justify;\">Wer hat noch nicht von Relativity Space geh\u00f6rt? Das kalifornische Unternehmen hat sich seit seiner Gr\u00fcndung im Jahr 2015 schnell einen Namen gemacht und arbeitet an seinem Ziel, eine vollst\u00e4ndig 3D-gedruckte Rakete zu entwickeln. Und es ist fast soweit! Terran 1, die erste Rakete des Unternehmens, wurde im M\u00e4rz 2023 erfolgreich gestartet, obwohl sie die Umlaufbahn nicht erreichte. Diese Rakete wurde fast vollst\u00e4ndig mit DED und Laser-Pulverbettfusion in 3D gedruckt und war zum Zeitpunkt ihres Starts die h\u00f6chste jemals gebaute 3D-gedruckte Metallstruktur. Jetzt setzt das Unternehmen seine Arbeit mit der Terran R fort, die voraussichtlich zu 90 % in 3D gedruckt wird und 20 Mal mehr Nutzlast tragen kann als ihr Vorg\u00e4nger. Die Terran R wird ab 2026 vom Startkomplex 16 auf der Cape Canaveral Space Force Base starten und damit direkt in die Zukunft der Weltraumforschung fliegen.<\/p>\n<div id=\"attachment_58414\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58414\" class=\"wp-image-58414 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/terran_r-1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/terran_r-1.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/terran_r-1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/terran_r-1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58414\" class=\"wp-caption-text\">(Bild: Relativity Space)<\/p><\/div>\n<h3 style=\"text-align: justify;\"><strong>Navier, das franz\u00f6sische Triebwerk, das mit additiver Fertigung hergestellt wird<\/strong><\/h3>\n<p style=\"text-align: justify;\">Latitude (ehemals Venture Orbital Systems) ist ein franz\u00f6sisches Startup-Unternehmen, das sich auf die Entwicklung von Mikrotr\u00e4gern spezialisiert hat. Sein erstes Modell ist der Zephyr, der 19 Meter lang ist und einen Durchmesser von 1,5 m hat. Er ist mit einem Motor ausgestattet, der durch 3D-Metalldruck &#8211; genauer gesagt durch Laserschmelzen auf einem Pulverbett &#8211; hergestellt wird. Er hei\u00dft Navier, ist 45 Zentimeter hoch und wiegt 30 Kilogramm bei einer Schubkraft von 1,2 Tonnen. Er wurde aus Inconel 718 auf einer SLM 500-Maschine in nur wenigen Tagen hergestellt. Anfang 2023 war Latitude die Z\u00fcndung von Navier gelungen, ein gro\u00dfer Schritt f\u00fcr das in Reims ans\u00e4ssige Startup.<\/p>\n<div id=\"attachment_58395\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58395\" class=\"wp-image-58395 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Rocket_Navier.jpg\" alt=\"3D-gedruckte Raketen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Rocket_Navier.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Rocket_Navier-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Rocket_Navier-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58395\" class=\"wp-caption-text\">(Bild: Latitude)<\/p><\/div>\n<h3><strong>Der Rutherford-Motor von Rocket Lab<\/strong><\/h3>\n<p style=\"text-align: justify;\">Das kalifornische <a href=\"https:\/\/www.3dnatives.com\/de\/rocket-lab-rakete-test-230520171-2\/\">Startup Rocket Lab<\/a>, ein privates Luftfahrtunternehmen, entwickelte die weltweit erste batteriebetriebene Rakete, die Electron-Rakete, welche 2017 erfolgreich ihren ersten Start mit einem 3D-gedruckten Rutherford-Motor absolvierte. Der Motor ist nach dem neuseel\u00e4ndischen Wissenschaftler Ernest Rutherford benannt und zu den 3D-gedruckten Komponenten geh\u00f6ren die Schubkammer, zwei Pumpen, der Injektor und die Haupttreibstoffventile. F\u00fcr den ersten Flug nutzte Rocket Lab ein zehnt\u00e4giges Startfenster, um die Rakete von der Mahia-Halbinsel in Neuseeland zu starten. Bei dem zweiten Flug, der 2018 stattfand, handelte es sich um einen orbital Raumflug. Nach diesem beschloss das Unternehmen, in den kommerziellen Betrieb zu gehen. Durch den Einsatz der additiven Fertigung bei der Herstellung des Rutherford-Motors konnten Zeit und Gewicht eingespart werden, was in der Luft- und Raumfahrt von Wichtigkeit ist und auch weiterhin m\u00f6chte das Unternehmen Raketen herstellen, welche Satelliten in den Weltraum bef\u00f6rdern.<\/p>\n<div id=\"attachment_58396\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58396\" class=\"wp-image-58396 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/rocket-lab-engine.jpg\" alt=\"3D-gedruckte Raketen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/rocket-lab-engine.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/rocket-lab-engine-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/rocket-lab-engine-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58396\" class=\"wp-caption-text\">(Bild: Rocket Lab)<\/p><\/div>\n<h3>Eine Brennkammer aus dem 3D-Drucker<\/h3>\n<p style=\"text-align: justify;\">OPUS Aerospace ist ein weiteres franz\u00f6sisches Unternehmen, das sich auf die Entwicklung von Tr\u00e4gerraketen und Raumfahrzeugen spezialisiert hat. Sie hat zwei verschiedene Tr\u00e4gerraketen entwickelt, Mesange und Sterne. Die erste ist in Wirklichkeit der Demonstrator des franz\u00f6sischen Start-ups. Mesange soll als Test dienen und den Weg f\u00fcr Sterne ebnen. In beiden F\u00e4llen enth\u00e4lt die Tr\u00e4gerrakete den Torgos-Motor, dessen Brennkammer in einem einzigen Arbeitsgang aus 3D-Metall gedruckt wurde. Der Start von Mesange ist f\u00fcr 2024 von Franz\u00f6sisch-Guayana aus geplant und wird somit die Sterne-Tr\u00e4gerrakete weiterentwickeln.<\/p>\n<div id=\"attachment_58397\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58397\" class=\"wp-image-58397 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/OPUS.jpg\" alt=\"3D-gedruckte Raketen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/OPUS.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/OPUS-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/OPUS-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58397\" class=\"wp-caption-text\">(Bild: OPUS Aerospace)<\/p><\/div>\n<h3>Stoke Space druckt Brennkammern f\u00fcr wiederverwendbare Raketen<\/h3>\n<p style=\"text-align: justify;\">Das amerikanische Unternehmen Stoke Space bietet mit NOVA eine vollst\u00e4ndig wiederverwendbare Rakete f\u00fcr t\u00e4gliche Fl\u00fcge ins All. Um dies zu erreichen, setzt das Unternehmen auch auf den 3D-Druck. Stoke Space druckt Brennkammern aus Kupfer, um die Kammern einerseits schnell zu drucken, und andererseits die Wiederverwendbarkeit zu erm\u00f6glichen. Die Kupferlegierung der Brennkammern ist n\u00e4mlich besonders leitf\u00e4hig und kann daher wiederverwendet werden. Die Brennkammern weisen aufgrund der regenerativen K\u00fchlkan\u00e4le gebogene Verteilerrohre und innen liegende Hohlr\u00e4ume auf. AM macht es aber m\u00f6glich, dieses komplexe Design umzusetzen. Das in Seattle ans\u00e4ssige Unternehmen testet seine Entwicklungen im nahe gelegenen Moses Lake.<\/p>\n<div id=\"attachment_58403\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58403\" class=\"wp-image-58403 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Stoke-Space-rocket.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Stoke-Space-rocket.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Stoke-Space-rocket-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Stoke-Space-rocket-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58403\" class=\"wp-caption-text\">(Bild: Stoke Space)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Wie finden Sie 3D-gedruckte Raketen und was hat Ihnen am besten gefallen? <span data-contrast=\"none\">Lassen Sie uns dazu einen Kommentar da, oder teilen Sie es uns auf<\/span>\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\"><span data-contrast=\"none\">Facebook<\/span><\/a><span data-contrast=\"none\">\u202foder\u202f<\/span><a href=\"https:\/\/www.linkedin.com\/groups\/13502336\/\"><span data-contrast=\"none\">LinkedIN\u00a0<\/span><\/a><span data-contrast=\"none\">mit. M\u00f6chten Sie au\u00dferdem eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der Additiven Fertigung direkt und bequem in Ihr Postfach erhalten? Dann registrieren Sie sich jetzt f\u00fcr unseren\u202f<\/span><a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\"><span data-contrast=\"none\">w\u00f6chentlichen Newsletter<\/span><\/a><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit der Mondlandung im Jahr 1969 hat die Menschheit nie aufgeh\u00f6rt, nach den Sternen zu greifen. Was sich jedoch ge\u00e4ndert hat, sind die Mittel, um dorthin zu gelangen. Seit Apollo 11 haben sich die Raketen stark ver\u00e4ndert. Innovation ist das&hellip;<\/p>\n","protected":false},"author":6112,"featured_media":58391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,153,34],"tags":[],"class_list":["post-58390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-luft-und-raumfahrt","category-rankings"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/58390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6112"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=58390"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/58390\/revisions"}],"predecessor-version":[{"id":58416,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/58390\/revisions\/58416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/58391"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=58390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=58390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=58390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}