{"id":56859,"date":"2024-07-03T13:00:11","date_gmt":"2024-07-03T11:00:11","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=56859"},"modified":"2025-03-03T13:50:12","modified_gmt":"2025-03-03T12:50:12","slug":"hand-gemacht-ueber-3d-gescannte-objekte-die-geschichten-erzaehlen-030720241","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/hand-gemacht-ueber-3d-gescannte-objekte-die-geschichten-erzaehlen-030720241\/","title":{"rendered":"hand.gemacht \u00fcber 3D-gescannte Objekte, die Geschichten erz\u00e4hlen"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Das Projekt hand.gemacht wurde am 1. Juli 2022 ins Leben gerufen und erweitert mithilfe der <a href=\"https:\/\/www.3dnatives.com\/de\/10-gruende-warum-3d-scannen-nuetzlich-ist-180620241\/\">3D-Scantechnologie<\/a> die M\u00f6glichkeiten<\/span><span style=\"font-weight: 400;\"> im Kulturbereich. Im Fokus stehen handgefertigte Objekte, die einen Bezug zur Oberpfalz haben und interessante Geschichten erz\u00e4hlen. Mittels <a href=\"https:\/\/www.3dnatives.com\/de\/category\/3d-scanner\/\">3D-Scans<\/a> werden virtuelle Abbilder dieser Objekte erstellt, die f\u00fcr verschiedene Zwecke und Angebote genutzt werden k\u00f6nnen. Das <a href=\"https:\/\/www.3dnatives.com\/de\/die-spannendsten-biomimetik-3d-druck-projekte-200620241\/\">Projekt<\/a> dient somit als Ged\u00e4chtnistr\u00e4ger, der Forschern und Interessierten zur Verf\u00fcgung steht. Zudem hat jeder die M\u00f6glichkeit, sich an diesem musealen Sammlungsprozess zu beteiligen. <\/span><span style=\"font-weight: 400;\">Aktuell wird daran gearbeitet, die erhobenen Daten zu kuratieren und in einer speziell entwickelten Web-App mit Sammlungs- und Modellansichten zu pr\u00e4sentieren. Ziel ist es, die Hintergr\u00fcnde und Verkn\u00fcpfungen der Gegenst\u00e4nde aufzuzeigen und ihre individuellen Geschichten zu erz\u00e4hlen.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: K\u00f6nnten Sie sich kurz vorstellen und erz\u00e4hlen, wie es zu der Idee des Projekts hand.gemacht kam?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Wir sind Michaela Stauber und Julian Moder, Projektleiter und wissenschaftliche Mitarbeiter im Forschungsprojekt hand.gemacht. Das Projekt selbst wurde \u00fcber einen F\u00f6rderantrag an das Bayerische Staatsministerium der Finanzen und f\u00fcr Heimat ins Leben gerufen. Die F\u00f6rderrichtlinie \u201eHeimat-Digital-Regional\u201c des Ministeriums hat das Ziel, regionale Kultur durch digitale Projekte zu unterst\u00fctzen und sichtbar zu machen. <\/span><span style=\"font-weight: 400;\">Mit hand.gemacht gehen wir diesem Ziel insofern nach, als wir die Kreativit\u00e4t und den Erfindergeist der Oberpf\u00e4lzer in Form von <a href=\"https:\/\/www.3dnatives.com\/de\/experteninterview-3d-scanner-170520171\/\">3D-gescannten<\/a> Objekten sammeln. Dabei interessiert uns vor allem, wie und weshalb ein Objekt hergestellt wurde und welche Geschichte daran h\u00e4ngt. Unser Anliegen ist es nicht zuletzt, solchen Gegenst\u00e4nden Aufmerksamkeit zu schenken, die auf den ersten Blick eher unscheinbar oder unwichtig wirken und weniger in <a href=\"https:\/\/www.3dnatives.com\/de\/der-einsatz-des-3d-drucks-in-der-welt-der-kunst-080320221\/\">Museen<\/a> zu finden sind. Ganz untypisch f\u00fcr\u00a0 Sammlungsprozesse geht das Objekt nach der Erhebung \u00fcbrigens direkt wieder an seinen Besitzer. Dadurch kann der Gegenstand weiter \u201ebelebt\u201c werden und vielleicht, in seiner Zukunft, noch einmal von uns aufgenommen werden.<\/span><\/p>\n<div id=\"attachment_56862\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56862\" class=\"wp-image-56862 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/HG-TEAM.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/HG-TEAM.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/HG-TEAM-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/HG-TEAM-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-56862\" class=\"wp-caption-text\">Julian Moder und Michaela Stauber von Projekt hand.gemacht. (Bild: hand.gemacht)<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Welche Personen, Einrichtungen etc. reichen Objekte bei Ihnen ein und um welche Objekte handelt es sich zum Gro\u00dfteil?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Die Menschen hinter unseren gesammelten Objekten sind meist Privatpersonen. Zu den h\u00e4ufigsten Gr\u00fcnden, weshalb diese Menschen auf uns zukommen, geh\u00f6ren Stolz auf das eigene Werk und der Wunsch, die Familiengeschichte und Erinnerung an Angeh\u00f6rige festzuhalten. Ein wichtiger Faktor ist auch unsere innovative Sammlungsstrategie. Sie erlaubt es dem Objekt, eine Art \u201eDoppelleben\u201c zu f\u00fchren. Es kehrt nach der digitalen Reproduktion als Original in das Leben der Besitzer zur\u00fcck und nimmt gleichzeitig, als digitales Abbild, eine Rolle als Denkmal und Kommunikationsmedium ein. F\u00fcr viele ist das ein Weg, die eigene Handarbeit oder die Erinnerung an einen Menschen zu w\u00fcrdigen, ohne dabei einen emotional wertvollen Ged\u00e4chtnistr\u00e4ger hergeben zu m\u00fcssen. Die Hemmschwelle, den selbst hergestellten Gegenstand oder das Familienerbst\u00fcck an ein Museum abzugeben, ist oft hoch. Es besteht eben h\u00e4ufig eine starke emotionale Bindung dazu. Au\u00dferdem erfassen wir aber auch Objekte, die von Vereinen \u2013 oft im Rahmen von Br\u00e4uchen und Festen \u2013 selbst gemacht werden, denn derlei Gegenst\u00e4nde und ihre Hintergr\u00fcnde sind in der Regel wenig dokumentiert. Wir bieten die M\u00f6glichkeit, solche Objekte vor dem Vergessen zu bewahren, und machen sie zu einem Sprachrohr f\u00fcr Oberpf\u00e4lzer Kultur.<\/span><\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-1379349256\"><div id=\"dnati-4130333117\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<h3 style=\"text-align: justify;\">3DN: Wie w\u00e4hlen Sie dann die Objekte aus, die digitalisiert werden und welche interessanten Objekte haben Sie bisher 3D-gescannt?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">R\u00e4umlich gesehen begrenzen wir uns aus der F\u00f6rderrichtlinie heraus, aber auch aus logistischen Gr\u00fcnden, auf die Oberpfalz. Eine Verbindung des Objekts in die Region ist ausschlaggebend. Dabei ist es aber nicht wichtig, ob der Gegenstand hier erstellt wurde, denn gerade auch Mitgebrachtes, beispielsweise im Zuge von Migration, birgt spannende Erz\u00e4hlungen. Zeitlich sammeln wir ungef\u00e4hr 80 Jahre in die Vergangenheit bis in die Gegenwart. Das macht es wahrscheinlich, dass die Erinnerungen und Geschichten noch im kommunikativen Ged\u00e4chtnis verankert sind oder von Zeitzeugen selbst stammen. Die handgemachten Gegenst\u00e4nde m\u00fcssen zudem aus informeller Herstellung stammen. Das bedeutet, sie sind nicht f\u00fcr kommerzielle Zwecke und nicht in hoher St\u00fcckzahl erstellt worden. Der klassische <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-kunst-300620161\/\">Kunsthandwerksmarkt<\/a> ist f\u00fcr uns weniger interessant. Dort fehlen die Geschichten, Erinnerungen und individuellen Motivationen zur Herstellung und zum Gebrauch der Gegenst\u00e4nde. Da es sich bei allen Objekten in unserer Sammlung um selbstgemachte Dinge handelt, gibt es so gut wie immer spannende Aspekte. Mal ist der Gegenstand selbst oder die handwerkliche Umsetzung sehr ausgefallen, ein anderes Mal ist die Motivation oder eine mit dem Objekt verkn\u00fcpfte Erinnerung faszinierend.<\/span><\/p>\n<div id=\"attachment_56865\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56865\" class=\"wp-image-56865 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/compressed-Schneidem.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/compressed-Schneidem.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/compressed-Schneidem-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/compressed-Schneidem-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-56865\" class=\"wp-caption-text\">Der Scan einer alten Tabakschneidemaschine. (Bild: hand.gemacht)<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Wir sammeln Gegenst\u00e4nde, die bis zu ca. 80 Jahre alt sind. Aber auch neue Dinge finden sich in unserer Sammlung. Dadurch konnten wir schnell Verbindungen zwischen den Objekten und Menschen zu unterschiedlichen Zeiten und Umst\u00e4nden ausmachen. Ein alter Spiegelrahmen, welcher in einem Lazarett w\u00e4hrend oder kurz nach dem ersten Weltkrieg gefertigt wurde, entstand aus einer \u00e4hnlichen Motivation heraus wie ein Dirndl, das w\u00e4hrend der Corona-Pandemie von einem Musiker gefertigt wurde. In diesen F\u00e4llen suchte man einen sinnvollen Zeitvertreib w\u00e4hrend einer Phase extremer Unterbesch\u00e4ftigung und Langeweile. Ein weiteres oft aufkommendes Thema ist Ressourcenknappheit \u2013 man denke an die Nachkriegszeit des Zweiten Weltkriegs, in der zum Beispiel ein Ofen aus alten Wehrmachtsbest\u00e4nden selbst gefertigt wurde, und die <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-covid-19-301220201\/\">Corona-Pandemie<\/a> mit selbstgebauten T\u00fcr\u00f6ffnern oder selbstgen\u00e4hten Masken. Aus den von uns gesammelten Gegenst\u00e4nden und Kontexten l\u00e4sst sich viel \u00fcber den Umgang mit Material und Objekten zu Krisenzeiten herauslesen. Andere Objekte wiederum erz\u00e4hlen uns mehr \u00fcber Br\u00e4uche und Traditionen, <a href=\"https:\/\/www.3dnatives.com\/de\/umwelt-3ddruck-21012016\/\">Nachhaltigkeit<\/a> und <a href=\"https:\/\/www.3dnatives.com\/de\/recycling-fuer-den-3d-druck-projekte-im-dienste-unseres-planeten-180320221\/\">Recycling<\/a> oder DIY-<a href=\"https:\/\/www.3dnatives.com\/de\/trends-additiven-fertigung-grosse-bauteile-und-spezifische-materialien-160620241\/\">Trends<\/a>.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: Welche 3D-Scanner benutzen Sie und welchen Schwierigkeiten begegnen Sie beim Scannen?<\/h3>\n<p style=\"text-align: justify;\">Da wir als Projektteam sehr flexibel an unterschiedlichen Orten scannen m\u00fcssen, war die Wahl eines Scanger\u00e4ts recht fr\u00fch gekl\u00e4rt. Der <a href=\"https:\/\/www.3dnatives.com\/de\/test-3d-scanner-artec-leo-150320211\/\">Artec Leo HD<\/a> ist durch seine Mobilit\u00e4t, einfache Bedienung von Hard- und <a href=\"https:\/\/www.3dnatives.com\/de\/category\/3d-software\/\">Software<\/a> und Genauigkeit schnell zum Favoriten avanciert. Niedrige Scanzeiten erm\u00f6glichen es uns, unterwegs gleichzeitig die kulturwissenschaftlichen Interviews zu f\u00fchren und die Objekte zu digitalisieren. So sind externe Termine f\u00fcr uns meist innerhalb von wenigen Stunden erledigt.<\/p>\n<p style=\"text-align: justify;\">Unser zweiter Scanner deckt im Gegensatz dazu ganz andere Anforderungen ab. Der Botspot Botscan Momentum erm\u00f6glicht uns ein repetitives Scannen bei einer immer gleichbleibenden Umgebung. Der Scanner arbeitet, anders als der Artec Leo, ausschlie\u00dflich mit <a href=\"https:\/\/www.3dnatives.com\/de\/photogrammetrie-200520221\/\">Photogrammetrie<\/a>, und zwar in einer geschlossenen Kammer mit polarisiertem Licht. Das ist beispielsweise beim Scan eines geschnitzten Schachsets mit vielen einzelnen Elementen ein unschlagbarer Vorteil. Die beiden Ger\u00e4te erg\u00e4nzen sich wunderbar durch das abgedeckte Spektrum an Objektgr\u00f6\u00dfen. In der Kammer des Botspots k\u00f6nnen Objekte bis zu einem Kantenma\u00df von 40 cm erfasst werden, aber eben auch sehr kleine Geometrien. Zusammen mit dem Artec Leo k\u00f6nnen wir alle Objektgr\u00f6\u00dfen bis zu mehreren Metern Kantenl\u00e4nge digitalisieren<\/p>\n<div id=\"attachment_56866\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56866\" class=\"wp-image-56866 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Kammer-HG.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Kammer-HG.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Kammer-HG-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Kammer-HG-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-56866\" class=\"wp-caption-text\">Die beleuchtete Kammer des Botspot Botscan Momentum. (Bild: hand.gemacht)<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Die \u00fcblichen Schwierigkeiten beim <a href=\"https:\/\/www.3dnatives.com\/de\/top10-low-cost-3d-scanner-191020161\/\">Scannen<\/a> bereiten Transparenzen, Reflexionen, flexible <a href=\"https:\/\/www.3dnatives.com\/de\/category\/materialien\/\">Materialien<\/a> wie Stoffe oder leicht bewegliche Teile. Dunkle Kontraste, komplexe Geometrien und sehr tiefe Aush\u00f6hlungen sind ebenfalls schwierig zu scannen. Hinzu kommt in unserem Fall der Verzicht auf die Behandlung mit Sprays zur Reflexionsminderung. Aber diese Ph\u00e4nomene lassen sich alle durch die eingesetzte <a href=\"https:\/\/www.3dnatives.com\/de\/3d-technologies\/\">Technologie<\/a> erkl\u00e4ren.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Eine ganz andere Herausforderung ist es, der riesigen Varianz an unterschiedlichen Objekten Herr zu werden. Jeder Gegenstand, der von uns im Projekt erhoben wird, bedarf einer \u00dcberlegung, mit welchem <a href=\"https:\/\/www.3dnatives.com\/de\/top10-low-cost-3d-scanner-191020161\/\">Ger\u00e4t<\/a> gescannt wird, welche Orientierung das Objekt haben soll, wie man an schwierige Stellen kommt, wie man mit beweglichen Teilen oder Einzelteilen umgeht. Wie zuvor beschrieben, sind die von uns gescannten Objekte emotional wertvoll f\u00fcr die Objektgeber. Wir m\u00fcssen also mit entsprechender Vorsicht agieren.<\/span><\/p>\n<h3 style=\"text-align: justify;\">3DN: K\u00f6nnten Sie den Prozess der Aufbereitung und Digitalisierung n\u00e4her erl\u00e4utern?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Wir teilen die Nachbearbeitung der Scans und der kulturwissenschaftlichen Daten in verschiedene Phasen auf: Datenaufbereitung, <a href=\"https:\/\/www.3dnatives.com\/de\/10-gruende-fuer-nachbearbeitung-3d-druck-230420241\/\">Nachbearbeitung<\/a>, Katalogisierung, Kuration, virtuelle Aufbereitung und Ver\u00f6ffentlichung.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"> Die rohen Scandaten bestehen aus Punktwolken und zugeordneten Texturen. Diese m\u00fcssen zun\u00e4chst bereinigt, dann aufeinander ausgerichtet und schlie\u00dflich zu mehreren Modellen, in verschiedenen Detailstufen, verrechnet und texturiert werden. Danach richten wir die Objekte aus. Ein stehender Spiegel sieht in einem 3D-Viewer wesentlich interessanter aus als ein liegender. Animationen, kleine Korrekturen oder \u00e4hnliche Arbeiten werden ebenfalls in diesem Schritt erledigt. Die Modelle werden anschlie\u00dfend in einer Datenbank weiter f\u00fcr die Nutzung in einer Webapp vorbereitet. Um die Geschichte eines Objekts erz\u00e4hlen zu k\u00f6nnen, m\u00fcssen wir die gef\u00fchrten Interviews transkribieren, interessante Informationen ausw\u00e4hlen, diese zu Texten umschreiben und die Inhalte an hervorgehobenen Punkten am Modell platzieren. Es ist also ein langer Weg vom Original bis zum virtuellen Ged\u00e4chtnistr\u00e4ger.<\/span><\/p>\n<div id=\"attachment_56869\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56869\" class=\"wp-image-56869 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/SCAN-HG.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/SCAN-HG.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/SCAN-HG-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/SCAN-HG-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-56869\" class=\"wp-caption-text\">Der 3D-Scan mit dem Artec Leo. (Bild: hand.gemacht)<\/p><\/div>\n<h3 style=\"text-align: justify;\">3DN: Haben Sie noch abschlie\u00dfende Worte an unsere Leserschaft?<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Was unser Forschungsprojekt antreibt und \u00fcberhaupt erst m\u00f6glich macht, ist das Interesse der Menschen daran, ihre Geschichte(n) festzuhalten und weiter zu erz\u00e4hlen. Gegenst\u00e4nde waren dabei schon immer ein wesentlicher Faktor, ob als Tr\u00e4ger von Erinnerung oder mit ganz eigenen narrativen Eigenschaften. Der gro\u00dfe Versuch, den wir mit hand.gemacht unternehmen, ist es, eine relativ unterrepr\u00e4sentierte Gruppe von Objekten zu sammeln und sie gleichzeitig als Original in ihrem Gebrauchskontext zu belassen. Dabei legen wir den inhaltlichen Fokus auf die Beziehung zwischen Mensch und Objekt. Diese Verbindung von Mensch, Gegenstand, Kultur und Geschichte kommunizieren wir durch eine moderne und innovative virtuelle Umgebung, um r\u00fcckwirkend ein Kulturbewusstsein in der Oberpfalz zu st\u00e4rken. Wir freuen uns nat\u00fcrlich, dass unsere Forschungsarbeit so viel Interesse weckt und auch in der 3D Community Anklang findet. Gerade befinden wir uns in einer sehr spannenden Phase. In den n\u00e4chsten Wochen wird unsere Website enth\u00fcllt, die Webapp soll planm\u00e4\u00dfig in wenigen Monaten in eine Testphase gehen. In der Zwischenzeit k\u00f6nnt ihr uns gerne auf <a href=\"https:\/\/www.instagram.com\/projekt_hand.gemacht\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a> oder <a href=\"https:\/\/www.facebook.com\/profile.php?id=100088442624617\" target=\"_blank\" rel=\"noopener\">Facebook<\/a> folgen. Mehr \u00fcber das Projekt und Kontaktdaten finden Sie <a href=\"https:\/\/www.freilandmuseum-oberpfalz.de\/das-oberpfaelzer-freilandmuseum\/projekt-hand-gemacht\" target=\"_blank\" rel=\"noopener\">HIER<\/a>.<\/span><\/p>\n<p style=\"text-align: justify;\">Was halten Sie von dem Projekt hand.gemacht? Lassen Sie uns zu diesem Thema gerne einen Kommentar da oder teilen Sie es uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>, oder\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\/\">LinkedIN<\/a>\u00a0mit. M\u00f6chten Sie au\u00dferdem eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach erhalten? Dann registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>!<\/p>\n<p><em>*Bildnachweise: hand.gemacht<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Projekt hand.gemacht wurde am 1. Juli 2022 ins Leben gerufen und erweitert mithilfe der 3D-Scantechnologie die M\u00f6glichkeiten im Kulturbereich. Im Fokus stehen handgefertigte Objekte, die einen Bezug zur Oberpfalz haben und interessante Geschichten erz\u00e4hlen. Mittels 3D-Scans werden virtuelle Abbilder&hellip;<\/p>\n","protected":false},"author":6112,"featured_media":56868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[14,49,10,256],"tags":[],"class_list":["post-56859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3d-scanner","category-aktuelles","category-interviews","category-projekte"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/56859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6112"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=56859"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/56859\/revisions"}],"predecessor-version":[{"id":61743,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/56859\/revisions\/61743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/56868"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=56859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=56859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=56859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}