{"id":5244,"date":"2017-04-28T00:02:30","date_gmt":"2017-04-27T22:02:30","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=5244"},"modified":"2017-12-11T15:08:34","modified_gmt":"2017-12-11T14:08:34","slug":"startup-des-monats-biomodex-280420171","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/startup-des-monats-biomodex-280420171\/","title":{"rendered":"Startup des Monats: BIOMODEX und der 3D-Druck von Organen"},"content":{"rendered":"<p style=\"text-align: justify;\">Der 3D-Druck hat in den letzten Jahren viele interessante Startups hervorgebracht, aus denen zum Teil sehr erfolgreiche Firmen wurden. Jeden Monat gibt es hier auf 3Dnatives das Startup des Monats, eine Rubrik f\u00fcr die interessanten Ideen, Entwicklungen und Innovationen in allen Facetten der Branche. Das Startup f\u00fcr den M\u00e4rz war ONO mit ihrem Mini-3D-Drucker, der nur durch ein Smartphone und dessen Display funktioniert. F\u00fcr diesen Monat haben wir eine Firma, die sich in einem ganz anderen Bereich spezialisiert hat: BIOMODEX revolutioniert die chirurgische Welt. Nachdem die beiden Gr\u00fcnder realisiert haben, dass Fehler in medizinischen Eingriffen die dritth\u00e4ufigste Todesursache in den USA ist, haben\u00a0sie sofort nach einer L\u00f6sung f\u00fcr dieses Problem gesucht. Herausgekommen ist ein Startup, welches den 3D-Druck nutzt, um reale Organmodelle zum Training von Chirurgen herzustellen und somit das Risiko eines Fehlers w\u00e4hrend der OP reduziert. Wir haben den Mitbegr\u00fcnder Thomas Marchand getroffen und mehr \u00fcber das Startup erfahren.<\/p>\n<h4 style=\"text-align: justify;\">K\u00f6nnen Sie uns BIOMODEX kurz vorstellen?<\/h4>\n<div id=\"attachment_5249\" style=\"width: 209px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5249\" class=\"wp-image-5249\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio1-1.jpg\" alt=\"biomodex\" width=\"199\" height=\"165\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio1-1.jpg 314w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio1-1-160x132.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio1-1-300x248.jpg 300w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><p id=\"caption-attachment-5249\" class=\"wp-caption-text\">Thomas Marchand<\/p><\/div>\n<p style=\"text-align: justify;\">Wir sind ein franz\u00f6sische Startup aus Paris und Boston zur Entwicklung von synthetischen Organen, die von Patienten abgebildet und anschlie\u00dfend 3D gedruckt werden.\u00a0Heutzutage ist ein Training unter realen Bedingungen zwingend notwendig, mit BIOMODEX k\u00f6nnen sich die \u00c4rtze auf bestimme Eingriffe\u00a0pr\u00e4operativ vorbereiten. Dieses Projekt ist aus einem Treffen mit meinem Mitbegr\u00fcnder Sidarth Radjou entstanden, da er sich damit besch\u00e4ftigt hat, die Tomografie (bzw. Bildaufzeichnung) von Organen f\u00fcr den 3D-Druck zu verbessern. Ich selbst habe zu diesem Zeitpunkt an meiner Masterarbeit mit folgendem Thema gearbeitet:\u00a0&#8222;3D-Druck in der Gesundheitsindustrie, welche M\u00f6glichkeiten gibt es?&#8220;. 15 Tage nach unserem Treffen war unsere Zusammenarbeit selbstverst\u00e4ndlich.<\/p>\n<h4 style=\"text-align: justify;\">Was ist Ihre Rolle bei BIOMODEX und die Verbindung zum 3D-Druck<\/h4>\n<p style=\"text-align: justify;\">Unsere Aufgabe ist es, das chirurgische Training in zweierlei Hinsicht zu verbessern: Bei der\u00a0einen Achse unserer Arbeit\u00a0m\u00fcssen wir Organe, wie zum Beispiel ein Ohr, und deren komplexe Anatomie (Geh\u00f6rknochen bzw. inneres Ohr)\u00a0sowie m\u00f6gliche Traumata (Fraktionen) reproduzieren. Das bietet\u00a0eine echte Alternative im Vergleich zu chirurgischen Szenarios\u00a0die ungenau und nicht zufriedenstellend sind, das sind vor allem Tranings an Patienten oder anatomischen K\u00f6rperteilen von toten Menschen bzw. Tieren, welche ebenfalls ethische Probleme hervorrufen.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5250\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio2.jpg\" alt=\"biomodex\" width=\"620\" height=\"330\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio2.jpg 620w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio2-600x319.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio2-160x85.jpg 160w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\">Die andere Achse stellt die Entwicklung von pr\u00e4operativen Trainings dar. \u00dcber eine Webplattform kann der behandelnde Arzt medizinische Bilder von Scannern, MRT (Magnetresonanztomografie) oder Ultraschall hochladen. Einige Tage sp\u00e4ter erh\u00e4lt das Krankenhaus\u00a0dann das synthetische Organ von BIOMODEX mit dem er trainieren, die richtige Herangehensweise ausprobieren und die korrekte Behandlung bzw. Prothese (in Bezug auf Gr\u00f6\u00dfe und Position) finden kann. Aufgrund der gesundheitlichen Vorteile f\u00fcr die Patienten\u00a0setzen wir uns enorm f\u00fcr die personalisierte Medizin ein und hoffen, die Risiken bei einer OP wesentlich zu minimieren.<\/p>\n<p style=\"text-align: justify;\">Im kommenden Jahr planen wir 1.000 synthetische Organe zu drucken, haupts\u00e4chlich in den Vereinigten Staaten.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5251\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio3.jpg\" alt=\"biomodex\" width=\"620\" height=\"330\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio3.jpg 620w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio3-600x319.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio3-160x85.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio3-300x160.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<h4 style=\"text-align: justify;\">Wie stellt ihr die Modelle f\u00fcr Mediziner her?<\/h4>\n<p style=\"text-align: justify;\">BIOMODEX hat eine eigene, patentierte Technologie genannt INVIVOTECH. Dabei nutzen wir\u00a0das Bildmaterial aus der Behandlung (Scanner, MRT oder Ultraschall) und nach einigen Schritten haben wir ein k\u00fcnstliches Organ reproduziert, welches genauso\u00a0wie ein echtes auf medizinische Eingriffe reagiert. Der Kern unserer Technologie ist die Herstellung\u00a0eines Verbundmaterials, das die Eigenschaften von\u00a0menschlichem Gewebe hat, egal ob\u00a0hart oder weich. Wir sind in der Lage einen kompletten Kn\u00f6chel mit allen anatomischen Elementen zu 3D drucken, dazu z\u00e4hlen Haut, Knochen, B\u00e4ndern, Sehnen, Knorpel, usw.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5252\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio4.jpg\" alt=\"biomodex\" width=\"620\" height=\"330\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio4.jpg 620w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio4-600x319.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio4-160x85.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bio4-300x160.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\">Wir sind sehr froh dar\u00fcber die Unterst\u00fctzung des 3D Experience Labs in unseren ersten Jahren bekommen zu haben, denn ohne die Mentoren von Dassault Systems w\u00e4re die Entwicklung von BIOMODEX mit Sicherheit nicht so verlaufen. Dar\u00fcber hinaus verschafft\u00a0uns dieser hochrangige Support einen zus\u00e4tzlichen Wettbewerbsvorteil um der weltweite Marktf\u00fchrer in dieser Industrie zu werden.<\/p>\n<h4 style=\"text-align: justify;\">Welche zuk\u00fcnftigen Entwicklungen stehen BIOMODEX bevor?<\/h4>\n<p style=\"text-align: justify;\">Nachdem wir bereits Modelle in der HNO-Medizin und in der Orthop\u00e4die entwickelt haben, wird sich der Fokus\u00a0in den kommenden Jahren auf vaskul\u00e4re und kardiovaskul\u00e4re Bereiche konzentrieren. Herzkrankheiten und -probleme sind die h\u00e4ufigste Todesursache auf der Welt, und BIOMODEX kann eine entscheidende Rolle spielen, um dem entgegenzuwirken. Wir werden von einigen der besten Chirurgen begleitet und unterst\u00fctzt, als da sind Professor Jacques Moret, Professor Alain Cribier und Professor Jean-Pierre Becquemin. Diese Referenzen schaffen Vertrauen auf dem internationalen Markt, und mit deren Hilfe werden wir anhand von wissenschaftlichen Studien und Publikationen beweisen, dass wir\u00a0Medizinern ein besseres Training erm\u00f6glichen und das Risiko bei OPs senken k\u00f6nnen.<\/p>\n<p style=\"text-align: justify;\">Hier die Simulation einer Kn\u00f6chel Athroskopie:<\/p>\n<p>https:\/\/www.youtube.com\/watch?list=PLB4tbhCIgBtJ6vUiKM2gXdToblj3iyALr&#038;v=gJupVIv_qgE<\/p>\n<h4 style=\"text-align: justify;\">Wie sehen Sie die Zukunft von 3D Operationen?<\/h4>\n<p style=\"text-align: justify;\">Wir sehen vorher, dass personalisierte\u00a0Heilverfahren\u00a0eine Revolution in der Chirurgie sein werden, um Patienten risikobewusster und effizienter zu behandeln. Das erreichen wir durch den 3D-Druck, der den wichtigsten Aspekt mit sich bringt: Einfache Anpassung bei geringen Kosten.<\/p>\n<h4 style=\"text-align: justify;\">Haben Sie noch ein letztes Wort an unsere Leser?<\/h4>\n<p style=\"text-align: justify;\">Heutzutage sieht es f\u00fcr den 3D-Druck Markt eher\u00a0d\u00fcster aus, nicht zuletzt wegen des wertm\u00e4\u00dfigen R\u00fcckgangs gro\u00dfer Firmen and der B\u00f6rse in den USA seit 2012 oder der Streichung von 50% der Arbeitspl\u00e4tze bei Makerbot. Nichtsdestotrotz muss man zuversichtlich f\u00fcr diese revolution\u00e4re Technologie bleiben. Nach dem ganzen Hype um den 3D-Druck sind wir jetzt in der Phase der Marktkorrektur angelangt. Wir wechseln von einer\u00a0Nachfrage nach Rapid Prototyping in eine \u00c4ra der Massenproduktion. BIOMODEX m\u00f6chte eine der ersten Firmen f\u00fcr die industrielle Fertigung von synthetischen Organen sein.<\/p>\n<p style=\"text-align: justify;\">Im folgenden Video stellt Thomas Marchand das Startup auf der CES in Las Vegas vor:<\/p>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"BIOMODEX at CES 2017 - Dassault Syst\u00e8mes\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/n9gCcmgNP9A?start=172&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p style=\"text-align: justify;\">Glauben Sie, dass der 3D-Druck die Zukunft von Operationen revolutionieren kann? Teilen Sie es uns in den sozialen Netzen\u00a0<a href=\"https:\/\/twitter.com\/3Dnatives_DE\"><span class=\"s2\">Twitter<\/span><\/a>\u00a0oder\u00a0<span class=\"s2\"><a href=\"http:\/\/www.facebook.com\/3dnatives\">Facebook<\/a>\u00a0mit!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der 3D-Druck hat in den letzten Jahren viele interessante Startups hervorgebracht, aus denen zum Teil sehr erfolgreiche Firmen wurden. Jeden Monat gibt es hier auf 3Dnatives das Startup des Monats, eine Rubrik f\u00fcr die interessanten Ideen, Entwicklungen und Innovationen in&hellip;<\/p>\n","protected":false},"author":6049,"featured_media":10106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[13,32,10,40],"tags":[],"class_list":["post-5244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forschung","category-gesundheit","category-interviews","category-medizin"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/5244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6049"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=5244"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/5244\/revisions"}],"predecessor-version":[{"id":5258,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/5244\/revisions\/5258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/10106"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=5244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=5244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=5244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}