{"id":51067,"date":"2023-10-27T11:00:49","date_gmt":"2023-10-27T09:00:49","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=51067"},"modified":"2023-10-27T11:21:49","modified_gmt":"2023-10-27T09:21:49","slug":"recht-auf-reparatur-271020231","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/recht-auf-reparatur-271020231\/","title":{"rendered":"Recht auf Reparatur durch 3D-Druck vom EU-Parlament vorgestellt"},"content":{"rendered":"<p style=\"text-align: justify;\">In Anbetracht der enormen j\u00e4hrlichen Mengen an Abfall in der EU in Form von gebrauchsf\u00e4higen Konsumg\u00fctern hat der Binnenmarkt- und Verbraucherausschuss des EU-Parlaments sich f\u00fcr das Recht auf Reparatur eingesetzt und nun nach etwa zehn Jahren seiner Bem\u00fchungen Erfolg verzeichnen k\u00f6nnen. Die bislang hohe Menge an Abfall hat eine erhebliche negative Umweltbelastung zur Folge. Das Wegwerfen der G\u00fcter produziert n\u00e4mlich j\u00e4hrlich 35 Millionen Tonnen Abfall, 261 Millionen Tonnen CO2-\u00c4quivalent und einen Ressourcenverbrauch von 30 Millionen Tonnen. Auch f\u00fcr die Konsumenten selber stellt die Situation ein Problem dar, da sie durch die Entsorgung ihrer Produkte j\u00e4hrlich einen Verlust in H\u00f6he von 12 Milliarden Euro davon tragen, der durch Reparaturen vermieden werden k\u00f6nnte.<\/p>\n<p style=\"text-align: justify;\">Das EU-Parlament hat nun einige Ma\u00dfnahmen beschlossen, um Konsumenten die Reparatur im Vergleich zum Neukauf schmackhaft zu machen, wobei unter anderem die <a href=\"https:\/\/www.3dnatives.com\/de\/additive-fertigung\/\">additive Fertigung<\/a> bei der flexiblen Produktion von Ersatzteilen Abhilfe leisten kann. Die Ma\u00dfnahmen dienen der Verl\u00e4ngerung des Lebenskreislauf von Produkten und tragen zum Umweltschutz bei. So sollen sich zum einen die Verk\u00e4ufer zur kostenlosen Ausbesserung innerhalb der gesetzlichen Garantiezeit verpflichten. Es soll hingegen auf Reparaturen verzichtet werden, wenn der Ersatz durch ein neues Produkt g\u00fcnstiger als die Ausbesserung ist oder die Wiederherstellung des Artikels dem Kosumenten Umst\u00e4nde bereitet. Zum anderen sollen Reparaturen den Nachfragern schmackhaft gemacht werden, etwa in Form von Garantieverl\u00e4ngerungen reparierter G\u00fcter um ein Jahr oder durch Gutscheine. Jedoch sollen Unternehmen auch f\u00fcr die Reparatur von einer gewissen Menge an Produkten aufkommen, die nicht im Rahmen der gesetzlichen Garantie liegen. Dazu z\u00e4hlen beispielsweise technische Ger\u00e4te. W\u00e4hrend der Reparaturzeit sollen Unternehmen zudem G\u00fcter an die Kunden verleihen, um eine Ersatzleistung f\u00fcr den gewissen Zeitraum zu bieten.<\/p>\n<div id=\"attachment_51071\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-51071\" class=\"wp-image-51071 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Reparatur.jpg\" alt=\"Recht auf Reparatur\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Reparatur.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Reparatur-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Reparatur-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-51071\" class=\"wp-caption-text\">Bild: Euractiv<\/p><\/div>\n<h3 style=\"text-align: justify;\">Folgen des Rechts auf Reparatur<\/h3>\n<p style=\"text-align: justify;\">Durch das Recht auf Reparatur wird sich auch eine neue Umgebung von Services um die Reparatur herum entwickeln. Demnach werden unabh\u00e4ngige Werkst\u00e4tten f\u00fcr die Reparatur, Instandsetzer und Konsumenten f\u00fcr die Gesamtdauer des Produktlebenszyklus zu jeder Zeit Zugriff auf die n\u00f6tigen Ersatzteile haben, ohne daf\u00fcr ein Verm\u00f6gen ausgeben zu m\u00fcssen. Dies kann zus\u00e4tzlich durch Online-Plattformen, die \u00fcber Reparaturbedingungen, -m\u00f6glichkeiten und -orte informieren, beg\u00fcnstigt werden. Die EU-Parlamentarier erhoffen sich durch das Recht auf Reparatur eine Senkung der Reparaturkosten, eine Steigerung des Wettbewerbs und mehr Auswahl f\u00fcr Nachfrager. Der Berichterstatter Ren\u00e9 Repasi (S&amp;D, DE) nahm ebenfalls Stellung zu der Bedeutung des Ausma\u00dfes des Rechts auf Reparatur:<\/p>\n<blockquote><p>&#8222;Heute [den 25.10.2023] haben wir direkte Reparaturverpflichtungen f\u00fcr Hersteller eingef\u00fchrt und neue Anreize f\u00fcr Verbraucher geschaffen, sich f\u00fcr eine Reparatur zu entscheiden. Wir haben die Rolle der unabh\u00e4ngigen Werkst\u00e4tten gest\u00e4rkt und stellen sie in den Mittelpunkt der Verbesserung der Reparatur in Europa. Durch einen besseren Zugang zu relevanten technischen Reparaturinformationen und erschwinglichen Ersatzteilen f\u00fcr Werkst\u00e4tten, einschlie\u00dflich der F\u00f6rderung des 3D-Drucks von Teilen, wird mehr Wettbewerb die Reparaturkosten senken. Wir haben dies mit einer Verpflichtung der Mitgliedstaaten verbunden, finanzielle Anreize zu schaffen, um den Reparatursektor anzukurbeln.&#8220;<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Die entg\u00fcltige Fassung des Rechts auf Reparatur steht noch aus. Die Europaabgeordneten werden \u00fcber den Mandatsentwurf auf der kommenden Plenartagung im November abstimmen und das weitere Vorgehen besprechen. Weitere Informationen finden sie <a href=\"https:\/\/www.europarl.europa.eu\/news\/en\/press-room\/20231023IPR08160\/right-to-repair-incentives-for-consumers-to-repair-rather-than-replace\" target=\"_blank\" rel=\"noopener\">HIER<\/a>.<\/p>\n<p style=\"text-align: justify;\">Was halten Sie von dem Recht auf Reparatur? Lassen Sie uns gerne einen Kommentar da, oder teilen Sie es uns auf <a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>\u00a0oder\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\/\">LinkedIN<\/a>\u00a0\u00a0mit. M\u00f6chten Sie au\u00dferdem eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach erhalten? Dann registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>.<\/p>\n<p style=\"text-align: justify;\"><em>*Titelbildnachweis: PhoneArena<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Anbetracht der enormen j\u00e4hrlichen Mengen an Abfall in der EU in Form von gebrauchsf\u00e4higen Konsumg\u00fctern hat der Binnenmarkt- und Verbraucherausschuss des EU-Parlaments sich f\u00fcr das Recht auf Reparatur eingesetzt und nun nach etwa zehn Jahren seiner Bem\u00fchungen Erfolg verzeichnen&hellip;<\/p>\n","protected":false},"author":6107,"featured_media":51069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49],"tags":[],"class_list":["post-51067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/51067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6107"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=51067"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/51067\/revisions"}],"predecessor-version":[{"id":51092,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/51067\/revisions\/51092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/51069"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=51067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=51067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=51067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}