{"id":4762,"date":"2024-08-22T14:59:12","date_gmt":"2024-08-22T12:59:12","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=4762"},"modified":"2024-08-22T15:43:20","modified_gmt":"2024-08-22T13:43:20","slug":"top-12-verruckte-filamente-210320171","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/top-12-verruckte-filamente-210320171\/","title":{"rendered":"Die verr\u00fccktesten Materialien f\u00fcr den 3D-Druck"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">In den letzten Jahren hat sich die <a href=\"https:\/\/www.3dnatives.com\/de\/category\/materialien\/\">Material-Palette f\u00fcr 3D-Druck<\/a> stetig weiter entwickelt. Mittlerweile k\u00f6nnen nicht nur <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-materialien-kunststoffe\/\">Plastik<\/a> und <a href=\"https:\/\/www.3dnatives.com\/de\/3d-metalldruck\/\">Metalle<\/a> verarbeitet werden, sondern auch <a href=\"https:\/\/www.3dnatives.com\/de\/leitfaden-glas-3d-druck-040620241\/\">Glas<\/a>, <a href=\"https:\/\/www.3dnatives.com\/de\/eroberung-des-3d-betondrucks-in-der-schweiz-erstes-3d-gedrucktes-gebaeude-050620241\/\">Beton<\/a> und <a href=\"https:\/\/www.3dnatives.com\/de\/die-verschiedenen-keramikarten-fuer-den-3d-druck-301120231\/\">Keramiken<\/a>. Im Rahmen der <a href=\"https:\/\/www.3dnatives.com\/de\/10-gruende-warum-der-3d-druck-als-nachhaltiger-gilt-300720241\/\">Kreislaufwirtschaft<\/a> konzentrieren sich immer mehr Materialhersteller auch auf das Recyceln von Abf\u00e4llen und der erneuten Verarbeitung zu 3D-Druckmaterial. So finden wir <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-in-korallenriffen-100820231\/\">recycelte Ozeanabf\u00e4lle<\/a>, Industrie-Abf\u00e4lle und <a href=\"https:\/\/www.3dnatives.com\/de\/neues-3d-gedrucktes-holz-als-umweltfreundlichere-alternative-260320241\/\">Holz als Filament<\/a>. Au\u00dferdem steigt die Anzahl an unkonventionellen Materialien, die im Zusammenhang mit dem <a href=\"https:\/\/www.3dnatives.com\/de\/additive-fertigung\/\">3D-Druck<\/a> eher \u00fcberraschend wirken; darunter Schokolade, Lebensmittelabf\u00e4lle, Zigarettenstummel und sogar Mondstaub! Wir haben einige dieser au\u00dfergew\u00f6hnlichen Materialien und Anwendungen zusammengefasst und eine Liste erstellt.<\/span><\/p>\n<h3>Schokolade, das wohl s\u00fc\u00dfeste Material f\u00fcr den 3D-Druck<\/h3>\n<p style=\"text-align: justify;\">Dieses 3D-Druckmaterial ist vielleicht nicht so au\u00dfergew\u00f6hnlich wie einige der anderen auf der Liste, aber es geh\u00f6rt sicherlich zu den am h\u00e4ufigsten verwendeten. Das Schokoladen-3D-Druckverfahren \u00e4hnelt der <a href=\"https:\/\/www.3dnatives.com\/depot-de-matiere-fondue-fdm\/\">FDM-Technologie<\/a>, hat aber andere K\u00fchleigenschaften als Kunststoff, weshalb der Prozess l\u00e4nger dauert. Die Popularit\u00e4t dieser Technologie hat im Laufe der Jahre zugenommen und viele Unternehmen dazu veranlasst, verschiedene Projekte und sogar <a href=\"https:\/\/www.3dnatives.com\/de\/lebensmittel-3d-drucker-ranking-161220211\/\">Schokoladen-3D-Drucker<\/a>\u00a0zu entwickeln, wobei insbesondere die neue Cocoa Press eine gro\u00dfe Fangemeinde unter 3D-Druck-Enthusiasten hat. Es gibt eine Reihe von Projekten, die sich mit dem 3D-Druck von Schokolade befassen, darunter Unternehmen wie More Than Shape, das mit dieser Technologie neue Geschmackserlebnisse schaffen will, sowie Forscher, die mithilfe des 3D-Drucks eine noch ges\u00fcndere Schokolade herstellen wollen. W\u00e4ren Sie bereit, dieses k\u00f6stliche 3D-Druckmaterial zu essen?<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/tRmFsf-mwyw\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h3>3D-Druckmaterial aus Asche zur Erinnerung an Ihre Liebsten<\/h3>\n<p style=\"text-align: justify;\">Das spanische Unternehmen Narb\u00f3n widmet sich der Einf\u00fchrung neuer Technologien und Innovationen im Bestattungssektor. Der Service 3DMemories nutzt den 3D-Druck, um aus der Asche, den Haaren, der DNA oder den Skelettresten eines geliebten Menschen originellen, einzigartigen und exklusiven <a href=\"https:\/\/www.3dnatives.com\/de\/page\/2\/?s=keramik\">Keramikschmuck<\/a> herzustellen. Dazu muss das Muster bearbeitet und anschlie\u00dfend mit Porzellan kombiniert werden, bevor der Schmuck im 3D-Druck hergestellt werden kann. Dann wird das Emaille aufgetragen und das St\u00fcck wird fixiert. Der Dienst bietet eine Reihe von Produkten f\u00fcr M\u00e4nner und Frauen an. Zweifellos stellt 3DMemories mit ihrem Schmucksortiment eine au\u00dfergew\u00f6hnliche Art und Weise dar, den geliebten Menschen in Erinnerung zu bewahren.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-3987217385\"><div id=\"dnati-1817005757\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<div id=\"attachment_33894\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33894\" class=\"wp-image-33894 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Ashes.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Ashes.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Ashes-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Ashes-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-33894\" class=\"wp-caption-text\">Bild: Narb\u00f3n<\/p><\/div>\n<h3 class=\"p1\"><span class=\"s1\"><b>Komposit mit Leinen<\/b><\/span><\/h3>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s1\">Eine weitere interessante Filamentalternative stellt ein Komposit aus <a href=\"https:\/\/www.3dnatives.com\/de\/pla-ein-leitfaden-zu-diesem-3d-druckmaterial-190820191\/\">PLA<\/a> und Leinen dar. Das finden wir beispielsweise im Sortiment des franz\u00f6sischen Herstellers Nanovia. Das Unternehmen gibt an, dass das Kompositmaterial nicht nur eine nachhaltige Alternative zu herk\u00f6mmlichen <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-fuer-anfaenger-wie-waehle-ich-das-richtige-filament-090820241\/\">Filamenten<\/a> darstelle, sondern unter Anwendung verschiedener Druckparameter auch unterschiedliche braunt\u00f6ne erzielt werden k\u00f6nnten. Daf\u00fcr muss im Druckprozess lediglich die Drucktemperatur modifiziert werden. Was die Nachbearbeitung betrifft, so empfiehlt der Hersteller die gedruckten Teile mit einer UV-Schutzbehandlung zu versiegeln, damit die gedruckten St\u00fccke m\u00f6glichst lange sch\u00f6n bleiben<\/span><\/p>\n<div id=\"attachment_33897\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33897\" class=\"wp-image-33897 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Nanovia-Linen.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Nanovia-Linen.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Nanovia-Linen-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Nanovia-Linen-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-33897\" class=\"wp-caption-text\">Bild: Nanovia<span style=\"font-size: 1em; text-align: justify;\">.<\/span><span class=\"Apple-converted-space\" style=\"font-size: 1em; text-align: justify;\">\u00a0<\/span><\/p><\/div>\n<h3 style=\"text-align: left;\">3D-Druck mit Zucker<\/h3>\n<p style=\"text-align: justify;\">The Sugar Lab wurde vor fast zehn Jahren von 3D Systems aufgekauft, 2020 ausgegliedert und als 3D-Druckunternehmen f\u00fcr Spezials\u00fc\u00dfwaren f\u00fcr den Direktvertrieb neu gegr\u00fcndet. Wie der Name bereits erahnen l\u00e4sst, spezialisiert sich der Hersteller auf den 3D-Druck mit Zucker. Mithilfe des\u00a0Brill 3D Culinary Studio (zuvor erh\u00e4ltlich als ChefJet Pro), erstellt das Unternehmen S\u00fc\u00dfigkeiten und Dekorationen in komplexen Formen. Das in Los Angeles ans\u00e4ssige Unternehmen soll nach eigenen Angaben in der Lage sein, S\u00fc\u00dfigkeiten in allen Geschmacksrichtungen und Farben herzustellen. Ob f\u00fcr Geburtstage, Hochzeiten oder Weihnachtsfeiern &#8211; <a href=\"https:\/\/www.3dnatives.com\/de\/the-sugar-lab-weihnachten-241220201\/\">The Sugar Lab<\/a> bietet alle Arten von S\u00fc\u00dfigkeiten aus dem 3D-Drucker an. Und was die Menge betrifft: Der 3D-Drucker scheint in der Lage zu sein mehrere hundert Bonbons pro Tag zu produzieren. The Sugar Lab ist zwar das bekannteste Unternehmen, das Zucker als Druckmaterial verwendet, aber auch andere Unternehmen wie The Modernist Cuisine versuchen sich am 3D-Druck mit Zucker.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/CltzXuXEuT4\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h3>3D-Druckmaterial inspiriert von Elfenbein<\/h3>\n<p style=\"text-align: justify;\">Unter der Vielzahl von Materialien, die f\u00fcr den 3D-Druck verwendet werden, gibt es einige, die ad hoc entwickelt wurden, um bestimmte Anforderung zu erf\u00fcllen und alte Probleme innovativ zu l\u00f6sen. Ein solches Material ist <a href=\"https:\/\/www.3dnatives.com\/de\/elfenbein-alternative-3d-druck\/\">Digory<\/a>, das von der Universit\u00e4t Wien in Zusammenarbeit mit der Cubicure GmbH entwickelt wurde, um den Bedarf an der Restaurierung alter Denkm\u00e4ler und Gegenst\u00e4nde aus Elfenbein zu decken. Es handelt sich um ein Kunstharz mit Calciumphosphatpartikeln und Siliziumoxidpulver. Forscher haben dieses neue Material mit elfenbein\u00e4hnlichen Merkmalen und Eigenschaften entwickelt, um Objekte mit dem 3D-Druck bzw. der <a href=\"https:\/\/www.3dnatives.com\/de\/stereolithografie\/\">SLA-Technologie<\/a> zu restaurieren. Die \u00c4hnlichkeit zwischen den beiden Materialien ist bemerkenswert &#8211; es ist kaum ein Unterschied zu erkennen!<\/p>\n<div id=\"attachment_33907\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33907\" class=\"wp-image-33907 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Design-ohne-Titel-35.png\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Design-ohne-Titel-35.png 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Design-ohne-Titel-35-600x343.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2016\/07\/Design-ohne-Titel-35-160x91.png 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-33907\" class=\"wp-caption-text\">Das Digory-Material auf der rechten Seite, das dem Elfenbein auf der linken Seite sehr \u00e4hnlich ist. (Bild: Technische Universit\u00e4t Wien)<\/p><\/div>\n<h3>Diamanten<\/h3>\n<p style=\"text-align: justify;\">Es mag f\u00fcr viele \u00fcberraschend sein, dass es tats\u00e4chlich m\u00f6glich ist, eines der h\u00e4rtesten Materialien der Erde, n\u00e4mlich den Diamant, in 3D zu drucken. Im Jahr 2019 gab Sandvik Additive Manufacturing bekannt, dass es den ersten 3D-gedruckten Diamantverbundwerkstoff entwickelt hat. Obwohl das Material nicht funkelt, w\u00fcrde es Herstellern dennoch erm\u00f6glichen, mit diesem superharten Material 3D zu drucken, was insbesondere die Werkzeugindustrie revolutionieren w\u00fcrde. Diamant wird in vielen unterschiedlichen Branchen wie dem Bergbau bis hin zur maschinellen Bearbeitung sowie f\u00fcr medizinische Implantate vor allem wegen seiner verschlei\u00dffesten Eigenschaften eingesetzt, ist jedoch schwer bearbeitbar. Mit diesem Durchbruch bei den Verbundwerkstoffen ist es Sandvik zufolge nun m\u00f6glich, das Material in hochkomplexen Formen zu drucken, weshalb das Unternehmen gro\u00dfe Hoffnungen in das Produkt hat.<\/p>\n<p><center><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/9YjIOGljQ28\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_end\">\ufeff<\/span><\/iframe>\u00a0<\/center><\/p>\n<h3 style=\"text-align: justify;\">Weltraummaterialien<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Mondregolith, der graue Staub, der auf dem Mond reichlich vorhanden ist, wird immer h\u00e4ufiger f\u00fcr den 3D-Druck erforscht. In einer Studie der University of Central Florida wurden 3D-gedruckte Ziegel aus Mondregolith und Salzwasser entwickelt, die sich f\u00fcr den Bau von St\u00fctzpunkten im Artemis-Basislager eignen k\u00f6nnten. So f\u00fchrten die Forscher verschiedene Tests durch, um zu pr\u00fcfen, ob diese Ziegel sich f\u00fcr den Bau von Wohnh\u00e4usern im Weltraum eignen. Bei der Herstellung kam das Binder Jetting-Verfahren zum Einsatz, das besonders f\u00fcr keramik\u00e4hnliche Materialien von Vorteil ist. Zusammen mit einem Bindemittel aus Salzwasser sowie dem Regolith aus dem Exolith Labor der UVF wurden die Ziegel dann gedruckt. Trotz des theoretischen Charakters des Projekts zeigen die Ergebnisse, dass die 3D-gedruckten Ziegel extremen Bedingungen standhalten k\u00f6nnen. <\/span><span style=\"font-weight: 400;\">Ein weiteres Beispiel ist das Projekt der ESA und NASA im Rahmen eines Artemis-Programms untersuchte, ob Weltraummaterialien wie Regolith zur Herstellung von Bausteinen geeignet sind, um aus diesen anschlie\u00dfend Lebensr\u00e4ume, Startrampen oder St\u00fctzstrukturen zu entwickeln. Dar\u00fcber hinaus verfolgten die <a href=\"https:\/\/www.3dnatives.com\/de\/lego-steine-aus-mondstaub-260620241\/\">LEGO-Steine aus Regolith<\/a> ein p\u00e4dagogisches Ziel: Sie sollen Kinder f\u00fcr den Weltraum und das Bauen begeistern. 15 dieser Bausteine wurden deshalb in LEGO-Stores weltweit verkauft. Obwohl der 3D-Druck mit Mondstaub h\u00e4ufig eher hypothetisch bleibt und noch selten angewendet wird, k\u00f6nnte sich das in naher Zukunft \u00e4ndern.<\/span><\/p>\n<div id=\"attachment_58234\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58234\" class=\"wp-image-58234 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/Lego-brick_3d-materials.jpg\" alt=\"verr\u00fccktesten Materialien f\u00fcr den 3D-Druck\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/Lego-brick_3d-materials.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/Lego-brick_3d-materials-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/Lego-brick_3d-materials-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58234\" class=\"wp-caption-text\">(Bild: LEGO Group)<\/p><\/div>\n<h3 style=\"text-align: justify;\"><b>Wolle<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Wolle, die in der Textilindustrie wegen ihrer Feinheit nicht genutzt werden kann, landet normalerweise im Abfall. Das Projekt der niederl\u00e4ndischen Designerin Christien Meindertsma in Zusammenarbeit mit dem TFT-Unternehmen setzt dem jedoch ein Ende. Ein ma\u00dfgeschneiderter <a href=\"https:\/\/www.3dnatives.com\/de\/wolle-3d-druck-241120231\/\">Roboterarm namens FLOCKS Wobot<\/a> tr\u00e4gt diese Wolle Schicht f\u00fcr Schicht auf, \u00e4hnlich wie bei der additiven Fertigung, und formt unterschiedliche Gegenst\u00e4nde, ohne zus\u00e4tzliche Materialien oder Wasser zu verwenden. Dieses innovative Projekt ist ein wichtiger Beitrag zur Kreislaufwirtschaft und bietet enormes Potential, denn die Wolle ist recyclebar, biologisch abbaubar sowie isolierend. Zuk\u00fcnftige Anwendungen k\u00f6nnten in den Bereichen Akustik, Isolierung, Design und M\u00f6belbau liegen. Auch das urbane Labor von Dylan, d-house, erforscht den 3D-Druck mit Merinowolle. Gemeinsam mit The Woolmark Company und Stratasys wurde das Projekt \u201eKnitting the Future\u201c ins Leben gerufen, an dem auch Studenten des Royal College of Art in London beteiligt sind, die 3D-gedruckte Designs aus Strickwolle entwickeln m\u00f6chten. Die Designer sind von der Wolle besonders begeistert, da sie vielf\u00e4ltige Farbvariationen, Farbverl\u00e4ufe und Schimmereffekte erm\u00f6glicht und gleichzeitig weniger Abfall produziert.<\/span><\/p>\n<div id=\"attachment_58235\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58235\" class=\"wp-image-58235 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/wool_material.jpg\" alt=\"verr\u00fccktesten Materialien f\u00fcr den 3D-Druck\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/wool_material.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/wool_material-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/wool_material-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58235\" class=\"wp-caption-text\">(Bild: TFT Tools for Technology, Sara Alvarez, Bart Harteloh, Doosan Robotics, Dormac Cobots, Martin Oosthoek, De Wassum, Havivank, Gelderland, Rotterdam Circulair, Lisa Hardon, Creative Industries Fund NL et Stichting DOEN.)<\/p><\/div>\n<h3>Lebensmittel <strong>&#8211; und Lebensmittelproduktionsabf\u00e4lle<\/strong><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Es gibt mittlerweile zahlreiche Materialien, die auf Basis von Essensresten oder Abfall aus der Lebensmittelproduktion hergestellt werden. Ein Beispiel sind Orangenschalen. Das italienische Designstudio Krill Design etwa stellt 3D-gedruckte Lampen auf Basis von getrockneten Orangenschalen her, welche zu Pulver gemahlen werden und als Biomaterial per 3D-Druck verarbeitet werden. Ein \u00e4hnliches Projekt ist die von <a href=\"https:\/\/www.3dnatives.com\/de\/wasp-nachhaltig-bauen-270520211\/\">WASP<\/a> und dem Architekten Carlo Ratti entwickelte Maschine <a href=\"https:\/\/www.3dnatives.com\/de\/eine-saftbar-verwandelt-orangenschalen-in-3d-gedruckte-becher-200920191\/\">\u201cFeel the Peel\u201d<\/a>. Diese ist einerseits Saftbar, indem sie Orangensaft presst, gleichzeitig aber auch 3D-Drucker, denn die Orangenschalen werden gesammelt, getrocknet, mit <a href=\"https:\/\/www.3dnatives.com\/de\/feature-story-3d-druck-material-pla-nachhaltig-230720191\/\">PLA<\/a> vermengt und bilden das Ausgangsmaterial f\u00fcr 3D-gedruckte Becher. Abf\u00e4lle von Zitrusfr\u00fcchten sind nicht die einzigen Rohstoffe, die mittlerweile zu 3D-Druckmaterialien werden. Im Cacao Eco Village wurden so Kakaobohnen- und Abf\u00e4lle verwendet, um <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-haeuser-unternehmen-hersteller-170620191\/\">3D-gedruckte Geb\u00e4ude<\/a> herzustellen, indem die Schalen der Kakaofr\u00fcchte zu Bioplastik verarbeitet wurden. Des Weiteren finden wir Filamente von einigen Herstellern, welche auf Austern-oder Muschelabf\u00e4llen basieren. Smartmaterials f\u00fchrt ein solches biologisches Druckmaterial und auch der franz\u00f6sische Filamenthersteller Francofil vertreibt PLA mit Resten von <a href=\"https:\/\/www.3dnatives.com\/de\/fraunhofer-institut-biomimetischer-klebstoff-fuer-3d-druck-080120241\/\">Miesmuscheln<\/a>, Jakobsmuscheln oder Austern. Neben den Muschelresten f\u00fchrt Francofil auch ein Filament aus Bierresten, bei dem das Braunebenprodukt mit PLA zum neuen Druckmaterial wird. Diese Beispiele geben einen Einblick, wie Abf\u00e4lle aus der Lebensmittelproduktion zu 3D-Druckmaterialien verarbeitet werden. Im Rahmen der Kreislaufwirtschaft und des Trends zum \u201cUpcycling\u201d finden wir aber zahlreiche solcher innovativen Ans\u00e4tze.<\/span><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/Bx9missz73A?si=cMdwWPOZOAjs7Clx\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h3>Kaffee<\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.3dnatives.com\/de\/kaffeesatz-fuer-3d-druck-eine-umweltfreundliche-loesung-mit-koffein-kick-241120231\/\">Kaffee<\/a> geh\u00f6rt zu den am meisten konsumierten Getr\u00e4nken der Welt. Sch\u00e4tzungen zufolge werden t\u00e4glich weltweit 2,5 Milliarden Tassen Kaffee getrunken. Stellen Sie sich also vor, dass man diesen Konsum nutzen k\u00f6nnte, um Material f\u00fcr den 3D-Druck zu entwerfen? In der Tat haben sich in letzter Zeit mehrere Initiativen entwickelt, die darauf abzielen, den Kaffeesatz, d. h. die R\u00fcckst\u00e4nde des Br\u00fchvorgangs, zu recyceln und ihm eine Polymerbasis hinzuzuf\u00fcgen: So erh\u00e4lt man ein Material, das f\u00fcr den 3D-Druck bereit ist, in den meisten F\u00e4llen ein Filament. Zu diesen Initiativen geh\u00f6rt Lowpoly, das aus dem <a href=\"https:\/\/www.3dnatives.com\/de\/ein-kaffeehaus-aus-kaffeesatz-kreislaufwirtschaft-170620241\/\">Kaffeesatz 3D-gedruckte M\u00f6bel<\/a> f\u00fcr ein Caf\u00e9 entworfen hat. Weitere Beispiele sind die University of Colorado oder Krill Design, die Liste ist nicht vollst\u00e4ndig.<\/span><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/mYRKvPawfO0?si=_04brxCEkv69YylQ\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h3>Organische 3D-Druckmaterialien<\/h3>\n<p style=\"text-align: justify;\">Wenn Sie an Algen oder Pilze denken, kommt Ihnen wahrscheinlich nicht sofort die additive Fertigung in den Sinn. In den letzten Jahren haben wir jedoch gesehen, dass diese organischen Materialien in verschiedenen Projekten f\u00fcr den 3D-Druck verwendet werden. Pilze, genauer gesagt <a href=\"https:\/\/www.3dnatives.com\/de\/material-myzel-3d-druck-220420241\/\">Pilzmyzel<\/a>, werden aufgrund ihrer Umweltfreundlichkeit als Baumaterial erforscht, aber auch f\u00fcr Anwendungen wie Innenarchitektur, Konsumg\u00fcter und sogar im Gesundheitswesen. Inzwischen werden Algen f\u00fcr alles M\u00f6gliche verwendet, von 3D-gedruckten organischen Fliesen bis hin zu nachhaltigerer Medizin. Und nicht nur das: Algentinte wird entwickelt, um nahrhafte Lebensmittel, darunter auch kultiviertes Fleisch, herzustellen. Beides sind unglaubliche Beispiele daf\u00fcr, wie die additive Fertigung zu einem noch gr\u00fcneren Prozess werden kann.<\/p>\n<div id=\"attachment_58249\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-58249\" class=\"wp-image-58249 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/mycelium_algae.jpg\" alt=\"verr\u00fccktesten Materialien f\u00fcr den 3D-Druck\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/mycelium_algae.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/mycelium_algae-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/mycelium_algae-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-58249\" class=\"wp-caption-text\">Links: 3D-gedrucktes Myzel (Bild: WASP); rechts: mit 3D-gedruckten Algen hergestellte Kacheln (Bild: bioMATTERS)<\/p><\/div>\n<h3><strong>Zigarettenstummel<\/strong><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ja, Sie haben richtig gelesen: Zigarettenstummel k\u00f6nnten das 3D-Druckmaterial der Zukunft werden. Eine Initiative, die unserem Planeten gut tun w\u00fcrde. Denn das Ziel ist es, alle Zigarettenstummel, die t\u00e4glich in die Natur geworfen werden, wiederzuverwenden. Sie wissen, wie sch\u00e4dlich Zigarettenstummel f\u00fcr unsere Umwelt sind. Ein einziger Stummel verschmutzt bis zu 500 Liter Wasser oder einen Kubikmeter Schnee! Stellen Sie sich das also auf globaler Ebene vor. Um dagegen anzuk\u00e4mpfen, wurde Filaret3D gegr\u00fcndet: Es handelt sich um ein Unternehmen, das Zigarettenstummel sammelt und sie in neue Materialien umwandelt, sei es Papier oder Filament f\u00fcr den 3D-Druck. Dieses entfernt den Filter der Zigaretten ab, entgiftet und w\u00e4scht ihn, bevor sie Polymere und andere Zusatzstoffe hinzuf\u00fcgt. All das wird zu Granulat und dann zu Filament verarbeitet.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-58236 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/ranking_filaret-e1724313356463.jpg\" alt=\"verr\u00fccktesten Materialien f\u00fcr den 3D-Druck\" width=\"700\" height=\"337\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/ranking_filaret-e1724313356463.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/ranking_filaret-e1724313356463-600x289.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/01\/ranking_filaret-e1724313356463-160x77.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Kennen Sie weitere au\u00dfergew\u00f6hnliche Materialien f\u00fcr den 3D-Druck? Lassen Sie uns dazu einen Kommentar da, oder teilen Sie es uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>\u00a0oder\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\/\">LinkedIN<\/a>\u00a0\u00a0mit. M\u00f6chten Sie au\u00dferdem eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der Additiven Fertigung direkt und bequem in Ihr Postfach erhalten? Dann registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den letzten Jahren hat sich die Material-Palette f\u00fcr 3D-Druck stetig weiter entwickelt. Mittlerweile k\u00f6nnen nicht nur Plastik und Metalle verarbeitet werden, sondern auch Glas, Beton und Keramiken. Im Rahmen der Kreislaufwirtschaft konzentrieren sich immer mehr Materialhersteller auch auf das&hellip;<\/p>\n","protected":false},"author":6049,"featured_media":58263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,12,34],"tags":[],"class_list":["post-4762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-materialien","category-rankings"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/4762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6049"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=4762"}],"version-history":[{"count":4,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/4762\/revisions"}],"predecessor-version":[{"id":58265,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/4762\/revisions\/58265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/58263"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=4762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=4762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=4762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}