{"id":4743,"date":"2017-03-19T10:00:43","date_gmt":"2017-03-19T10:00:43","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=4743"},"modified":"2017-03-24T08:58:46","modified_gmt":"2017-03-24T08:58:46","slug":"top-5-videos-triteia-makerbots-190320171","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/top-5-videos-triteia-makerbots-190320171\/","title":{"rendered":"TOP 5 Videos der Woche: Satellit Triteia und die Armee aus Makerbots"},"content":{"rendered":"<p style=\"text-align: justify;\">Wir pr\u00e4sentieren euch die Top 5 Videos der Woche rund um den 3D-Druck. Eine Woche ist vorbei und wie jeden Sonntag gibt es hier das interessanteste und innovativste aus der Welt des 3D-Drucks zu bestaunen. Angenehmen Sonntag w\u00fcnscht euch das Team von 3Dnatives!<\/p>\n<h3 style=\"text-align: left;\">Platz 5 &#8211; Der erste Android-3D Drucker<\/h3>\n<p style=\"text-align: justify;\">Diesen Freitag haben wir euch den neuen Drucker aus dem Hause BQ vorgestellt. Er ist der erste 3D Drucker mit einem Android Betriebssystem, den man mit dem Smartphone steuern und \u00fcberwachen kann. Mit seinem\u00a0minimalistischen Design passt er in jede Umgebung, egal ob zuhause oder im B\u00fcro. Die Witbox Go! wird voraussichtlich im Herbst dieses Jahres erscheinen und 599,90\u20ac kosten, die Jungs von TechVideo konnten jedoch\u00a0auf dem Event in M\u00fcnchen bereits jetzt die neue\u00a0Witbox Go! ausprobieren.<\/p>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"BQ Witbox Go ist der erste Android 3D Drucker\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/umHzCRTaqic?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h3 style=\"text-align: left;\">Platz 4 &#8211;\u00a0Die additive Fertigung ist bereit f\u00fcr die Massenproduktion<\/h3>\n<p style=\"text-align: justify;\">Die gro\u00dfen Automobilhersteller in Deutschland gehen bereits die ersten Schritte, den 3D Druck in ihre Produktionsabl\u00e4ufe zu integrieren. Eine Liga h\u00f6her ist allerdings die Produktion von Turbinen f\u00fcr die Energiewirtschaft und Flugzeugindustrie. Der 3D Druck spielt auch hier eine Rolle: Wenngleich nicht das ganze Triebwerk aus dem 3D Drucker stammt, so machen doch die kleinen Bauteile auch den Unterschied. Bei GE Aviation hat die additive Fertigung den Produktionsprozess vereinfacht und die Bauteile optimiert &#8211; der 3D Druck ist bereit f\u00fcr die Massenproduktion.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-1710992983\"><div id=\"dnati-3734646514\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p>https:\/\/www.youtube.com\/watch?v=ITpxeKn6Cug<\/p>\n<h3 style=\"text-align: left;\">Platz 3 &#8211; Rambo, der 3D gedruckte Granatwerfer in Action<\/h3>\n<p style=\"text-align: justify;\">Am vergangenen Dienstag haben wir euch \u00fcber die erste additiv gefertigte Waffe berichtet. Der RAMBO Granatwerfer besteht aus ca. 50 Einzelteilen und ist dem M203 Orginalmodell nachgebaut. Selbst die Munition ist 3D gedruckt! Im Video seht ihr wie die Waffe zu Testzwecken abgefeuert wird:<\/p>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"RAMBO: The 3D-Printed Grenade Launcher\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/HFr-B5PMu10?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h3 style=\"text-align: left;\">Platz 2 &#8211; Triteia, der Satellit mit dem 3D gedruckten Motor<\/h3>\n<p style=\"text-align: justify;\">Das\u00a0Team aus Studenten der UC San Diego entwickelt einen Satelliten, der zum Mond geschickt werden soll. Um die &#8222;Cube Quest Challenge&#8220; der NASA zu gewinnen und ihrem &#8222;Triteia&#8220; einen Platz in der Raumf\u00e4hre zu sichern, verlassen sich die Studenten auf den 3D Druck. Der Motor wurde komplett additiv gefertigt und soll die Sonde in der Umlaufbahn des Mondes halten. Das Projekt soll auf die M\u00f6glichkeiten des 3D Drucks in der Raumfahrt aufmerksam machen.<\/p>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Triteia \u2013 3D Printing the Way to the Moon!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/NHOsJeIlwx8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h3 style=\"text-align: left;\">Platz 1 &#8211; Die Armee von 3D Druckern<\/h3>\n<p style=\"text-align: justify;\">Der Druckservice\u00a0Voodoo Manufacturing hat eine ganz besondere Art, die ca. 160 Makerbot zu verwalten. Mit einem eigens gebauten Roboter kann das Unternehmen aus New York ihre Drucker 24 Stunden lang in Betrieb halten, ohne Pause.\u00a0Der Austausch der Printbetter ist eigentlich der Job von Mitarbeitern, doch mit dieser Optimierung geht das voll automatisch, und steigert die Produktivit\u00e4t dabei noch um 400%.<\/p>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"This Robot Operates A Fleet Of 3D-Printers\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/qmPA-dRx4pg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p style=\"text-align: justify;\"><span class=\"s1\"><a href=\"https:\/\/www.3dnatives.com\/feed\/\" target=\"_blank\">RSS-Feed<\/a><\/span><span class=\"s2\">\u00a0abonnieren und\u00a0per\u00a0<a href=\"http:\/\/www.facebook.com\/3dnatives\" target=\"_blank\"><span class=\"s1\">Facebook<\/span><\/a>,\u00a0<a href=\"https:\/\/twitter.com\/3Dnatives_DE\" target=\"_blank\"><span class=\"s1\">Twitter<\/span><\/a>\u00a0und\u00a0<a href=\"https:\/\/plus.google.com\/u\/0\/b\/110137870176740423201\/110137870176740423201\/posts\" target=\"_blank\"><span class=\"s1\">Google+<\/span><\/a>\u00a0stets auf dem Laufenden bleiben!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir pr\u00e4sentieren euch die Top 5 Videos der Woche rund um den 3D-Druck. Eine Woche ist vorbei und wie jeden Sonntag gibt es hier das interessanteste und innovativste aus der Welt des 3D-Drucks zu bestaunen. Angenehmen Sonntag w\u00fcnscht euch das&hellip;<\/p>\n","protected":false},"author":6049,"featured_media":4752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-4743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/4743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6049"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=4743"}],"version-history":[{"count":3,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/4743\/revisions"}],"predecessor-version":[{"id":4825,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/4743\/revisions\/4825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/4752"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=4743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=4743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=4743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}