{"id":39792,"date":"2022-08-09T08:27:37","date_gmt":"2022-08-09T06:27:37","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=39792"},"modified":"2022-08-09T08:28:14","modified_gmt":"2022-08-09T06:28:14","slug":"stratasys-3d-systems-uebernahmen-090820221","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/stratasys-3d-systems-uebernahmen-090820221\/","title":{"rendered":"Stratasys und 3D Systems k\u00fcndigen neue \u00dcbernahmen an"},"content":{"rendered":"<p style=\"text-align: justify;\">Zwei der weltweit gr\u00f6\u00dften Hersteller von 3D-Druckern, <a href=\"https:\/\/www.3dnatives.com\/de\/ssys-2y22-reflection-collection-080620221\/\">Stratasys<\/a> und <a href=\"https:\/\/www.3dnatives.com\/de\/3d-systems-united-therapeutics-3d-gedrucktes-lungengeruest-080720221\/\">3D Systems<\/a>, gaben neue \u00dcbernahmen bekannt, die ein Zeichen f\u00fcr das anhaltende Wachstum des 3D-Druckmarktes sind. Stratasys gab als erstes bekannt, dass es eine endg\u00fcltige Vereinbarung zur \u00dcbernahme des Gesch\u00e4ftsbereichs Additive Manufacturing Materials von Covestro, einem f\u00fchrenden Anbieter von Premium-Polymeren, unterzeichnet hat. Es wird erwartet, dass die \u00dcbernahme Stratasys helfen wird, sein Materialangebot in den Bereichen Stereolithographie, DLP und Pulver weiter auszubauen. In der Zwischenzeit k\u00fcndigte 3D Systems die \u00dcbernahme der dp polar GmbH an, um die additive Fertigung von Gro\u00dfserien dank der Plattform von dp polar zu beschleunigen, die den kontinuierlichen 3D-Druck von Komponenten mit hoher Geschwindigkeit erm\u00f6glicht.<\/p>\n<p style=\"text-align: justify;\">Obwohl der Sommer tendenziell eine langsamere Zeit ist, da viele eine wohlverdiente Pause einlegen, um die Hitze zu bek\u00e4mpfen, hat sich der 3D-Druckmarkt keineswegs verlangsamt. Diese neuesten Nachrichten zeigen vor allem die anhaltende St\u00e4rke von Stratasys, trotz der <a href=\"https:\/\/www.3dnatives.com\/de\/stratasys-aktionaersrechte-plan-280720221\/\">Bedenken \u00fcber eine \u00dcbernahme vor wenigen Wochen<\/a>. Dar\u00fcber hinaus zeigt 3D Systems nach einem ruhigeren Jahr, das eher von Verk\u00e4ufen als von K\u00e4ufen gepr\u00e4gt war, dass das Unternehmen immer noch im Akquisitionsmodus ist, nachdem es durch die \u00dcbernahme von Titan Robotics und Kumovis wieder in den <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-schmelzschichtung\/\">FDM<\/a>-3D-Druckmarkt eingestiegen ist.<\/p>\n<div id=\"attachment_39760\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39760\" class=\"wp-image-39760 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2022\/08\/Untitled-design-29.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-39760\" class=\"wp-caption-text\">dp polar ist bekannt f\u00fcr hochvolumigen, industriellen 3D-Druck (Bild: dp polar GmbH)<\/p><\/div>\n<h3>Stratasys erwirbt das AM-Materialgesch\u00e4ft von Covestro<\/h3>\n<p style=\"text-align: justify;\">Dies ist nicht das erste Mal, dass Stratasys und Covestro miteinander verbunden sind. Tats\u00e4chlich sind die 3D-Druckmaterialien von Covestro schon seit einigen Jahren Teil des 3rd-Party-\u00d6kosystems von Stratasys (Materialien von au\u00dferhalb des Unternehmens, die mit den Maschinen des Unternehmens kompatibel sind). In der Tat ist Covestro dank seiner innovativen Materiall\u00f6sungen, die insbesondere auf <a href=\"https:\/\/www.3dnatives.com\/de\/umwelt-3ddruck-21012016\/\">Nachhaltigkeit<\/a> und Kreislaufwirtschaft ausgerichtet sind, seit geraumer Zeit eine wichtige St\u00fctze im Bereich AM. Durch die \u00dcbernahme werden insbesondere die Nutzer der Origin P3\u2122-, Neo\u00ae-Stereolithographie- und H350\u2122-Drucker von Stratasys profitieren, da sie Zugang zu erweiterten Materialien f\u00fcr den Einsatz in der Stereolithographie, DLP und Pulver erhalten.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-860170289\"><div id=\"dnati-4112955043\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\">Laut der Pressemitteilung wird Stratasys F&amp;E-Einrichtungen und -Aktivit\u00e4ten, globale Entwicklungs- und Vertriebsteams in Europa, den USA und China, ein Portfolio von etwa 60 AM-Materialien und ein umfangreiches IP-Portfolio mit Hunderten von Patenten und Patentanmeldungen erwerben. In Anbetracht der Tatsache, dass die Materialforschung und -entwicklung derzeit eine der gr\u00f6\u00dften Herausforderungen im Bereich AM darstellt, d\u00fcrfte dieser Schritt nicht nur eine Erweiterung des Angebots f\u00fcr die Kunden erm\u00f6glichen, sondern auch den Zugang zu den Forschungsergebnissen, die Covestro bisher im Bereich der 3D-Druckmaterialien erzielt hat. Es wird erwartet, dass sich die \u00dcbernahme sofort positiv auswirkt, d.h. den Gewinn pro Aktie des Erwerbers erh\u00f6ht. Der Kaufpreis f\u00fcr Covestro bel\u00e4uft sich auf rund 43 Millionen Euro zuz\u00fcglich zus\u00e4tzlicher Vorr\u00e4te und abz\u00fcglich bestimmter Verbindlichkeiten. Es besteht eine potenzielle Gewinnbeteiligung von bis zu 37 Millionen Euro.<\/p>\n<p style=\"text-align: justify;\">Dr. Yoav Zeif, CEO von Stratasys, kommentierte die Entscheidung wie folgt: <em>&#8222;Innovative Materialien sind der Treibstoff der additiven Fertigung und f\u00fchren direkt zur Schaffung neuer Anwendungsm\u00f6glichkeiten f\u00fcr den 3D-Druck, insbesondere bei der Herstellung von Endverbrauchsteilen wie Zahnspangen und Automobilkomponenten. Die \u00dcbernahme des hoch angesehenen Gesch\u00e4ftsbereichs Additive Manufacturing von Covestro versetzt uns in die Lage, die Verbreitung unserer neuesten Technologien weiter voranzutreiben. Wir werden nun in der Lage sein, Spitzenentwicklungen im Bereich der 3D-Druckmaterialien zu beschleunigen und unsere Strategie voranzutreiben, das beste und umfassendste Polymer-3D-Druck-Portfolio der Branche anzubieten.&#8220;<\/em><\/p>\n<div id=\"attachment_39757\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39757\" class=\"wp-image-39757 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/2022\/08\/covestro.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-39757\" class=\"wp-caption-text\">Ein Autok\u00fchlergrill, der auf einem Stratasys Neo800 Stereolithografiesystem mit dem klaren Somos WaterShed CX 11122 Material von Covestro 3D-gedruckt wurde (Bild: Business Wire)<\/p><\/div>\n<h3>3D Systems will AM in gro\u00dfen St\u00fcckzahlen durch \u00dcbernahme von dp polar beschleunigen<\/h3>\n<p style=\"text-align: justify;\">In der Zwischenzeit hat 3D Systems die \u00dcbernahme der dp polar GmbH bekannt gegeben. dp polar ist ein deutscher Entwickler und Hersteller des laut 3D Systems <em>&#8222;ersten additiven Fertigungssystems der Branche, das f\u00fcr eine echte Hochgeschwindigkeits-Massenproduktion kundenspezifischer Komponenten entwickelt wurde&#8220;<\/em>. Ihr einzigartiges System erm\u00f6glicht kontinuierliches Drucken dank einer segmentierten, rotierenden Druckplattform dank einer patentierten Polarkoordinatensteuerung, die einen Druckkopf station\u00e4r \u00fcber einer rotierenden Plattform h\u00e4lt. Stratasys hofft, dass das System mit seinem eigenen Polymer-Materialportfolio und der Softwaretechnologie von Oqton kombiniert werden kann, um die Hochgeschwindigkeits-Massenproduktion von AM in einer Reihe von kritischen Branchen zu erm\u00f6glichen.<\/p>\n<p style=\"text-align: justify;\">Dr. Jeffrey Graves, Pr\u00e4sident und CEO von 3D Systems, sagte abschlie\u00dfend: <em>&#8222;Diese Akquisition ist der n\u00e4chste Schritt in der Umsetzung unserer Investitionsstrategie, um unseren Kunden ein branchenf\u00fchrendes L\u00f6sungsportfolio f\u00fcr die additive Fertigung zu bieten, mit dem sie die Herausforderungen ihrer kritischen Anwendungen bew\u00e4ltigen k\u00f6nnen. dp polar hat ein sehr einzigartiges System entwickelt, das eine echte Massenproduktion erm\u00f6glicht. Die F\u00e4higkeit, eine breite Palette von Materialien zu drucken, zusammen mit dem modularen Design des Druckers, das mehrere Prozesse in einer Hochgeschwindigkeitsplattform erm\u00f6glicht, erh\u00f6ht nicht nur die Produktivit\u00e4t um Gr\u00f6\u00dfenordnungen, sondern reduziert auch die Gesamtbetriebskosten.&#8220;<\/em> Der Abschluss der Transaktion wird f\u00fcr das vierte Quartal 2022 erwartet. Weitere Informationen zu den beiden \u00dcbernahmen finden Sie in der Pressemitteilung von Stratasys <a href=\"https:\/\/investors.stratasys.com\/news-events\/press-releases\/detail\/792\/stratasys-signs-agreement-to-acquire-covestros-additive\" target=\"_blank\" rel=\"noopener\">HIER<\/a> und von 3D Systems <a href=\"https:\/\/www.3dsystems.com\/press-releases\/3d-systems-accelerate-high-volume-additive-manufacturing-acquisition-dp-polar-gmbh\" target=\"_blank\" rel=\"noopener\">HIER<\/a>.<\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"auto\">Was halten Sie von den \u00dcbernahmen von Stratasys und 3D Systems? <\/span>Lassen Sie uns dazu gerne einen Kommentar da oder teilen Sie es uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/3Dnatives_DE\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\/\">LinkedIN\u00a0<\/a>oder\u00a0<a href=\"https:\/\/www.xing.com\/communities\/groups\/3d-druck-und-additive-fertigung-94e8-1091770\/posts\">Xing<\/a>\u00a0mit. M\u00f6chten Sie au\u00dferdem eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der Additiven Fertigung direkt und bequem in Ihr Postfach erhalten? Dann registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zwei der weltweit gr\u00f6\u00dften Hersteller von 3D-Druckern, Stratasys und 3D Systems, gaben neue \u00dcbernahmen bekannt, die ein Zeichen f\u00fcr das anhaltende Wachstum des 3D-Druckmarktes sind. Stratasys gab als erstes bekannt, dass es eine endg\u00fcltige Vereinbarung zur \u00dcbernahme des Gesch\u00e4ftsbereichs Additive&hellip;<\/p>\n","protected":false},"author":6089,"featured_media":39793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,8],"tags":[],"class_list":["post-39792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/39792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6089"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=39792"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/39792\/revisions"}],"predecessor-version":[{"id":39796,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/39792\/revisions\/39796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/39793"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=39792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=39792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=39792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}