{"id":36880,"date":"2022-05-05T14:00:40","date_gmt":"2022-05-05T12:00:40","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=36880"},"modified":"2022-05-05T11:51:43","modified_gmt":"2022-05-05T09:51:43","slug":"mobile-gantry-kombinierte-technologie-mars-050520221","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/mobile-gantry-kombinierte-technologie-mars-050520221\/","title":{"rendered":"Mobile Gantry: eine kombinierte Technologie, die vielleicht bald das Leben auf dem Mars erm\u00f6glicht?"},"content":{"rendered":"<p style=\"text-align: justify;\">Wir haben erst vor Kurzem dargestellt, wie ein <a href=\"https:\/\/www.3dnatives.com\/de\/wie-dank-des-3d-drucks-der-weltraum-erobert-wird\/\">potenzielles Leben im Weltall<\/a> aussehen k\u00f6nnte. Mit verschiedenen Applikationen wie Raumanz\u00fcge, Lebensr\u00e4ume und auch Pflaster, die allesamt direkt vor Ort 3D-gedruckten werden k\u00f6nnen. Nun haben auch Forscher des Departments of Physics and Engineering der Taylor University in den USA einen mobilen Spezial-3D-Drucker entwickelt. Dieser soll laut eigenen Angaben des Forscherteams, bestehend aus Peter J. Staritz, Caleb S. Miller, Josiah C. McClurg, mehr Flexibilit\u00e4t zum Erschlie\u00dfen des Wohnraums auf dem <a href=\"https:\/\/www.3dnatives.com\/de\/zebro-roboter-mars-besiedelung-150620211\/\">Mars<\/a> beitragen &#8211; ein erster Probedurchlauf mit dem Prototypen ihres Mobile Gantrys wurde bereits erfolgreich durchgef\u00fchrt.<\/p>\n<p style=\"text-align: justify;\">Mit dem Ziel die menschliche Pr\u00e4senz auf dem Mars zu erm\u00f6glichen waren sich die Forscher einig, dass sie das Potenzial der <a href=\"https:\/\/www.3dnatives.com\/de\/additive-fertigung\/\">additiven Fertigungstechnologien<\/a> vollkommen ausgesch\u00f6pft werden muss. Hierf\u00fcr haben sie einen einen Roboter-Ansatz f\u00fcr den 3D-Druck von Habitaten entwickelt, der in der Lage ist, gr\u00f6\u00dfere, st\u00e4rkere und leistungsf\u00e4higere Strukturen herzustellen. Da hierbei gewisse Hindernisse f\u00fcr einen erfolgreichen 3D-Druck erst aus dem Weg ger\u00e4umt werden m\u00fcssen, wurde von Seiten der Forscher eine Kombination aus einem mobilen Roboter und Gantry Robotern kreiert. Der Mobile Gantry 3D-Drucker profitiert daher von der Zusammenf\u00fchrung verschiedener positiven und gewinnbringenden Eigenschaften der beiden Technologien wie beispielsweise sequenzieller Aufbau und parallele Konstruktionen.<\/p>\n<div id=\"attachment_36890\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36890\" class=\"wp-image-36890 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-1.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-1-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-36890\" class=\"wp-caption-text\">K\u00f6nnen wir dank des Mobile Gantrys schon bald auf dem Mars unsere Habitate planen? (Bild: Taylor University)<\/p><\/div>\n<h3>Der Mobile Gantry verbindet die Vorteile zweier Technologien<\/h3>\n<p style=\"text-align: justify;\">Mit den verbundenen Technologien sei man laut Angaben der Forscher in der Lage, effizient Strukturen auf dem Mars in 3D zu drucken, die gr\u00f6\u00dfer als der Mobile Gantry selbst sind. Nicht mehr durch die Gr\u00f6\u00dfe des Roboters begrenzt, kann dieser auch problemlos \u00fcber unebene und unbekannte Planetenoberfl\u00e4chen fahren, was im Umkehrschluss ebenfalls bedeutet, dass er sich auf Oberfl\u00e4chen fortbewegen kann, die er selbst gedruckt hat. Um dies umsetzen zu k\u00f6nnen, druckt der Roboter Strukturen mit W\u00e4nden und inneren Trennw\u00e4nden, auf denen die R\u00e4der ausgerichtet sind. Damit sp\u00e4testens Elon Musks Vorhaben auf dem Mars zu leben vielleicht schon bald umgesetzt werde kann, erm\u00f6glicht der Mobile Gantry die Funktion der parallelen Konstruktion. Konkret bedeutet dies, dass effiziente, aber daf\u00fcr weniger komplexe Konstruktionen von Anlagen durchgef\u00fchrt werden k\u00f6nnen &#8211; gleichzeitig! Durch die parallele Arbeit der Roboter an derselben Struktur kann die Zeit bis zur finalen Fertigstellung des <a href=\"https:\/\/www.3dnatives.com\/de\/deutsch-britisches-forscherteam-arbeitet-an-nachhaltigen-3d-druck-von-beton-210320221\/\">Beton<\/a>-3D-gedruckten Habitats erheblich verk\u00fcrzt werden.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-881358332\"><div id=\"dnati-413514368\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\">Der Prototyp, der den Namen Mud Dauber tr\u00e4gt, wird derzeit an der Taylor University getestet. Mit dem integrierten Mobilit\u00e4tssystem kann der Mobile Gantry selbst auf unebenen Oberfl\u00e4chen drucken und ist dank Positionierungssystem ebenfalls in der Lage den Druckkopf pr\u00e4zise zu positionieren. Insgesamt ist man von der Leistung des Mobile Gantry \u00fcberzeugt, vor allem durch die geringere Steuerungskomplexit\u00e4t kann eine einfache und risikoarme Steuerung mit gleichzeitig hohen Druckgeschwindigkeiten sicher gestellt werden, die zudem \u00fcber eine bessere Druckqualit\u00e4t verf\u00fcgen. Wenn Sie mehr \u00fcber die spannende Arbeit zum zuk\u00fcnftigen Leben auf dem Mars wissen m\u00f6chten, finden Sie <a href=\"https:\/\/engrxiv.org\/preprint\/view\/2313\/4506\" target=\"_blank\" rel=\"noopener\">HIER<\/a> in der Forschungsarbeit weitere Informationen.<\/p>\n<div id=\"attachment_36891\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36891\" class=\"wp-image-36891 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-2.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-2.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-2-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Mobile-Gantry-2-160x91.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-36891\" class=\"wp-caption-text\">So bewegt sich der Mobile Gantry auf der selbst gedruckten Oberfl\u00e4che fort (Bild: Taylor University)<\/p><\/div>\n<p style=\"text-align: justify;\">Was ist Ihre Meinung zum Mobile Gantry und dem Leben auf dem Mars? Teilen Sie uns Ihre Eindr\u00fccke und Erfahrungen mit und kontaktieren Sie uns. M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">\u00a0w\u00f6chentlichen Newsletter<\/a>\u00a0und folgen Sie uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook\u00a0<\/a>und\u00a0<a href=\"https:\/\/twitter.com\/?lang=en\">Twitter<\/a>, um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf\u00a0<a href=\"https:\/\/www.xing.com\/communities\/groups\/3d-druck-und-additive-fertigung-c15a-1091770\">XING\u00a0<\/a>und\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>\u00a0zu finden.<\/p>\n<p><em>*Titelbildnachweis: Taylor University<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir haben erst vor Kurzem dargestellt, wie ein potenzielles Leben im Weltall aussehen k\u00f6nnte. Mit verschiedenen Applikationen wie Raumanz\u00fcge, Lebensr\u00e4ume und auch Pflaster, die allesamt direkt vor Ort 3D-gedruckten werden k\u00f6nnen. Nun haben auch Forscher des Departments of Physics and&hellip;<\/p>\n","protected":false},"author":6089,"featured_media":36889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[9,49,153],"tags":[],"class_list":["post-36880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3d-drucker","category-aktuelles","category-luft-und-raumfahrt"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/36880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6089"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=36880"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/36880\/revisions"}],"predecessor-version":[{"id":36893,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/36880\/revisions\/36893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/36889"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=36880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=36880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=36880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}