{"id":22742,"date":"2020-02-12T00:01:43","date_gmt":"2020-02-11T23:01:43","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=22742"},"modified":"2020-02-12T09:08:13","modified_gmt":"2020-02-12T08:08:13","slug":"22742-2-120220201","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/22742-2-120220201\/","title":{"rendered":"Urwahn Bikes entwickelt 3D-gedrucktes Carbonrad"},"content":{"rendered":"<p style=\"text-align: justify;\">Der in Magdeburg ans\u00e4ssige Hersteller Urwahn Bikes hat unter Zusammenarbeit mit Schmolke Carbon, spezialisiert auf die Herstellung von Carbonr\u00e4dern, einen 3D-gedruckten Fahrradrahmen entwickelt. Dabei handelt es sich nicht um den ersten R\u00fcckgriff Uhrwahn Bikes auf 3D-Technologie zur Optimierung von Fahrradrahmen: ganz im Gegenteil: Bereits 2019 hat das Unternehmen beim Stadtfuchs-Rad mittels 3D-Druck einen Stahlrahmen gedruckt. Nun hat sich das Unternehmen dazu entschieden, das kupferbeschichtete Rad so zu konzipieren, dass die von Schmolke Carbon entwickelten Leichtmetallfasern eingearbeitet werden.<\/p>\n<p style=\"text-align: justify;\">Kohlefaser \u00fcberzeugt durch das Verh\u00e4ltnis von Masse u Festigkeit. So verbessert sie die Widerstandsf\u00e4higkeit eines Teils und wirkt sich dennoch nicht negative auf dessen Gewicht aus. In der 3D-Druckindustrie ist die Kohlefaser das beliebteste Verst\u00e4rkungsmaterial in Verbundwerkstoffen. Immer mehr 3D-Drucker verwenden Kohlefaserverbundwerkstoffe zur Herstellung von Teilen, um deren Eigenschaften zu verbessern.<\/p>\n<div id=\"attachment_19036\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19036\" class=\"wp-image-19036 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/copper-bike.jpg\" alt=\"Urwahn Bikes\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-19036\" class=\"wp-caption-text\">Urwahn Bikes Fahrrad &#8222;Platzhirsch&#8220; (Bildnachweis: Urwahn Bikes)<\/p><\/div>\n<h3>Leistunssteigerung durch besonderes Design<\/h3>\n<p style=\"text-align: justify;\">Das erste, was Ihnen vermutlich beim Betrachten des Urban Bikes &#8222;Platzhirsch&#8220; auff\u00e4llt, ist die Kupferbeschichtung des 3D-gedruckten Stahlrahmens. Neben der ausgefallenen Optik durch die Farbgebung hat dieses Rennrad einen geometrischen Vorteil gegen\u00fcber anderen Fahrr\u00e4dern. Schmolke Carbon erkl\u00e4rt: &#8222;D<em>ie elastische Federung des Hinterrads bietet dem Fahrer zus\u00e4tzlichen Fahrkomfort, ohne dass das Tretlager darunter leidet. Dieser Effekt macht sich vor allem bei l\u00e4ngeren Fahrten und unebenem Untergrund bemerkbar<\/em>&#8222;. Urwahn Bikes gab auch an, dass es in der Lage war, &#8222;j<em>egliche Einschr\u00e4nkungen hinsichtlich der Teilegeometrie zu vermeiden<\/em>&#8222;, indem d\u00fcnnwandige Teile mit der <a href=\"https:\/\/www.3dnatives.com\/de\/selektives-lasersintern\/\">selektiven Lasersintern<\/a> (SLM)-Technologie hergestellt wurden. Diese Designfreiheit erm\u00f6glichte es dem Unternehmen, verschiedene technische Komponenten in den Stahlrahmen zu integrieren, darunter ein LED-Beleuchtungssystem und ein GPS-System.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-2883833712\"><div id=\"dnati-3260407704\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\">Schmolke Carbon lieferte verschiedene zus\u00e4tzliche Teile, darunter den TLO Evo-Lenker und die TLO-Satteleinheit, die auf Leichtbauweise getrimmt wurden. Das Unternehmen entwickelte au\u00dferdem einen 45 mm dicken Carbon-Drahtreifen f\u00fcr das Fahrrad, der aerodynamische Richtungsstabilit\u00e4t und ein geschmeidiges Fahrgef\u00fchl bietet.<\/p>\n<div id=\"attachment_19039\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19039\" class=\"wp-image-19039 size-full\" src=\"https:\/\/www.3dnatives.com\/en\/wp-content\/uploads\/sites\/2\/bike-1-copy.jpg\" alt=\"\" width=\"700\" height=\"400\" \/><p id=\"caption-attachment-19039\" class=\"wp-caption-text\">Ausgefallenes Design (Bildquelle: Urwahn Bikes)<\/p><\/div>\n<p style=\"text-align: justify;\">Urwahn Bikes schreibt auf seiner Webseite: &#8222;<em>Als Technologiepioniere sind wir stetig auf der Suche nach neuen Querdenkern und Kreativen, die uns auf den Weg zur Weltherrschaft begleiten. <\/em><em>Als junges und dynamisches Team setzen wir auf eine flache Hierarchie und transparente Arbeitsstrukturen gepaart mit modernsten Prozessen und Vorgehensmodellen. Interdisziplin\u00e4r erg\u00e4nzt durch eine Vielzahl qualitativer Industrie- und Kooperationspartner, vereinen wir die Produktentwicklung, Fertigung und Produktion sowie die Gesch\u00e4ftsfeldentwicklung unter einem Dach.&#8220;<\/em> Um die Leistungsf\u00e4higkeit des Fahrrads zu testen, haben die Unternehmen schlie\u00dflich den Bahnrad-Weltmeister Stefan B\u00f6tticher damit beauftragt, einige Testfahrten mit dem Rad auf dem Velodrom durchzuf\u00fchren.<\/p>\n<p style=\"text-align: justify;\">Weitere Informationen finden Sie <a href=\"https:\/\/www.urwahnbikes.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a>.<\/p>\n<p style=\"text-align: justify;\">M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-technologies\/\">Additiven Fertigung<\/a>\u00a0direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>\u00a0und folgen Sie uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>\u00a0und\u00a0<a href=\"https:\/\/twitter.com\/3Dnatives_DE\">Twitter<\/a>\u00a0um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>\u00a0und auf\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCFwYeLWwNQbQiz1ZTeQwwlQ?view_as=subscriber\">Youtube<\/a>\u00a0zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der in Magdeburg ans\u00e4ssige Hersteller Urwahn Bikes hat unter Zusammenarbeit mit Schmolke Carbon, spezialisiert auf die Herstellung von Carbonr\u00e4dern, einen 3D-gedruckten Fahrradrahmen entwickelt. Dabei handelt es sich nicht um den ersten R\u00fcckgriff Uhrwahn Bikes auf 3D-Technologie zur Optimierung von Fahrradrahmen:&hellip;<\/p>\n","protected":false},"author":6071,"featured_media":22746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,31],"tags":[],"class_list":["post-22742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-designkunst"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/22742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6071"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=22742"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/22742\/revisions"}],"predecessor-version":[{"id":22766,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/22742\/revisions\/22766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/22746"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=22742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=22742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=22742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}