{"id":20705,"date":"2019-09-12T00:01:39","date_gmt":"2019-09-11T22:01:39","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=20705"},"modified":"2019-09-11T11:40:18","modified_gmt":"2019-09-11T09:40:18","slug":"chinesisches-start-up-erhaelt-investitionen-von-evonik-fuer-herstellung-3d-gedruckter-implantate-120920191","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/chinesisches-start-up-erhaelt-investitionen-von-evonik-fuer-herstellung-3d-gedruckter-implantate-120920191\/","title":{"rendered":"Chinesisches Start-Up Meditool erh\u00e4lt Investitionen von EVONIK f\u00fcr die Herstellung 3D-gedruckter Implantate"},"content":{"rendered":"<p style=\"text-align: justify;\">Evonik, ein 2006 gegr\u00fcndetes deutsches Unternehmen im Bereich der Spezialchemie hat mit seiner Venture Capital Einheit in ein chinesisches 3D-Druck Start-Up mit dem Namen Meditool investiert. Kurz gefasst ist Meditool in der <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-in-der-medizin-170720181\/\">Medizinbranche<\/a> aktiv und stellt mit Hilfe der <a href=\"https:\/\/www.3dnatives.com\/de\/3d-technologies\/\">additiven Fertigung<\/a> Implantate f\u00fcr die Neuro- oder Wirbels\u00e4ulenchirurgie her. Dies soll vor allem f\u00fcr eine deutlich schneller Genesung der Patienten beitragen sowie Risiken bei gef\u00e4hrlichen Operationen verringern.<\/p>\n<p style=\"text-align: justify;\">Evonik Venture Capital hat bereits \u00fcber 25 Investitionen in Direkt- bzw. Fondsanlagen get\u00e4tigt, vor allem in Bereichen wie Health &amp; Care, Smart Materials, Animal Nutrition und Specialty Additives versuchen sie aufstrebende Unternehmen zu unterst\u00fctzen. <em>\u201eDas ist unsere erste Direktinvestition in China und die erste Direktinvestition nach Auflage unseres zweiten Venture Capital Fonds, den wir in diesem Jahr initiiert haben\u201c<\/em>, sagt Bernhard Mohr, Leiter von Evonik Venture Capital. <em>\u201eMeditool ist ein Beleg daf\u00fcr, wie Evonik sich durch Wagniskapital den Zugang zu disruptiven Technologien sichert.&#8220;<\/em><\/p>\n<div id=\"attachment_20707\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20707\" class=\"size-full wp-image-20707\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool1.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool1-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool1-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-20707\" class=\"wp-caption-text\">Meditool zusammen mit Evonik &#8211; Quelle: Evonik<\/p><\/div>\n<p style=\"text-align: justify;\">Meditool hat eine System entwickelt, dass Daten von Patienten aus Magnetresonanztomographen (MRT) und Computertomographen (CT) analysiert und daraus ein 3D-Modell erstellt. Die Modelle werden an den 3D-Drucker gesendet und dann mit dem Hochleistungsmaterial <a href=\"https:\/\/www.3dnatives.com\/de\/experteninterview-hochleistungskunststoffe-230520191\/\">PEEK<\/a>, von Evonik gedruckt.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-2967446114\"><div id=\"dnati-2003855453\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\"><em>\u201eMeditool geh\u00f6rt zu den Vorreitern bei der Entwicklung von 3D-Druckverfahren f\u00fcr medizinische PEEK-Implantate\u201c<\/em>, sagt Ken Jin, Mitbegr\u00fcnder und Chief Technology Officer von Meditool. <em>\u201eEvonik ist dabei unser zuverl\u00e4ssiger Partner f\u00fcr qualitativ hochwertige Materialien. Die Investition gibt uns einen zus\u00e4tzlichen Schub, innovative L\u00f6sungen f\u00fcr Patienten und Chirurgen in China und dem Rest der Welt zu entwickeln.\u201c<\/em><\/p>\n<p style=\"text-align: justify;\">Im Vergleich zu <a href=\"https:\/\/www.3dnatives.com\/de\/ubersicht-hersteller-metall-3d-druck\/\">Metall<\/a>, das zur Zeit f\u00fcr Implantate meist genutzt wird ist die Erstellung per 3D-Druck und dem Material PEEK etwas ganz Neues. Durch die additive Fertigung entstehen zahlreiche neue Optionen, wie beispielsweise eine individuelle Anpassung um die gedruckte Platte genau an den Sch\u00e4del des Patienten abzustimmen. Die Anzahl weiterer Eingriffe soll hierdurch verringert werden, ebenso sind weitere Untersuchen per MRT oder CT m\u00f6glich. Auch was die Temperatur angeht ist PEEK als Material deutlich unempfindlicher als Metall, sodass Sch\u00e4den an lebendem Gewebe verhindert werden k\u00f6nnen.<\/p>\n<div id=\"attachment_20713\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20713\" class=\"size-full wp-image-20713\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool2.jpg\" alt=\"meditool\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool2.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool2-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool2-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/meditool2-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-20713\" class=\"wp-caption-text\">3D-gedrucktes Sch\u00e4delimplantat aus dem Hochleistungsmaterial PEEK &#8211; Quelle: Evonik<\/p><\/div>\n<p>F\u00fcr Meditool ist Evonik der Hauptinvestor mit einem hohen einstelligen Betrag im Millionenbereich. Weitere Investoren sind ZN Ventures, Morningside Ventures und Puhua Capital. Erfahren Sie mehr <a href=\"https:\/\/corporate.evonik.de\/de\/presse\/pressemitteilungen\/pages\/article.aspx?articleId=116818\" target=\"_blank\" rel=\"noopener noreferrer\">HIER<\/a> in der offiziellen Pressemitteilung.<\/p>\n<p><em>Bildquelle Titelbild: Evonik<\/em><\/p>\n<p style=\"text-align: justify;\">Was halten Sie von dieser Investition? Teilen Sie es uns mit und kontaktieren Sie uns. M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>\u00a0und folgen Sie uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>\u00a0und\u00a0<a href=\"https:\/\/twitter.com\/3Dnatives_DE\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a>\u00a0um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>\u00a0zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evonik, ein 2006 gegr\u00fcndetes deutsches Unternehmen im Bereich der Spezialchemie hat mit seiner Venture Capital Einheit in ein chinesisches 3D-Druck Start-Up mit dem Namen Meditool investiert. Kurz gefasst ist Meditool in der Medizinbranche aktiv und stellt mit Hilfe der additiven&hellip;<\/p>\n","protected":false},"author":6066,"featured_media":20714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,8,40],"tags":[],"class_list":["post-20705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-business","category-medizin"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/20705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6066"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=20705"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/20705\/revisions"}],"predecessor-version":[{"id":20716,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/20705\/revisions\/20716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/20714"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=20705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=20705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=20705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}