{"id":19623,"date":"2019-07-31T00:01:32","date_gmt":"2019-07-30T22:01:32","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=19623"},"modified":"2019-06-28T12:26:43","modified_gmt":"2019-06-28T10:26:43","slug":"3d-druck-haare-forschung-310720191","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/3d-druck-haare-forschung-310720191\/","title":{"rendered":"3D-Druck hilft echtes Haar im Labor wachsen zu lassen"},"content":{"rendered":"<p style=\"text-align: justify;\">An der Columbia University in den Vereinigten Staaten nutzte ein Team von Forschern den 3D-Druck, um Haare in einer Petrischale wachsen zu lassen! Die Technologie erlaubte es ihnen, auf einfache Weise Kunststoffformen herzustellen, die dann zum Z\u00fcchten von Haarfollikeln verwendet wurden. Eine wichtige Innovation f\u00fcr den medizinischen Bereich: Es ist sehr schwierig, Echthaar unter Laborbedingungen zu z\u00fcchten.<\/p>\n<p style=\"text-align: justify;\">Schon 2016 berichteten wir, wie der 3D-Druck beim wissenschaftlichen Haarwachstum eingesetzt wurde: Es ging um eine <a href=\"https:\/\/www.3dnatives.com\/de\/loreal-poietis-bekampfung-von-haarausfall-mit-3d-bioprinting-061020161\/\">Partnerschaft zwischen dem Franzosen Poietis und der Gruppe L&#8217;Or\u00e9al<\/a>, die Forschungsarbeiten zum Thema Bio-Print Haare initiiert hatten und damit eine L\u00f6sung f\u00fcr alle Alopeziekranken bietet. Und das ist das Problem, das diese amerikanischen Forscher angehen wollen: Sie haben jedoch einen etwas anderen Ansatz, da sie keine Zellen, sondern nur Plastikformen drucken, die das Wachstum von Haarfollikeln erleichtern.<\/p>\n<div id=\"attachment_19626\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19626\" class=\"size-full wp-image-19626\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux.jpg\" alt=\"\" width=\"700\" height=\"500\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux-600x429.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux-160x114.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux-300x214.jpg 300w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux-100x70.jpg 100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-19626\" class=\"wp-caption-text\">Querschnitt eines Haarfollikels. Bildnachweis: Angela Christiano \/ Columbia University Irving Medical Center.<\/p><\/div>\n<h3 style=\"text-align: justify;\">3D-gedruckte Formen f\u00fcr den Haarwuchs<\/h3>\n<p style=\"text-align: justify;\">Das Team ging von einer klaren Beobachtung aus: Zellen, die von der Basis des menschlichen Haares genommen wurden, wachsen nicht, wenn sie im Labor angebaut werden, im Gegensatz zu Tierhaaren wie M\u00e4usen oder Ratten. Sie sind zu widerstandsf\u00e4hig und w\u00fcrden dann die Rekonstruktion der Kapillaren und Transplantate einschr\u00e4nken. Um dieses Problem zu \u00fcberwinden, schufen die Wissenschaftler eine Kunststoffform welche eine eine nat\u00fcrliche Mikroumgebung reproduzieren soll, die das Wachstum der Haarfollikel stimuliert. Diese Form hat sehr feine kleine, einen halben Millimeter breite Spitzen, in denen die Zellen wachsen. &#8222;<em>Traditionelle Fertigungstechniken waren nicht in der Lage, solche feinen Strukturen zu erzeugen. Diese Arbeit wurde durch die Innovationen der 3D-Drucktechnologie erheblich erleichter<\/em>t&#8220;, erkl\u00e4rt Angela Christiano, die diese Studie gestartet hat.<\/p>\n<div id=\"attachment_19627\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19627\" class=\"size-full wp-image-19627\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux2.jpg\" alt=\"haare\" width=\"700\" height=\"450\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux2.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux2-600x386.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux2-160x103.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/cheveux2-300x193.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-19627\" class=\"wp-caption-text\">Angela Christiano leitet die Forschungsarbeit.<\/p><\/div>\n<p style=\"text-align: justify;\">Das Team erkl\u00e4rt, dass sie Haarfollikelzellen um diese Spitzen und dann \u00fcber ihnen platziert haben. Es sind Zellen, die Keratin produzieren, das Protein, aus dem das Haar hergestellt wird. Nach einer dreiw\u00f6chigen Kultivierungszeit begannen die Haare zu wachsen. Die Formen wurden in 3D auf einem 3D-FDM-Desktopdrucker, genau genommen dem <a href=\"https:\/\/www.3dnatives.com\/de\/3D-compare\/imprimante\/3dwox-2x\">Sindoh 3DWOX<\/a>, gedruckt.<\/p>\n<p style=\"text-align: justify;\">Angela Christiano f\u00e4hrt fort: &#8222;<em>Wir k\u00f6nnen eine Art Haarfarm schaffen, d.h. ein Netzwerk von Haaren, das richtig gestaltet und geformt ist, so dass es in die Kopfhaut desselben Patienten transplantiert werden kann. Die Haarwiederherstellung wird so f\u00fcr alle Patienten, ob m\u00e4nnlich oder weiblich, wesentlich zug\u00e4nglicher. Wir werden nicht mehr durch die Anzahl der Haarspender begrenzt sein &#8211; in der Regel braucht es etwa 2000 gesunde Follikel, um eine erfolgreiche Transplantation durchzuf\u00fchren.<\/em>&#8220; K\u00fcnstliche Follikel k\u00f6nnten auch von der Pharmaindustrie verwendet werden, um neue Medikamente f\u00fcr das Haarwachstum zu erforschen. Weitere Informationen zu dieser Studie finden Sie <a href=\"https:\/\/www.cuimc.columbia.edu\/news\/studies-uncover-new-approaches-combat-hair-loss-men-and-women\" target=\"_blank\" rel=\"noopener noreferrer\">HIER<\/a>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/B39H6R1ZjMo\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p style=\"text-align: justify;\">Was denken Sie \u00fcber diese Anwendung des 3D-Drucks? Teilen Sie uns Ihre Meinung mit und kontaktieren Sie uns. M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>\u00a0und folgen Sie uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>\u00a0und\u00a0<a href=\"https:\/\/twitter.com\/?lang=en\">Twitter\u00a0<\/a>\u00a0um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>\u00a0zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An der Columbia University in den Vereinigten Staaten nutzte ein Team von Forschern den 3D-Druck, um Haare in einer Petrischale wachsen zu lassen! Die Technologie erlaubte es ihnen, auf einfache Weise Kunststoffformen herzustellen, die dann zum Z\u00fcchten von Haarfollikeln verwendet&hellip;<\/p>\n","protected":false},"author":6065,"featured_media":19625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,13],"tags":[],"class_list":["post-19623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-forschung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/19623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6065"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=19623"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/19623\/revisions"}],"predecessor-version":[{"id":19629,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/19623\/revisions\/19629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/19625"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=19623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=19623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=19623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}