{"id":18379,"date":"2019-04-12T00:01:12","date_gmt":"2019-04-11T22:01:12","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=18379"},"modified":"2024-02-20T15:52:40","modified_gmt":"2024-02-20T14:52:40","slug":"arevo-3d-e-bike-rahmen-120420191","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/arevo-3d-e-bike-rahmen-120420191\/","title":{"rendered":"AREVO bringt 3D-gedruckten E-Bikerahmen auf den Markt"},"content":{"rendered":"<p style=\"text-align: justify;\">Emery, ein kalifornisches Unternehmen f\u00fcr Elektromobilit\u00e4t, k\u00fcndigte die Markteinf\u00fchrung seines Emery ONE eBike an, ein 3D-gedrucktes E-Bike in Zusammenarbeit mit Franco Bicyles und dem jungen Unternehmen AREVO, das bereits im vergangenen Jahr sein Konzept f\u00fcr einen Karbonfaserrahmen vorgestellt hatte. Emery pr\u00e4sentiert erstmals einen 3D-gedruckten Monocoque Rahmen, ebenfalls aus Kohlefaser. Das E-Bike wird derzeit auf der Sea Otter Classic in Monterey bis zum 14. April vorgestellt. Bereits 2017 berichteten wir \u00fcber ein <a href=\"https:\/\/www.3dnatives.com\/de\/vw-druckt-elektrofahrrad-in-3d-271020171\/\">3D-gedrucktes E-Bike von VW<\/a>.<\/p>\n<p style=\"text-align: justify;\">Das Start-Up AREVO hatte mit seiner neuen additiven Fertigungsplattform, die es erm\u00f6glichte, ein komplettes E-Bike in nur 18 Tagen zu entwerfen und gleichzeitig eine gewisse Komplexit\u00e4t im Design zu bieten, f\u00fcr Schlagzeilen gesorgt.&nbsp; Das Unternehmen nutzte diese Einf\u00fchrung, um 12,5 Millionen Dollar zu sammeln, und zeigte damit deutlich seinen Wunsch, sein Know-how zu erweitern und die 3D-Technologien in diesem Bereich voranzutreiben. Eine Strategie, die sich auszahlt, da Arevo jetzt eine neue Partnerschaft mit Emery eingeht, um ein erstes 3D-gedrucktes E-Bike zu entwickeln.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18382 aligncenter\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bike1-1.jpg\" alt=\"arevo\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bike1-1.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bike1-1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bike1-1-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bike1-1-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Die Technologie von AREVO hat es daher erm\u00f6glicht, einen Schalenbau Fahrradrahmen herzustellen: Durch den Druck in einem St\u00fcck und nicht durch die Montage verschiedener Verbundkomponenten hat das Unternehmen eine \u00fcberlegene strukturelle Stabilit\u00e4t f\u00fcr dieses E-Bike erreicht. Zus\u00e4tzlich zu diesen Leistungsvorteilen ist der 3D-gedruckte Rahmen billiger und schneller zu produzieren. Das Elektrofahrrad wird mit dem eBike-Antriebsstrang von Bosch ausgestattet sein, der \u00fcber ein 45 km\/h starkes elektrisches Hilfspedal verf\u00fcgt.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-1922565693\"><div id=\"dnati-4212045930\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\">Hector Rodriguez, Mitgr\u00fcnder und CEO von Franco Bicycles and Emery, erkl\u00e4rt: &#8222;<em>Der 3D-Druckprozess von Arevo hat uns mit seiner F\u00e4higkeit beeindruckt, Konzepte w\u00e4hrend der Produktentwicklung zu wiederholen und schnell zu validieren. Aber auch die Verlagerung der Produktion nach Kalifornien und die Geschwindigkeit, mit der wir Produkte vermarkten k\u00f6nnen spielen eine Rolle. W\u00e4hrend all diese Vorteile wichtig sind, ist die Hauptsache, dass das Fahrrad eine hohe Leistung hat und dies auf globaler Ebene. Arevos Fachwissen und die kontinuierliche Kohlefasertechnologie haben entscheidend dazu beigetragen, die hohen Leistungs- und Fahrqualit\u00e4tsanforderungen zu erf\u00fcllen, die wir an Emery ONE gestellt haben.<\/em>&#8222;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/3MbOL0M2k20\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">Die Wahl der Kohlefaser ist kein Zufall , da dass das Material vergleichbare Eigenschaften mit Stahl aufweist und gleichzeitig viel leichter ist. Dies ist eine wichtige Eigenschaft bei der Herstellung eines Fahrrads. Weitere Informationen finden Sie <a href=\"https:\/\/arevo.com\/\" target=\"_blank\" rel=\"noopener\">HIER<\/a>.<\/p>\n<p style=\"text-align: justify;\">Was halten Sie von dem E-Bike? Teilen Sie uns Ihre Meinung mit und kontaktieren Sie uns. M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren&nbsp;<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>&nbsp;und folgen Sie uns auf&nbsp;<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook&nbsp;<\/a>und&nbsp;<a href=\"https:\/\/twitter.com\/?lang=en\">Twitter<\/a>, um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf&nbsp;<a href=\"https:\/\/www.xing.com\/communities\/groups\/3d-druck-und-additive-fertigung-c15a-1091770\">XING&nbsp;<\/a>und&nbsp;<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>&nbsp;zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emery, ein kalifornisches Unternehmen f\u00fcr Elektromobilit\u00e4t, k\u00fcndigte die Markteinf\u00fchrung seines Emery ONE eBike an, ein 3D-gedrucktes E-Bike in Zusammenarbeit mit Franco Bicyles und dem jungen Unternehmen AREVO, das bereits im vergangenen Jahr sein Konzept f\u00fcr einen Karbonfaserrahmen vorgestellt hatte. Emery&hellip;<\/p>\n","protected":false},"author":6065,"featured_media":18381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,152,41],"tags":[],"class_list":["post-18379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-automotive","category-transport"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/18379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6065"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=18379"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/18379\/revisions"}],"predecessor-version":[{"id":18384,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/18379\/revisions\/18384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/18381"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=18379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=18379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=18379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}