{"id":18067,"date":"2019-03-26T15:18:46","date_gmt":"2019-03-26T14:18:46","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=18067"},"modified":"2019-03-26T15:18:48","modified_gmt":"2019-03-26T14:18:48","slug":"3d-hubs-finanzierung-260320191","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/3d-hubs-finanzierung-260320191\/","title":{"rendered":"3D Hubs: 18 Mio USD Wachstumsfinanzierungen f\u00fcr Ausbau autonomer Fertigungsplattform"},"content":{"rendered":"<p style=\"text-align: justify;\">Die Online-Service-Plattform 3D Hubs gab heute die von Endeit Capital geleitete Series-C-Runde in H\u00f6he von 18 Mio USD bekannt. Diese Runde des Unternehmens, welche die bisher gr\u00f6\u00dfte war, vereint die gesamten Finanzmittel von 30 Mio USD unter der Beteiligung von Hearst ventures, EQT Venture, Balderton Capital, Arthur Kosten, dem Gr\u00fcnder von Booking.com) und Erik de Bruijn, dem Gr\u00fcnder von <a href=\"https:\/\/www.3dnatives.com\/de\/3D-compare\">Ultimaker<\/a>. Dies \u00fcbertrifft die Finanzierungsrunde von <a href=\"https:\/\/www.3dnatives.com\/de\/3d-hubs-7-mio-in-3d-druck-plattform-040820161\/\">2016<\/a> bei weitem.<\/p>\n<p style=\"text-align: justify;\">Die Wachstumsfinanzierung soll dazu eingesetzt werden, die Outsourcing-L\u00f6sung f\u00fcr die Fertigung weiter zu automatisieren sowie die Angebotserstellung, Designvalidierung und das intelligente Order-Routing an das globale Lieferantennetzwerk des Unternehmens weiter voranzutreiben. Au\u00dferdem soll die Pr\u00e4senz des Unternehmens in den USA mit einer neuen Niederlassung ausgebaut werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18070 aligncenter\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/hubs1.jpg\" alt=\"3d hubs\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/hubs1.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/hubs1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/hubs1-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/hubs1-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">3D-Hubs ist eine Plattform, welche es seinen Kunden erm\u00f6glicht, ihre CAD-Dateien f\u00fcr ein sofortiges Angebot mit weniger Vorlaufzeit hochzuladen, bevor im Backend automatisch ein Anbieter beschafft wird. Normalerweise dauert ein solcher Vorgang mehrere Wochen, kann aber laut 3D Hubs so in wenigen Minuten abgeschlossen werden. 3D Hubs hat Zulieferer auf vier Kontinenten und versorgt Unternehmen aus den Branchen Luft- und Raumfahrt, Energie, Gesundheitswesen und Robotik mit additive gefertigten Teilen. Au\u00dferdem spezialisierte sich die Plattform in den letzten beiden Jahren auch auf CNC-Bearbeitung und Spritzgie\u00dfen.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-4050475163\"><div id=\"dnati-1380862749\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<div id=\"attachment_18072\" style=\"width: 292px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-18072\" class=\" wp-image-18072\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram.jpg\" alt=\"3d hubs\" width=\"282\" height=\"282\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram.jpg 400w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram-300x300.jpg 300w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram-160x160.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram-150x150.jpg 150w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram-109x109.jpg 109w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram-100x100.jpg 100w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/bram-65x65.jpg 65w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><p id=\"caption-attachment-18072\" class=\"wp-caption-text\">Gr\u00fcnder Bram de Zwart<\/p><\/div>\n<p style=\"text-align: justify;\">Bram de Zwart, der Mitgr\u00fcnder und CEO von 3D Hubs sagt: \u201e<em>3D Hubs ist bestrebt, die 13-Billionen-Dollar-Fertigungsindustrie radikal zu innovieren \u2013 durch die Erstellung von Preis- und Herstellbarkeitsalgorithmen, die das gleiche Potenzial wie die Suchalgorithmen von Google haben sollen.<\/em>&#8222;<\/p>\n<p style=\"text-align: justify;\">&#8222;<em>Dank unserer Algorithmen sind 93 % der Fertigungsauftr\u00e4ge vollst\u00e4ndig automatisiert, sodass wir die Teile im Durchschnitt doppelt so schnell in die H\u00e4nde unserer Kunden bekommen. Diese letzte Finanzierungsrunde wird uns in die Lage versetzen, das Outsourcing in der Fertigung noch intelligenter und einfacher zu gestalten \u2013 f\u00fcr uns eine au\u00dferordentlich spannende Zeit<\/em>\u201c, f\u00fcgt der Gr\u00fcnder hinzu.<\/p>\n<p style=\"text-align: justify;\">Was denken Sie \u00fcber diese Finanzierungsrunde? Teilen Sie uns Ihre Meinung mit und kontaktieren Sie uns. M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>\u00a0und folgen Sie uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/?lang=en\">Twitter\u00a0<\/a>und\u00a0<a href=\"https:\/\/plus.google.com\/b\/110137870176740423201\/\">Google+<\/a>, um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf\u00a0<a href=\"https:\/\/www.xing.com\/communities\/groups\/3d-druck-und-additive-fertigung-c15a-1091770\">XING\u00a0<\/a>und\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>\u00a0zu finden.<\/p>\n<p style=\"text-align: justify;\">\u00a0Bildnachweise: 3D Hubs<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Online-Service-Plattform 3D Hubs gab heute die von Endeit Capital geleitete Series-C-Runde in H\u00f6he von 18 Mio USD bekannt. Diese Runde des Unternehmens, welche die bisher gr\u00f6\u00dfte war, vereint die gesamten Finanzmittel von 30 Mio USD unter der Beteiligung von&hellip;<\/p>\n","protected":false},"author":6065,"featured_media":18069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,8],"tags":[],"class_list":["post-18067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/18067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6065"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=18067"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/18067\/revisions"}],"predecessor-version":[{"id":18074,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/18067\/revisions\/18074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/18069"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=18067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=18067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=18067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}