{"id":14256,"date":"2018-09-21T00:01:23","date_gmt":"2018-09-20T22:01:23","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=14256"},"modified":"2018-09-20T14:18:05","modified_gmt":"2018-09-20T12:18:05","slug":"3d-gedruckte-sohlen","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/3d-gedruckte-sohlen\/","title":{"rendered":"3D-gedruckte Sohlen erm\u00f6glichen intensives Training"},"content":{"rendered":"<p style=\"text-align: justify;\">Wer schon einmal am Strand entlang gejoggt ist wei\u00df, wie anstrengend das ist. Der Ausblick mag sch\u00f6n sein, doch der Sand unter den F\u00fc\u00dfen macht das Ganze deutlich kraftaufw\u00e4ndiger. F\u00fcr Athleten ist das sogenannte Sandd\u00fcnen Training sehr attraktiv. Diese intensive \u00dcbung erzielt schon nach relativ kurze kurzer Zeit effektive Ergebnisse.<\/p>\n<p style=\"text-align: justify;\">Um diese Disziplin auch an anderen Orten nachahmen zu k\u00f6nnen, arbeitete Adidas mit Aarish Netarwala zusammen und erstellte \u201eThe Grit\u201c mit einer speziellen, 3D-gedruckten Sohle.<\/p>\n<h3>Additive Fertigung f\u00fcr die Herstellung von Sportschuhen<\/h3>\n<p style=\"text-align: justify;\">Die 3D-Technologie ist im Bereich der Mode nichts Neues mehr. Viele Designer nutzen den 3D-Druck f\u00fcr Ihre Kollektionen. Und gerade bei Sportschuhen scheint das Potenzial jedoch gro\u00df zu sein. Nike fertigte bereits <a href=\"https:\/\/www.3dnatives.com\/de\/nike-3d-druck-schuhe-120620171\/\">3D-gedruckte Sportschuhe<\/a>\u00a0und Reebok er\u00f6ffnete die <a href=\"https:\/\/www.3dnatives.com\/de\/liquid-factory-reebok-241020161\/\">Liquid Factory<\/a> f\u00fcr die Produktion 3D-gedruckter Schuhe.<\/p>\n<p style=\"text-align: justify;\">Der gro\u00dfe Vorteil eines 3D-gedruckten Sportschuhs ist die M\u00f6glichkeit, den Schuh an seinen Tr\u00e4ger anatomisch genau anzupassen. Dies geschieht zumeist durch 3D-gedruckte Sohlen, welche individuell f\u00fcr die Kunden gemacht werden. Dadurch steigt der Komfort f\u00fcr den Tr\u00e4ger erheblich und der Sport wird dementsprechend attraktiver.<\/p>\n<p style=\"text-align: justify;\">Auch Adidas nutzt den 3D-Druck innerhalb der <a href=\"https:\/\/www.3dnatives.com\/de\/adidas-speedfactory-190120171\/\">SpeedFactory<\/a>, in welcher haupts\u00e4chlich 3D-Drucker als Produktionsmittel eingesetzt werden.<\/p>\n<p style=\"text-align: justify;\">Nun setzt sich Adidas zusammen mit Aarish Netarwala an ein neues Projekt: The Grit. Dieses neue Schuhkonzept wurde speziell daf\u00fcr designed, dass es das widerstandsf\u00e4hige Training beim Laufen auf dem Sand simuliert.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14261 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas.jpg\" alt=\"3D-gedruckte Sohlen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Die Idee kam Arisha Netarwala, als er einige Athleten beim Training in den Sandd\u00fcnen beobachtete. \u201eAls ich erfuhr, dass im Sandd\u00fcnen-Park eine gro\u00dfe Nachfrage nach Bewegung bestand, wollte ich verstehen, warum die Menschen zu dieser scheinbar anstrengenden und schwierigen \u00dcbungsmethode str\u00f6mten\u201c, so der Designer.<\/p>\n<p style=\"text-align: justify;\">Das Laufen auf Sand ist zwar unangenehm, baut jedoch deutlich mehr Beinkraft in k\u00fcrzerer Zeit auf und reduziert dennoch die Muskelschmerzen nach dem Training. Diese effektive Methode war die Inspiration f\u00fcr The Grit.<\/p>\n<p style=\"text-align: justify;\">Zun\u00e4chst experimentierte Netarwala mit Sandbeuteln an der Sohle des Laufschuhs herum um die Instabilit\u00e4t und Dynamik der Bewegung im Sand zu verstehen. Es folgten einige Prototypen, bis er zu der Entwicklung der 3D-gedruckten Gittersohle kam.<\/p>\n<div id=\"attachment_14260\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14260\" class=\"wp-image-14260 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas2-1.jpg\" alt=\"3D-gedruckte Sohlen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas2-1.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas2-1-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas2-1-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/adidas2-1-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-14260\" class=\"wp-caption-text\">Die 3D-gedruckten Sohlen erm\u00f6glichen ein intensives Training<\/p><\/div>\n<h3>Wie simuliert die 3D-gedruckte Sohlen das Sandd\u00fcnen Training?<\/h3>\n<p style=\"text-align: justify;\">Wenn der Fu\u00df auf dem Boden auftritt, absorbiert die Gittersohle den Aufprall. Im weitern Verlauf verlagert der L\u00e4ufer sein Gewicht auf die Vorderseite des Fu\u00dfes. Hier sinkt die Sohle ein. Die Vorw\u00e4rtsbewegung des Tr\u00e4gers wird so verringert und es entsteht ein h\u00f6herer Widerstand. Beim Anheben des Fu\u00dfes nimmt der Schuh wieder seine urspr\u00fcngliche Form an.<\/p>\n<p style=\"text-align: justify;\">Diese Simulation erh\u00f6ht die ben\u00f6tigte Energie, l\u00e4sst die Muskeln schneller erm\u00fcden und sorgt so f\u00fcr ein intensiveres Training in k\u00fcrzerer Zeit.<\/p>\n<h3 style=\"text-align: justify;\">Der Aufbau von The Grit<\/h3>\n<p style=\"text-align: justify;\">Die 3D-gedruckte Gittersohle besteht aus recyceltem, aber dennoch widerstandsf\u00e4higem und strapazierbarem Elasomer-Polyurethan. Die Gitterstruktur ist der Teil des Schuhs, welche den Tr\u00e4ger destabilisiert und so das Laufen auf dem Sand simuliert.<\/p>\n<p style=\"text-align: justify;\">Der Rest des Schuhs wurde aus dem Adidas Primeknit Material gedruckt. Beide Teile k\u00f6nnen einfach zusammengen\u00e4ht werden.<\/p>\n<p style=\"text-align: justify;\">Noch gibt es kein offizielles Datum, wann der Schuh verf\u00fcgbar sein soll. Bis dahin k\u00f6nnen Sie sich weitere Informationen zu dem Projekt auf der <a href=\"https:\/\/www.aarishnetarwala.com\/#\/grit\/\" target=\"_blank\" rel=\"noopener\">Website<\/a> von Aarish Netarwala ansehen.<\/p>\n<p style=\"text-align: justify;\">3D-gedruckte Sohlen f\u00fcr Sandd\u00fcnen Training wo Sie wollen, w\u00fcrden Sie es ausprobieren?\u00a0Teilen Sie uns Ihre Meinung mit und kontaktieren Sie uns. M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>\u00a0und folgen Sie uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/?lang=en\">Twitter\u00a0<\/a>und\u00a0<a href=\"https:\/\/plus.google.com\/b\/110137870176740423201\/\">Google+<\/a>, um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf\u00a0<a href=\"https:\/\/www.xing.com\/communities\/groups\/3d-druck-und-additive-fertigung-c15a-1091770\">XING\u00a0<\/a>und\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>\u00a0zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer schon einmal am Strand entlang gejoggt ist wei\u00df, wie anstrengend das ist. Der Ausblick mag sch\u00f6n sein, doch der Sand unter den F\u00fc\u00dfen macht das Ganze deutlich kraftaufw\u00e4ndiger. F\u00fcr Athleten ist das sogenannte Sandd\u00fcnen Training sehr attraktiv. Diese intensive&hellip;<\/p>\n","protected":false},"author":6061,"featured_media":14258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,43],"tags":[],"class_list":["post-14256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-art-design"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/14256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6061"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=14256"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/14256\/revisions"}],"predecessor-version":[{"id":14765,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/14256\/revisions\/14765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/14258"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=14256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=14256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=14256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}