{"id":13958,"date":"2018-08-13T00:01:12","date_gmt":"2018-08-12T22:01:12","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=13958"},"modified":"2018-08-29T11:51:16","modified_gmt":"2018-08-29T09:51:16","slug":"3d-druck-in-flugzeugen-110920181","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/3d-druck-in-flugzeugen-110920181\/","title":{"rendered":"3D-Druck in Flugzeugen: leichter, kosteng\u00fcnstiger, schneller"},"content":{"rendered":"<p style=\"text-align: justify;\">Auch f\u00fcr Fluggesellschaften werden die Techniken der additiven Fertigung immer interessanter. Gerade f\u00fcr die Reduktion der Lagerbest\u00e4nde und des Gewichtes bietet der 3D-Druck in Flugzeugen diverse Verbesserungsm\u00f6glichkeiten. Unternehmen wie Emirates und Airbus sind schon dabei, 3D-Technologien zu integrieren und es wurden bereits <a href=\"\/de\/airbus-titanbauteil180920171\/\" target=\"_blank\" rel=\"noopener\">3D gedruckte Titanbauteile serienm\u00e4\u00dfig in die A350 von Airbus verbaut<\/a>. .<\/p>\n<p style=\"text-align: justify;\">Durch die Partnerschaft mit Zenith Tecnia steigt auch Air New Zealand in den 3D-Druck von Flugzeugteilen ein. Das neue Partnerunternehmen hat sich zumeist auf die Entwicklung und Herstellung von 3D gedrucktem Titan und anderen Metallen spezialisiert und benutzt vor allem <a href=\"\/de\/elektronenstrahl-schmelzen\/\">Elektronenstrahlschmelze-Technologie (EBM)<\/a>.<\/p>\n<p style=\"text-align: justify;\">Insgesamt sollen bei diesem Projekt 3D gedruckte Materialteile f\u00fcr Flugzeuge und Werkzeuge untersucht werden.<\/p>\n<h3 style=\"text-align: justify;\">3D-Druck in Flugzeugen: die komplette Innenausstattung<\/h3>\n<p style=\"text-align: justify;\">Die Innenausstattung eines Flugzeuges besteht aus zehntausenden von Teilen und bietet eine gro\u00dfe Spannbreite f\u00fcr Einsatzm\u00f6glichkeiten des 3D-Drucks. W\u00e4hrend die traditionelle Fertigungsmethode mit Verz\u00f6gerungen bei der Lieferung verbunden sein kann und dazu noch deutlich teurer als das additive Verfahren ist, hat der 3D-Druck deutliche Vorteile.<\/p>\n<p style=\"text-align: justify;\">Hinzu kommt, dass keine Einbu\u00dfen in der Qualit\u00e4t gemacht werden m\u00fcssen. Sicherheit, Festigkeit und Haltbarkeit sind bei den 3D gedruckten Teilen ebenso effizient und es kann vor allem vergleichsweise schnell ein Ersatzteil gedruckt werden. Bei der traditionellen Fertigung w\u00fcrde dieses erst geliefert und zuvor bereits gelagert worden sein.<\/p>\n<p style=\"text-align: justify;\">Das Projekt konzentriert sich dabei vor allem darauf, mit der neuen Technologie Kosten und Zeit zu sparen. Hierf\u00fcr wurden bereits einige kleine Anwendungen gefunden. Von verbesserten Kleinteile der Bildschirme bis hin zu Cocktailschalen und Weink\u00fchler f\u00fcr die Business Class.<\/p>\n<div id=\"attachment_13965\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13965\" class=\"wp-image-13965 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Weinku\u0308hlerdingen.jpg\" alt=\"3D-Druck in Flugzeugen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Weinku\u0308hlerdingen.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Weinku\u0308hlerdingen-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Weinku\u0308hlerdingen-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Weinku\u0308hlerdingen-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-13965\" class=\"wp-caption-text\">Ein 3D gedruckter Weinbel\u00fcfter f\u00fcr die Businees Premier Sitze<\/p><\/div>\n<p style=\"text-align: justify;\">Die herunterklappbaren Cocktailschalen beim Business Premier Sitz wurde in Zusammenarbeit mit der Auckland University entwickelt. Weiterhin arbeitet die Fluggesellschaft mit vielen weiteren Organisationen an solchen Innovationen.<\/p>\n<p style=\"text-align: justify;\">Das neuseel\u00e4ndische Unternehmen berichtet von der Zusammenarbeit mit ST Engineering Aerospace, der Victoria University of Wellington und anderen Technologieunternehmen. Es soll alles ausprobiert und damit die Grenzen der neuen Prozesse untersucht werden.<\/p>\n<h3 style=\"text-align: justify;\">Die Nutzung von 3D-Druck in Flugzeugen spart bereits Millionen Dollar<\/h3>\n<p style=\"text-align: justify;\">Air New Zealand ist nicht das erste Unternehmen, welches den 3D-Druck in Flugzeugen einsetzt und damit effektive Verbesserungen erreicht.<\/p>\n<p style=\"text-align: justify;\">Etihad Airways stellte bereits auf der Global Manufacturing and Industrialization Summit ihr neues 3D gedrucktes Flugzeuginterieur vor.<\/p>\n<p style=\"text-align: justify;\">Airbus arbeitete mit der Technischen Universit\u00e4t Chemnitz an einem 3D gedruckten Spoilerantrieb aus Metall f\u00fcr seine A380-Flugzeuge, welche tats\u00e4chlich 35% leichter waren, als die herk\u00f6mmlichen Antriebe.<\/p>\n<p style=\"text-align: justify;\">Andreas Bastian, Autodesk Designer erstellte Flugzeugsitze in 3D, die mit verbessertem Design auch noch 56% leichter waren.<\/p>\n<div id=\"attachment_13964\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13964\" class=\"wp-image-13964 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/leichter-Rahmen.jpg\" alt=\"3D-Druck in Flugzeugen\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/leichter-Rahmen.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/leichter-Rahmen-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/leichter-Rahmen-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/leichter-Rahmen-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-13964\" class=\"wp-caption-text\">Andreas Bastian demonstriert die Leichtigkeit der neuen Materialien<\/p><\/div>\n<p style=\"text-align: justify;\">Im Gegensatz zur traditionellen Fertigung m\u00fcssen weiterhin keine gro\u00dfen Lagerbest\u00e4nde f\u00fcr Ersatzteile erstellt und gelagert werden.<\/p>\n<p style=\"text-align: justify;\">Die immer fortschrittlichere Gewichtsreduktion soll die Kraftstoffemission der Flugzeuge minimieren. Dies senkt zum einen die Kosten der Flugzeuge und sch\u00fctzt zudem die Umwelt.<\/p>\n<p style=\"text-align: justify;\">Weitere Informationen zu dem neuen Projekt finden Sie unter den offiziellen Websiten von<a href=\"https:\/\/www.airnewzealand.co.nz\/\" target=\"_blank\" rel=\"noopener\"> Air New Zealand <\/a>und <a href=\"http:\/\/zenithtecnica.com\/\" target=\"_blank\" rel=\"noopener\">Zenith Tecnia<\/a>.<\/p>\n<p style=\"text-align: justify;\">Der 3D-Druck in Flugzeugen bietet eine gro\u00dfe Bandbreite an Chancen. Wie weit wird das wirklich gehen?\u00a0Teilen Sie uns Ihre Meinung mit und kontaktieren Sie uns. M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren\u00a0<a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a>\u00a0und folgen Sie uns auf\u00a0<a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/?lang=en\">Twitter\u00a0<\/a>und\u00a0<a href=\"https:\/\/plus.google.com\/b\/110137870176740423201\/\">Google+<\/a>, um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf\u00a0<a href=\"https:\/\/www.xing.com\/communities\/groups\/3d-druck-und-additive-fertigung-c15a-1091770\">XING\u00a0<\/a>und\u00a0<a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a>\u00a0zu finden.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch f\u00fcr Fluggesellschaften werden die Techniken der additiven Fertigung immer interessanter. Gerade f\u00fcr die Reduktion der Lagerbest\u00e4nde und des Gewichtes bietet der 3D-Druck in Flugzeugen diverse Verbesserungsm\u00f6glichkeiten. Unternehmen wie Emirates und Airbus sind schon dabei, 3D-Technologien zu integrieren und es&hellip;<\/p>\n","protected":false},"author":6061,"featured_media":13967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[49,8],"tags":[],"class_list":["post-13958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/13958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6061"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=13958"}],"version-history":[{"count":2,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/13958\/revisions"}],"predecessor-version":[{"id":14293,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/13958\/revisions\/14293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/13967"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=13958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=13958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=13958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}